{"id":11539,"date":"2014-03-06T19:34:59","date_gmt":"2014-03-06T14:04:59","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=11539"},"modified":"2014-03-06T19:34:59","modified_gmt":"2014-03-06T14:04:59","slug":"%d9%85%d9%88%d8%b3%db%8c%d9%82%d8%a7%d8%b1-%d8%b1%d9%88%db%8c-%d8%b4%d9%86%da%a9%d8%b1-%da%a9%db%92-%db%8c%d9%88%d9%85-%d9%88%d9%81%d8%a7%d8%aa-%d9%be%d8%b1-%d8%ae%d8%b5%d9%88%d8%b5%db%8c-%d9%be%db%8c","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d9%85%d9%88%d8%b3%db%8c%d9%82%d8%a7%d8%b1-%d8%b1%d9%88%db%8c-%d8%b4%d9%86%da%a9%d8%b1-%da%a9%db%92-%db%8c%d9%88%d9%85-%d9%88%d9%81%d8%a7%d8%aa-%d9%be%d8%b1-%d8%ae%d8%b5%d9%88%d8%b5%db%8c-%d9%be%db%8c\/","title":{"rendered":"\u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u0631\u0648\u06cc \u0634\u0646\u06a9\u0631 \u06a9\u06d2 \u06cc\u0648\u0645 \u0648\u0641\u0627\u062a \u067e\u0631 \u062e\u0635\u0648\u0635\u06cc \u067e\u06cc\u0634\u06a9\u0634"},"content":{"rendered":"<p style=\"text-align: right;\"><a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/03\/Ravi-Shankar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"Ravi Shankar\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/03\/Ravi-Shankar.jpg\" width=\"229\" height=\"172\" \/><\/a>\u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u062f\u0631\u062c\u0646 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u0627\u06cc\u0633\u06d2 \u06c1\u0648\u0626\u06d2 \u06c1\u06cc\u06ba \u062c\u0646 \u06a9 \u0645\u0648\u0633\u06cc\u0642\u06cc \u06a9\u0627 \u062c\u0627\u062f\u0648 \u0627\u0653\u062c \u0628\u06be\u06cc \u0628\u0631\u0642\u0631\u0627\u0631 \u06c1\u06d2\u06d4 \u0627\u0646\u06c1\u06cc\u06ba \u0627\u06cc\u06a9 \u062f\u0631\u062c\u0646 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0646\u0648\u0634\u0627\u062f\u060c\u0627\u06cc\u0633 \u0688\u06cc \u0628\u0631\u0645\u0646 \u060c \u0645\u062f\u0646 \u0645\u0648\u06c1\u0646 \u060c\u0627\u0648\u067e\u06cc \u0646\u06cc\u0631 \u060c\u0631\u0648\u0634\u0646\u060c\u062e\u06cc\u0627\u0645 \u060c\u0634\u0646\u06a9\u0631 \u062c\u0626\u06d2 \u06a9\u0634\u0646 \u060c\u06a9\u0644\u06cc\u0627\u0646 \u062c\u06cc \u0627\u0653\u0646\u0646\u062f \u062c\u06cc \u060c \u0644\u06a9\u0634\u0645\u06cc \u06a9\u0627\u0646\u062a \u067e\u06cc\u0627\u0631\u06d2 \u0644\u0627\u0644 \u0648\u063a\u06cc\u0631\u06c1 \u06a9\u06cc \u0641\u06c1\u0631\u0633\u062a \u0645\u06cc\u06ba \u0631\u0648\u06cc \u0634\u0646\u06a9\u0631 \u06a9\u0627 \u0628\u06be\u06cc \u0646\u0627\u0645 \u0627\u0653\u062a\u0627 \u06c1\u06d2\u06d4 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u0631\u0648\u06cc \u0634\u0646\u06a9\u0631 \u06a9\u0627 \u067e\u0648\u0631\u0627 \u0646\u0627\u0645 \u0631\u0648\u06cc \u0634\u0646\u06a9\u0631 \u0634\u0631\u0645\u0627 \u06c1\u06d2\u06d4 \u0644\u06cc\u06a9\u0646 \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u0645\u06cc\u06ba \u06cc\u06c1 \u0641\u0642\u0637 \u0631\u0648\u06cc \u06a9\u06d2 \u0646\u0627\u0645 \u0633\u06d2 \u062c\u0627\u0646\u06d2 \u062c\u0627\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4<br \/>\n\u0627\u067e\u0646\u06cc \u067e\u0631\u06a9\u0634\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0633\u06d2 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u0686\u0627\u0631 \u062f\u06c1\u0627\u0626\u06cc \u062a\u06a9 \u0646\u0627\u0638\u0631\u06cc\u0646 \u06a9\u0648 \u062f\u06cc\u0627\u0648\u0646\u06c1 \u0628\u0646\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0631\u0648\u06cc \u06a9\u0627 \u0646\u0627\u0645 \u0627\u06cc\u06a9 \u0627\u06cc\u0633\u06d2 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u06cc\u0627\u062f \u06a9\u06cc\u0627 \u062c\u0627\u062a\u0627\u06c1\u06d2 \u062c\u0646 \u06a9\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u0633\u06d2 \u0627\u0653\u0631\u0627\u0633\u062a\u06c1 \u0646\u063a\u0645\u0648\u06ba \u06a9\u0648 \u0633\u0646 \u06a9\u0631 \u0646\u0627\u0638\u0631\u06cc\u0646 \u06a9\u06d2 \u062f\u0644 \u0633\u06d2 \u0635\u0631\u0641 \u0627\u06cc\u06a9 \u06c1\u06cc \u0627\u0653\u0648\u0627\u0632 \u0646\u06a9\u0644\u062a\u06cc \u06c1\u06d2 \u062c\u0648 \u0628\u06be\u06cc \u06c1\u0648\u062a\u0645 \u062e\u062f\u0627 \u06a9\u06cc \u0642\u0633\u0645 \u0644\u0627\u062c\u0648\u0627\u0628 \u06c1\u0648\u06d4 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u0631\u0648\u06cc \u06a9\u0627 \u0646\u0627\u0645 \u0631\u0648\u06cc \u0634\u0646\u06a9\u0631 \u0634\u0631\u0645\u0627 \u06c1\u06d2 \u0627\u0646 \u067e\u06cc\u062f\u0627\u0626\u0634 \u062a\u06cc\u0646 \u0645\u0627\u0631\u0686 \u06f1\u06f9\u06f2\u06f6\u0621 \u06a9\u0648 \u06c1\u0648\u0626\u06cc \u062a\u06be\u06cc \u0628\u0686\u067e\u0646 \u06a9\u06d2 \u062f\u0646\u0648\u06ba \u0633\u06d2 \u06c1\u06cc \u0631\u0648\u06cc \u06a9\u0627 \u0631\u062d\u062c\u0627\u0646 \u0645\u0648\u0633\u06cc\u0642\u06cc \u06a9\u06cc \u0637\u0631\u0641 \u062a\u06be\u0627 \u0627\u0648\u0631 \u0648\u06c1 \u06af\u0644\u0648\u06a9\u0627\u0631 \u0628\u0646\u0646\u0627 \u0686\u0627\u06c1\u062a\u06d2 \u062a\u06be\u06d2 \u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u0627\u0646\u06c1\u0648\u06ba\u0646\u06d2 \u06a9\u0633\u06cc \u0627\u0633\u062a\u0627\u062f \u0633\u06d2 \u0645\u0648\u0633\u06cc\u0642\u06cc \u06a9\u06cc \u062a\u0639\u0644\u06cc\u0645 \u062d\u0627\u0635\u0644 \u0646\u06c1\u06cc\u06ba \u06a9\u06cc \u062a\u06be\u06cc \u06d4 \u067e\u0686\u0627\u0633 \u06a9\u06cc \u062f\u06c1\u0627\u0626\u06cc \u0645\u06cc\u06ba \u0628\u0637\u0648\u0631 \u06af\u0644\u0648\u06a9\u0627\u0631 \u0628\u0646\u0646\u06d2 \u06a9\u06cc \u062e\u0648\u0627\u06c1\u0634 \u0644\u0626\u06d2 \u0631\u0648\u06cc \u0645\u0645\u0628\u0626\u06cc \u0627\u0653\u06af\u0626\u06d2 \u06d4\u0645\u0645\u0628\u0626\u06cc \u0645\u06cc\u06ba \u0631\u0648\u06cc \u06a9\u06cc \u0645\u0644\u0627\u0642\u0627\u062a \u0641\u0644\u0645 \u0633\u0627\u0632 \u06c1\u062f\u0627\u06cc\u062a \u06a9\u0627\u0631 \u062f\u0648\u06cc\u0646\u062f\u0631 \u06af\u0648\u0626\u0644 \u0633\u06d2 \u06c1\u0648\u0626\u06cc \u062c\u0648 \u0627\u0646 \u062f\u0646\u0648\u06ba \u0627\u067e\u0646\u06cc \u0641\u0644\u0645 \u0648\u0686\u0646 \u06a9\u06cc\u0644\u0626\u06d2 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u06a9\u06cc \u062a\u0644\u0627\u0634 \u06a9\u0631\u0631\u06c1\u06d2 \u062a\u06be\u06d2 \u062f\u0648\u06cc\u0646\u062f\u0631 \u06af\u0648\u0626\u0644 \u0646\u06d2 \u0631\u0648\u06cc \u06a9\u06cc \u0635\u0644\u0627\u062d\u06cc\u062a \u06a9\u0648\u067e\u06c1\u0686\u0627\u0646 \u06a9\u0631 \u0627\u0646\u06c1\u06cc\u06ba \u0627\u067e\u0646\u06cc \u0641\u0644\u0645 \u0648\u0686\u0646 \u0645\u06cc\u06ba \u0628\u0637\u0648\u0631 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u06a9\u0627\u0645 \u06a9\u0631\u0646\u06d2 \u06a9\u0627 \u0645\u0648\u0642\u0639 \u062f\u06cc\u0627 \u0627\u067e\u0646\u06cc \u067e\u06c1\u0644\u06cc \u06c1\u06cc \u0641\u0644\u0645 \u0648\u0686\u0646 \u0645\u06cc\u06ba \u0631\u0648\u06cc \u0646\u06d2 \u0628\u06c1\u062a\u0631\u06cc\u0646 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0633\u06d2 \u0646\u0627\u0638\u0631\u06cc\u0646 \u06a9\u0627 \u062f\u0644 \u062c\u06cc\u062a \u0644\u06cc\u0627 \u06d4\u06f1\u06f9\u06f5\u06f5\u0621 \u0645\u06cc\u06ba \u0627\u0653\u0626\u06cc \u0641\u0644\u0645 \u0648\u0686\u0646 \u0645\u06cc\u06ba \u06af\u0644\u0648\u06a9\u0627\u0631\u06c1 \u0627\u0653\u0634\u0627 \u0628\u06be\u0648\u0633\u0644\u06d2 \u06a9\u06cc \u0627\u0653\u0648\u0627\u0632 \u0645\u06cc\u06ba \u06cc\u06c1 \u0646\u063a\u0645\u06c1 \u0686\u0646\u062f\u0627 \u0645\u0627\u0645\u0627 \u062f\u0648\u0631 \u06a9\u06d2 \u06c1\u0648\u0627 \u067e\u06a9\u0627\u0626\u06d2 \u0628\u06be\u0648\u0631 \u06a9\u06d2 \u0627\u0646 \u062f\u0648\u0646\u0648\u06ba \u06a9\u0627\u0641\u06cc \u0633\u067e\u0631 \u06c1\u0679 \u06c1\u0648\u0626\u06d2 \u0627\u0648\u0631 \u0627\u0653\u062c \u0628\u06be\u06cc \u0628\u0686\u0648\u06ba \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u06a9\u0627\u0641\u06cc \u0645\u0642\u0628\u0648\u0644 \u06c1\u06cc\u06ba\u06d4 \u0641\u0644\u0645 \u0648\u0686\u0646 \u06a9\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06a9\u06d2 \u0628\u0639\u062f \u0631\u0648\u06cc \u06a9\u0686\u06be \u062d\u062f\u062a\u06a9 \u0627\u067e\u0646\u06cc \u0634\u0646\u0627\u062e\u062a \u0642\u0627\u0626\u0645 \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u06a9\u0627\u0645\u06cc\u0627\u0628 \u06c1\u0648\u06af\u0626\u06d2\u06d4 \u0627\u067e\u0646\u06d2 \u0648\u062c\u0648\u062f \u06a9\u0648 \u062a\u0644\u0627\u0634 \u06a9\u0631\u062a\u06d2 \u0631\u0648\u06cc \u06a9\u0648 \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u0645\u06cc\u06ba \u0635\u062d\u06cc\u062d \u0645\u0642\u0627\u0645 \u062d\u0627\u0635\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc\u0644\u0626\u06d2 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u067e\u0627\u0646\u0686 \u0633\u0627\u0644 \u0627\u0646\u062a\u0638\u0627\u0631 \u06a9\u0631\u0646\u0627 \u067e\u0691\u0627\u06d4 \u0627\u0633 \u062f\u0631\u0645\u06cc\u0627\u0646 \u0627\u0646\u06c1\u0648\u06ba\u0646\u06d2 \u0627\u0644\u0628\u06cc\u0644\u06cc \u060c \u067e\u0631\u0628\u06be\u0648 \u06a9\u06cc \u0645\u0627\u06cc\u0627 \u060c \u0627\u062c\u0648\u062f\u06be\u06cc\u0627 \u067e\u062a\u06cc \u060c \u0646\u0631\u0633\u06cc \u0628\u06be\u06af\u062a \u060c \u062f\u06cc\u0648\u0631 \u0628\u06be\u0627\u0628\u06be\u06cc \u060c \u0627\u06cc\u06a9 \u0633\u0627\u0644 \u060c \u06af\u06be\u0631 \u0633\u0646\u0633\u0627\u0631 \u060c\u0645\u06c1\u062f\u06cc \u062c\u06cc\u0633\u06cc \u06a9\u0626\u06cc \u062f\u0648\u0626\u0645 \u062f\u0631\u062c\u06c1 \u06a9\u06cc \u0641\u0644\u0645 \u06a9\u06cc\u0644\u0626\u06d2 \u0645\u0648\u0633\u06cc\u0642\u06cc \u062f\u06cc \u06d4 \u0627\u0653\u062c \u0628\u06be\u06cc \u0627\u0633 \u0641\u0644\u0645 \u06a9\u06d2 \u0646\u063a\u0645\u06d2 \u0646\u0627\u0638\u0631\u06cc\u0646 \u06a9\u0627 \u062f\u0644 \u062c\u06cc\u062a \u0644\u06cc\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0686\u0648\u062f\u06be\u0648\u06cc\u06ba \u06a9\u0627 \u0686\u0627\u0646\u062f \u06cc\u0627\u0627\u0653\u0641\u062a\u0627 \u0628 \u06c1\u0648 \u060c\u0628\u062f\u0644\u06d2 \u0628\u062f\u0644\u06d2 \u0645\u06cc\u0631\u06d2 \u0633\u0631\u06a9\u0627\u0631 \u0646\u0638\u0631\u0627\u0653\u062a\u06d2 \u06c1\u06cc\u06ba \u062c\u06cc\u0633\u06d2 \u0641\u0644\u0645 \u06a9\u06d2 \u0627\u0646 \u0646\u063a\u0645\u0648\u06ba \u06a9\u06cc \u062a\u0627\u062b\u06cc\u0631 \u0627\u0653\u062c \u0628\u06be\u06cc \u0628\u0631\u0642\u0631\u0627\u0631 \u06c1\u06d2\u06d4 \u0641\u0644\u0645 \u0686\u0648\u062f\u06be\u0648\u06cc\u06ba \u06a9\u0627 \u0686\u0627\u0646\u062f \u06a9\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06a9\u06d2 \u0628\u0639\u062f \u0631\u0648\u06cc \u06a9\u0648 \u0628\u0691\u06d2 \u0628\u062c\u0679 \u06a9\u06cc \u06a9\u0626\u06cc \u0627\u0686\u06be\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u067e\u06cc\u0634\u06a9\u0634 \u0634\u0631\u0648\u0639 \u06c1\u0648\u06af\u0626\u06cc \u062c\u0646 \u0645\u06cc\u06ba \u06af\u06be\u0631 \u06a9\u06cc \u0644\u0627\u062c \u060c \u06af\u06be\u0648\u06af\u06be\u0646\u0679 \u060c \u06af\u06be\u0631\u0627\u0646\u06c1 \u060c \u0686\u0627\u0626\u0646\u06c1 \u0679\u0627\u0626\u0648\u0646 \u060c \u0631\u0627\u06a9\u06be\u06cc \u060c \u0628\u06be\u0631\u0648\u0633\u06c1 \u060c\u06af\u06be\u0631\u0633\u062a\u06cc \u060c \u0627\u0648\u0631 \u06af\u0645\u0631\u0627\u06c1 \u062c\u06cc\u0633\u06cc \u0628\u0691\u06d2 \u0628\u062c\u0679 \u06a9\u06cc \u0641\u0644\u0645\u06cc\u06ba \u0634\u0627\u0645\u0644 \u06c1\u06cc\u06ba \u06d4 \u0627\u0646 \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06a9\u06d2 \u0628\u0639\u062f \u0631\u0648\u06cc \u0646\u06d2 \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06a9\u06cc \u0646\u0626\u06cc \u0628\u0644\u0646\u062f\u06cc\u0648\u06ba \u06a9\u0648 \u0686\u06be\u0648\u0627 \u0627\u0648\u0631 \u0627\u06cc\u06a9 \u0633\u06d2 \u0628\u0691\u06be \u06a9\u0631 \u0627\u06cc\u06a9 \u0645\u0648\u0633\u06cc\u0642\u06cc \u062f\u06d2 \u06a9\u0631 \u0646\u0627\u0638\u0631\u06cc\u0646 \u06a9\u0627 \u062f\u0644 \u062c\u06cc\u062a \u0644\u06cc\u0627\u06d4 \u06f1\u06f9\u06f6\u06f5\u0621 \u0631\u0648\u06cc \u06a9\u06d2 \u0641\u0644\u0645\u06cc \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u06a9\u0627 \u0627\u06c1\u0645 \u0645\u0648\u0691 \u062b\u0627\u0628\u062a \u06c1\u0648\u0627\u06d4<br \/>\n\u0627\u0633 \u0633\u0627\u0644 \u0627\u0646 \u06a9\u06cc \u0648\u0642\u062a \u060c \u062e\u0627\u0646\u062f\u0627\u0646 \u0627\u0648\u0631 \u06a9\u0627\u062c\u0644 \u062c\u06cc\u0633\u06cc \u0633\u067e\u0631 \u06c1\u0679 \u0641\u0644\u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc\u06ba\u06d4 \u0628\u06cc \u0627\u0653\u0631 \u0686\u0648\u067e\u0691\u0627 \u06a9\u06cc \u0641\u0644\u0645 \u0648\u0642\u062a \u0645\u06cc\u06ba \u0631\u0648\u06cc \u06a9\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u06a9\u0627 \u0627\u06cc\u06a9 \u0627\u0644\u06af \u0627\u0646\u062f\u0627\u0632 \u062f\u06cc\u06a9\u06be\u0646\u06d2 \u06a9\u0648 \u0645\u0644\u0627\u06d4 \u0641\u0644\u0645 \u0645\u06cc\u06ba \u0627\u062f\u0627\u06a9\u0627\u0631 \u0628\u0644\u0631\u0627\u062c \u0633\u0627\u06c1\u0646\u06cc \u067e\u0631 \u0641\u0644\u0645\u0627\u0626\u06cc \u06cc\u06c1 \u0642\u0648\u0627\u0644\u06cc \u0627\u06d2 \u0645\u06cc\u0631\u06cc \u0632\u06c1\u0631\u06c1 \u062c\u0628\u06cc\u06ba \u062a\u062c\u06be\u06d2 \u0645\u0639\u0644\u0648\u0645 \u0646\u06c1\u06cc\u06ba \u06d4\u0641\u0644\u0645\u06cc \u0634\u0627\u0626\u0642\u06cc\u0646 \u0627\u0653\u062c \u0628\u06be\u06cc \u0628\u06be\u0648\u0644 \u0646\u06c1\u06cc\u06ba \u067e\u0627\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0641\u0644\u0645 \u06a9\u0627\u0644\u062c \u0631\u0648\u06cc \u06a9\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u0645\u06cc\u06ba \u06af\u0644\u0648\u06a9\u0627\u0631 \u0627\u0653\u0634\u0627 \u0628\u06be\u0648\u0633\u0644\u06d2 \u06a9\u06cc \u0627\u0653\u0648\u0627\u0632 \u0645\u06cc\u06ba \u0645\u06cc\u0646\u0627 \u06a9\u0645\u0627\u0631\u06cc \u067e\u0631 \u0641\u0644\u0645\u0627\u06cc\u0627 \u06cc\u06c1 \u0646\u063a\u0645\u06c1 \u0645\u06cc\u0631\u06d2 \u0628\u06be\u06cc\u0627 \u0645\u06cc\u0631\u06d2 \u0686\u0646\u062f\u0627 \u0645\u06cc\u0631\u06d2 \u0627\u0646\u0645\u0648\u0644 \u0631\u062a\u0646 \u0627\u0653\u062c \u0628\u06be\u06cc \u0631\u0627\u06a9\u06be\u06cc \u06a9\u06d2 \u0645\u0648\u0642\u0639 \u067e\u0631 \u0633\u0646\u0627\u0626\u06cc \u062f\u06d2 \u062c\u0627\u062a\u0627 \u06c1\u06d2\u06d4 \u0633\u062a\u0631 \u06a9\u06cc \u062f\u06c1\u0627\u0626\u06cc \u0645\u06cc\u06ba \u0645\u063a\u0631\u0628\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u06a9\u06cc \u0686\u0645\u06a9 \u0633\u06d2 \u0641\u0644\u0645\u0633\u0627\u0632 \u06c1\u062f\u0627\u06cc\u062a \u06a9\u0627\u0631 \u062e\u0648\u062f \u06a9\u0648 \u0645\u062d\u0641\u0648\u0638 \u0646\u06c1 \u0631\u06a9\u06be \u0633\u06a9\u06d2 \u0627\u0648\u0631 \u0627\u0653\u06c1\u0633\u062a\u06c1 \u0627\u0653\u06c1\u0633\u062a\u06c1 \u06c1\u062f\u0627\u06cc\u062a \u06a9\u0627\u0631\u0648\u06ba \u0646\u06d2 \u0631\u0648\u06cc \u06a9\u06cc \u0637\u0631\u0641 \u0633\u06d2 \u0627\u067e\u0646\u0627 \u0645\u0646\u06c1 \u0645\u0648\u0691 \u0644\u06cc\u0627\u06d4 \u06f1\u06f9\u06f8\u06f2\u0621 \u0645\u06cc\u06ba \u0627\u0653\u0626\u06cc \u0641\u0644\u0645 \u0646\u06a9\u0627\u062d \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u0631\u0648\u06cc \u0646\u06d2 \u0627\u06cc\u06a9 \u0628\u0627\u0631 \u067e\u06be\u0631 \u0633\u06d2 \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u0645\u06cc\u06ba \u0648\u0627\u067e\u0633\u06cc \u06a9\u06cc \u06a9\u0648\u0634\u0634 \u06a9\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u0646\u06c1\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u062e\u0627\u0635 \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u0646\u06c1\u06cc\u06ba \u0645\u0644\u06cc \u06d4 \u0633\u0644\u0645\u06c1 \u0627\u0653\u063a\u0627 \u06a9\u06cc \u0627\u0653\u0648\u0627\u0632 \u0645\u06cc\u06ba\u0627\u0646 \u06a9\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u0645\u06cc\u06ba \u06cc\u06c1 \u0646\u063a\u0645\u06c1 \u062f\u0644 \u06a9\u06d2 \u0627\u0631\u0645\u0627\u06ba \u0627\u0653\u0646\u0633\u0648\u0626\u0648\u06ba \u0645\u06cc\u06ba \u0628\u06c1\u06c1 \u06af\u0626\u06d2 \u0646\u0627\u0638\u0631\u06cc\u0646 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u06a9\u0627\u0641\u06cc \u0645\u0642\u0628\u0648\u0644 \u06c1\u0648\u0626\u06d2\u06d4 \u0627\u0633\u06cc \u06a9\u06cc \u062f\u06c1\u0627\u0626\u06cc \u0645\u06cc\u06ba \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u0645\u06cc\u06ba \u062e\u0648\u062f \u06a9\u0648 \u0646\u0638\u0631\u0627\u0646\u062f\u0627\u0632 \u06a9\u0626\u06d2 \u062c\u0627\u0646\u06d2 \u067e\u0631 \u0631\u0648\u06cc \u0646\u06d2 \u0645\u0646\u06c1 \u0645\u0648\u0691 \u0644\u06cc\u0627 \u0628\u0639\u062f \u0645\u06cc\u06ba \u0645\u0644\u06cc\u0627\u0644\u0645 \u0641\u0644\u0645\u0648\u06ba \u06a9\u06d2 <a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/03\/Ravi-Shankar.jpg\"><br \/>\n<\/a>\u0645\u0634\u06c1\u0648\u0631 \u0641\u0644\u0645 \u0633\u0627\u0632 \u06c1\u062f\u0627\u06cc\u062a \u06a9\u0627\u0631 \u06c1\u0631\u06cc \u06c1\u0631\u0646 \u06a9\u06d2 \u06a9\u06c1\u0646\u06d2 \u067e\u0631 \u0631\u0648\u06cc \u0646\u06d2 \u0645\u0644\u06cc\u0627\u0644\u0645 \u0641\u0644\u0645\u0648\u06ba\u06a9\u06cc\u0644\u0626\u06d2 \u0645\u0648\u0633\u06cc\u0642\u06cc \u062f\u06cc\u0646\u06d2 \u06a9\u06cc \u067e\u06cc\u0634\u06a9\u0634 \u0642\u0628\u0648\u0644 \u06a9\u0631\u0644\u06cc \u06d4 \u06f1\u06f9\u06f8\u06f6\u0621 \u0645\u06cc\u06ba \u0627\u0653\u0626\u06cc \u0641\u0644\u0645 \u0645\u0644\u06cc\u0627\u0644\u0645 \u0641\u0644\u0645 \u067e\u0646\u0686 \u06af\u0646\u06cc \u0633\u06d2 \u0628\u0637\u0648\u0631 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u0631\u0648\u06cc \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0641\u0644\u0645\u06cc \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u06a9\u06cc \u062f\u0648\u0633\u0631\u06cc \u0627\u0646\u0646\u06af \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f\u06cc \u06d4 \u0631\u0648\u06cc \u0627\u067e\u0646\u06d2 \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u0645\u06cc\u06ba \u062f\u0648 \u0628\u0627\u0631 \u0641\u0644\u0645 \u0641\u06cc\u0626\u0631 \u0627\u06cc\u0648\u0627\u0631\u0688 \u0633\u06d2 \u0646\u0648\u0627\u0632\u06d2 \u06af\u0626\u06d2 \u06d4 \u0633\u0628 \u0633\u06d2 \u067e\u06c1\u0644\u06d2 \u0627\u0646\u06c1\u06cc\u06ba \u06f1\u06f9\u06f6\u06f1\u0621 \u0645\u06cc\u06ba \u0641\u0644\u0645 \u06af\u06be\u0631\u0627\u0646\u06c1 \u06a9\u06cc \u0633\u067e\u0631\u06c1\u0679 \u0645\u0648\u0633\u06cc\u0642\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u0641\u0644\u0645 \u0641\u06cc\u0626\u0631 \u0627\u06cc\u0648\u0627\u0631\u0688 \u062f\u06cc\u0627\u06af\u06cc\u0627 \u062a\u06be\u0627 \u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u06f1\u06f9\u06f6\u06f5\u0621 \u0645\u06cc\u06ba \u0641\u0644\u0645 \u062e\u0627\u0646\u062f\u0627\u0646 \u06a9\u06cc\u0644\u0626\u06d2 \u0628\u06be\u06cc \u0627\u0646\u06c1\u06cc\u06ba \u0641\u0644\u0645 \u0641\u06cc\u0626\u0631 \u0627\u06cc\u0648\u0627\u0631\u0688 \u062f\u06cc\u0627\u06af\u06cc\u0627\u06d4 \u0631\u0648\u06cc \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0686\u0627\u0631 \u062f\u06c1\u0627\u0626\u06cc \u0637\u0648\u06cc\u0644 \u0641\u0644\u0645\u06cc \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u0645\u06cc\u06ba \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u062f\u0648 \u0633\u0648 \u0641\u0644\u0645\u0648\u06ba \u0627\u0648\u0631 \u063a\u06cc\u0631 \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc\u0644\u0626\u06d2 \u0645\u0648\u0633\u06cc\u0642\u06cc \u062f\u06cc \u06c1\u06d2 \u0627\u0646\u06c1\u0648\u06ba\u0646\u06d2 \u06c1\u0646\u062f\u06cc \u06a9\u06d2 \u0639\u0644\u0627\u0648\u06c1 \u0645\u0644\u06cc\u0627\u0644\u0645 \u060c \u067e\u0646\u062c\u0627\u0628\u06cc \u060c\u06af\u062c\u0631\u0627\u062a\u06cc \u060c \u062a\u06cc\u0644\u06af\u0648 \u060c \u0627\u0648\u0631 \u06a9\u0646\u0691 \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc\u0644\u0626\u06d2 \u0628\u06be\u06cc \u0645\u0648\u0633\u06cc\u0642\u06cc \u062f\u06cc\u06d4 \u0627\u067e\u0646\u06cc \u067e\u0631\u06a9\u0634\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0633\u06d2 \u0646\u0627\u0638\u0631\u06cc\u0646 \u06a9\u0627 \u062f\u0644 \u062c\u06cc\u062a\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0631\u0648\u06cc \u0646\u06d2 \u0633\u0627\u062a \u0645\u0627\u0631\u0686 \u06f2\u06f0\u06f1\u06f2\u0621 \u06a9\u0648 \u0627\u0633 \u062f\u0646\u06cc\u0627 \u0633\u06d2 \u0627\u0644\u0648\u062f\u0627\u0639 \u06a9\u06c1\u06c1 \u06af\u0626\u06d2\u06d4<br \/>\n\u0642\u0627\u0631\u0626\u06cc\u0646 \u06a9\u0648 \u0645\u0636\u0645\u0648\u0646 \u06a9\u06d2 \u0627\u0653\u062e\u0631 \u0645\u06cc\u06ba \u06cc\u06c1 \u0628\u06be\u06cc \u0628\u062a\u0627\u062a\u06d2 \u0686\u0644\u06cc\u06ba \u06a9\u06c1 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u0631\u0648\u06cc \u0627\u06cc\u06a9 \u0627\u0686\u06be\u06d2 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0627\u06cc\u06a9 \u0627\u0686\u06be\u06d2 \u0634\u0627\u0639\u0631 \u0628\u06be\u06cc \u062a\u06be\u06d2\u06d4 \u0641\u0644\u0645 \u06af\u06be\u0679\u0646\u0627 \u062c\u0648 \u06a9\u06c1 \u06f1\u06f9\u06f7\u06f4\u0621 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u062a\u06be\u06cc \u062c\u0633 \u0645\u06cc\u06ba \u0644\u062a\u0627 \u0645\u0646\u06af\u06cc\u0634\u06a9\u0631 \u0646\u06d2 \u0627\u06cc\u06a9 \u0646\u063a\u0645\u06c1 \u06af\u0627\u06cc\u0627 \u062a\u06be\u0627 \u062c\u0633 \u06a9\u06d2 \u0628\u0648\u0644 \u062a\u06be\u06d2 \u06c1\u0632\u0627\u0631 \u0628\u0627\u062a\u06d2 \u06a9\u0631\u06d2 \u0632\u0645\u0627\u0646\u06c1 \u0645\u06cc\u0631\u06cc \u0648\u0641\u0627\u067e\u06c1 \u06cc\u0642\u06cc\u0646 \u0631\u06a9\u06be\u0646\u0627 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u0631\u0648\u06cc \u0646\u06d2 \u06c1\u06cc \u0644\u06a9\u06be\u0627 \u062a\u06be\u0627 \u0627\u0633 \u0641\u0644\u0645 \u06a9\u06d2 \u0628\u0627\u0642\u06cc \u0646\u063a\u0645\u06d2 \u0628\u06be\u06cc \u0631\u0648\u06cc \u0646\u06d2 \u06c1\u06cc \u0644\u06a9\u06be\u06d2 \u062a\u06be\u06d2\u06d4<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u062f\u0631\u062c\u0646 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631 \u0627\u06cc\u0633\u06d2 \u06c1\u0648\u0626\u06d2 \u06c1\u06cc\u06ba \u062c\u0646 \u06a9 \u0645\u0648\u0633\u06cc\u0642\u06cc \u06a9\u0627 \u062c\u0627\u062f\u0648 \u0627\u0653\u062c \u0628\u06be\u06cc \u0628\u0631\u0642\u0631\u0627\u0631 \u06c1\u06d2\u06d4 \u0627\u0646\u06c1\u06cc\u06ba \u0627\u06cc\u06a9 \u062f\u0631\u062c\u0646 \u0645\u0648\u0633\u06cc\u0642\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0646\u0648\u0634\u0627\u062f\u060c\u0627\u06cc\u0633 \u0688\u06cc \u0628\u0631\u0645\u0646 \u060c \u0645\u062f\u0646 \u0645\u0648\u06c1\u0646 \u060c\u0627\u0648\u067e\u06cc \u0646\u06cc\u0631 \u060c\u0631\u0648\u0634\u0646\u060c\u062e\u06cc\u0627\u0645 \u060c\u0634\u0646\u06a9\u0631 \u062c\u0626\u06d2 \u06a9\u0634\u0646 \u060c\u06a9\u0644\u06cc\u0627\u0646 \u062c\u06cc \u0627\u0653\u0646\u0646\u062f \u062c\u06cc \u060c \u0644\u06a9\u0634\u0645\u06cc \u06a9\u0627\u0646\u062a \u067e\u06cc\u0627\u0631\u06d2 \u0644\u0627\u0644 \u0648\u063a\u06cc\u0631\u06c1 \u06a9\u06cc \u0641\u06c1\u0631\u0633\u062a \u0645\u06cc\u06ba \u0631\u0648\u06cc \u0634\u0646\u06a9\u0631 \u06a9\u0627 \u0628\u06be\u06cc \u0646\u0627\u0645 \u0627\u0653\u062a\u0627 \u06c1\u06d2\u06d4 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,32],"tags":[],"class_list":["post-11539","post","type-post","status-publish","format-standard","category-entertainment","category-film"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/11539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=11539"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/11539\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=11539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=11539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=11539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}