{"id":14112,"date":"2014-04-02T17:41:33","date_gmt":"2014-04-02T12:11:33","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=14112"},"modified":"2014-04-02T17:41:33","modified_gmt":"2014-04-02T12:11:33","slug":"%d9%81%d9%84%d9%85-%d8%a7%d9%86%da%88%d8%b3%d9%b9%d8%b1%db%8c-%d9%85%db%8c%da%ba-%da%a9%d9%88%d8%a6%db%8c-%da%a9%d8%b3%db%8c-%da%a9%d8%a7-%d8%af%d9%88%d8%b3%d8%aa-%d9%86%db%81%db%8c%da%ba","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d9%81%d9%84%d9%85-%d8%a7%d9%86%da%88%d8%b3%d9%b9%d8%b1%db%8c-%d9%85%db%8c%da%ba-%da%a9%d9%88%d8%a6%db%8c-%da%a9%d8%b3%db%8c-%da%a9%d8%a7-%d8%af%d9%88%d8%b3%d8%aa-%d9%86%db%81%db%8c%da%ba\/","title":{"rendered":"\u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u0645\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u06a9\u0633\u06cc \u06a9\u0627 \u062f\u0648\u0633\u062a \u0646\u06c1\u06cc\u06ba"},"content":{"rendered":"<p style=\"text-align: right;\"><a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/04\/Neha-Sharma.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"Neha-Sharma\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/04\/Neha-Sharma.jpg\" width=\"323\" height=\"243\" \/><\/a>\u0645\u0645\u0628\u0626\u06cc: \u0628\u0627\u0644\u06cc \u0648\u0648\u0688 \u0627\u062f\u06a9\u0627\u0631\u06c1 \u0646\u06cc\u06c1\u0627 \u0634\u0631\u0645\u0627 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u0645\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u06a9\u0633\u06cc \u06a9\u0627 \u062f\u0648\u0633\u062a \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u062a\u0627\u06d4 \u062e\u0628\u0631 \u0627\u06cc\u062c\u0646\u0633\u06cc \u06a9\u0648 \u0627\u0646\u0679\u0631\u0648\u06cc\u0648 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0646\u06cc\u06c1\u0627 \u0634\u0631\u0645\u0627 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u062a\u06be\u0627 \u06a9\u06c1 \u0645\u06cc\u06ba \u0646\u06d2 \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u06a9\u0627 \u0627\u0653\u063a\u0627\u0632 \u0633\u0627\u0648\u062a\u06be \u0627\u0646\u0688\u06cc\u0646 \u0641\u0644\u0645\u0648\u06ba \u0633\u06d2 \u06a9\u06cc\u0627 \u0628\u0639\u062f \u0627\u0632\u0627\u06ba \u06c1\u0646\u062f\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u0627 \u0631\u062e \u06a9\u0631\u0644\u06cc\u0627 \u0644\u06cc\u06a9\u0646 \u0627\u0628 \u0628\u06be\u06cc \u0628\u0627\u0644\u06cc \u0648\u0648\u0688 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u067e\u0631\u0627\u0626\u06cc \u0633\u06cc \u0644\u06af\u062a\u06cc \u06c1\u06d2 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0627\u0646\u06be\u06cc\u06ba \u0628\u0637\u0648\u0631 \u06c1\u06cc\u0631\u0648\u0626\u0646 \u0627\u0628\u06be\u06cc \u0628\u06be\u06cc \u0628\u0691\u06d2 \u067e\u06cc\u0645\u0627\u0646\u06d2 \u067e\u0631 \u0642\u0628\u0648\u0644 \u0646\u06c1\u06cc\u06ba \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4\u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u0645\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u06a9\u0633\u06cc \u06a9\u0627 \u062f\u0648\u0633\u062a \u0646\u06c1\u06cc\u06ba \u0635\u0631\u0641 \u06c1\u0631 \u0627\u06cc\u06a9 \u06a9\u0627 \u062f\u0648\u0633\u0631\u06d2 \u0633\u06d2 \u067e\u06cc\u0634\u06c1 \u0648\u0627\u0631\u0627\u0646\u06c1 \u0631\u0627\u0628\u0637\u06c1 \u06c1\u06d2\u06d4\u0648\u06c1 \u0627\u0628 \u0628\u06be\u06cc \u0628\u0627\u06a9\u0633 \u0627\u0653\u0641\u0633 \u0627\u0648\u0631 \u0628\u0627\u0644\u06cc \u0648\u0648\u0688 \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u06d2 \u0645\u0642\u0627\u0635\u062f \u06a9\u0648 \u062a\u0644\u0627\u0634 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u062c\u0633\u062a\u062c\u0648 \u0645\u06cc\u06ba \u0644\u06af\u06cc \u06c1\u0648\u0626\u06cc \u06c1\u06cc\u06ba\u06d4\u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u0646\u06d2 \u0627\u067e\u0646\u06cc \u0646\u0626\u06cc \u0641\u0644\u0645 \u2019\u2019\u06cc\u0646\u06af\u06cc\u0633\u062a\u0627\u0646\u2018\u2018 \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0628\u0627\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0641\u0644\u0645 \u067e\u0631 \u0627\u0628 \u062a\u06a9 \u0627\u0686\u06be\u0627 \u0631\u062f \u0639\u0645\u0644 \u062f\u06cc\u06a9\u06be\u0646\u06d2 \u0645\u06cc\u06ba \u0633\u0627\u0645\u0646\u06d2 \u0627\u0653\u06cc\u0627 \u06c1\u06d2\u06d4<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0645\u0628\u0626\u06cc: \u0628\u0627\u0644\u06cc \u0648\u0648\u0688 \u0627\u062f\u06a9\u0627\u0631\u06c1 \u0646\u06cc\u06c1\u0627 \u0634\u0631\u0645\u0627 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u0645\u06cc\u06ba \u06a9\u0648\u0626\u06cc \u06a9\u0633\u06cc \u06a9\u0627 \u062f\u0648\u0633\u062a \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u062a\u0627\u06d4 \u062e\u0628\u0631 \u0627\u06cc\u062c\u0646\u0633\u06cc \u06a9\u0648 \u0627\u0646\u0679\u0631\u0648\u06cc\u0648 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0646\u06cc\u06c1\u0627 \u0634\u0631\u0645\u0627 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u062a\u06be\u0627 \u06a9\u06c1 \u0645\u06cc\u06ba \u0646\u06d2 \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u06a9\u0627 \u0627\u0653\u063a\u0627\u0632 \u0633\u0627\u0648\u062a\u06be \u0627\u0646\u0688\u06cc\u0646 \u0641\u0644\u0645\u0648\u06ba \u0633\u06d2 \u06a9\u06cc\u0627 \u0628\u0639\u062f \u0627\u0632\u0627\u06ba \u06c1\u0646\u062f\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u0627 \u0631\u062e \u06a9\u0631\u0644\u06cc\u0627 \u0644\u06cc\u06a9\u0646 \u0627\u0628 \u0628\u06be\u06cc \u0628\u0627\u0644\u06cc \u0648\u0648\u0688 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u067e\u0631\u0627\u0626\u06cc \u0633\u06cc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,32],"tags":[],"class_list":["post-14112","post","type-post","status-publish","format-standard","category-entertainment","category-film"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/14112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=14112"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/14112\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=14112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=14112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=14112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}