{"id":14570,"date":"2014-04-06T18:17:34","date_gmt":"2014-04-06T12:47:34","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=14570"},"modified":"2014-04-06T18:17:34","modified_gmt":"2014-04-06T12:47:34","slug":"%d8%b5%d8%ad%d8%aa-%d9%85%d9%86%d8%af-%d8%af%d8%a7%d9%86%d8%aa%d9%88%da%ba-%da%a9%d8%a7-%da%a9%da%be%d9%84%d8%a7%da%91%db%8c%d9%88%da%ba-%da%a9%db%8c-%da%a9%d8%a7%d9%85%db%8c%d8%a7%d8%a8%db%8c-%d9%85","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%b5%d8%ad%d8%aa-%d9%85%d9%86%d8%af-%d8%af%d8%a7%d9%86%d8%aa%d9%88%da%ba-%da%a9%d8%a7-%da%a9%da%be%d9%84%d8%a7%da%91%db%8c%d9%88%da%ba-%da%a9%db%8c-%da%a9%d8%a7%d9%85%db%8c%d8%a7%d8%a8%db%8c-%d9%85\/","title":{"rendered":"\u0635\u062d\u062a \u0645\u0646\u062f \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u0627 \u06a9\u06be\u0644\u0627\u0691\u06cc\u0648\u06ba \u06a9\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u0645\u06cc\u06ba \u0627\u06c1\u0645 \u06a9\u0631\u062f\u0627\u0631"},"content":{"rendered":"<p style=\"text-align: right;\"><a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/04\/helth.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"helth\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/04\/helth.jpg\" width=\"213\" height=\"120\" \/><\/a>\u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06d2 \u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06cc\u0633\u06cc\u0627\u06cc\u062a\u06be\u06cc\u0644\u0679 \u06a9\u06d2 \u06af\u0648\u0644\u0688 \u0645\u06cc\u0688\u0644 \u062c\u06cc\u062a\u0646\u06d2 \u06a9\u06d2 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0628\u0691\u06be \u062c\u0627\u062a\u06d2 \u06c1\u06cc\u06ba \u062c\u0646 \u06a9\u06d2 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u0635\u062d\u062a \u0627\u0686\u06be\u06cc \u06c1\u06d2\u06d4\u0644\u0646\u062f\u0646 \u0645\u06cc\u06ba \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u2019\u0627\u0648\u0631 \u06c1\u06cc\u0644\u062a\u06be \u0627\u0648\u0631 \u06a9\u06be\u06cc\u0644 \u0645\u06cc\u06ba \u06a9\u0627\u0631\u06a9\u0631\u062f\u06af\u06cc\u2018 \u06a9\u06d2 \u0645\u0648\u0636\u0648\u0639 \u067e\u0631 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0627\u06cc\u06a9 \u06a9\u0627\u0646\u0641\u0631\u0646\u0633 \u0645\u06cc\u06ba \u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062c\u0646 \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679\u0633 \u06a9\u06d2 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u0635\u062d\u062a \u0627\u0686\u06be\u06cc \u0646\u06c1\u06cc\u06ba \u06c1\u06d2 \u0627\u0646 \u06a9\u06cc \u062a\u0631\u0628\u06cc\u062a \u0627\u0648\u0631 \u06a9\u0627\u0631\u06a9\u0631\u062f\u06af\u06cc \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u062a\u06cc \u06c1\u06d2\u06d4 \u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0639\u0644\u06cc\u0670 \u0633\u0637\u062d \u06a9\u06cc \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679\u06a9\u0633 \u06a9\u06be\u06cc\u0644\u0648\u06ba \u0645\u06cc\u06ba \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u0627\u0648\u0631 \u0646\u0627\u06a9\u0627\u0645\u06cc \u0645\u06cc\u06ba \u0641\u0631\u0642 \u0627\u0646\u062a\u06c1\u0627\u0626\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u062f\u0627\u0646\u062a<a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/04\/helth.jpg\"><br \/>\n<\/a>\u0648\u06ba \u06a9\u06cc \u0628\u06c1\u062a\u0631 \u0635\u062d\u062a \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679 \u06a9\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06a9\u0627 \u0628\u0627\u0639\u062b \u0628\u0646 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4\u0627\u0648\u0644\u0645\u067e\u06a9\u0633 \u0645\u06cc\u06ba \u0634\u0631\u06a9\u062a \u06a9\u06cc\u0644\u06cc\u06d2 \u062a\u06cc\u0627\u0631 \u06a9\u06cc \u062c\u0627\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0628\u0631\u0637\u0627\u0646\u0648\u06cc \u0633\u06a9\u0648\u0627\u0688 \u0645\u06cc\u06ba \u0634\u0627\u0645\u0644 \u0628\u0627\u06a9\u0633\u0631\u0648\u06ba \u06a9\u06d2 \u0645\u0646\u06be \u06a9\u06cc \u0635\u062d\u062a \u067e\u0631 \u062e\u0635\u0648\u0635\u06cc \u062a\u0648\u062c\u06c1 \u062f\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u06c1\u06d2\u06d4\u0628\u0631\u0637\u0627\u0646\u06cc\u06c1 \u06a9\u06d2 \u062c\u0631\u06cc\u062f\u06d2 \u2019\u0633\u067e\u0648\u0631\u0679\u0633 \u0645\u06cc\u0688\u06cc\u0633\u0646\u2018 \u0645\u06cc\u06ba \u0686\u06be\u067e\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0627\u06cc\u06a9 \u062a\u062d\u0642\u06cc\u0642 \u0645\u06cc\u06ba \u06a9\u06c1\u0627\u06af\u06cc\u0627 \u06a9\u06c1 \u0628\u06cc\u0633 \u0641\u06cc\u0635\u062f \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679\u0633 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062f\u0627\u0646\u062a\u0648\u06ba \u0645\u06cc\u06ba \u062a\u06a9\u0644\u06cc\u0641 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u0627\u0646 \u06a9\u06cc \u06a9\u0627\u0631\u06a9\u0631\u062f\u06af\u06cc \u067e\u0631 \u0628\u0631\u0627 \u0627\u062b\u0631 \u067e\u0691\u0627 \u06c1\u06d2\u06d4\u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06d2 \u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062f\u0627\u0646\u062a\u0648\u06ba \u0645\u06cc\u06ba \u062a\u06a9\u0644\u06cc\u0641 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679\u0633 \u06a9\u06cc \u0646\u06cc\u0646\u062f \u062e\u0631\u0627\u0628 \u06c1\u0648\u062a\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u0633\u06d2 \u0627\u0646 \u06a9\u06cc \u0679\u0631\u06cc\u0646\u0646\u06af \u0628\u06be\u06cc \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u062a\u06cc \u06c1\u06d2\u06d4\u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0645\u0633\u0648\u0691\u06be\u0648\u06ba \u06a9\u06cc \u0633\u0648\u062c\u0646 \u062c\u0633\u0645 \u06a9\u06d2 \u0628\u0627\u0642\u06cc \u062d\u0635\u0648\u06ba \u06a9\u0648 \u0645\u062a\u0627\u062b\u0631 \u06a9\u0631\u062a\u06cc \u06c1\u06d2 \u062c\u0633 \u0633\u06d2 \u06a9\u06be\u0644\u0627\u0691\u06cc\u0648\u06ba \u06a9\u06cc \u06a9\u0627\u0631\u06a9\u0631\u062f\u06af\u06cc \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4<br \/>\n\u0628\u0631\u0637\u0627\u0646\u0648\u06cc \u0627\u062f\u0627\u0631\u06c1 \u0635\u062d\u062a \u0627\u06cc\u0646 \u0627\u06cc\u0686 \u0627\u06cc\u0633 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062e\u0631\u0627\u0628 \u062f\u0627\u0646\u062a \u0630\u06cc\u0627\u0628\u06cc\u0637\u0633 \u0627\u0648\u0631 \u062f\u0644 \u06a9\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc\u0648\u06ba \u06a9\u0627 \u0628\u0627\u0639\u062b \u0628\u0646 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4\u0627\u0644\u0628\u062a\u06c1 \u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u0635\u0641\u0627\u0626\u06cc\u060c \u0645\u0627\u0648\u0654\u062a\u06be \u0648\u0627\u0634 \u06a9\u06cc \u0628\u0648\u062a\u0644 \u0627\u0648\u0631 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u0648 \u0635\u0627\u0641 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0627\u0686\u06be\u06d2 \u06a9\u0686\u06be \u06af\u0631 \u06c1\u0641\u062a\u06c1 \u0648\u0627\u0631 \u062c\u0627\u06a9\u0646\u06af \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u0648\u06ba \u06a9\u0648 \u0627\u0648\u0644\u0645\u067e\u06a9 \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679 \u0646\u06c1\u06cc\u06ba \u0628\u0646\u0627 \u0633\u06a9\u062a\u06d2\u06d4\u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0639\u0644\u06cc\u0670 \u0633\u0637\u062d \u06a9\u06cc \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679\u06a9\u0633 \u0645\u06cc\u06ba \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u0627\u0648\u0631 \u0646\u0627\u06a9\u0627\u0645\u06cc \u0645\u06cc\u06ba \u0641\u0631\u0642 \u0627\u0646\u062a\u06c1\u0627\u0626\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u06c1\u06d2\u06d4\u06cc\u0648\u0646\u06cc\u0648\u0631\u0633\u0679\u06cc \u06a9\u0627\u0644\u062c \u0644\u0646\u062f\u0646 \u06a9\u06d2 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u0627\u06cc\u0646 \u0646\u06cc\u0688\u0644\u0645\u06cc\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0686\u06be\u0648\u0679\u06cc \u0686\u06be\u0648\u0679\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc\u0627\u06ba \u0627\u06cc\u06a9 \u0628\u0691\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06a9\u06cc \u0628\u0646\u06cc\u0627\u062f \u0628\u0646 \u062c\u0627\u062a\u06cc \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u0635\u062d\u062a \u0628\u06be\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u0645\u06cc\u06ba \u0627\u06c1\u0645 \u06a9\u0631\u062f\u0627\u0631 \u0627\u062f\u0627 \u06a9\u0631 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4\u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0644\u0646\u062f\u0646 \u0627\u0648\u0644\u0645\u067e\u06a9\u0633 \u0645\u06cc\u06ba \u062d\u0635\u06c1 \u0644\u06cc\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679\u0633 \u067e\u0631 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u062a\u062d\u0642\u06cc\u0642 \u0633\u06d2 \u067e\u062a\u0627 \u0686\u0644\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062c\u0633\u0645\u0627\u0646\u06cc \u0637\u0648\u0631 \u067e\u0631 \u062a\u06cc\u0627\u0631 \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679\u0633 \u06a9\u06cc \u0627\u06cc\u06a9 \u0628\u0691\u06cc \u062a\u0639\u062f\u0627\u062f \u06a9\u06cc \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u0635\u062d\u062a \u0632\u06cc\u0627\u062f\u06c1 \u0627\u0686\u06be\u06cc \u0646\u06c1\u06cc\u06ba \u062a\u06be\u06cc \u0627\u0648\u0631 \u0627\u0646 \u0645\u06cc\u06ba \u0633\u06d2 \u0627\u06cc\u06a9 \u0628\u0691\u06cc \u062a\u0639\u062f\u0627\u062f \u0646\u06d2 \u0634\u06a9\u0627\u06cc\u062a \u06a9\u06cc \u06a9\u06c1 \u062f\u0627\u0646\u062a\u0648\u06ba \u0645\u06cc\u06ba \u062a\u06a9\u0644\u06cc\u0641 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u0627\u0646 \u06a9\u06cc \u062a\u0631\u0628\u06cc\u062a \u067e\u0631 \u0628\u0631\u0627 \u0627\u062b\u0631 \u067e\u0691\u0627 \u06c1\u06d2\u06d4\u0688\u0627\u06a9\u0679\u0631 \u0645\u0627\u0626\u06cc\u06a9 \u0644\u0648\u0632\u0645\u0648\u0631 \u062c\u0648 \u067e\u0686\u06be\u0644\u06d2 \u0633\u062a\u0631\u06c1 \u0628\u0631\u0633\u0648\u06ba \u0633\u06d2 \u0628\u0631\u0637\u0627\u0646\u06cc\u06c1 \u06a9\u06cc \u0628\u0627\u06a9\u0633\u0646\u06af \u0679\u06cc\u0645 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u0646\u0633\u0644\u06a9 \u06c1\u06cc\u06ba\u060c \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u0633\u0627\u0644\u0648\u06ba \u06a9\u06d2 \u062a\u062c\u0631\u0628\u06d2 \u0633\u06d2 \u0633\u06cc\u06a9\u06be\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062c\u0646 \u0628\u0627\u06a9\u0633\u0631\u0648\u06ba \u06a9\u06d2 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u0635\u062d\u062a \u0627\u0686\u06be\u06cc \u0646\u06c1\u06cc\u06ba \u06c1\u06d2 \u0627\u0633 \u0633\u06d2 \u0627\u0646 \u06a9\u06cc \u062a\u0631\u0628\u06cc\u062a \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u062a\u06cc \u06c1\u06d2\u06d4\u0627\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062c\u0628 \u0633\u06d2 \u0628\u0627\u06a9\u0633\u0631\u0648\u06ba \u06a9\u06d2 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u062a\u0648\u0627\u062a\u0631 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0686\u06cc\u06a9\u0646\u06af \u0634\u0631\u0648\u0639 \u06a9\u06cc \u06af\u0626\u06cc\u060c \u062d\u0627\u0644\u0627\u062a \u0628\u06c1\u062a\u0631 \u06c1\u0648 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u06a9\u062b\u0631 \u0628\u0627\u06a9\u0633\u0631 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u0627 \u0645\u0639\u0627\u0626\u0646\u06c1 \u06a9\u0631\u0627\u0646\u0627 \u067e\u0633\u0646\u062f \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06d2\u06d4<\/p>\n<p style=\"text-align: right;\">\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06d2 \u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06cc\u0633\u06cc\u0627\u06cc\u062a\u06be\u06cc\u0644\u0679 \u06a9\u06d2 \u06af\u0648\u0644\u0688 \u0645\u06cc\u0688\u0644 \u062c\u06cc\u062a\u0646\u06d2 \u06a9\u06d2 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0628\u0691\u06be \u062c\u0627\u062a\u06d2 \u06c1\u06cc\u06ba \u062c\u0646 \u06a9\u06d2 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u0635\u062d\u062a \u0627\u0686\u06be\u06cc \u06c1\u06d2\u06d4\u0644\u0646\u062f\u0646 \u0645\u06cc\u06ba \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u2019\u0627\u0648\u0631 \u06c1\u06cc\u0644\u062a\u06be \u0627\u0648\u0631 \u06a9\u06be\u06cc\u0644 \u0645\u06cc\u06ba \u06a9\u0627\u0631\u06a9\u0631\u062f\u06af\u06cc\u2018 \u06a9\u06d2 \u0645\u0648\u0636\u0648\u0639 \u067e\u0631 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0627\u06cc\u06a9 \u06a9\u0627\u0646\u0641\u0631\u0646\u0633 \u0645\u06cc\u06ba \u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062c\u0646 \u0627\u06cc\u062a\u06be\u0644\u06cc\u0679\u0633 \u06a9\u06d2 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u06cc \u0635\u062d\u062a \u0627\u0686\u06be\u06cc \u0646\u06c1\u06cc\u06ba \u06c1\u06d2 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45,44],"tags":[],"class_list":["post-14570","post","type-post","status-publish","format-standard","category-health","category-health-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/14570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=14570"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/14570\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=14570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=14570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=14570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}