{"id":15923,"date":"2014-04-18T19:21:28","date_gmt":"2014-04-18T13:51:28","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=15923"},"modified":"2014-04-18T19:21:28","modified_gmt":"2014-04-18T13:51:28","slug":"%d8%a7%d9%86%d9%88%d8%b4%da%a9%d8%a7-%d8%a7%d9%88%d8%b1-%d8%b1%d9%86%d8%a8%db%8c%d8%b1-%da%a9%db%8c-%d9%81%d9%84%d9%85-%d8%a8%d8%a7%d9%85%d8%a8%db%92-%d9%88%db%8c%d9%84%d9%88%db%8c%d9%b9","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%a7%d9%86%d9%88%d8%b4%da%a9%d8%a7-%d8%a7%d9%88%d8%b1-%d8%b1%d9%86%d8%a8%db%8c%d8%b1-%da%a9%db%8c-%d9%81%d9%84%d9%85-%d8%a8%d8%a7%d9%85%d8%a8%db%92-%d9%88%db%8c%d9%84%d9%88%db%8c%d9%b9\/","title":{"rendered":"\u0627\u0646\u0648\u0634\u06a9\u0627 \u0627\u0648\u0631 \u0631\u0646\u0628\u06cc\u0631 \u06a9\u06cc \u0641\u0644\u0645 \u0628\u0627\u0645\u0628\u06d2 \u0648\u06cc\u0644\u0648\u06cc\u0679 \u2018 \u06a9\u06cc \u0639\u06a9\u0633 \u0628\u0646\u062f\u06cc \u0645\u06a9\u0645\u0644"},"content":{"rendered":"<p style=\"text-align: right;\"><a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/04\/Anushka-and-ranbeer.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"Anushka and ranbeer\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/04\/Anushka-and-ranbeer.jpg\" width=\"161\" height=\"150\" \/><\/a>\u0645\u0628\u0626\u06cc: \u0627\u0646\u0648\u0634\u06a9\u0627 \u0634\u0631\u0645\u0627 \u06a9\u06cc \u0631\u0646\u0628\u06cc\u0631 \u06a9\u067e\u0648\u0631 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u067e\u06c1\u0644\u06cc \u0641\u0644\u0645 \u2019\u2019\u0628\u0645\u0628\u0626\u06cc \u0648\u06cc\u0644\u0648\u0679\u2018\u2018 \u06a9\u06cc \u0639\u06a9\u0633\u0628\u0646\u062f\u06cc \u06af\u0632\u0634\u062a\u06c1 \u062f\u0646\u0648\u06ba \u062e\u062a\u0645 \u06c1\u0648\u06af\u0626\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0628 \u06c1\u062f\u0627\u06cc\u062a\u06a9\u0627\u0631 \u0627\u0646\u0648\u0631\u0627\u06af \u06a9\u0634\u06cc\u067e \u0646\u06d2 \u0627\u0633\u06d2 \u0628\u0627\u0642\u0627\u0639\u062f\u06c1 \u0637\u0648\u0631 \u067e\u0631 28 \u0646\u0648\u0645\u0628\u0631 \u06a9\u0648 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u06a9\u06cc \u0632\u06cc\u0646\u062a \u0628\u0646\u0627\u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u0631 \u062f\u06cc\u0627 \u06c1\u06d2\u06d4\u0641\u06cc\u0646\u0679\u0645 \u0641\u0644\u0645\u0632 \u0641\u0627\u06a9\u0633 \u0627\u0633\u0679\u0627\u0631 \u0627\u0633\u0679\u0648\u0688\u06cc\u0648\u0632 \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0645\u06cc\u06ba \u062a\u06cc\u0627\u0631 \u06a9\u06cc \u06af\u0626\u06cc \u0627\u0633 \u0641\u0644\u0645 \u0645\u06cc\u06ba \u0627\u0646\u0648\u0634\u06a9\u0627 \u0634\u0631\u0645\u0627 \u067e\u0627\u067e \u06af\u0644\u0648\u06a9\u0627\u0631\u06c1 \u06a9\u0627 \u0645\u0631\u06a9\u0632\u06cc \u06a9\u0631\u062f\u0627\u0631 \u06a9\u0631 \u0631\u06c1\u06cc \u06c1\u0648\u06ba\u062c\u0628 \u06a9\u06c1 \u0631\u0646\u0628\u06cc\u0631 \u06a9\u067e\u0648\u0631 \u0627\u06cc\u06a9 \u0628\u0627\u06a9\u0633\u0631 \u0627\u0648\u0631 \u06af\u0644\u06cc\u0648\u06ba \u0644\u0691\u0627\u0626\u06cc \u062c\u06be\u06af\u0691\u0627 \u06a9\u0631\u0646\u06cc\u0648\u0627\u0644\u06d2 \u0646\u0648\u062c\u0648\u0627\u0646 \u06a9\u0627 \u06a9\u0631\u062f\u0627\u0631 \u0627\u062f\u0627 \u06a9\u0631\u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0641\u0644\u0645 \u06a9\u0627 \u0645\u06cc\u0648\u0632\u06a9 \u0627\u0645\u06cc\u062a \u062a\u0631\u0648\u06cc\u062f\u06cc \u0646\u06d2 \u062a\u0631\u062a\u06cc\u0628 \u062f\u06cc\u0627 \u06c1\u06d2 \u062c\u0628 \u06a9\u06c1 \u0631\u0648\u06cc\u0646\u06c1 \u0679\u0646\u0688\u0646 \u060c \u06a9\u0631\u0646 \u062c\u0648\u06c1\u0631 \u060c \u06a9\u06d2 \u06a9\u06d2 \u0645\u06cc\u0646\u0646 \u060c \u0633\u062f\u06be\u0627\u0631\u062a\u06be \u0628\u0627\u0633\u0648\u0628\u06be\u06cc \u0627\u06c1\u0645 \u06a9\u0631\u062f\u0627\u0631 \u0646\u0628\u06be\u0627 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0641\u0644\u0645 \u0628\u0645\u0628\u06d2 \u0633\u0645\u0648\u0631\u0627\u0626\u06cc \u06a9\u0648 \u067e\u06c1\u0644\u06d2 \u06a9\u0631\u0633\u0645\u0633 \u06a9\u06d2 \u062f\u0646\u0648\u06ba \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06cc\u06d2 \u062c\u0627\u0646\u06d2 \u06a9\u0627 \u067e\u0631\u0648\u06af\u0631\u0627\u0645 \u062a\u06be\u0627 \u0645\u06af\u0631 \u0627\u0628 \u0627\u0633\u06d2 \u06a9\u0686\u06be \u06c1\u0641\u062a\u06d2 \u0642\u0628\u0644 \u06c1\u06cc \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u06a9\u06cc \u0632\u06cc\u0646\u062a \u0628\u0646\u0627\u06cc\u0627 \u062c\u0627\u0631\u06c1\u0627 \u06c1\u06d2 \u0627\u0633 \u0633\u0644\u0633\u0644\u06c1 \u0645\u06cc\u06ba \u06c1\u062f\u0627\u06cc\u062a\u06a9\u0627\u0631 \u0627\u0646\u0648\u0631\u0627\u06af \u06a9\u06cc\u0634\u067e \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06a9\u0631\u0633\u0645\u0633 \u06a9\u06d2 \u062f\u0646\u0648\u06ba \u0633\u067e\u0631 \u0627\u0633\u0679\u0627\u0631 \u0639\u0627\u0645\u0631 \u062e\u0627\u0646 \u06a9\u06cc \u0641\u0644\u0645 \u2019\u2019\u067e\u06cc \u06a9\u06d2\u2018\u2018 \u0628\u06be\u06cc \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u0627 \u062a\u06be\u06cc \u062c\u0633 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u062f\u0646\u0648\u06ba \u0641\u0644\u0645\u0648\u06ba \u06a9\u0627 \u0628\u0632\u0646\u0633 \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u0646\u06d2 \u06a9\u0627 \u062e\u062f\u0634\u06c1 \u062a\u06be\u0627 \u0627\u0648\u0631 \u0627\u0633\u06cc \u06a9\u06d2 \u067e\u06cc\u0634 \u0646\u0638\u0631 \u06c1\u0645 \u0646\u06d2 \u0627\u067e\u0646\u06cc \u0641\u0644\u0645 \u06a9\u0648 \u067e\u06cc \u06a9\u06d2 \u0633\u06d2 \u067e\u06c1\u0644\u06d2 28 \u0646\u0648\u0645\u0628\u0631 \u06a9\u0648 \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u0631\u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u0631\u062f\u06cc\u0627 \u06c1\u06d2\u06d4\u0628\u0627\u0644\u06cc \u0648\u0688 \u06a9\u0646\u06af \u0634\u0627\u06c1 \u0631\u062e \u062e\u0627\u0646 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0641\u0644\u0645 \u2019\u2019\u0631\u0628 \u0646\u06d2 \u0628\u0646\u0627 \u062f\u06cc \u062c\u0648\u0691\u06cc\u2018\u2018 \u0633\u06d2 \u0641\u0644\u0645\u06cc \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u0634\u0631\u0648\u0639 \u06a9\u0631\u0646\u06cc\u0648\u0627\u0644\u06cc \u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u0627\u0646\u0648\u0634\u06a9\u0627 \u0634\u0631\u0645\u0627 \u062c\u0648 \u0631\u0646\u0648\u06cc\u0631 \u0633\u0646\u06af\u06be \u060c \u0639\u0645\u0631\u0627\u0646 \u062e\u0627\u0646 \u060c \u0634\u0627\u06c1\u062f \u06a9\u067e\u0648\u0631 \u0627\u0648\u0631 \u0627\u06a9\u0634\u06d2 \u06a9\u0645\u0627\u0631 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0641\u0644\u0645\u06cc\u06ba \u06a9\u0631\u0686\u06a9\u06cc \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u06af\u0632\u0634\u062a\u06c1 \u0628\u0631\u0633 \u0627\u0633 \u06a9\u06cc \u0639\u0645\u0631\u0627\u0646 \u062e\u0627\u0646 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0635\u0631\u0641 \u0627\u06cc\u06a9 \u0641\u0644\u0645 \u2019\u2019\u0645\u062a\u0631\u0648 \u06a9\u06cc \u0628\u062c\u0644\u06cc \u06a9\u0627 \u0645\u0646\u0688\u0648\u0644\u0627\u2018\u2018 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u0627\u0648\u0631 \u0648\u06c1 \u0628\u06be\u06cc \u0628\u0631\u06cc \u0637\u0631\u062d \u0641\u0644\u0627\u067e \u06c1\u0648\u06af\u0626\u06cc \u06a9\u0648 \u0627\u067e\u0646\u06cc \u0627\u0633 \u0641\u0644\u0645 \u0633\u06d2 \u0628\u06c1\u062a \u0627\u0645\u06cc\u062f\u06cc\u06ba \u0648\u0627\u0628\u0633\u062a\u06c1 \u06c1\u06cc\u06ba\u06d4 \u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u2019\u2019\u0628\u0645\u0628\u0626\u06d2 \u0648\u06cc\u0644\u0648\u0679\u2018\u2018 \u0645\u06cc\u0631\u06d2 \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u06a9\u06cc \u0627\u06cc\u06a9 \u0627\u06c1\u0645 \u0641\u0644\u0645 \u06c1\u06d2 \u062c\u0633 \u0645\u06cc\u06ba \u067e\u0627\u067e \u06af\u0644\u0648\u06a9\u0627\u0631\u06c1 \u06a9\u0627 \u0645\u0631\u06a9\u0632\u06cc \u06a9\u0631\u062f\u0627\u0631 \u06a9\u0631 \u0631\u06c1\u06cc \u06c1\u0648\u06ba \u062c\u0633 \u06a9\u0648 \u067e\u0631\u0641\u0627\u0631\u0645 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u067e\u0627\u067e \u06af\u0644\u0648\u06a9\u0627\u0631\u0627\u0648\u0654\u06ba \u06a9\u06d2 \u0644\u0627\u0626\u0641 \u0627\u0633\u0679\u0627\u0626\u0644 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u067e\u0691\u06be\u0627 \u0627\u0648\u0631 \u062f\u06cc\u06a9\u06be\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u0633\u0644\u0633\u0644\u06c1 \u0645\u06cc\u06ba \u06c1\u062f\u0627\u06cc\u062a\u06a9\u0627\u0631 \u0688\u0627\u0626\u0631\u06cc\u06a9\u0679\u0631 \u0627\u0646\u0648\u0631\u0627\u06af \u06a9\u06cc\u0634\u067e \u0646\u06d2 \u0628\u06be\u06cc \u0645\u06cc\u0631\u06cc \u0628\u06c1\u062a \u0645\u062f\u062f \u06a9\u06cc \u06c1\u06d2\u06d4 \u0627\u0645\u06cc\u062f \u06c1\u06d2 \u0645\u062f\u0627\u062d\u0648\u06ba \u06a9\u0648 \u0645\u06cc\u0631\u06cc \u067e\u0631\u0641\u0627\u0631\u0645\u0646\u0633 \u067e\u0633\u0646\u062f \u0627\u0653\u0626\u06d2 \u06af\u06cc \u0627\u0648\u0631 \u06cc\u06c1 \u0641\u0644\u0645 \u0645\u06cc\u0631\u06d2 \u06a9\u06cc\u0631\u0626\u06cc\u0631 \u06a9\u06cc \u06cc\u0627\u062f\u06af\u0627\u0631 \u0641\u0644\u0645 \u062b\u0627\u0628\u062a \u06c1\u0648\u06af\u06cc\u06d4\u062f\u0648\u0633\u0631\u06cc \u0637\u0631\u0641 \u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u0627\u0633 \u0628\u0631\u0633 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0627\u06cc\u06a9 \u0627\u0648\u0631 \u0641\u0644\u0645 \u067e\u06cc \u06a9\u06d2 \u0645\u06cc\u06ba \u0628\u0627\u0644\u06cc \u0648\u0648\u062f \u0633\u067e\u0631 \u0627\u0633\u0679\u0627\u0631 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u06cc\u0646\u0645\u0627 \u0627\u0633\u06a9\u0631\u06cc\u0646 \u067e\u0631 \u062c\u0644\u0648\u06c1 \u06af\u0631 \u06c1\u0648\u0631\u06c1\u06cc \u06c1\u06cc\u06ba\u06d4 \u0641\u0644\u0645\u06cc \u067e\u0646\u0688\u062a\u0648\u06ba \u0646\u06d2 \u0641\u0644\u0645 \u2019\u2019\u0628\u0627\u0645\u0628\u06d2 \u0648\u06cc\u0644\u0648\u06cc\u0679\u2018\u2018 \u0627\u0648\u0631 \u2019\u2019 \u067e\u06cc \u06a9\u06d2\u2018\u2018 \u06a9\u0648 \u0628\u0691\u06cc \u0641\u0644\u0645\u06cc\u06ba \u0642\u0631\u0627\u0631 \u062f\u06cc\u0627 \u06c1\u06d2\u06d4 \u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u06a9\u06cc \u0628\u06be\u0627\u0631\u062a\u06cc \u06a9\u0631\u06a9\u0679\u0631 \u0648\u06cc\u0631\u0627\u062a \u06a9\u0648\u06c1\u0644\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0627\u0641\u06cc\u0626\u0631 \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba \u0628\u06be\u06cc \u06af\u0631\u0645 \u06c1\u06cc\u06ba \u062c\u0633 \u067e\u0631 \u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u06a9\u0627\u0641\u06cc \u067e\u0631\u06cc\u0634\u0627\u0646 \u0628\u06be\u06cc \u06c1\u06cc\u06ba \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0648\u06c1 \u0646\u06c1\u06cc\u06ba \u0686\u0627\u06c1\u062a\u06cc \u06a9\u06c1 \u0645\u06cc\u0688\u06cc\u0627 \u0645\u06cc\u06ba \u0627\u0633 \u0637\u0631\u062d \u06a9\u06cc \u062e\u0628\u0631\u0648\u06ba \u0633\u06d2 \u0627\u0646 \u06a9\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u0628\u0631\u0627 \u0627\u062b\u0631 \u067e\u0691\u06d2 \u0627\u0633\u06cc \u0644\u06cc\u06d2 \u0648\u06c1 \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u0627\u06cc\u0633\u06d2 \u0633\u0648\u0627\u0644\u0627\u062a \u06a9\u06d2 \u062c\u0648\u0627\u0628\u0627\u062a \u062f\u06cc\u0646\u06d2 \u0633\u06d2 \u06af\u0631\u06cc\u0632 \u06a9\u0631 \u0631\u06c1\u06cc \u06c1\u06cc\u06ba\u06d4\u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u067e\u062a\u06c1 \u0646\u06c1\u06cc\u06ba \u06a9\u06c1 \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u0648 \u0627\u067e\u0646\u06cc \u0630\u0627\u062a\u06cc \u0644\u0627\u0626\u0641 \u06a9\u06d2 \u067e\u06cc\u0686\u06be\u06d2 \u06a9\u06cc\u0648\u06ba \u067e\u0691\u06d2 \u06c1\u06cc\u06ba \u060c \u0627\u0646\u06be\u06cc\u06ba \u0686\u0627\u06c1\u06cc\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0635\u0631\u0641 \u06c1\u0645\u0627\u0631\u06d2 \u067e\u0631\u0627\u062c\u06cc\u06a9\u0679\u0633 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0644\u06a9\u06be\u06cc\u06ba \u0627\u0648\u0631 \u067e\u0648\u0686\u06be\u06cc\u06ba\u06d4 \u0645\u062c\u06be\u06d2 \u0627\u0633 \u06a9\u06cc \u06a9\u0648\u0626\u06cc \u067e\u0631\u0648\u0627\u06c1 \u0646\u06c1\u06cc\u06ba \u06a9\u0648\u0646 \u06a9\u06cc\u0627 \u06a9\u06c1\u06c1 \u0631\u06c1\u0627 \u06c1\u06d2 \u0645\u06cc\u06ba \u062a\u0648 \u0635\u0631\u0641 \u0627\u062a\u0646\u0627 \u062c\u0627\u0646\u062a\u06cc \u06c1\u0648\u06ba \u06a9\u06c1 \u0645\u062c\u06be\u06d2 \u062c\u0648 \u06a9\u0686\u06be \u0628\u06be\u06cc \u06a9\u0631\u0646\u0627 \u06c1\u06d2 \u0627\u0633 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u0633\u06cc \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u0646\u06c1\u06cc\u06ba \u06c1\u06d2\u06d4<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0628\u0626\u06cc: \u0627\u0646\u0648\u0634\u06a9\u0627 \u0634\u0631\u0645\u0627 \u06a9\u06cc \u0631\u0646\u0628\u06cc\u0631 \u06a9\u067e\u0648\u0631 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u067e\u06c1\u0644\u06cc \u0641\u0644\u0645 \u2019\u2019\u0628\u0645\u0628\u0626\u06cc \u0648\u06cc\u0644\u0648\u0679\u2018\u2018 \u06a9\u06cc \u0639\u06a9\u0633\u0628\u0646\u062f\u06cc \u06af\u0632\u0634\u062a\u06c1 \u062f\u0646\u0648\u06ba \u062e\u062a\u0645 \u06c1\u0648\u06af\u0626\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0628 \u06c1\u062f\u0627\u06cc\u062a\u06a9\u0627\u0631 \u0627\u0646\u0648\u0631\u0627\u06af \u06a9\u0634\u06cc\u067e \u0646\u06d2 \u0627\u0633\u06d2 \u0628\u0627\u0642\u0627\u0639\u062f\u06c1 \u0637\u0648\u0631 \u067e\u0631 28 \u0646\u0648\u0645\u0628\u0631 \u06a9\u0648 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u06a9\u06cc \u0632\u06cc\u0646\u062a \u0628\u0646\u0627\u0646\u06d2 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u06a9\u0631 \u062f\u06cc\u0627 \u06c1\u06d2\u06d4\u0641\u06cc\u0646\u0679\u0645 \u0641\u0644\u0645\u0632 \u0641\u0627\u06a9\u0633 \u0627\u0633\u0679\u0627\u0631 \u0627\u0633\u0679\u0648\u0688\u06cc\u0648\u0632 \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0645\u06cc\u06ba \u062a\u06cc\u0627\u0631 \u06a9\u06cc \u06af\u0626\u06cc \u0627\u0633 \u0641\u0644\u0645 \u0645\u06cc\u06ba [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,32],"tags":[],"class_list":["post-15923","post","type-post","status-publish","format-standard","category-entertainment","category-film"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/15923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=15923"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/15923\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=15923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=15923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=15923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}