{"id":164188,"date":"2025-07-23T11:10:46","date_gmt":"2025-07-23T05:40:46","guid":{"rendered":"https:\/\/dailyaag.com\/phase2\/?p=164188"},"modified":"2025-07-23T11:10:46","modified_gmt":"2025-07-23T05:40:46","slug":"medical-miracle-in-iran-the-girl-who-is-alive-with-a-third-heart","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/medical-miracle-in-iran-the-girl-who-is-alive-with-a-third-heart\/","title":{"rendered":"\u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u06ba \u0637\u0628\u06cc \u0645\u0639\u062c\u0632\u06c1\u061b \u0648\u06c1 \u0644\u0691\u06a9\u06cc \u062c\u0648 \u062a\u06cc\u0633\u0631\u06d2 \u062f\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0632\u0646\u062f\u06c1 \u06c1\u06d2"},"content":{"rendered":"<h3 style=\"text-align: right;\">\u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0646\u06c1\u0627\u06cc\u062a \u067e\u06cc\u0686\u06cc\u062f\u06c1 \u0622\u067e\u0631\u06cc\u0634\u0646 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0627\u06cc\u06a9 \u0644\u0691\u06a9\u06cc \u06a9\u0648 \u062f\u0648\u0633\u0631\u06cc \u0628\u0627\u0631 \u062f\u0644 \u06a9\u0627 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-164190\" src=\"https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/5606269.jpg\" alt=\"\" width=\"720\" height=\"480\" srcset=\"https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/5606269.jpg 720w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/5606269-300x200.jpg 300w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/5606269-90x60.jpg 90w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/5606269-180x120.jpg 180w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/5606269-95x64.jpg 95w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/>\u067e\u06cc\u0648\u0646\u062f \u0644\u06af\u0627\u06cc\u0627 \u06af\u06cc\u0627\u06d4<br \/>\n\u0627\u06cc\u0631\u0627\u0646 \u0646\u06d2 \u0627\u06cc\u06a9 \u0627\u0648\u0631 \u0633\u0646\u06af \u0645\u06cc\u0644 \u0639\u0628\u0648\u0631 \u06a9\u0631 \u0644\u06cc\u0627\u060c \u062c\u0628 \u0627\u06cc\u06a9 16 \u0633\u0627\u0644\u06c1 \u0644\u0691\u06a9\u06cc \u06a9\u0648 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0627 \u062a\u06cc\u0633\u0631\u0627 \u0645\u0648\u0642\u0639 \u062f\u0644 \u06a9\u0627 \u062f\u0648\u0633\u0631\u0627 \u067e\u06cc\u0648\u0646\u062f \u0644\u06af\u0627 \u06a9\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627\u06d4 \u0627\u0633 \u067e\u06cc\u0686\u06cc\u062f\u06c1 \u0633\u0631\u062c\u0631\u06cc \u0646\u06d2 \u0646\u06c1 \u0635\u0631\u0641 \u0627\u06cc\u0631\u0627\u0646\u06cc \u0637\u0628\u06cc \u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u06cc \u0645\u06c1\u0627\u0631\u062a \u06a9\u0627 \u0644\u0648\u06c1\u0627 \u0645\u0646\u0648\u0627\u06cc\u0627 \u0628\u0644\u06a9\u06c1 \u0627\u0646\u0633\u0627\u0646 \u062f\u0648\u0633\u062a\u06cc \u0627\u0648\u0631 \u0642\u0631\u0628\u0627\u0646\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u0632\u0646\u062f\u06c1 \u0645\u062b\u0627\u0644 \u0628\u06be\u06cc \u067e\u06cc\u0634 \u06a9\u06cc\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0628\u0686\u06cc \u062c\u0633 \u06a9\u0627 \u067e\u06c1\u0644\u0627 \u067e\u06cc\u0648\u0646\u062f 2017 \u0645\u06cc\u06ba \u06c1\u0648\u0627 \u062a\u06be\u0627\u060c \u06a9\u0686\u06be \u0639\u0631\u0635\u06c1 \u0642\u0628\u0644 \u062f\u0648\u0628\u0627\u0631\u06c1 \u067e\u06cc\u0686\u06cc\u062f\u06c1 \u0639\u0627\u0631\u0636\u06c1 \u0642\u0644\u0628 \u0645\u06cc\u06ba \u0645\u0628\u062a\u0644\u0627 \u06c1\u0648\u0626\u06cc\u06d4 \u0627\u0633\u06d2 \u06a9\u0631\u0648\u0646\u0631\u06cc \u0622\u0631\u0679\u0631\u06cc \u0648\u0627\u0633\u06a9\u0648\u0644\u0648\u067e\u06cc\u062a\u06be\u06cc \u062a\u0634\u062e\u06cc\u0635 \u06c1\u0648\u0626\u06cc\u060c \u062c\u0648 \u067e\u06cc\u0648\u0646\u062f \u06a9\u06d2 \u0628\u0639\u062f \u062f\u06be\u06cc\u0631\u06d2 \u062f\u06be\u06cc\u0631\u06d2 \u0634\u0631\u06cc\u0627\u0646\u0648\u06ba \u06a9\u06d2 \u0628\u0646\u062f \u06c1\u0648\u0646\u06d2 \u06a9\u06cc \u0627\u06cc\u06a9 \u062e\u0637\u0631\u0646\u0627\u06a9 \u06a9\u06cc\u0641\u06cc\u062a \u06c1\u06d2\u06d4 \u062d\u0627\u0644\u062a \u0627\u062a\u0646\u06cc \u0646\u0627\u0632\u06a9 \u06c1\u0648\u06af\u0626\u06cc \u06a9\u06c1 \u0628\u0686\u06cc \u06a9\u0648 \u062a\u06cc\u0646 \u0645\u06c1\u06cc\u0646\u06d2 \u062a\u06a9 \u0627\u0646\u062a\u06c1\u0627\u0626\u06cc \u0646\u06af\u06c1\u062f\u0627\u0634\u062a \u06a9\u06d2 \u0648\u0627\u0631\u0688 \u0645\u06cc\u06ba \u0631\u06a9\u06be\u0627 \u06af\u06cc\u0627\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u062a\u06cc\u0646 \u0645\u0627\u06c1 \u062a\u06a9 \u0648\u06c1 \u0628\u0686\u06cc \u0632\u0646\u062f\u06af\u06cc \u0627\u0648\u0631 \u0645\u0648\u062a \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u0645\u0639\u0644\u0642 \u0631\u06c1\u06cc\u06d4 \u067e\u06be\u0631 \u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u0646\u06d2 \u06c1\u0645\u062a \u0628\u0627\u0646\u062f\u06be\u06cc \u0627\u0648\u0631 \u0641\u06cc\u0635\u0644\u06c1 \u06a9\u06cc\u0627 \u06a9\u06c1 \u0648\u06c1 \u0627\u06cc\u06a9 \u0628\u0627\u0631 \u067e\u06be\u0631 \u062f\u0644 \u06a9\u0627 \u067e\u06cc\u0648\u0646\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u06cc\u06ba \u06af\u06d2\u06d4 \u0628\u0686\u0648\u06ba \u0645\u06cc\u06ba \u062f\u0648\u0628\u0627\u0631\u06c1 \u067e\u06cc\u0648\u0646\u062f \u0642\u0644\u0628 \u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u0646\u0627\u06cc\u0627\u0628 \u0627\u0648\u0631 \u0628\u06d2 \u062d\u062f \u062e\u0637\u0631\u0646\u0627\u06a9 \u062a\u0635\u0648\u0631 \u06a9\u06cc\u0627 \u062c\u0627\u062a\u0627 \u06c1\u06d2\u060c \u0644\u06cc\u06a9\u0646 \u0627\u06cc\u0631\u0627\u0646\u06cc \u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u0646\u06d2 \u0627\u0633 \u0686\u06cc\u0644\u0646\u062c \u06a9\u0648 \u0642\u0628\u0648\u0644 \u06a9\u06cc\u0627\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u0633\u06cc \u062f\u0648\u0631\u0627\u0646 \u0627\u06cc\u06a9 32 \u0633\u0627\u0644\u06c1 \u062e\u0627\u062a\u0648\u0646 \u0627\u06cc\u06a9 \u062d\u0627\u062f\u062b\u06d2 \u0645\u06cc\u06ba \u0645\u0631\u06af \u0645\u063a\u0632\u06cc \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u0648\u06af\u0626\u06cc\u06d4 \u0627\u0633 \u06a9\u06d2 \u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u062f\u06a9\u06be \u06a9\u0648 \u062e\u062f\u0645\u062a \u06a9\u06d2 \u062c\u0630\u0628\u06d2 \u0645\u06cc\u06ba \u0628\u062f\u0644\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u0633 \u06a9\u0627 \u062f\u0644 \u0639\u0637\u06cc\u06c1 \u06a9\u0631\u062f\u06cc\u0627 \u062a\u0627\u06a9\u06c1 \u0627\u06cc\u06a9 \u0627\u0648\u0631 \u0632\u0646\u062f\u06af\u06cc \u0628\u0686\u0627\u0626\u06cc \u062c\u0627\u0633\u06a9\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0622\u067e\u0631\u06cc\u0634\u0646 \u06a9\u0627 \u0639\u0645\u0644 12 \u06af\u06be\u0646\u0679\u06d2 \u062a\u06a9 \u062c\u0627\u0631\u06cc \u0631\u06c1\u0627\u06d4 \u0633\u0631\u062c\u0631\u06cc \u06a9\u0627 \u0639\u0645\u0644 \u0646\u0627\u06a9\u0627\u0645 \u06c1\u0648\u0646\u06d2 \u06a9\u0627 \u062e\u0637\u0631\u06c1 \u06c1\u0631 \u0644\u0645\u062d\u06d2 \u0645\u0648\u062c\u0648\u062f \u062a\u06be\u0627 \u0644\u06cc\u06a9\u0646 \u0634\u06c1\u06cc\u062f \u0631\u062c\u0627\u0626\u06cc \u06a9\u0627\u0631\u0688\u06cc\u0627\u0644\u0648\u062c\u06cc \u0633\u06cc\u0646\u0679\u0631 \u06a9\u06d2 \u0645\u0627\u06c1\u0631\u06cc\u0646 \u0646\u06d2 \u06c1\u0645\u062a \u0646\u06c1 \u06c1\u0627\u0631\u06cc\u060c \u062c\u062f\u0648\u062c\u06c1\u062f \u06a9\u06cc\u060c \u0627\u0648\u0631 \u0628\u0686\u06cc \u06a9\u0648 \u0627\u06cc\u06a9 \u0628\u0627\u0631 \u067e\u06be\u0631 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06cc \u0633\u0627\u0646\u0633\u06cc\u06ba \u0645\u0644 \u06af\u0626\u06cc\u06ba\u06d4 \u0622\u062c \u0648\u06c1 \u0646\u06c1 \u0635\u0631\u0641 \u0645\u0635\u0646\u0648\u0639\u06cc \u0633\u0627\u0646\u0633 \u06a9\u06d2 \u0622\u0644\u06d2 \u0633\u06d2 \u0622\u0632\u0627\u062f \u06c1\u06d2 \u0628\u0644\u06a9\u06c1 \u0645\u0633\u062a\u062d\u06a9\u0645 \u062d\u0627\u0644\u062a \u0645\u06cc\u06ba \u06c1\u06d2\u06d4 \u06cc\u06c1 \u0646\u06c1 \u0635\u0631\u0641 \u0627\u06cc\u06a9 \u06a9\u0627\u0645\u06cc\u0627\u0628 \u0633\u0631\u062c\u0631\u06cc \u06c1\u06d2\u060c \u0628\u0644\u06a9\u06c1 \u0627\u0646\u0633\u0627\u0646\u06cc \u06c1\u0645\u062f\u0631\u062f\u06cc\u060c \u0633\u0627\u0626\u0646\u0633\u06cc \u062a\u0631\u0642\u06cc\u060c \u0627\u0648\u0631 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0634\u0639\u0648\u0631 \u06a9\u06cc \u062c\u06cc\u062a \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u06cc\u06a9 \u0644\u0691\u06a9\u06cc \u062c\u0648 \u0628\u0631\u0633\u0648\u06ba \u0633\u06d2 \u067e\u06cc\u0648\u0646\u062f \u0634\u062f\u06c1 \u062f\u0644 \u06a9\u06d2 \u0633\u06c1\u0627\u0631\u06d2 \u0632\u0646\u062f\u06c1 \u062a\u06be\u06cc\u060c \u0627\u06cc\u06a9 \u0628\u0627\u0631 \u067e\u06be\u0631 \u0645\u0648\u062a \u06a9\u06d2 \u062f\u06c1\u0627\u0646\u06d2 \u067e\u0631 \u067e\u06c1\u0646\u0686 \u06af\u0626\u06cc\u06d4 \u067e\u0648\u0631\u06d2 \u06af\u06be\u0631 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0627\u062f\u0627\u0633 \u0627\u0648\u0631 \u06af\u06c1\u0631\u06cc \u062e\u0627\u0645\u0648\u0634\u06cc \u0686\u06be\u0627\u0626\u06cc \u06c1\u0648\u0626\u06cc \u062a\u06be\u06cc\u06d4 \u0635\u0631\u0641 \u062f\u0648 \u0622\u0648\u0627\u0632\u06cc\u06ba \u0633\u0646\u0627\u0626\u06cc \u062f\u06d2 \u0631\u06c1\u06cc \u062a\u06be\u06cc\u06ba\u06d4 \u0627\u06cc\u06a9 \u0645\u0627\u06ba \u06a9\u06cc \u0679\u0648\u0679\u06cc \u067e\u06be\u0648\u0679\u06cc \u0622\u06c1\u0648\u06ba \u06a9\u06cc\u060c \u0627\u0648\u0631 \u062f\u0648\u0633\u0631\u06cc \u0627\u0633 \u0644\u0691\u06a9\u06cc \u06a9\u06d2 \u0645\u062f\u06be\u0645 \u06a9\u0631\u0627\u06c1\u0648\u06ba \u06a9\u06cc \u062c\u0648 \u0627\u0628 \u0645\u0632\u06cc\u062f \u0642\u0648\u062a \u0646\u06c1\u06cc\u06ba \u0631\u06a9\u06be\u062a\u06cc \u062a\u06be\u06cc\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u06cc\u06c1 16 \u0633\u0627\u0644\u06c1 \u0644\u0691\u06a9\u06cc\u060c \u062c\u0648 \u06a9\u0626\u06cc \u0633\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0627\u06cc\u06a9 \u0639\u0637\u06cc\u06c1 \u06a9\u0631\u062f\u06c1 \u062f\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0632\u0646\u062f\u06c1 \u062a\u06be\u06cc\u060c \u0627\u0628 \u0627\u0633 \u06a9\u06cc \u0633\u0627\u0646\u0633\u06cc\u06ba \u0645\u062f\u06be\u0645 \u0627\u0648\u0631 \u0628\u06d2 \u062c\u0627\u0646 \u06c1\u0648\u062a\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u062a\u06be\u06cc\u06ba\u06d4 \u0627\u0633 \u06a9\u06cc \u0646\u0638\u0631\u06cc\u06ba \u0686\u06be\u062a \u067e\u0631 \u062c\u0645\u06cc \u06c1\u0648\u0626\u06cc \u062a\u06be\u06cc\u06ba\u060c \u062c\u06cc\u0633\u06d2 \u0648\u06c1 \u06a9\u0633\u06cc \u0627\u06cc\u0633\u06cc \u0634\u06d2 \u06a9\u06cc \u0645\u0646\u062a\u0638\u0631 \u06c1\u0648 \u062c\u0633 \u06a9\u06d2 \u0648\u0642\u062a\u0650\u0644 \u0622\u0645\u062f \u06a9\u0627 \u06a9\u0633\u06cc \u06a9\u0648 \u0639\u0644\u0645 \u0646\u06c1\u06cc\u06ba\u060c \u06cc\u0627 \u0634\u0627\u06cc\u062f \u0648\u06c1 \u0622\u0626\u06d2 \u06c1\u06cc \u0646\u06c1\u06cc\u06ba\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0648\u0627\u0644\u062f \u062e\u0627\u0645\u0648\u0634\u06cc \u0633\u06d2 \u06a9\u0645\u0631\u06d2 \u0645\u06cc\u06ba \u0679\u06c1\u0644 \u0631\u06c1\u06d2 \u062a\u06be\u06d2\u060c \u0645\u0627\u06ba \u0627\u067e\u0646\u06d2 \u0622\u0646\u0633\u0648 \u0686\u06be\u067e\u0627\u0646\u06d2 \u06a9\u06cc \u06a9\u0648\u0634\u0634 \u06a9\u0631 \u0631\u06c1\u06cc \u062a\u06be\u06cc\u06d4 \u0627\u0645\u06cc\u062f \u0627\u0646 \u06a9\u06cc \u0646\u06af\u0627\u06c1\u0648\u06ba \u0633\u06d2 \u06a9\u0628 \u06a9\u06cc \u0631\u062e\u0635\u062a \u06c1\u0648 \u0686\u06a9\u06cc \u062a\u06be\u06cc\u06d4 \u0627\u0628 \u0635\u0631\u0641 \u0627\u06cc\u06a9 \u0645\u0639\u062c\u0632\u06c1 \u06c1\u06cc \u0634\u0627\u06cc\u062f&#8230; \u0627\u0648\u0631 \u067e\u06be\u0631 \u0648\u06c1 \u062e\u0628\u0631 \u0622\u0626\u06cc!<\/h3>\n<h3 style=\"text-align: right;\">\u0679\u06cc\u0644\u06cc\u0641\u0648\u0646 \u06a9\u06cc \u06af\u06be\u0646\u0679\u06cc \u0628\u062c\u06cc\u06d4 \u062f\u0648\u0633\u0631\u06cc \u0637\u0631\u0641 \u0633\u06d2 \u0622\u0648\u0627\u0632 \u0622\u0626\u06cc: &#8220;\u0627\u06cc\u06a9 \u062f\u0644 \u0645\u0644 \u06af\u06cc\u0627 \u06c1\u06d2&#8230;&#8221;<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u06cc\u06a9 \u0645\u0627\u06ba \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0628\u0686\u06d2 \u06a9\u0627 \u062f\u0644 \u0639\u0637\u06cc\u06c1 \u06a9\u0631\u0646\u06d2 \u06a9\u0627 \u0641\u06cc\u0635\u0644\u06c1 \u06a9\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u0627\u0628\u060c \u0648\u06c1\u06cc \u0644\u0691\u06a9\u06cc \u0627\u06cc\u06a9 \u0632\u0646\u062f\u06c1 \u0645\u0639\u062c\u0632\u06c1 \u0628\u0646 \u0686\u06a9\u06cc \u06c1\u06d2\u06d4 \u0648\u06c1 \u0644\u0691\u06a9\u06cc \u062c\u0633 \u0646\u06d2 \u0627\u067e\u0646\u06cc \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u06ba \u062a\u06cc\u0646 \u062f\u0644\u0648\u06ba \u06a9\u0627 \u062a\u062c\u0631\u0628\u06c1 \u06a9\u06cc\u0627: \u067e\u06c1\u0644\u0627 \u062f\u0644 \u0627\u0633 \u06a9\u0627 \u0627\u067e\u0646\u0627\u060c \u062c\u0648 \u0642\u062f\u0631\u062a \u0646\u06d2 \u0627\u0633\u06d2 \u062f\u06cc\u0627 \u062a\u06be\u0627\u061b \u062f\u0648\u0633\u0631\u0627 \u062f\u0644 \u067e\u06c1\u0644\u0627 \u0639\u0637\u06cc\u06c1 \u0634\u062f\u06c1 \u062f\u0644\u060c \u062c\u0633 \u0646\u06d2 \u0627\u0633\u06d2 \u0646\u0626\u06cc \u0632\u0646\u062f\u06af\u06cc \u062f\u06cc\u061b \u062a\u06cc\u0633\u0631\u0627 \u062f\u0644 \u0627\u06cc\u06a9 \u0627\u0648\u0631 \u0645\u0627\u06ba \u06a9\u06d2 \u0627\u06cc\u062b\u0627\u0631 \u06a9\u0627 \u062b\u0645\u0631\u060c \u062c\u0633 \u0646\u06d2 \u0627\u06cc\u06a9 \u0645\u0631\u062a\u0628\u06c1 \u067e\u06be\u0631 \u0627\u0633 \u06a9\u0648 \u0632\u0646\u062f\u06af\u06cc \u06a9\u06cc \u0627\u0645\u06cc\u062f \u0639\u0637\u0627 \u06a9\u06cc\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u0628 \u0627\u0633 \u0644\u0691\u06a9\u06cc \u06a9\u06cc \u06c1\u0631 \u062f\u06be\u0691\u06a9\u0646 \u0645\u06cc\u06ba \u0632\u0646\u062f\u06af\u06cc\u060c \u0627\u06cc\u062b\u0627\u0631 \u0627\u0648\u0631 \u0646\u0626\u06cc \u0627\u0645\u06cc\u062f \u06a9\u06cc \u062f\u0627\u0633\u062a\u0627\u0646 \u0686\u06be\u067e\u06cc \u06c1\u06d2\u06d4 \u0644\u06cc\u06a9\u0646 \u0627\u0628 \u0627\u0633 \u06a9\u06d2 \u062f\u0644 \u06a9\u0627 \u0628\u0648\u062c\u06be \u0635\u0631\u0641 \u062c\u0633\u0645\u0627\u0646\u06cc \u0646\u06c1\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u0627\u062e\u0644\u0627\u0642\u06cc \u0627\u0648\u0631 \u0631\u0648\u062d\u0627\u0646\u06cc \u0628\u06be\u06cc \u06c1\u06d2 \u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0648\u06c1 \u062c\u0627\u0646\u062a\u06cc \u06c1\u06d2 \u06a9\u06c1 \u0627\u0633\u06d2 \u0627\u0633 \u0639\u0637\u06cc\u06c1 \u06a9\u0631\u062f\u06c1 \u062f\u0644 \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u0635\u0631\u0641 \u0627\u067e\u0646\u06d2 \u0644\u06cc\u06d2 \u0646\u06c1\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u0627\u0646 \u0645\u0627\u06ba \u0628\u0627\u067e \u06a9\u06d2 \u0644\u06cc\u06d2 \u0628\u06be\u06cc \u06a9\u0631\u0646\u06cc \u06c1\u06d2 \u062c\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0628\u0686\u06d2 \u06a9\u06d2 \u0628\u0686\u06be\u0691\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u06a9\u0633\u06cc \u0627\u0648\u0631 \u06a9\u06cc \u0632\u0646\u062f\u06af\u06cc \u0628\u0686\u0627\u0646\u06d2 \u06a9\u0627 \u0641\u06cc\u0635\u0644\u06c1 \u06a9\u06cc\u0627\u06d4 \u0627\u0628 \u0648\u06c1 \u067e\u06c1\u0644\u06d2 \u0633\u06d2 \u0628\u0691\u06be \u06a9\u0631 \u067e\u0631\u0639\u0632\u0645 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u067e\u0646\u0627 \u062e\u0648\u0627\u0628 \u067e\u0648\u0631\u0627 \u06a9\u0631\u06d2\u061b \u0627\u06cc\u06a9 \u06a9\u0627\u0631\u0688\u06cc\u0627\u0644\u0648\u062c\u0633\u0679 \u0628\u0646\u0646\u06d2 \u06a9\u0627 \u062e\u0648\u0627\u0628\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u06cc\u0631\u0627\u0646 \u06a9\u0627 \u0628\u0686\u0648\u06ba \u06a9\u06d2 \u062f\u0644 \u06a9\u06cc \u067e\u06cc\u0648\u0646\u062f\u06a9\u0627\u0631\u06cc \u0645\u06cc\u06ba \u062f\u0631\u062e\u0634\u0627\u06ba \u0645\u0642\u0627\u0645<\/h3>\n<h3 style=\"text-align: right;\">\u06c1\u0645 \u0646\u06d2 \u067e\u0648\u0686\u06be\u0627 \u06a9\u06c1 \u06a9\u06cc\u0627 \u0627\u0633 \u0644\u0691\u06a9\u06cc \u0633\u06d2 \u06af\u0641\u062a\u06af\u0648 \u0645\u0645\u06a9\u0646 \u06c1\u06d2\u061f \u062a\u0648 \u0688\u0627\u06a9\u0679\u0631 \u0646\u06d2 \u06c1\u0645\u062f\u0631\u062f\u0627\u0646\u06c1 \u0645\u0633\u06a9\u0631\u0627\u06c1\u0679 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u062d\u0642\u06cc\u0642\u062a \u067e\u0633\u0646\u062f\u0627\u0646\u06c1 \u0627\u0646\u062f\u0627\u0632 \u0645\u06cc\u06ba \u062c\u0648\u0627\u0628 \u062f\u06cc\u0627: \u0641\u06cc \u0627\u0644\u062d\u0627\u0644 \u0646\u06c1\u06cc\u06ba\u06d4 \u0622\u067e\u0631\u06cc\u0634\u0646 \u06a9\u06d2 \u0628\u0639\u062f \u062c\u0633\u0645\u0627\u0646\u06cc \u062d\u0627\u0644\u062a \u0627\u0648\u0631 \u0646\u06af\u06c1\u062f\u0627\u0634\u062a \u06a9\u06d2 \u062a\u0642\u0627\u0636\u06d2 \u0627\u06cc\u0633\u06cc \u0627\u062c\u0627\u0632\u062a \u0646\u06c1\u06cc\u06ba \u062f\u06cc\u062a\u06d2\u06d4 \u0644\u06cc\u06a9\u0646 \u0627\u062a\u0646\u0627 \u062c\u0627\u0646 \u0644\u06cc\u0646\u0627 \u06a9\u0627\u0641\u06cc \u06c1\u06d2 \u06a9\u06c1 \u0627\u0628 \u0648\u06c1 \u0644\u0691\u06a9\u06cc \u0648\u06cc\u0646\u0679\u06cc \u0644\u06cc\u0679\u0631 \u0633\u06d2 \u06c1\u0679\u0627 \u062f\u06cc \u06af\u0626\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u06cc\u06a9 \u0645\u0633\u062a\u062d\u06a9\u0645 \u062d\u0627\u0644\u062a \u0645\u06cc\u06ba \u0632\u0646\u062f\u06af\u06cc \u06af\u0632\u0627\u0631 \u0631\u06c1\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u06cc\u06c1\u06cc \u0633\u0628 \u0633\u06d2 \u0628\u0691\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u06ba \u0628\u0686\u0648\u06ba \u06a9\u06d2 \u062f\u0644 \u06a9\u06cc \u067e\u06cc\u0648\u0646\u062f\u06a9\u0627\u0631\u06cc \u06a9\u0627 \u0646\u06cc\u0627 \u0627\u0648\u0631 \u062c\u062f\u06cc\u062f \u0639\u0645\u0644 \u0633\u0627\u0644 2012 \u0633\u06d2 \u0628\u0627\u0636\u0627\u0628\u0637\u06c1 \u0637\u0648\u0631 \u067e\u0631 \u0634\u0631\u0648\u0639 \u06a9\u06cc\u0627 \u06af\u06cc\u0627\u06d4 \u0627\u064f\u0633 \u0648\u0642\u062a \u0634\u0627\u06cc\u062f \u0628\u06c1\u062a \u06a9\u0645 \u0644\u0648\u06af \u06cc\u0642\u06cc\u0646 \u0631\u06a9\u06be\u062a\u06d2 \u062a\u06be\u06d2 \u06a9\u06c1 \u0627\u06cc\u0631\u0627\u0646 \u0627\u0633 \u0645\u06cc\u062f\u0627\u0646 \u0645\u06cc\u06ba \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u062a\u0631\u0642\u06cc \u06cc\u0627\u0641\u062a\u06c1 \u0645\u0645\u0627\u0644\u06a9 \u06a9\u06cc \u0635\u0641 \u0645\u06cc\u06ba \u06a9\u06be\u0691\u0627 \u06c1\u0648 \u0633\u06a9\u06d2 \u06af\u0627\u06d4 \u0644\u06cc\u06a9\u0646 \u0622\u062c \u0627\u06cc\u0631\u0627\u0646 \u0646\u06d2 \u0627\u0633 \u0634\u0639\u0628\u06d2 \u0645\u06cc\u06ba \u0646\u0645\u0627\u06cc\u0627\u06ba \u0645\u0642\u0627\u0645 \u062d\u0627\u0635\u0644 \u06a9\u0631 \u0644\u06cc\u0627 \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u06ba \u0637\u0628\u06cc \u0645\u0639\u062c\u0632\u06c1\u061b \u0648\u06c1 \u0644\u0691\u06a9\u06cc \u062c\u0648 \u062a\u06cc\u0633\u0631\u06d2 \u062f\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0632\u0646\u062f\u06c1 \u06c1\u06d2<\/h3>\n<h3 style=\"text-align: right;\">\u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u06c1\u0631 \u0633\u0627\u0644 \u0628\u0686\u0648\u06ba \u06a9\u06d2 \u062f\u0644 \u06a9\u06cc \u062a\u0642\u0631\u06cc\u0628\u0627 550 \u0633\u06d2 600 \u067e\u06cc\u0648\u0646\u062f\u06a9\u0627\u0631\u06cc\u0627\u06ba \u06c1\u0648\u062a\u06cc \u06c1\u06cc\u06ba\u060c \u062c\u0646 \u0645\u06cc\u06ba \u0633\u06d2 30 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u06ba \u0627\u0646\u062c\u0627\u0645 \u067e\u0627\u062a\u06cc \u06c1\u06cc\u06ba\u06d4 \u06cc\u06c1 \u0627\u0639\u062f\u0627\u062f \u0648 \u0634\u0645\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646 \u06a9\u06cc \u0627\u0633 \u0634\u0639\u0628\u06d2 \u0645\u06cc\u06ba \u0642\u0627\u0628\u0644\u0650 \u062a\u0648\u062c\u06c1 \u067e\u06cc\u0634 \u0631\u0641\u062a \u06a9\u06cc \u06af\u0648\u0627\u06c1\u06cc \u062f\u06cc\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u06cc\u0631\u0627\u0646 \u0633\u06d2 \u062d\u0627\u0644\u06cc\u06c1 \u0634\u0627\u0626\u0639 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0627\u06cc\u06a9 \u062c\u062f\u06cc\u062f \u062a\u062d\u0642\u06cc\u0642 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642\u060c \u0628\u0686\u0648\u06ba \u06a9\u06d2 \u062f\u0644 \u06a9\u06cc \u067e\u06cc\u0648\u0646\u062f\u06a9\u0627\u0631\u06cc \u06a9\u06d2 \u0628\u0639\u062f \u067e\u0627\u0646\u0686 \u0633\u0627\u0644\u06c1 \u0628\u0642\u0627\u0621 \u06a9\u06cc \u0634\u0631\u062d 70 \u0641\u06cc\u0635\u062f \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06c1\u06d2\u06d4 \u06cc\u06c1 \u0634\u0631\u062d \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0633\u0628 \u0633\u06d2 \u062c\u062f\u06cc\u062f \u0627\u0648\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a\u06c1 \u0637\u0628\u06cc \u0645\u0631\u0627\u06a9\u0632 \u06a9\u06d2 \u0628\u0631\u0627\u0628\u0631 \u0628\u0644\u06a9\u06c1 \u0628\u0639\u0636 \u0627\u0648\u0642\u0627\u062a \u0627\u0646 \u0633\u06d2 \u0628\u06c1\u062a\u0631 \u06c1\u06d2\u06d4 \u06cc\u06c1 \u0627\u0633 \u0628\u0627\u062a \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a \u06c1\u06d2 \u06a9\u06c1 \u0627\u06cc\u0631\u0627\u0646 \u0646\u06c1 \u0635\u0631\u0641 \u062f\u0646\u06cc\u0627 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0642\u062f\u0645 \u0645\u0644\u0627 \u06a9\u0631 \u0686\u0644 \u0631\u06c1\u0627 \u06c1\u06d2\u060c \u0628\u0644\u06a9\u06c1 \u0628\u0639\u0636 \u0634\u0639\u0628\u0648\u06ba \u0645\u06cc\u06ba \u0622\u06af\u06d2 \u0628\u06be\u06cc \u0628\u0691\u06be \u0631\u06c1\u0627 \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u062d\u06a9\u0648\u0645\u062a \u06a9\u0627 \u0646\u06cc\u0627 \u0627\u0642\u062f\u0627\u0645\u060c \u0628\u0686\u0648\u06ba \u06a9\u0648 \u0645\u0641\u062a \u0639\u0644\u0627\u062c \u06a9\u06cc \u0641\u0631\u0627\u06c1\u0645\u06cc<\/h3>\n<h3 style=\"text-align: right;\">\u067e\u06cc\u0648\u0646\u062f\u06a9\u0627\u0631\u06cc \u06a9\u0627 \u0639\u0645\u0644 \u0627\u0646\u062c\u0627\u0645 \u062f\u06cc\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0688\u0627\u06a9\u0679\u0631 \u0645\u0647\u062f\u0648\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06d2 \u0627\u06cc\u06a9 \u0627\u06c1\u0645 \u0627\u0648\u0631 \u062d\u0648\u0635\u0644\u06c1 \u0627\u0641\u0632\u0627 \u0627\u0642\u062f\u0627\u0645 \u06a9\u06cc \u0637\u0631\u0641 \u0627\u0634\u0627\u0631\u06c1 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u062d\u0627\u0644 \u06c1\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0645\u0646\u0635\u0648\u0628\u06c1 \u0634\u0631\u0648\u0639 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2 \u062c\u0633 \u06a9\u06d2 \u062a\u062d\u062a \u0633\u0627\u062a \u0633\u0627\u0644 \u0633\u06d2 \u06a9\u0645 \u0639\u0645\u0631 \u0628\u0686\u0648\u06ba \u06a9\u0627 \u0639\u0644\u0627\u062c \u0645\u0641\u062a \u06c1\u0648\u06af\u0627\u06d4 \u06cc\u06c1 \u0628\u0686\u0648\u06ba \u06a9\u06cc \u062c\u0627\u0646 \u0628\u0686\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0633\u0628 \u0633\u06d2 \u0627\u0645\u06cc\u062f\u0628\u062e\u0634 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0645\u06cc\u06ba \u0633\u06d2 \u0627\u06cc\u06a9 \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0645\u0627\u0636\u06cc \u0645\u06cc\u06ba \u0628\u06c1\u062a \u0633\u06d2 \u062e\u0627\u0646\u062f\u0627\u0646 \u0645\u0627\u0644\u06cc \u0645\u0634\u06a9\u0644\u0627\u062a \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u06c1\u0633\u067e\u062a\u0627\u0644 \u06a9\u0627 \u0631\u062e \u0628\u06be\u06cc \u0646\u06c1\u06cc\u06ba \u06a9\u0631\u062a\u06d2 \u062a\u06be\u06d2\u060c \u0627\u0648\u0631 \u0627\u0641\u0633\u0648\u0633 \u06a9\u06cc \u0628\u0627\u062a \u06c1\u06d2 \u06a9\u06c1 \u0627\u0646 \u06a9\u06d2 \u0628\u0686\u06d2 \u0648\u06c1\u06cc\u06ba \u062f\u0645 \u062a\u0648\u0691 \u062f\u06cc\u062a\u06d2 \u062a\u06be\u06d2\u06d4 \u0644\u06cc\u06a9\u0646 \u0627\u0628 \u0627\u0633 \u0645\u0646\u0635\u0648\u0628\u06d2 \u06a9\u06cc \u0628\u062f\u0648\u0644\u062a\u060c \u0627\u06af\u0631 \u0622\u067e \u0635\u0631\u0641 \u06c1\u0633\u067e\u062a\u0627\u0644 \u06a9\u06d2 \u0635\u062d\u0646 \u0645\u06cc\u06ba \u0686\u06c1\u0644 \u0642\u062f\u0645\u06cc \u06a9\u0631\u06cc\u06ba\u060c \u062a\u0648 \u0622\u067e \u062f\u06cc\u06a9\u06be\u06cc\u06ba \u06af\u06d2 \u06a9\u06c1 \u06a9\u062a\u0646\u06d2 \u06c1\u06cc \u0645\u062d\u0631\u0648\u0645 \u062e\u0627\u0646\u062f\u0627\u0646 \u0627\u067e\u0646\u06d2 \u0628\u0686\u0648\u06ba \u06a9\u06d2<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0646\u06c1\u0627\u06cc\u062a \u067e\u06cc\u0686\u06cc\u062f\u06c1 \u0622\u067e\u0631\u06cc\u0634\u0646 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0627\u06cc\u06a9 \u0644\u0691\u06a9\u06cc \u06a9\u0648 \u062f\u0648\u0633\u0631\u06cc \u0628\u0627\u0631 \u062f\u0644 \u06a9\u0627 \u067e\u06cc\u0648\u0646\u062f \u0644\u06af\u0627\u06cc\u0627 \u06af\u06cc\u0627\u06d4 \u0627\u06cc\u0631\u0627\u0646 \u0646\u06d2 \u0627\u06cc\u06a9 \u0627\u0648\u0631 \u0633\u0646\u06af \u0645\u06cc\u0644 \u0639\u0628\u0648\u0631 \u06a9\u0631 \u0644\u06cc\u0627\u060c \u062c\u0628 \u0627\u06cc\u06a9 16 \u0633\u0627\u0644\u06c1 \u0644\u0691\u06a9\u06cc \u06a9\u0648 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0627 \u062a\u06cc\u0633\u0631\u0627 \u0645\u0648\u0642\u0639 \u062f\u0644 \u06a9\u0627 \u062f\u0648\u0633\u0631\u0627 \u067e\u06cc\u0648\u0646\u062f \u0644\u06af\u0627 \u06a9\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627\u06d4 \u0627\u0633 \u067e\u06cc\u0686\u06cc\u062f\u06c1 \u0633\u0631\u062c\u0631\u06cc \u0646\u06d2 \u0646\u06c1 \u0635\u0631\u0641 \u0627\u06cc\u0631\u0627\u0646\u06cc \u0637\u0628\u06cc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,47,39,38],"tags":[],"class_list":["post-164188","post","type-post","status-publish","format-standard","category-highlighted-news","category-marque","category-special","category-special-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=164188"}],"version-history":[{"count":1,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164188\/revisions"}],"predecessor-version":[{"id":164191,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164188\/revisions\/164191"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=164188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=164188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=164188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}