{"id":164277,"date":"2025-07-26T13:14:33","date_gmt":"2025-07-26T07:44:33","guid":{"rendered":"https:\/\/dailyaag.com\/phase2\/?p=164277"},"modified":"2025-07-26T13:14:33","modified_gmt":"2025-07-26T07:44:33","slug":"bomb-scare-at-mumbai-airport-police-conduct-secret-search","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/bomb-scare-at-mumbai-airport-police-conduct-secret-search\/","title":{"rendered":"\u0645\u0645\u0628\u0626\u06cc \u0627\u06cc\u0626\u0631 \u067e\u0648\u0631\u0679 \u067e\u0631 \u0628\u0645 \u06a9\u06cc \u062e\u0628\u0631 \u0633\u06d2 \u0627\u0641\u0631\u0627 \u062a\u0641\u0631\u06cc\u060c \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0686\u067e\u0651\u06d2 \u0686\u067e\u0651\u06d2 \u06a9\u06cc \u0644\u06cc \u062a\u0644\u0627\u0634\u06cc"},"content":{"rendered":"<h4 style=\"text-align: right;\">\u0645\u0645\u0628\u0626\u06cc \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0646\u0679\u0631\u0648\u0644 \u0631\u0648\u0645 \u06a9\u0648 \u06cc\u06a9\u06d2 \u0628\u0639\u062f \u062f\u06cc\u06af\u0631\u06d2 \u062a\u06cc\u0646 \u0627\u0644\u06af \u0627\u0644\u06af \u0646\u0645\u0628\u0631\u0648\u06ba \u0633\u06d2 \u0627\u0653\u0626\u06d2 \u062f\u06be\u0645\u06a9\u06cc \u0628\u06be\u0631\u06d2 \u0641\u0648\u0646 \u0633\u06d2 \u06c1\u0646\u06af\u0627\u0645\u06c1 \u0645\u0686 \u06af\u06cc\u0627\u06d4 \u0641\u0648\u0646 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0646\u06d2 \u062f\u0639\u0648\u06cc\u0670 \u06a9\u06cc\u0627 \u06a9\u06c1 \u0645\u0645\u0628\u0626\u06cc \u0627\u0646\u0679\u0631\u0646\u06cc\u0634\u0646\u0644 \u0627\u06cc\u0626\u0631 \u067e\u0648\u0631\u0679 \u067e\u0631 \u0628\u0645 \u0631\u06a9\u06be\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u06a9\u0686\u06be \u06c1\u06cc \u062f\u06cc\u0631 \u0645\u06cc\u06ba \u0632\u0648\u0631\u062f\u0627\u0631 \u062f\u06be\u0645\u0627\u06a9\u06c1 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u0627 \u06c1\u06d2\u06d4<\/h4>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-164279 aligncenter\" src=\"https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/mumbai.jpg\" alt=\"\" width=\"680\" height=\"400\" srcset=\"https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/mumbai.jpg 680w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2025\/07\/mumbai-300x176.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/h4>\n<h4 style=\"text-align: right;\">\u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u06cc\u0626\u0631 \u067e\u0648\u0631\u0679 \u0645\u06cc\u06ba \u0645\u0648\u062c\u0648\u062f \u0633\u06cc\u06a9\u0648\u0631\u06cc\u0679\u06cc \u0627\u06c1\u0644\u06a9\u0627\u0631 \u0645\u0633\u062a\u0639\u062f \u06c1\u0648 \u06af\u0626\u06d2 \u0627\u0648\u0631 \u067e\u0648\u0631\u06d2 \u0627\u062d\u0627\u0637\u06d2 \u0645\u06cc\u06ba \u062a\u0644\u0627\u0634\u06cc \u0645\u06c1\u0645 \u0634\u0631\u0648\u0639 \u06a9\u0631 \u062f\u06cc\u06d4 \u0627\u0633 \u062a\u0644\u0627\u0634\u06cc \u0645\u06cc\u06ba \u06a9\u0686\u06be \u0628\u06be\u06cc \u0645\u0634\u062a\u0628\u06c1 \u0645\u0644\u0646\u06d2 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0646\u06c1\u06cc\u06ba \u06c1\u06d2\u06d4<\/h4>\n<h4 style=\"text-align: right;\">\u0627\u06cc\u06a9 \u0627\u0641\u0633\u0631 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0648 \u062c\u0645\u0639\u06c1 \u06a9\u06cc \u062f\u06cc\u0631 \u0631\u0627\u062a \u0686\u06be\u062a\u0631\u067e\u062a\u06cc \u0634\u06cc\u0648\u0627\u062c\u06cc \u0645\u06c1\u0627\u0631\u0627\u062c \u0628\u06cc\u0646 \u0627\u0644\u0627\u0642\u0648\u0627\u0645\u06cc \u06c1\u0648\u0627\u0626\u06cc \u0627\u0688\u06d2 (\u0633\u06cc \u0627\u06cc\u0633 \u0627\u06cc\u0645 \u0627\u0653\u0626\u06cc \u0627\u06d2) \u06a9\u06d2 \u0679\u0631\u0645\u06cc\u0646\u0644 2 \u067e\u0631 \u062f\u06be\u0645\u06a9\u06cc \u0628\u06be\u0631\u0627 \u0641\u0648\u0646 \u0627\u0653\u06cc\u0627\u06d4 \u0627\u0633 \u062f\u06be\u0645\u06a9\u06cc \u06a9\u06d2 \u0628\u0639\u062f \u067e\u0648\u0631\u06d2 \u06c1\u0648\u0627\u0626\u06cc \u0627\u0688\u06c1 \u0627\u062d\u0627\u0637\u06d2 \u0645\u06cc\u06ba \u0627\u0641\u0631\u0627 \u062a\u0641\u0631\u06cc \u0645\u0686 \u06af\u0626\u06cc\u06d4 \u06c1\u0648\u0627\u0626\u06cc \u0627\u0688\u06c1 \u0627\u0646\u062a\u0638\u0627\u0645\u06cc\u06c1 \u0646\u06d2 \u0627\u0644\u0631\u0679 \u062c\u0627\u0631\u06cc \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u062a\u0644\u0627\u0634\u06cc \u0645\u06c1\u0645 \u0634\u0631\u0648\u0639 \u06a9\u0631 \u062f\u06cc \u062c\u0648 \u062a\u06cc\u0646 \u06af\u06be\u0646\u0679\u06d2 \u062a\u06a9 \u0686\u0644\u06cc\u06d4<\/h4>\n<h4 style=\"text-align: right;\">\u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u062c\u0627\u0646\u0686 \u0645\u06cc\u06ba \u06a9\u0686\u06be \u0628\u06be\u06cc \u0645\u0634\u062a\u0628\u06c1 \u0646\u06c1\u06cc\u06ba \u0645\u0644\u0627 \u0627\u0648\u0631 \u0645\u0645\u0628\u0626\u06cc \u067e\u0648\u0644\u06cc\u0633 \u06a9\u06d2 \u06a9\u0646\u0679\u0631\u0648\u0644 \u0631\u0648\u0645 \u0645\u06cc\u06ba \u0627\u0653\u06cc\u0627 \u06cc\u06c1 \u0641\u0648\u0646 \u06a9\u0627\u0644 \u0641\u0631\u0636\u06cc \u062b\u0627\u0628\u062a \u06c1\u0648\u0627\u06d4 \u0627\u0641\u0633\u0631 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0627\u06cc\u06a9 \u0627\u0648\u0631 \u06a9\u0627\u0644 \u0628\u06be\u06cc \u0627\u0653\u06cc\u0627 \u062a\u06be\u0627 \u062c\u0633 \u0645\u06cc\u06ba \u062f\u0639\u0648\u06cc\u0670 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06a9\u06c1 \u062f\u06be\u0645\u0627\u06a9\u06c1 \u0634\u0627\u0645 6:15 \u0628\u062c\u06d2 \u06c1\u0648\u06af\u0627\u06d4 \u062c\u0627\u0646\u0686 \u0645\u06cc\u06ba \u067e\u062a\u06c1 \u0686\u0644\u0627 \u06a9\u06c1 \u062f\u0648\u0646\u0648\u06ba \u0641\u0648\u0646 \u0627\u06cc\u06a9 \u06c1\u06cc \u0634\u062e\u0635 \u0646\u06d2 \u06a9\u06cc\u06d2 \u062a\u06be\u06d2\u06d4 \u0627\u0633 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0645\u0639\u0627\u0645\u0644\u06c1 \u062f\u0631\u062c \u06a9\u0631\u06a9\u06d2 \u0627\u0653\u06af\u06d2 \u06a9\u06cc \u06a9\u0627\u0631\u0631\u0648\u0627\u0626\u06cc \u06a9\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u06c1\u06d2\u06d4<\/h4>\n<h4 style=\"text-align: right;\">\u0627\u06cc\u06a9 \u062f\u06cc\u06af\u0631 \u0627\u0641\u0633\u0631 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0631\u06cc\u0644\u0648\u06d2 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u06d2 \u06a9\u0646\u0679\u0631\u0648\u0644 \u0631\u0648\u0645 \u06a9\u0648 \u0628\u06be\u06cc \u0686\u06be\u062a\u0631\u067e\u062a\u06cc \u0634\u06cc\u0648\u0627\u062c\u06cc \u0645\u06c1\u0627\u0631\u0627\u062c \u0679\u0631\u0645\u06cc\u0646\u0633 \u067e\u0631 \u062f\u06be\u0645\u0627\u06a9\u06c1 \u06c1\u0648\u0646\u06d2 \u06a9\u0627 \u062f\u06be\u0645\u06a9\u06cc \u0628\u06be\u0631\u0627 \u0641\u0648\u0646 \u0627\u0653\u06cc\u0627 \u062a\u06be\u0627\u060c \u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u0628\u0645 \u0688\u0633\u067e\u0648\u0632\u0644 \u062f\u0633\u062a\u06d2 \u0627\u0648\u0631 \u0688\u0627\u06af \u0627\u0633\u06a9\u0648\u0627\u0688 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06c1 \u06af\u06c1\u0631\u06cc \u062c\u0627\u0646\u0686 \u06a9\u06d2 \u0628\u0639\u062f \u06cc\u06c1 \u0628\u06be\u06cc \u0627\u06cc\u06a9 \u0641\u0631\u0636\u06cc \u0641\u0648\u0646 \u06a9\u0627\u0644 \u062b\u0627\u0628\u062a \u06c1\u0648\u0627\u06d4<\/h4>\n<h4 style=\"text-align: right;\">\u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u062c\u0627\u0646\u0686 \u0645\u06cc\u06ba \u0633\u0627\u0645\u0646\u06d2 \u0627\u0653\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06cc\u06c1 \u062f\u06be\u0645\u06a9\u06cc \u0628\u06be\u0631\u06d2 \u06a9\u0627\u0644 \u0627\u0653\u0633\u0627\u0645 \u0627\u0648\u0631 \u0645\u063a\u0631\u0628\u06cc \u0628\u0646\u06af\u0627\u0644 \u0633\u0631\u062d\u062f \u06a9\u06d2 \u067e\u0627\u0633 \u0641\u0639\u0627\u0644 \u0645\u0648\u0628\u0627\u0626\u0644 \u0646\u0645\u0628\u0631\u0648\u06ba \u06a9\u0627 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u06a9\u06d2 \u06a9\u06cc\u06d2 \u06af\u0626\u06d2 \u062a\u06be\u06d2\u06d4 \u0645\u0645\u0628\u0626\u06cc \u06a9\u06cc \u0627\u0653\u0632\u0627\u062f \u0645\u06cc\u062f\u0627\u0646 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0646\u0627\u0645\u0639\u0644\u0648\u0645 \u0641\u0648\u0646 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u062c\u0627\u0646\u0686 \u0634\u0631\u0648\u0639 \u06a9\u0631 \u062f\u06cc \u06c1\u06d2\u06d4<\/h4>\n<h4 style=\"text-align: right;\">\u0641\u06cc \u0627\u0644\u062d\u0627\u0644 \u067e\u0648\u0644\u06cc\u0633 \u0627\u0633 \u067e\u0648\u0631\u06d2 \u0645\u0639\u0627\u0645\u0644\u06d2 \u06a9\u06cc \u06af\u06c1\u0631\u0627\u0626\u06cc \u0633\u06d2 \u062c\u0627\u0646\u0686 \u06a9\u0631 \u0631\u06c1\u06cc \u06c1\u06d2 \u062a\u0627\u06a9\u06c1 \u062f\u06be\u0645\u06a9\u06cc \u062f\u06cc\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0634\u062e\u0635 \u062a\u06a9 \u067e\u06c1\u0646\u0686\u0627 \u062c\u0627 \u0633\u06a9\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06d2 \u0627\u0631\u0627\u062f\u0648\u06ba \u06a9\u0627 \u067e\u062a\u06c1 \u0644\u06af\u0627\u06cc\u0627 \u062c\u0627 \u0633\u06a9\u06d2\u06d4<\/h4>\n<h4 style=\"text-align: right;\">\u06cc\u06c1 \u067e\u06c1\u0644\u06cc \u0645\u0631\u062a\u0628\u06c1 \u0646\u06c1\u06cc\u06ba \u06c1\u06d2 \u062c\u0628 \u0645\u0645\u0628\u0626\u06cc \u0645\u06cc\u06ba \u06c1\u0648\u0627\u0626\u06cc \u0627\u0688\u06d2 \u06a9\u0648 \u0628\u0645 \u0633\u06d2 \u0627\u0691\u0627\u0646\u06d2 \u06a9\u06cc \u062f\u06be\u0645\u06a9\u06cc \u0645\u0644\u06cc \u06c1\u06d2\u06d4 \u0627\u0633 \u0633\u06d2 \u067e\u06c1\u0644\u06d2 19-17 \u062c\u0648\u0644\u0627\u0626\u06cc \u06a9\u0648 \u0646\u0648\u06cc \u0645\u0645\u0628\u0626\u06cc \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0645\u0634\u0646\u0631 \u0627\u0648\u0631 \u062c\u0648\u0627\u0626\u0646\u0679 \u06a9\u0645\u0634\u0646\u0631 \u06a9\u06d2 \u062f\u0641\u0627\u062a\u0631 \u0645\u06cc\u06ba \u06a9\u0626\u06cc \u062f\u06be\u06a9\u06cc \u0628\u06be\u0631\u06d2 \u0641\u0648\u0646 \u0627\u0653\u0626\u06d2 \u062a\u06be\u06d2\u06d4<\/h4>\n<h4 style=\"text-align: right;\">\u0627\u0646 \u0645\u06cc\u06ba \u0645\u0645\u0628\u0626\u06cc-\u0627\u062d\u0645\u062f \u0627\u0653\u0628\u0627\u062f \u06a9\u06cc \u0627\u0691\u0627\u0646 \u0645\u06cc\u06ba \u0628\u0645 \u06c1\u0648\u0646\u06d2 \u0627\u0648\u0631 \u06c1\u0648\u0627\u0626\u06cc \u0627\u0688\u06d2 \u067e\u0631 \u062f\u06be\u0645\u0627\u06a9\u06c1 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u062f\u06be\u0645\u06a9\u06cc \u062f\u06cc \u06af\u0626\u06cc \u062a\u06be\u06cc\u06d4 \u0627\u0646 \u0633\u0628\u06be\u06cc \u062f\u06be\u0645\u06a9\u06cc\u0648\u06ba \u06a9\u0648 \u062c\u0627\u0646\u0686 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u0641\u0648\u0627\u06c1 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627 \u0627\u0648\u0631 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0646\u0627\u0645\u0639\u0644\u0648\u0645 \u0644\u0648\u06af\u0648\u06ba \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0645\u0639\u0627\u0645\u0644\u06c1 \u062f\u0631\u062c \u06a9\u06cc\u0627\u06d4<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0645\u0628\u0626\u06cc \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0646\u0679\u0631\u0648\u0644 \u0631\u0648\u0645 \u06a9\u0648 \u06cc\u06a9\u06d2 \u0628\u0639\u062f \u062f\u06cc\u06af\u0631\u06d2 \u062a\u06cc\u0646 \u0627\u0644\u06af \u0627\u0644\u06af \u0646\u0645\u0628\u0631\u0648\u06ba \u0633\u06d2 \u0627\u0653\u0626\u06d2 \u062f\u06be\u0645\u06a9\u06cc \u0628\u06be\u0631\u06d2 \u0641\u0648\u0646 \u0633\u06d2 \u06c1\u0646\u06af\u0627\u0645\u06c1 \u0645\u0686 \u06af\u06cc\u0627\u06d4 \u0641\u0648\u0646 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0646\u06d2 \u062f\u0639\u0648\u06cc\u0670 \u06a9\u06cc\u0627 \u06a9\u06c1 \u0645\u0645\u0628\u0626\u06cc \u0627\u0646\u0679\u0631\u0646\u06cc\u0634\u0646\u0644 \u0627\u06cc\u0626\u0631 \u067e\u0648\u0631\u0679 \u067e\u0631 \u0628\u0645 \u0631\u06a9\u06be\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u06a9\u0686\u06be \u06c1\u06cc \u062f\u06cc\u0631 \u0645\u06cc\u06ba \u0632\u0648\u0631\u062f\u0627\u0631 \u062f\u06be\u0645\u0627\u06a9\u06c1 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u0627 \u06c1\u06d2\u06d4 \u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u06cc\u0626\u0631 \u067e\u0648\u0631\u0679 \u0645\u06cc\u06ba \u0645\u0648\u062c\u0648\u062f \u0633\u06cc\u06a9\u0648\u0631\u06cc\u0679\u06cc \u0627\u06c1\u0644\u06a9\u0627\u0631 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,47,23,22],"tags":[],"class_list":["post-164277","post","type-post","status-publish","format-standard","category-highlighted-news","category-marque","category-national","category-national-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=164277"}],"version-history":[{"count":2,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164277\/revisions"}],"predecessor-version":[{"id":164280,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164277\/revisions\/164280"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=164277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=164277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=164277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}