{"id":164549,"date":"2025-08-05T11:03:04","date_gmt":"2025-08-05T05:33:04","guid":{"rendered":"https:\/\/dailyaag.com\/phase2\/?p=164549"},"modified":"2025-08-05T11:03:04","modified_gmt":"2025-08-05T05:33:04","slug":"actors-body-found-in-car-parked-in-parking-lot","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/actors-body-found-in-car-parked-in-parking-lot\/","title":{"rendered":"\u067e\u0627\u0631\u06a9\u0646\u06af \u0645\u06cc\u06ba \u06a9\u06be\u0691\u06cc \u06af\u0627\u0691\u06cc \u0633\u06d2 \u0627\u062f\u0627\u06a9\u0627\u0631 \u06a9\u06cc \u0644\u0627\u0634 \u0628\u0631\u0627\u0653\u0645\u062f"},"content":{"rendered":"<h3 style=\"text-align: right;\">\u062c\u0646\u0648\u0628\u06cc \u06a9\u0648\u0631\u06cc\u0627 \u06a9\u06d2 \u0645\u0639\u0631\u0648\u0641 \u0627\u062f\u0627\u06a9\u0627\u0631 \u0633\u0648\u0646\u06af \u06cc\u0648\u0646\u06af \u06a9\u06cc\u0648 \u067e\u0627\u0631\u06a9\u0646\u06af \u0645\u06cc\u06ba \u06a9\u06be\u0691\u06cc \u06af\u0627\u0691\u06cc \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u0645\u0631\u062f\u06c1 \u067e\u0627\u0626\u06d2 \u06af\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/people.com\/thmb\/RghAef3VLmb18UXzKFEBTXqioEk=\/4000x0\/filters:no_upscale():max_bytes(150000):strip_icc():focal(753x250:755x252):format(webp)\/song-young-kyu-love-marriage-prm-8425-8f25cf495f3c4a57a27f6cb114004bf5.jpg\" alt=\"South Korean actor Song Young-Kyu attends the TV Chosun Drama &quot;Love And Marriage&quot; press conference on September 22, 2014 in Seoul, South Korea. The drama will open on September 27, in South Korea.\" \/><\/p>\n<h3 style=\"text-align: right;\">\u062c\u0646\u0648\u0628\u06cc \u06a9\u0648\u0631\u06cc\u0627 \u06a9\u06cc \u0646\u06cc\u0648\u0632 \u0627\u06cc\u062c\u0646\u0633\u06cc \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 55 \u0633\u0627\u0644\u06c1 \u0627\u062f\u0627\u06a9\u0627\u0631 \u0633\u0648\u0646\u06af \u06cc\u0648\u0646\u06af \u06a9\u06cc \u0644\u0627\u0634 \u067e\u06cc\u0631\u060c 4 \u0627\u06af\u0633\u062a \u06a9\u0648 \u0633\u06cc\u0626\u0648\u0644 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u0627\u064f\u0646 \u06a9\u06d2 \u0631\u06c1\u0627\u0626\u0634\u06cc \u06a9\u0645\u067e\u0644\u06cc\u06a9\u0633 \u0645\u06cc\u06ba \u06a9\u06be\u0691\u06cc \u06af\u0627\u0691\u06cc \u0633\u06d2 \u0628\u0631\u0622\u0645\u062f \u06c1\u0648\u0626\u06cc\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0631\u067e\u0648\u0631\u0679 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0627\u062f\u0627\u06a9\u0627\u0631 \u06a9\u0648 \u0635\u0628\u062d 8 \u0628\u062c\u06d2 \u0627\u06cc\u06a9 \u062c\u0627\u0646\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0646\u06d2 \u06af\u0627\u0691\u06cc \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u0645\u0631\u062f\u06c1 \u062d\u0627\u0644\u062a \u0645\u06cc\u06ba \u067e\u0627\u06cc\u0627\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u0648 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0627\u062f\u0627\u06a9\u0627\u0631 \u06a9\u06cc \u06af\u0627\u0691\u06cc \u0633\u06d2 \u06a9\u0648\u0626\u06cc \u062e\u0648\u062f\u06a9\u0634\u06cc \u06a9\u0627 \u0646\u0648\u0679 \u0645\u0644\u0627 \u0627\u0648\u0631 \u0646\u06c1 \u06c1\u06cc \u0627\u062f\u0627\u06a9\u0627\u0631 \u06a9\u06d2 \u0642\u062a\u0644 \u06a9\u06d2 \u06a9\u0648\u0626\u06cc \u0634\u0648\u0627\u06c1\u062f \u0633\u0627\u0645\u0646\u06d2 \u0622\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u062a\u0627\u06c1\u0645 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0644\u0627\u0634 \u06a9\u06cc \u067e\u0648\u0633\u0679 \u0645\u0627\u0631\u0679\u0645 \u0631\u067e\u0648\u0631\u0679 \u06a9\u06d2 \u0628\u0639\u062f \u06c1\u06cc \u0645\u0648\u062a \u06a9\u06cc \u0627\u0635\u0644 \u0648\u062c\u06c1 \u06a9\u0627 \u0645\u0639\u0644\u0648\u0645 \u06c1\u0648\u0633\u06a9\u06d2 \u06af\u0627\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\n\u06cc\u0627\u062f \u0631\u06c1\u06d2 \u06a9\u06c1 \u0633\u0648\u0646\u06af \u06cc\u0648\u0646\u06af \u06a9\u06cc\u0648 \u062d\u0627\u0644 \u06c1\u06cc \u0645\u06cc\u06ba \u0688\u0650\u0631\u0646\u06a9 \u0688\u0631\u0627\u0626\u06cc\u0648\u0646\u06af \u06a9\u06d2 \u0627\u06cc\u06a9 \u0648\u0627\u0642\u0639\u06d2 \u0645\u06cc\u06ba \u0645\u0644\u0648\u062b \u067e\u0627\u0626\u06d2 \u06af\u0626\u06d2 \u062a\u06be\u06d2\u060c \u062c\u06c1\u0627\u06ba \u0648\u06c1 3 \u0645\u06cc\u0644 \u062a\u06a9 \u0646\u0634\u06d2 \u06a9\u06cc \u062d\u0627\u0644\u062a \u0645\u06cc\u06ba \u06af\u0627\u0691\u06cc \u0686\u0644\u0627\u062a\u06d2 \u0631\u06c1\u06d2\u06d4 \u0627\u0646 \u06a9\u06d2 \u062e\u0648\u0646 \u0645\u06cc\u06ba \u0627\u0644\u06a9\u062d\u0644 \u06a9\u06cc \u0633\u0637\u062d \u0627\u062a\u0646\u06cc \u0632\u06cc\u0627\u062f\u06c1 \u062a\u06be\u06cc \u06a9\u06c1 \u0688\u0631\u0627\u0626\u06cc\u0648\u0646\u06af \u0644\u0627\u0626\u0633\u0646\u0633 \u0645\u0646\u0633\u0648\u062e\u06cc \u06a9\u06cc \u062d\u062f \u0633\u06d2 \u062a\u062c\u0627\u0648\u0632 \u06a9\u0631 \u06af\u0626\u06cc\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0648\u0627\u0642\u0639\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u0646\u06c1\u06cc\u06ba \u062a\u06cc\u0646 \u0645\u0646\u0635\u0648\u0628\u0648\u06ba \u0633\u06d2 \u0627\u0644\u06af \u06a9\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627 \u062a\u06be\u0627\u060c \u062c\u0646 \u0645\u06cc\u06ba \u062f\u0648 \u0688\u0631\u0627\u0645\u06d2 &#8220;\u062f\u06cc \u0688\u06cc\u0641\u06cc\u06a9\u0679\u0633&#8221; \u0627\u0648\u0631 &#8220;\u062f\u06cc \u0648\u0646\u0646\u06af \u0679\u0631\u0627\u0626\u06d2&#8221; \u0634\u0627\u0645\u0644 \u062a\u06be\u06d2\u060c \u062c\u0628\u06a9\u06c1 \u0648\u06c1 \u0627\u06cc\u06a9 \u0627\u0633\u0679\u06cc\u062c \u0688\u0631\u0627\u0645\u06c1 &#8220;\u0634\u06cc\u06a9\u0633\u067e\u0626\u0631 \u0627\u0650\u0646 \u0644\u0648&#8221; \u0633\u06d2 \u0628\u06be\u06cc \u0628\u0627\u06c1\u0631 \u06c1\u0648 \u06af\u0626\u06d2 \u062a\u06be\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0633\u0648\u0646\u06af \u0646\u06d2 2019 \u06a9\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628 \u0641\u0644\u0645 &#8220;\u0627\u06cc\u06a9\u0633\u0679\u0631\u06cc\u0645 \u062c\u0627\u0628&#8221; \u0645\u06cc\u06ba \u0686\u06cc\u0641 \u06a9\u0627 \u06a9\u0631\u062f\u0627\u0631 \u0646\u0628\u06be\u0627\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u0648\u06c1 \u0646\u06cc\u0679 \u0641\u0644\u06a9\u0633 \u06a9\u06d2 &#8220;\u0646\u0627\u0631\u06a9\u0648 \u0633\u06cc\u0646\u0679\u0633&#8221; \u0627\u0648\u0631 \u0688\u0632\u0646\u06cc \u067e\u0644\u0633 \u06a9\u06cc \u0633\u06cc\u0631\u06cc\u0632 &#8220;\u0628\u06af \u0628\u06cc\u0679&#8221; \u0645\u06cc\u06ba \u0628\u06be\u06cc \u062c\u0644\u0648\u06c1 \u06af\u0631 \u06c1\u0648\u0626\u06d2 \u062a\u06be\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u062c\u0646\u0648\u0628\u06cc \u06a9\u0648\u0631\u06cc\u0627 \u06a9\u06d2 \u0645\u0639\u0631\u0648\u0641 \u0627\u062f\u0627\u06a9\u0627\u0631 \u0633\u0648\u0646\u06af \u06cc\u0648\u0646\u06af \u06a9\u06cc\u0648 \u067e\u0627\u0631\u06a9\u0646\u06af \u0645\u06cc\u06ba \u06a9\u06be\u0691\u06cc \u06af\u0627\u0691\u06cc \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u0645\u0631\u062f\u06c1 \u067e\u0627\u0626\u06d2 \u06af\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4 \u062c\u0646\u0648\u0628\u06cc \u06a9\u0648\u0631\u06cc\u0627 \u06a9\u06cc \u0646\u06cc\u0648\u0632 \u0627\u06cc\u062c\u0646\u0633\u06cc \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 55 \u0633\u0627\u0644\u06c1 \u0627\u062f\u0627\u06a9\u0627\u0631 \u0633\u0648\u0646\u06af \u06cc\u0648\u0646\u06af \u06a9\u06cc \u0644\u0627\u0634 \u067e\u06cc\u0631\u060c 4 \u0627\u06af\u0633\u062a \u06a9\u0648 \u0633\u06cc\u0626\u0648\u0644 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u0627\u064f\u0646 \u06a9\u06d2 \u0631\u06c1\u0627\u0626\u0634\u06cc \u06a9\u0645\u067e\u0644\u06cc\u06a9\u0633 \u0645\u06cc\u06ba \u06a9\u06be\u0691\u06cc \u06af\u0627\u0691\u06cc \u0633\u06d2 \u0628\u0631\u0622\u0645\u062f \u06c1\u0648\u0626\u06cc\u06d4 \u0631\u067e\u0648\u0631\u0679 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0627\u062f\u0627\u06a9\u0627\u0631 \u06a9\u0648 \u0635\u0628\u062d [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,46,32],"tags":[],"class_list":["post-164549","post","type-post","status-publish","format-standard","category-entertainment","category-highlighted-news","category-film"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=164549"}],"version-history":[{"count":1,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164549\/revisions"}],"predecessor-version":[{"id":164550,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164549\/revisions\/164550"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=164549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=164549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=164549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}