{"id":164838,"date":"2025-08-20T11:49:19","date_gmt":"2025-08-20T06:19:19","guid":{"rendered":"https:\/\/dailyaag.com\/phase2\/?p=164838"},"modified":"2025-08-20T11:49:19","modified_gmt":"2025-08-20T06:19:19","slug":"attack-on-delhi-chief-minister-rekha-gupta-accused-arrested","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/attack-on-delhi-chief-minister-rekha-gupta-accused-arrested\/","title":{"rendered":"\u062f\u06c1\u0644\u06cc \u06a9\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0644\u06cc\u0670 \u0631\u06cc\u06a9\u06be\u0627 \u06af\u067e\u062a\u0627 \u067e\u0631 \u062d\u0645\u0644\u06c1\u060c \u0645\u0644\u0632\u0645 \u06af\u0631\u0641\u062a\u0627\u0631"},"content":{"rendered":"<h3 style=\"text-align: right;\">\u062f\u0627\u0631\u0627\u0644\u062d\u06a9\u0648\u0645\u062a \u062f\u06c1\u0644\u06cc \u06a9\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0644\u06cc\u0670 \u0631\u06cc\u06a9\u06be\u0627 \u06af\u067e\u062a\u0627 \u067e\u0631 \u0622\u062c \u0635\u0628\u062d \u0627\u0650\u0646 \u06a9\u06cc \u0631\u06c1\u0627\u0626\u0634 \u06af\u0627\u06c1 \u067e\u0631 \u0645\u0646\u0639\u0642\u062f\u06c1 \u06a9\u06be\u0644\u06cc \u06a9\u0686\u06c1\u0631\u06cc \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0627\u06cc\u06a9 \u0686\u0627\u0644\u06cc\u0633 \u0633\u0627\u0644\u06c1 \u0634\u062e\u0635 \u0646\u06d2 \u062d\u0645\u0644\u06c1 \u06a9\u0631\u062f\u06cc\u0627\u06d4<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/jang.com.pk\/assets\/uploads\/updates\/2025-08-20\/1502355_2218893_News2_updates.jpg\" alt=\"\u0641\u0648\u0679\u0648 \u0628\u0634\u06a9\u0631\u06cc\u06c1 \u0628\u06be\u0627\u0631\u062a\u06cc \u0645\u06cc\u0688\u06cc\u0627\" \/><\/p>\n<h3 style=\"text-align: right;\">\u00a0\u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0648\u0632\u06cc\u0631\u0627\u0639\u0644\u06cc\u0670 \u0631\u06cc\u06a9\u06be\u0627 \u06af\u067e\u062a\u0627 \u06a9\u06cc \u0633\u06cc\u06a9\u06cc\u0648\u0631\u0679\u06cc \u0679\u06cc\u0645 \u0646\u06d2 \u0641\u0648\u0631\u06cc \u0637\u0648\u0631 \u067e\u0631 \u062d\u0645\u0644\u06c1 \u0622\u0648\u0631 \u06a9\u0648 \u062d\u0631\u0627\u0633\u062a \u0645\u06cc\u06ba \u0644\u06d2 \u06a9\u0631 \u062a\u0641\u062a\u06cc\u0634 \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f\u06cc \u06c1\u06d2\u060c \u062d\u0645\u0644\u06c1 \u0622\u0648\u0631 \u06a9\u06cc \u0634\u0646\u0627\u062e\u062a \u0631\u0627\u062c\u06cc\u0634 \u0633\u06a9\u0627\u0631\u06cc\u0627 \u06a9\u06d2 \u0646\u0627\u0645 \u0633\u06d2 \u06c1\u0648\u0626\u06cc \u06c1\u06d2 \u062c\u0648 \u0631\u06cc\u0627\u0633\u062a \u06af\u062c\u0631\u0627\u062a \u06a9\u0627 \u0631\u06c1\u0627\u0626\u0634\u06cc \u0628\u062a\u0627\u06cc\u0627 \u062c\u0627\u0631\u06c1\u0627 \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0639\u06cc\u0646\u06cc \u0634\u0627\u06c1\u062f\u06cc\u0646 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062d\u0645\u0644\u06c1 \u0622\u0648\u0631 \u06a9\u0686\u06be \u06a9\u0627\u063a\u0630\u0627\u062a \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0648\u0632\u06cc\u0631\u0627\u0639\u0644\u06cc\u0670 \u06a9\u06d2 \u0642\u0631\u06cc\u0628 \u0622\u06cc\u0627 \u0627\u0648\u0631 \u0628\u0627\u062a \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0627\u0686\u0627\u0646\u06a9 \u062d\u0645\u0644\u06c1 \u06a9\u0631\u062f\u06cc\u0627\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u00a0\u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0648\u0632\u06cc\u0631\u0627\u0639\u0644\u06cc\u0670 \u06a9\u0648 \u0641\u0648\u0631\u0627\u064b \u0627\u0633\u067e\u062a\u0627\u0644 \u0645\u0646\u062a\u0642\u0644 \u06a9\u0631\u062f\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u067e\u0648\u0644\u06cc\u0633 \u06a9\u0645\u0634\u0646\u0631 \u0627\u06cc\u0633 \u0628\u06cc \u06a9\u06d2 \u0633\u0646\u06af\u06be \u06a9\u0627 \u0627\u0633 \u0633\u06d2 \u0645\u062a\u0639\u0644\u0642 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06cc\u06c1 \u0645\u0639\u0627\u0645\u0644\u06c1 \u0627\u06cc\u06a9 \u0628\u0691\u06cc \u0633\u06cc\u06a9\u06cc\u0648\u0631\u0679\u06cc \u0646\u0627\u06a9\u0627\u0645\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06cc \u0627\u0639\u0644\u06cc\u0670 \u0633\u0637\u062d \u067e\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u06c1\u0648\u06ba \u06af\u06cc\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u062f\u0648\u0633\u0631\u06cc \u062c\u0627\u0646\u0628 \u0628\u06cc \u062c\u06d2 \u067e\u06cc \u06a9\u06d2 \u0633\u06cc\u0646\u0626\u0631 \u0631\u06c1\u0646\u0645\u0627 \u06c1\u0631\u06cc\u0634 \u06a9\u06be\u0631\u0627\u0646\u06c1 \u0646\u06d2 \u062d\u0645\u0644\u06d2 \u06a9\u06cc \u0645\u0630\u0645\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0688\u0627\u06a9\u0679\u0631\u0632 \u0648\u0632\u06cc\u0631\u0627\u0639\u0644\u06cc\u0670 \u06a9\u0627 \u0645\u0639\u0627\u0626\u0646\u06c1 \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u060c \u06cc\u06c1 \u0627\u0646\u062a\u06c1\u0627\u0626\u06cc \u0627\u0641\u0633\u0648\u0633\u0646\u0627\u06a9 \u0648\u0627\u0642\u0639\u06c1 \u06c1\u06d2\u060c \u06c1\u0645\u06cc\u06ba \u062f\u06cc\u06a9\u06be\u0646\u0627 \u06c1\u0648\u06af\u0627 \u06a9\u06c1 \u0622\u06cc\u0627 \u0627\u0633 \u06a9\u06d2 \u067e\u06cc\u0686\u06be\u06d2 \u06a9\u0648\u0626\u06cc \u0633\u06cc\u0627\u0633\u06cc \u0633\u0627\u0632\u0634 \u062a\u0648 \u0646\u06c1\u06cc\u06ba\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u00a0\u0627\u067e\u0648\u0632\u06cc\u0634\u0646 \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0633\u06d2 \u0628\u06be\u06cc \u0627\u0633 \u0648\u0627\u0642\u0639\u06d2 \u06a9\u06cc \u0645\u0630\u0645\u062a \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u062f\u0627\u0631\u0627\u0644\u062d\u06a9\u0648\u0645\u062a \u062f\u06c1\u0644\u06cc \u06a9\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0644\u06cc\u0670 \u0631\u06cc\u06a9\u06be\u0627 \u06af\u067e\u062a\u0627 \u067e\u0631 \u0622\u062c \u0635\u0628\u062d \u0627\u0650\u0646 \u06a9\u06cc \u0631\u06c1\u0627\u0626\u0634 \u06af\u0627\u06c1 \u067e\u0631 \u0645\u0646\u0639\u0642\u062f\u06c1 \u06a9\u06be\u0644\u06cc \u06a9\u0686\u06c1\u0631\u06cc \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0627\u06cc\u06a9 \u0686\u0627\u0644\u06cc\u0633 \u0633\u0627\u0644\u06c1 \u0634\u062e\u0635 \u0646\u06d2 \u062d\u0645\u0644\u06c1 \u06a9\u0631\u062f\u06cc\u0627\u06d4 \u00a0\u0645\u06cc\u0688\u06cc\u0627 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0648\u0632\u06cc\u0631\u0627\u0639\u0644\u06cc\u0670 \u0631\u06cc\u06a9\u06be\u0627 \u06af\u067e\u062a\u0627 \u06a9\u06cc \u0633\u06cc\u06a9\u06cc\u0648\u0631\u0679\u06cc \u0679\u06cc\u0645 \u0646\u06d2 \u0641\u0648\u0631\u06cc \u0637\u0648\u0631 \u067e\u0631 \u062d\u0645\u0644\u06c1 \u0622\u0648\u0631 \u06a9\u0648 \u062d\u0631\u0627\u0633\u062a \u0645\u06cc\u06ba \u0644\u06d2 \u06a9\u0631 \u062a\u0641\u062a\u06cc\u0634 \u0634\u0631\u0648\u0639 \u06a9\u0631\u062f\u06cc \u06c1\u06d2\u060c \u062d\u0645\u0644\u06c1 \u0622\u0648\u0631 \u06a9\u06cc \u0634\u0646\u0627\u062e\u062a \u0631\u0627\u062c\u06cc\u0634 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,47,23,22],"tags":[],"class_list":["post-164838","post","type-post","status-publish","format-standard","category-highlighted-news","category-marque","category-national","category-national-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=164838"}],"version-history":[{"count":1,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164838\/revisions"}],"predecessor-version":[{"id":164839,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164838\/revisions\/164839"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=164838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=164838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=164838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}