{"id":164911,"date":"2025-08-22T12:53:32","date_gmt":"2025-08-22T07:23:32","guid":{"rendered":"https:\/\/dailyaag.com\/phase2\/?p=164911"},"modified":"2025-08-22T12:53:32","modified_gmt":"2025-08-22T07:23:32","slug":"netanyahu-orders-immediate-talks-to-free-gaza-hostages","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/netanyahu-orders-immediate-talks-to-free-gaza-hostages\/","title":{"rendered":"\u0646\u06cc\u062a\u0646 \u06cc\u0627\u06c1\u0648 \u06a9\u06cc \u063a\u0632\u06c1 \u0633\u06d2 \u06cc\u0631\u063a\u0645\u0627\u0644\u06cc\u0648\u06ba \u06a9\u06cc \u0631\u06c1\u0627\u0626\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u0641\u0648\u0631\u06cc \u0645\u0630\u0627\u06a9\u0631\u0627\u062a \u06a9\u06cc \u06c1\u062f\u0627\u06cc\u062a"},"content":{"rendered":"<h3 style=\"text-align: right;\">\u0627\u0633\u0631\u0627\u0626\u06cc\u0644\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0638\u0645 \u0646\u06cc\u062a\u0646 \u06cc\u0627\u06c1\u0648 \u0646\u06d2 \u063a\u0632\u06c1 \u062c\u0646\u06af \u0628\u0646\u062f\u06cc \u0645\u0630\u0627\u06a9\u0631\u0627\u062a \u0634\u0631\u0648\u0639 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u06c1\u062f\u0627\u06cc\u062a \u06a9\u0631\u062f\u06cc\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u062a\u0644 \u0627\u0628\u06cc\u0628 \u0633\u06d2 \u062e\u0628\u0631 \u0627\u06cc\u062c\u0646\u0633\u06cc \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0646\u06cc\u062a\u0646 \u06cc\u0627\u06c1\u0648 \u0646\u06d2 \u063a\u0632\u06c1 \u0633\u06d2 \u06cc\u0631\u063a\u0645\u0627\u0644\u06cc\u0648\u06ba \u06a9\u06cc \u0631\u06c1\u0627\u0626\u06cc \u06a9\u06d2 \u0644\u06cc\u06d2 \u0641\u0648\u0631\u06cc \u0645\u0630\u0627\u06a9\u0631\u0627\u062a \u0634\u0631\u0648\u0639 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u06c1\u062f\u0627\u06cc\u062a \u06a9\u0631 \u062f\u06cc \u06c1\u06d2\u06d4<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-156540\" src=\"https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2024\/11\/benjamin.jpg\" alt=\"\" width=\"800\" height=\"499\" srcset=\"https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2024\/11\/benjamin.jpg 800w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2024\/11\/benjamin-300x187.jpg 300w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2024\/11\/benjamin-120x76.jpg 120w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2024\/11\/benjamin-308x192.jpg 308w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2024\/11\/benjamin-610x380.jpg 610w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3 style=\"text-align: right;\">\u0627\u0633\u0631\u0627\u0626\u06cc\u0644\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0638\u0645 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0627\u0633\u0631\u0627\u0626\u06cc\u0644 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0642\u0627\u0628\u0644 \u0642\u0628\u0648\u0644 \u0634\u0631\u0627\u0626\u0637 \u067e\u0631 \u062c\u0646\u06af \u06a9\u06d2 \u062e\u0627\u062a\u0645\u06d2 \u0633\u06d2 \u0645\u062a\u0639\u0644\u0642 \u0628\u0627\u062a \u0686\u06cc\u062a \u06a9\u06cc \u06c1\u062f\u0627\u06cc\u062a \u0628\u06be\u06cc \u06a9\u06cc \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\n\u0627\u0633\u0631\u0627\u0626\u06cc\u0644\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0638\u0645 \u0646\u06d2 \u0627\u0633\u0631\u0627\u0626\u06cc\u0644\u06cc \u0641\u0648\u062c \u06a9\u06d2 \u063a\u0632\u06c1 \u0688\u0648\u06cc\u0698\u0646 \u06a9\u06d2 \u062f\u0648\u0631\u06d2 \u0645\u06cc\u06ba \u063a\u0632\u06c1 \u0634\u06c1\u0631 \u067e\u0631 \u0642\u0628\u0636\u06d2 \u0627\u0648\u0631 \u062d\u0645\u0627\u0633 \u06a9\u0648 \u0634\u06a9\u0633\u062a \u062f\u06cc\u0646\u06d2 \u06a9\u06d2 \u0645\u0646\u0635\u0648\u0628\u06d2 \u06a9\u06cc \u0645\u0646\u0638\u0648\u0631\u06cc \u062f\u06cc\u06d4 \u062a\u06cc\u0646 \u0631\u0648\u0632 \u067e\u06c1\u0644\u06d2\u062d\u0645\u0627\u0633 \u063a\u0632\u06c1 \u062c\u0646\u06af \u0628\u0646\u062f\u06cc \u06a9\u06cc \u0646\u0626\u06cc \u062a\u062c\u0627\u0648\u06cc\u0632 \u06a9\u06cc \u0645\u0646\u0638\u0648\u0631\u06cc \u062f\u06d2 \u0686\u06a9\u06cc \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\">\u0639\u0644\u0627\u0648\u06c1 \u0627\u0632\u06cc\u06ba \u0627\u0633\u0631\u0627\u0626\u06cc\u0644\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0638\u0645 \u062f\u0641\u062a\u0631 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0633\u0631\u0627\u0626\u06cc\u0644\u06cc \u0648\u0641\u062f \u0642\u0637\u0631 \u06cc\u0627 \u0645\u0635\u0631 \u0628\u06be\u06cc\u062c\u0646\u06d2 \u06a9\u0627 \u06a9\u0648\u0626\u06cc \u0645\u0646\u0635\u0648\u0628\u06c1 \u0646\u06c1\u06cc\u06ba \u06c1\u06d2\u06d4<\/h3>\n<h3 style=\"text-align: right;\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0633\u0631\u0627\u0626\u06cc\u0644\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0638\u0645 \u0646\u06cc\u062a\u0646 \u06cc\u0627\u06c1\u0648 \u0646\u06d2 \u063a\u0632\u06c1 \u062c\u0646\u06af \u0628\u0646\u062f\u06cc \u0645\u0630\u0627\u06a9\u0631\u0627\u062a \u0634\u0631\u0648\u0639 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u06c1\u062f\u0627\u06cc\u062a \u06a9\u0631\u062f\u06cc\u06d4 \u062a\u0644 \u0627\u0628\u06cc\u0628 \u0633\u06d2 \u062e\u0628\u0631 \u0627\u06cc\u062c\u0646\u0633\u06cc \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0646\u06cc\u062a\u0646 \u06cc\u0627\u06c1\u0648 \u0646\u06d2 \u063a\u0632\u06c1 \u0633\u06d2 \u06cc\u0631\u063a\u0645\u0627\u0644\u06cc\u0648\u06ba \u06a9\u06cc \u0631\u06c1\u0627\u0626\u06cc \u06a9\u06d2 \u0644\u06cc\u06d2 \u0641\u0648\u0631\u06cc \u0645\u0630\u0627\u06a9\u0631\u0627\u062a \u0634\u0631\u0648\u0639 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u06c1\u062f\u0627\u06cc\u062a \u06a9\u0631 \u062f\u06cc \u06c1\u06d2\u06d4 \u0627\u0633\u0631\u0627\u0626\u06cc\u0644\u06cc \u0648\u0632\u06cc\u0631\u0627\u0639\u0638\u0645 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0627\u0633\u0631\u0627\u0626\u06cc\u0644 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0642\u0627\u0628\u0644 \u0642\u0628\u0648\u0644 \u0634\u0631\u0627\u0626\u0637 \u067e\u0631 \u062c\u0646\u06af \u06a9\u06d2 \u062e\u0627\u062a\u0645\u06d2 \u0633\u06d2 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,25,47,24],"tags":[],"class_list":["post-164911","post","type-post","status-publish","format-standard","category-highlighted-news","category-international","category-marque","category-international-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=164911"}],"version-history":[{"count":1,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164911\/revisions"}],"predecessor-version":[{"id":164912,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/164911\/revisions\/164912"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=164911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=164911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=164911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}