{"id":18441,"date":"2014-05-20T16:19:44","date_gmt":"2014-05-20T10:49:44","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=18441"},"modified":"2014-05-20T16:19:44","modified_gmt":"2014-05-20T10:49:44","slug":"%d8%a7%db%8c%d8%b3-%d9%be%db%8c-%d8%af%d9%81%d8%aa%d8%b1-%d9%85%db%8c%da%ba-%d8%af%d8%b1%d8%ac%db%81-%da%86%db%81%d8%a7%d8%b1%d9%85-%da%a9%db%92-%d9%85%d9%84%d8%a7%d8%b2%d9%85-%d9%86%db%92-%d9%84","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%a7%db%8c%d8%b3-%d9%be%db%8c-%d8%af%d9%81%d8%aa%d8%b1-%d9%85%db%8c%da%ba-%d8%af%d8%b1%d8%ac%db%81-%da%86%db%81%d8%a7%d8%b1%d9%85-%da%a9%db%92-%d9%85%d9%84%d8%a7%d8%b2%d9%85-%d9%86%db%92-%d9%84\/","title":{"rendered":"\u0627\u06cc\u0633 \u067e\u06cc \u062f\u0641\u062a\u0631 \u0645\u06cc\u06ba \u062f\u0631\u062c\u06c1 \u0686\u06c1\u0627\u0631\u0645 \u06a9\u06d2 \u0645\u0644\u0627\u0632\u0645 \u0646\u06d2 \u0644\u06af\u0627\u0626\u06cc \u067e\u06be\u0627\u0646\u0633\u06cc"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-10880\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/02\/fansi1.jpg\" alt=\"fansi\" width=\"249\" height=\"187\" \/>\u06a9\u0627\u0646\u067e\u0648\u0631 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u0627\u06cc\u0633 \u067e\u06cc \u0645\u063a\u0631\u0628\u06cc \u062f\u0641\u062a\u0631 \u0645\u06cc\u06ba \u062a\u0639\u06cc\u0646\u0627\u062a \u062f\u0631\u062c\u06c1 \u0686\u06c1\u0627\u0631\u0645 \u06a9\u06d2 \u0645\u0644\u0627\u0632\u0645 \u0646\u06d2 \u0633\u0627\u0691\u06cc \u06a9\u0627 \u067e\u06be\u0646\u062f\u06c1 \u0644\u06af\u0627 \u06a9\u0631 \u067e\u0646\u06a9\u06be\u06d2 \u06a9\u06d2 \u06a9\u0646\u0688\u06d2 \u0633\u06d2 \u0644\u0679\u06a9 \u06a9\u0631 \u062e\u0648\u062f\u06a9\u0634\u06cc \u06a9\u0631\u0644\u06cc\u06d4\u0688\u06cc\u0648\u0679\u06cc \u067e\u0631 \u062a\u0639\u06cc\u0646\u0627\u062a \u062f\u0627\u0631\u0648\u063a\u06c1 \u06a9\u0627 \u0645\u0644\u0627\u0632\u0645 \u06a9\u06cc \u0644\u0627\u0634 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u06c1\u0648\u0634 \u0627\u0691\u06af\u0626\u06d2\u06d4 \u0648\u0627\u0642\u0639\u06c1 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u0646\u06d2 \u067e\u0631 \u067e\u06c1\u0646\u0686\u06cc \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0644\u0627\u0634 \u06a9\u0648 \u0646\u06cc\u0686\u06d2 \u0627\u062a\u0627\u0631\u0627 \u0627\u0648\u0631 \u062a\u0641\u062a\u06cc\u0634 \u06a9\u06cc\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0648\u0627\u0642\u0639\u06c1 \u06a9\u0627 \u0633\u0628\u0628 \u0642\u0631\u0636 \u0627\u0648\u0631 \u0628\u06cc\u0679\u06d2 \u06a9\u06cc \u0645\u062d\u0628\u062a \u06a9\u06cc \u0634\u0627\u062f\u06cc \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u062e\u0627\u0646\u062f\u0627\u0646 \u0645\u06cc\u06ba \u0627\u062e\u062a\u0644\u0627\u0641 \u062a\u06be\u0627\u06d4\u0627\u0679\u0627\u0648\u06c1 \u06a9\u0627 \u0631\u06c1\u0646\u06d2 \u0648\u0627\u0644\u0627 \u06f3\u06f5\u0633\u0627\u0644\u06c1 \u0648\u06cc\u0631\u06cc\u0646\u062f\u0631 \u06a9\u0645\u0627\u0631 \u067e\u0648\u0644\u06cc\u0633 \u0645\u062d\u06a9\u0645\u06c1 \u0645\u06cc\u06ba \u062f\u0631\u062c\u06c1 \u0686\u06c1\u0627\u0631\u0645 \u0645\u06cc\u06ba \u0635\u0641\u0627\u0626\u06cc \u0645\u0644\u0627\u0632\u0645 \u062a\u06be\u0627\u06d4\u06cc\u06c1\u0627\u06ba \u067e\u0631 \u0645\u0644\u0627\u0632\u0645 \u0627\u06cc\u0633 \u067e\u06cc \u0645\u063a\u0631\u0628\u06cc \u062f\u0641\u062a\u0631 \u0633\u06d2 \u0645\u0646\u0633\u0644\u06a9 \u062a\u06be\u0627 \u0627\u0648\u0631 \u0648\u06c1\u0627\u06ba \u0635\u0641\u0627\u0626\u06cc \u06a9\u0627\u06a9\u0627\u0645 \u06a9\u0631\u062a\u0627\u062a\u06be\u0627\u06d4\u0645\u0644\u0627\u0632\u0645 \u067e\u0648\u0644\u06cc\u0633 \u0644\u0627\u0626\u0646 \u0645\u06cc\u06ba \u0632\u0648\u062c\u06c1 \u0633\u0646\u062f\u06be\u06cc\u0627 \u062f\u0648\u0628\u06cc\u0679\u0648\u06ba \u062c\u0627\u0646\u06cc \u0627\u0648\u0631 \u0628\u0631\u062c\u06cc\u0646\u062f\u0631 \u0627\u0648\u0631 \u0628\u06cc\u0679\u06cc \u0628\u0628\u0644\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0631\u06c1\u062a\u0627\u062a\u06be\u0627\u06d4\u0686\u06be \u0645\u0627\u06c1 \u0642\u0628\u0644 \u0627\u0633 \u0646\u06d2 \u0627\u067e\u0646\u06cc \u0644\u0691\u06a9\u06cc \u06a9\u06cc \u0634\u0627\u062f\u06cc \u06a9\u0631\u062f\u06cc \u062a\u06be\u06cc \u062c\u0633 \u0645\u06cc\u06ba \u0627\u0633 \u0646\u06d2 \u0627\u06cc\u06a9 \u06a9\u0627\u0631 \u0628\u06be\u06cc \u062f\u06cc \u062a\u06be\u06cc\u06d4<br \/>\n\u0634\u0627\u062f\u06cc \u0645\u06cc\u06ba \u062d\u06cc\u062b\u06cc\u062a \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u0633\u0627\u0645\u0627\u0646 \u062f\u06cc\u0646\u06d2 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u0627\u0633 \u067e\u0631 \u0642\u0631\u0636 \u06a9\u0627 \u0628\u0648\u062c\u06be \u06c1\u0648\u06af\u06cc\u0627\u06d4\u062f\u0648\u0633\u0631\u06cc \u0637\u0631\u0641 \u0686\u06be \u0645\u0627\u06c1 \u0642\u0628\u0644 \u0627\u0633 \u06a9\u06d2 \u0644\u0691\u06a9\u06d2 \u062c\u0627\u0646\u06cc \u0646\u06d2 \u0645\u062d\u0628\u062a \u06a9\u06cc \u0634\u0627\u062f\u06cc \u0628\u06be\u06cc \u06a9\u0631\u0644\u06cc \u062a\u06be\u06cc \u062c\u0633 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u06af\u06be\u0631 \u0645\u06cc\u06ba \u0627\u062e\u062a\u0644\u0627\u0641\u0627\u062a \u06c1\u0648\u0646\u06d2 \u0644\u06af\u06d2\u06d4\u062c\u0633 \u0633\u06d2 \u0639\u0627\u062c\u0632 \u06c1\u0648\u06a9\u0631 \u067e\u06cc\u0631 \u06a9\u06cc \u0635\u0628\u062d \u067e\u0627\u0646\u0686 \u0628\u062c\u06d2 \u0627\u06cc\u0633 \u067e\u06cc \u062f\u0641\u062a\u0631 \u067e\u06c1\u0646\u0686\u0627 \u0627\u0648\u0631 \u0641\u06cc\u0645\u0644\u06cc<br \/>\n\u0635\u0644\u0627\u062d \u0648\u0645\u0634\u0648\u0631 \u0645\u0631\u06a9\u0632 \u06a9\u06d2 \u06a9\u0645\u0631\u06d2 \u0645\u06cc\u06ba \u062c\u0627\u06a9\u0631 \u0632\u0648\u062c\u06c1 \u06a9\u06cc \u0633\u0627\u0691\u06cc \u06a9\u0627 \u067e\u06be\u0646\u062f\u06c1 \u0628\u0646\u0627\u06a9\u0631 \u067e\u06be\u0646\u06a9\u06be\u06d2 \u06a9\u06d2 \u06a9\u0646\u0688\u06c1 \u0645\u06cc\u06ba \u067e\u06be\u0627\u0646\u0633\u06cc \u0644\u06af\u0627 \u06a9\u0631 \u062e\u0648\u062f\u06a9\u0634\u06cc \u06a9\u0631\u0644\u06cc \u0648\u0627\u0642\u0639\u06c1 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0627\u0633 \u0648\u0642\u062a \u06c1\u0648\u0626\u06cc \u062c\u0628 \u0627\u06cc\u0633 \u067e\u06cc \u062f\u0641\u062a\u0631 \u0645\u06cc\u06ba \u062a\u0639\u06cc\u0646\u0627\u062a \u062f\u0627\u0631\u0648\u063a\u06c1 \u0627\u0634\u0648\u06a9 \u062f\u0648\u0628\u06d2 \u0635\u0628\u062d \u06f9\u0628\u062c\u06d2 \u0688\u06cc\u0648\u0679\u06cc \u067e\u0631 \u06af\u0626\u06d2\u06d4 \u06a9\u0645\u0631\u06d2 \u0645\u06cc\u06ba \u067e\u06be\u0627\u0646\u0633\u06cc \u067e\u0631 \u0644\u0679\u06a9\u06cc \u0644\u0627\u0634 \u062f\u06cc\u06a9\u06be \u0627\u0633 \u06a9\u06d2 \u06c1\u0648\u0634 \u0627\u0691 \u06af\u0626\u06d2\u06d4 \u0627\u0633 \u0646\u06d2 \u0648\u0627\u0642\u0639\u06c1 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0627\u0653\u0631 \u0627\u0653\u0626\u06cc \u0627\u0648\u062f\u06be\u06cc\u0634 \u067e\u0627\u0646\u062f\u06d2 \u060c\u0627\u06cc\u0633 \u067e\u06cc \u0645\u063a\u0631\u0628 \u06af\u0648\u0631\u0648 \u0633\u0646\u06af\u06be \u0627\u0648\u0631 \u062a\u06be\u0627\u0646\u06c1 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0648\u062a\u0648\u0627\u0644\u06cc \u06a9\u0648\u062f\u06cc\u06d4 \u0645\u0648\u0642\u0639 \u067e\u0631 \u06a9\u0648\u062a\u0648\u0627\u0644\u06cc \u0627\u0646\u0686\u0627\u0631\u062c \u0627\u0648\u0631 \u0627\u0639\u0644\u06cc\u0670 \u0627\u0641\u0633\u0631\u0627\u0646 \u0628\u06be\u06cc \u0627\u0653\u06af\u0626\u06d2\u06d4 \u0644\u0627\u0634 \u06a9\u0648 \u067e\u06be\u0627\u0646\u0633\u06cc \u0633\u06d2 \u0646\u06cc\u0686\u06d2 \u0627\u062a\u0627\u0631\u06a9\u0631 \u0627\u0633 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0627\u0633 \u06a9\u06d2 \u06a9\u0646\u0628\u06c1 \u0648\u0627\u0644\u0648\u06ba \u06a9\u0648 \u062f\u06cc\u06d4\u0627\u06cc\u0633 \u0627\u06cc\u0633 \u067e\u06cc \u0627\u062c\u06d2 \u06a9\u0645\u0627\u0631 \u0645\u0634\u0631\u0627 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u062a\u0641\u062a\u06cc\u0634 \u0645\u06cc\u06ba \u0645\u0644\u0627\u0632\u0645 \u06a9\u06d2 \u0628\u06cc\u0679\u06d2 \u06a9\u06cc \u0634\u0627\u062f\u06cc \u0627\u0648\u0631 \u0642\u0631\u0636 \u06a9\u06d2 \u0628\u0648\u062c\u06be \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u0627\u0633 \u0646\u06d2 \u062e\u0648\u062f\u06a9\u0634\u06cc \u06a9\u06cc \u06c1\u06d2\u06d4 \u0644\u0627\u0634 \u06a9\u0648 \u067e\u0648\u0633\u0679 \u0645\u0627\u0631\u0679\u0645 \u06a9\u06d2 \u0644\u0626\u06d2 \u0628\u06be\u06cc\u062c \u06a9\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u06a9\u06cc \u062c\u0627\u0631\u06c1\u06cc \u06c1\u06d2\u06d4<\/p>\n<p style=\"text-align: right;\">\n","protected":false},"excerpt":{"rendered":"<p>\u06a9\u0627\u0646\u067e\u0648\u0631 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u0627\u06cc\u0633 \u067e\u06cc \u0645\u063a\u0631\u0628\u06cc \u062f\u0641\u062a\u0631 \u0645\u06cc\u06ba \u062a\u0639\u06cc\u0646\u0627\u062a \u062f\u0631\u062c\u06c1 \u0686\u06c1\u0627\u0631\u0645 \u06a9\u06d2 \u0645\u0644\u0627\u0632\u0645 \u0646\u06d2 \u0633\u0627\u0691\u06cc \u06a9\u0627 \u067e\u06be\u0646\u062f\u06c1 \u0644\u06af\u0627 \u06a9\u0631 \u067e\u0646\u06a9\u06be\u06d2 \u06a9\u06d2 \u06a9\u0646\u0688\u06d2 \u0633\u06d2 \u0644\u0679\u06a9 \u06a9\u0631 \u062e\u0648\u062f\u06a9\u0634\u06cc \u06a9\u0631\u0644\u06cc\u06d4\u0688\u06cc\u0648\u0679\u06cc \u067e\u0631 \u062a\u0639\u06cc\u0646\u0627\u062a \u062f\u0627\u0631\u0648\u063a\u06c1 \u06a9\u0627 \u0645\u0644\u0627\u0632\u0645 \u06a9\u06cc \u0644\u0627\u0634 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u06c1\u0648\u0634 \u0627\u0691\u06af\u0626\u06d2\u06d4 \u0648\u0627\u0642\u0639\u06c1 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u0646\u06d2 \u067e\u0631 \u067e\u06c1\u0646\u0686\u06cc \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0644\u0627\u0634 \u06a9\u0648 \u0646\u06cc\u0686\u06d2 \u0627\u062a\u0627\u0631\u0627 \u0627\u0648\u0631 \u062a\u0641\u062a\u06cc\u0634 \u06a9\u06cc\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,26],"tags":[],"class_list":["post-18441","post","type-post","status-publish","format-standard","category-uttar-pradesh","category-uttar-pradesh-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/18441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=18441"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/18441\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=18441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=18441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=18441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}