{"id":19118,"date":"2014-05-28T14:05:14","date_gmt":"2014-05-28T08:35:14","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=19118"},"modified":"2014-05-28T14:05:14","modified_gmt":"2014-05-28T08:35:14","slug":"%d8%b1%db%8c%d8%a7%d8%b3%d8%aa-%d9%85%db%8c%da%ba-%d8%b5%d9%86%d8%b9%d8%aa%d9%88%da%ba-%da%a9%d9%88-%d9%81%d8%b1%d9%88%d8%ba-%d8%af%db%8c%d9%86%db%92-%da%a9%d8%a7-%d9%85%d9%86%d8%b5%d9%88%d8%a8%db%81","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%b1%db%8c%d8%a7%d8%b3%d8%aa-%d9%85%db%8c%da%ba-%d8%b5%d9%86%d8%b9%d8%aa%d9%88%da%ba-%da%a9%d9%88-%d9%81%d8%b1%d9%88%d8%ba-%d8%af%db%8c%d9%86%db%92-%da%a9%d8%a7-%d9%85%d9%86%d8%b5%d9%88%d8%a8%db%81\/","title":{"rendered":"\u0631\u06cc\u0627\u0633\u062a \u0645\u06cc\u06ba \u0635\u0646\u0639\u062a\u0648\u06ba \u06a9\u0648 \u0641\u0631\u0648\u063a \u062f\u06cc\u0646\u06d2 \u06a9\u0627 \u0645\u0646\u0635\u0648\u0628\u06c1"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-8487\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/02\/akhlesh-yadvo.jpg\" alt=\"akhlesh yadvo\" width=\"280\" height=\"210\" \/>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u0633\u0645\u0627\u062c\u0648 \u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0627\u06cc\u06a9 \u062a\u0631\u062c\u0645\u0627\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u0627\u06a9\u06be\u0644\u06cc\u0634 \u06cc\u0627\u062f\u0648 \u0631\u06cc\u0627\u0633\u062a \u0645\u06cc\u06ba \u0646\u0626\u06cc \u0635\u0646\u0639\u062a\u06cc\u06ba \u0642\u0627\u0626\u0645 \u06a9\u0631\u0627\u0646\u06d2 \u0627\u0648\u0631 \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u06a9\u0648\u0634\u0627\u06ba \u06c1\u06cc\u06ba\u06d4 \u0628\u0627\u0631\u06c1 \u062c\u0648\u0646 \u06a9\u0648 \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u062f\u06c1\u0644\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u067e\u0631\u0648\u06af\u0631\u0627\u0645 \u06a9\u0627 \u0627\u0646\u0639\u0642\u0627\u062f \u06a9\u0631\u06cc\u06ba \u06af\u06d2 \u062c\u0633 \u0645\u06cc\u06ba \u067e\u0648\u0631\u06cc \u062f\u0646\u06cc\u0627 \u06a9\u06cc \u067e\u0686\u0627\u0633 \u0633\u06d2 \u0632\u0627\u0626\u062f \u06a9\u0645\u067e\u0646\u06cc\u0627\u06ba \u0634\u0631\u06a9\u062a \u06a9\u0631\u06cc\u06ba \u06af\u06cc\u06d4 \u0645\u0630\u06a9\u0648\u0631\u06c1 \u067e\u0631\u0648\u06af\u0631\u0627\u0645 \u0645\u06cc\u06ba \u062c\u0631\u0645\u0646\u06cc\u060c \u06a9\u0646\u0627\u0688\u0627\u060c \u0627\u0679\u0644\u06cc\u060c \u062a\u0627\u0626\u06cc\u0648\u0627\u0646\u060c \u062a\u0631\u06a9\u06cc\u060c \u0686\u06cc\u06a9 \u0631\u06cc\u067e\u0628\u0644\u06a9 \u06a9\u06cc \u0635\u0646\u0639\u062a\u06cc \u062a\u0646\u0638\u06cc\u0645\u06cc\u06ba \u062d\u0635\u06c1 \u0644\u06cc\u06ba \u06af\u06cc\u06d4 \u067e\u0631\u0648\u06af\u0631\u0627\u0645 \u06a9\u0627 \u0645\u0642\u0635\u062f \u0632\u06cc\u0627\u062f\u06c1 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u0648\u06ba \u06a9\u0648 \u0631\u06cc\u0627\u0633\u062a \u06a9\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc\u0648\u06ba \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0627\u0653\u06af\u0627\u06c1 \u06a9\u0631\u0627\u0646\u0627 \u0627\u0648\u0631 \u0631\u06cc\u0627\u0633\u062a \u0645\u06cc\u06ba \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u06a9\u0648 \u0641\u0631\u0648\u063a \u062f\u06cc\u0646\u0627 \u06c1\u06d2\u06d4 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u062a\u0631\u062c\u0645\u0627\u0646 \u0631\u0627\u062c\u0646\u062f\u0631 \u0686\u0648\u062f\u06be\u0631\u06cc \u0646\u06d2 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0628\u062a\u0627\u06cc\u0627\u06a9\u06c1 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u062d\u06a9\u0648\u0645\u062a \u0646\u06d2 \u0627\u0653\u0628\u0627\u062f\u06cc \u06a9\u06d2<br \/>\n\u0644\u062d\u0627\u0638 \u0633\u06d2 \u0645\u0644\u06a9 \u06a9\u06cc \u0633\u0628 \u0633\u06d2 \u0628\u0691\u06cc \u0631\u06cc\u0627\u0633\u062a \u0627\u062a\u0631\u067e\u0631\u062f\u06cc\u0634 \u06a9\u06cc \u06c1\u0645\u06c1 \u062c\u06c1\u062a \u062a\u0631\u0642\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u0646\u0626\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc\u0627\u06ba \u0645\u0631\u062a\u0628 \u06a9\u06cc \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0627\u0646\u06c1\u06cc\u06ba \u0646\u0627\u0641\u0630 \u06a9\u0631\u06a9\u06d2 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u0627\u062a \u06a9\u0648 \u062a\u06cc\u0632 \u0631\u0641\u062a\u0627\u0631\u06cc \u062f\u06cc \u06c1\u06d2\u06d4 \u0632\u0631\u0627\u0639\u062a\u060c \u0635\u0646\u0639\u062a\u0648\u06ba \u06a9\u06cc \u062a\u0631\u0642\u06cc \u0627\u0648\u0631 \u0645\u062e\u062a\u0644\u0641 \u0627\u062f\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0633\u06c1\u0648\u0644\u06cc\u0627\u062a \u060c \u062a\u0648\u0627\u0646\u0627\u0626\u06cc \u0634\u0639\u0628\u06c1 \u0645\u06cc\u06ba \u062e\u0648\u062f \u06a9\u0641\u0627\u0644\u062a \u060c \u0637\u0628\u06cc \u062e\u062f\u0645\u0627\u062a \u0634\u0639\u0628\u06c1 \u0645\u06cc\u06ba \u062a\u0648\u0633\u06cc\u0639 \u060c \u0633\u0691\u06a9\u0648\u06ba \u06a9\u06cc \u0628\u06c1\u062a\u0631\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u0627\u0679\u06be\u0627\u0626\u06d2 \u06af\u0626\u06d2 \u0627\u06c1\u0645 \u0642\u062f\u0645\u0648\u06ba \u0633\u06d2 \u0631\u06cc\u0627\u0633\u062a \u06a9\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u0627\u062a \u06a9\u0648\u0645\u0636\u0628\u0648\u0637 \u0628\u0646\u0627\u06cc\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4 \u0631\u06cc\u0627\u0633\u062a \u0645\u06cc\u06ba \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u0635\u0646\u0639\u062a \u06a9\u0627\u0631\u0648\u06ba\u06a9\u0648 \u0631\u0627\u063a\u0628 \u06a9\u0631\u0646\u06d2 \u0627\u0648\u0631 \u0627\u0646\u06c1\u06cc\u06ba \u0646\u0626\u06d2 \u0645\u0646\u0635\u0648\u0628\u06d2 \u0642\u0627\u0621 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc\u0644\u0626\u06d2 \u0633\u06c1\u0648\u0644\u06cc\u0627\u062a \u062f\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u06c1\u06d2\u06d4 \u0645\u0633\u0679\u0631 \u0686\u0648\u062f\u06be\u0631\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u062a\u062d\u0631\u06cc\u06a9 \u06a9\u06d2 \u0628\u0627\u0646\u06cc \u0688\u0627\u06a9\u0679\u0631 \u0631\u0627\u0645 \u0645\u0646\u0648\u06c1\u0631 \u0644\u0648\u06c1\u06cc\u0627 \u0646\u06d2 \u2019\u0628\u06cc\u0631\u0648\u0632\u06af\u0627\u0631\u0648\u06ba\u06a9\u0648 \u06a9\u0627\u0645 \u062f\u0648 \u06cc\u0627 \u0628\u06be\u062a\u06c1 \u062f\u0648\u2018 \u06a9\u0627 \u0646\u0639\u0631\u06c1 \u062f\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u0627\u0633 \u0646\u0639\u0631\u06c1 \u06a9\u0648 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u06cc \u062d\u06a9\u0648\u0645\u062a \u0645\u06cc\u06ba \u0645\u0644\u0627\u0626\u0645 \u0633\u0646\u06af\u06be \u06cc\u0627\u062f\u0648 \u0627\u0648\u0631 \u0628\u0639\u062f \u0645\u06cc\u06ba \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u0627\u06a9\u06be\u0644\u06cc\u0634 \u06cc\u0627\u062f\u0648 \u0639\u0645\u0644 \u0645\u06cc\u06ba \u0644\u0627\u0626\u06d2\u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u0633\u0645\u0627\u062c\u0648 \u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0627\u06cc\u06a9 \u062a\u0631\u062c\u0645\u0627\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u0627\u06a9\u06be\u0644\u06cc\u0634 \u06cc\u0627\u062f\u0648 \u0631\u06cc\u0627\u0633\u062a \u0645\u06cc\u06ba \u0646\u0626\u06cc \u0635\u0646\u0639\u062a\u06cc\u06ba \u0642\u0627\u0626\u0645 \u06a9\u0631\u0627\u0646\u06d2 \u0627\u0648\u0631 \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u06a9\u0648\u0634\u0627\u06ba \u06c1\u06cc\u06ba\u06d4 \u0628\u0627\u0631\u06c1 \u062c\u0648\u0646 \u06a9\u0648 \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u062f\u06c1\u0644\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u067e\u0631\u0648\u06af\u0631\u0627\u0645 \u06a9\u0627 \u0627\u0646\u0639\u0642\u0627\u062f \u06a9\u0631\u06cc\u06ba \u06af\u06d2 \u062c\u0633 \u0645\u06cc\u06ba \u067e\u0648\u0631\u06cc \u062f\u0646\u06cc\u0627 \u06a9\u06cc \u067e\u0686\u0627\u0633 \u0633\u06d2 \u0632\u0627\u0626\u062f \u06a9\u0645\u067e\u0646\u06cc\u0627\u06ba \u0634\u0631\u06a9\u062a \u06a9\u0631\u06cc\u06ba \u06af\u06cc\u06d4 \u0645\u0630\u06a9\u0648\u0631\u06c1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,28],"tags":[],"class_list":["post-19118","post","type-post","status-publish","format-standard","category-lucknow","category-lucknow-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/19118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=19118"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/19118\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=19118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=19118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=19118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}