{"id":19188,"date":"2014-05-29T16:05:35","date_gmt":"2014-05-29T10:35:35","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=19188"},"modified":"2014-05-29T16:05:35","modified_gmt":"2014-05-29T10:35:35","slug":"%d8%b3%db%8c-%d8%a8%db%8c-%d8%a7%db%8c%d8%b3-%d8%a7%db%8c-%d8%a7%d9%85%d8%aa%d8%ad%d8%a7%d9%86-%d9%85%db%8c%da%ba-%d9%86%d8%a7%da%a9%d8%a7%d9%85%db%8c-%da%a9%db%92-%d8%a8%d8%b9%d8%af-%d8%b7%d8%a7","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%b3%db%8c-%d8%a8%db%8c-%d8%a7%db%8c%d8%b3-%d8%a7%db%8c-%d8%a7%d9%85%d8%aa%d8%ad%d8%a7%d9%86-%d9%85%db%8c%da%ba-%d9%86%d8%a7%da%a9%d8%a7%d9%85%db%8c-%da%a9%db%92-%d8%a8%d8%b9%d8%af-%d8%b7%d8%a7\/","title":{"rendered":"\u0633\u06cc \u0628\u06cc \u0627\u06cc\u0633 \u0627\u06cc \u0627\u0645\u062a\u062d\u0627\u0646 \u0645\u06cc\u06ba \u0646\u0627\u06a9\u0627\u0645\u06cc \u06a9\u06d2 \u0628\u0639\u062f \u0637\u0627\u0644\u0628\u06c1 \u0646\u06d2 \u06a9\u06cc \u062e\u0648\u062f\u06a9\u0634\u06cc"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-13962\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/04\/fansi.jpg\" alt=\"fansi\" width=\"228\" height=\"171\" \/>\u06af\u0648\u0631\u06a9\u06be\u067e\u0648\u0631 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u06a9\u06d2 \u0644\u0626\u06d2 \u0627\u0653\u062c \u062e\u0648\u0634\u06cc \u06a9\u0627\u062f\u0646 \u062a\u06be\u0627\u06d4\u0627\u0633 \u06a9\u06cc \u0648\u062c\u06c1 \u0628\u06cc\u0679\u06cc \u06a9\u06d2 \u0633\u06cc \u0628\u06cc \u0627\u06cc\u0633 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u06d2 \u0646\u062a\u0627\u0626\u062c \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u062a\u06be\u0627\u06d4\u0635\u0628\u062d \u0633\u06d2 \u06c1\u06cc \u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u0628\u06cc\u0679\u06cc \u06a9\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06a9\u06d2 \u0644\u0626\u06d2 \u062f\u0639\u0627 \u06a9\u0631\u0631\u06c1\u06d2 \u062a\u06be\u06d2 \u0644\u06cc\u06a9\u0646 \u0627\u0646\u06c1\u06cc\u06ba \u06cc\u06c1 \u0645\u0639\u0644\u0648\u0645 \u0646\u06c1\u06cc\u06ba \u062a\u06be\u0627 \u06a9\u06c1 \u0627\u0646 \u06a9\u06cc \u062e\u0648\u0634\u06cc \u063a\u0645 \u0645\u06cc\u06ba \u062a\u0628\u062f\u06cc\u0644 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06c1\u06d2 \u062c\u0633\u06d2 \u0641\u0631\u0627\u0645\u0648\u0634 \u06a9\u0631\u0646\u0627 \u0627\u0646 \u06a9\u06d2 \u0644\u0626\u06d2 \u0646\u0627\u0645\u0645\u06a9\u0646 \u06c1\u0648\u06af\u0627\u06d4\u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u062f\u0633 \u0628\u062c\u06d2 \u0628\u06cc\u0679\u06cc \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u062f\u06cc\u06a9\u06be\u0646\u06d2 \u06a9\u06d2 \u0644\u0626\u06d2 \u0633\u0627\u0626\u0628\u0631 \u06a9\u06cc\u0641\u06d2 \u062c\u0627\u0631\u06c1\u06cc \u062a\u06be\u06cc\u06d4\u0627\u0633\u06cc \u062f\u0648\u0631\u0627\u0646 \u0645\u0648\u0628\u0627\u0626\u0644 \u067e\u0631 \u0627\u0646\u06c1\u06cc\u06ba \u062e\u0628\u0631 \u0645\u0648\u0635\u0648\u0644 \u06c1\u0648\u0626\u06cc \u06a9\u06c1 \u0627\u0646 \u06a9\u06cc \u0628\u06cc\u0679\u06cc \u0631\u0627\u0633\u062a\u06c1 \u0645\u06cc\u06ba \u06af\u0631 \u067e\u0691\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06cc \u062d\u0627\u0644\u062a<br \/>\n\u062a\u0634\u0648\u06cc\u0634\u0646\u0627\u06a9 \u06c1\u06d2\u06d4 \u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u0645\u0648\u0642\u0639 \u067e\u0631 \u067e\u06c1\u0646\u0686\u06d2 \u0627\u0648\u0631 \u0627\u0633\u06d2 \u0627\u0633\u067e\u062a\u0627\u0644 \u0645\u06cc\u06ba \u062f\u0627\u062e\u0644 \u06a9\u0631\u0627\u06cc\u0627 \u062c\u06c1\u0627\u06ba \u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u0646\u06d2 \u0627\u0633\u06d2 \u0645\u0631\u062f\u06c1 \u0642\u0631\u0627\u0631\u062f\u06d2 \u062f\u06cc\u0627\u06d4\u0644\u0691\u06a9\u06cc \u0646\u06d2 \u0645\u0631\u0646\u06d2 \u0633\u06d2 \u0642\u0628\u0644 \u0627\u067e\u0646\u06d2 \u067e\u0627\u067e\u0627\u0633\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0633 \u0646\u06d2 \u0633\u0644\u0641\u0627\u0633 \u06a9\u06cc \u06af\u0648\u0644\u06cc \u06a9\u06be\u0627\u0644\u06cc \u06c1\u06d2 \u0644\u06cc\u06a9\u0646 \u0645\u06cc\u06ba \u0632\u0646\u062f\u06c1 \u0631\u06c1\u0646\u0627 \u0686\u0627\u06c1\u062a\u06cc \u06c1\u0648\u06ba\u06d4\u06cc\u06c1 \u0648\u0627\u0642\u0639\u06c1 \u06a9\u06cc\u0646\u0679 \u062d\u0644\u0642\u06c1 \u06a9\u06d2 \u0631\u0633\u062a\u0645 \u067e\u0648\u0631 \u06a9\u06d2 \u0628\u0627\u0634\u0646\u062f\u06d2 \u0627\u0631\u0648\u0646 \u06a9\u0645\u0627\u0631\u06a9\u06d2 \u0633\u0627\u062a\u06be \u067e\u06cc\u0634 \u0627\u0653\u06cc\u0627\u06d4\u0627\u0631\u0648\u0646 \u06a9\u0645\u0627\u0631 \u0628\u06cc\u0646\u06a9\u0627\u06a9 \u0645\u06cc\u06ba \u0631\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0627\u0653\u062c \u06a9\u0644 \u0648\u06c1 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u0627\u0653\u0626\u06d2 \u06c1\u0648\u0626\u06d2 \u06c1\u06cc\u06ba \u0627\u0646 \u06a9\u06cc \u0628\u06cc\u0679\u06cc \u0631\u0627\u0646\u06cc \u0634\u06a9\u0644\u0627 (\u06f1\u06f7)\u0633\u06cc\u0646\u0679\u0631\u0644 \u0627\u06a9\u0627\u062f\u0645\u06cc \u0627\u0633\u06a9\u0648\u0644 \u06a9\u06cc \u0628\u0627\u0631\u06c1\u0648\u06cc\u06ba \u062c\u0645\u0627\u0639\u062a \u06a9\u06cc \u0637\u0627\u0644\u0628\u06c1 \u06c1\u06d2\u06d4<br \/>\n\u0627\u0653\u062c \u0631\u0627\u0646\u06cc \u06a9\u0627 \u0633\u06cc \u0628\u06cc \u0627\u06cc\u0633 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0627\u0653\u06cc\u0627 \u06c1\u06d2\u06d4\u0646\u062a\u06cc\u062c\u06c1 \u062f\u06cc\u06a9\u06be\u0646\u06d2 \u06a9\u06d2 \u0644\u0626\u06d2 \u0648\u06c1 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u0635\u0628\u062d \u062f\u0633 \u0628\u062c\u06d2 \u06af\u06be\u0631 \u0633\u06d2 \u0633\u0627\u0626\u0628\u0631 \u06a9\u06cc\u0641\u06d2 \u0631\u0648\u0627\u0646\u06c1 \u06c1\u0648\u0626\u06cc\u06d4\u06a9\u06cc\u0648\u0646\u06a9\u06c1 \u0627\u0645\u062a\u062d\u0627\u0646 \u0645\u06cc\u06ba \u0648\u06c1 \u0646\u0627\u06a9\u0627\u0645 \u06c1\u0648\u06af\u0626\u06cc \u062a\u06be\u06cc\u06d4\u0645\u0627\u06cc\u0648\u0633 \u06c1\u0648\u06a9\u0631 \u0631\u0627\u0646\u06cc \u06af\u06be\u0631 \u06a9\u06cc \u0637\u0631\u0641 \u0631\u0648\u0627\u0646\u06c1 \u06c1\u0648\u06af\u0626\u06cc \u0644\u06cc\u06a9\u0646 \u0631\u0627\u0633\u062a\u06d2 \u0645\u06cc\u06ba \u06c1\u06cc \u0627\u0633 \u0646\u06d2 \u0633\u0644\u0641\u0627\u0633 \u06a9\u06cc \u06af\u0648\u0644\u06cc \u06a9\u06be\u0627\u06a9\u0631 \u062e\u0648\u062f\u06a9\u0634\u06cc \u06a9\u0631\u0644\u06cc\u06d4\u0631\u0627\u06c1\u06af\u06cc\u0631\u0648\u06ba \u0646\u06d2 \u0627\u0633 \u06a9\u06d2 \u0645\u0648\u0628\u0627\u0626\u0644 \u0633\u06d2 \u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u06a9\u0648 \u0627\u0637\u0644\u0627\u0639 \u062f\u06cc\u06d4\u06af\u06be\u0631 \u067e\u0631 \u0627\u0646\u062a\u0638\u0627\u0631 \u06a9\u0631\u0631\u06c1\u06d2 \u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u06a9\u0648 \u0633\u062e\u062a \u0635\u062f\u0645\u06c1 \u067e\u06c1\u0646\u0686\u0627 \u0627\u0648\u0631 \u0648\u06c1 \u0645\u0648\u0642\u0639 \u067e\u0631 \u067e\u06c1\u0646\u0686\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u0646\u06d2 \u0631\u0627\u0646\u06cc \u06a9\u0648 \u0636\u0644\u0639 \u0627\u0633\u067e\u062a\u0627\u0644 \u0644\u06d2 \u062c\u0627\u0646\u06d2 \u0644\u06af\u06d2\u06d4 \u0631\u0627\u0633\u062a\u06d2 \u0645\u06cc\u06ba \u0631\u0627\u0646\u06cc \u0634\u06a9\u0644\u0627 \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0648\u0627\u0644\u062f \u0633\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0648\u06c1 \u0627\u0645\u062a\u062d\u0627\u0646 \u0645\u06cc\u06ba \u0641\u06cc\u0644 \u06c1\u0648\u06af\u0626\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0645\u0627\u06cc\u0648\u0633 \u06c1\u0648\u06a9\u0631 \u0627\u0633 \u0646\u06d2 \u0633\u0644\u0641\u0627\u0633 \u06a9\u06cc \u06af\u0648\u0644\u06cc \u06a9\u06be\u0627\u0644\u06cc \u06c1\u06d2 \u0644\u06cc\u06a9\u0646 \u0648\u06c1 \u0632\u0646\u062f\u06c1 \u0631\u06c1\u0646\u0627 \u0686\u0627\u06c1\u062a\u06cc \u062a\u06be\u06cc\u06d4\u0627\u0633\u067e\u062a\u0627\u0644 \u067e\u06c1\u0646\u0686\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0688\u0627\u06a9\u0679\u0631\u0648\u06ba \u0646\u06d2 \u0645\u0639\u0627\u0626\u0646\u06c1 \u06a9\u06d2 \u0628\u0639\u062f \u0631\u0627\u0646\u06cc \u06a9\u0648 \u0645\u0631\u062f\u06c1 \u0642\u0631\u0627\u0631\u062f\u06d2 \u062f\u06cc\u0627\u06d4\u0627\u0633\u067e\u062a\u0627\u0644 \u0627\u0646\u062a\u0638\u0627\u0645\u06cc\u06c1 \u0646\u06d2 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0648 \u0627\u0633 \u0648\u0627\u0642\u0639\u06c1 \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u062f\u06cc\u06d4\u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0645\u0648\u0642\u0639 \u067e\u0631 \u067e\u06c1\u0646\u0686\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0644\u0627\u0634 \u06a9\u0648 \u0642\u0628\u0636\u06c1 \u0645\u06cc\u06ba \u0644\u06d2 \u06a9\u0631 \u067e\u0648\u0633\u0679 \u0645\u0627\u0631\u0679\u0645 \u06a9\u06d2 \u0644\u0626\u06d2 \u0628\u06be\u06cc\u062c \u062f\u06cc\u0627\u06d4<\/p>\n<p style=\"text-align: right;\">\n","protected":false},"excerpt":{"rendered":"<p>\u06af\u0648\u0631\u06a9\u06be\u067e\u0648\u0631 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u06a9\u06d2 \u0644\u0626\u06d2 \u0627\u0653\u062c \u062e\u0648\u0634\u06cc \u06a9\u0627\u062f\u0646 \u062a\u06be\u0627\u06d4\u0627\u0633 \u06a9\u06cc \u0648\u062c\u06c1 \u0628\u06cc\u0679\u06cc \u06a9\u06d2 \u0633\u06cc \u0628\u06cc \u0627\u06cc\u0633 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u06d2 \u0646\u062a\u0627\u0626\u062c \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646 \u062a\u06be\u0627\u06d4\u0635\u0628\u062d \u0633\u06d2 \u06c1\u06cc \u0627\u06c1\u0644 \u062e\u0627\u0646\u06c1 \u0628\u06cc\u0679\u06cc \u06a9\u06cc \u06a9\u0627\u0645\u06cc\u0627\u0628\u06cc \u06a9\u06d2 \u0644\u0626\u06d2 \u062f\u0639\u0627 \u06a9\u0631\u0631\u06c1\u06d2 \u062a\u06be\u06d2 \u0644\u06cc\u06a9\u0646 \u0627\u0646\u06c1\u06cc\u06ba \u06cc\u06c1 \u0645\u0639\u0644\u0648\u0645 \u0646\u06c1\u06cc\u06ba \u062a\u06be\u0627 \u06a9\u06c1 \u0627\u0646 \u06a9\u06cc \u062e\u0648\u0634\u06cc \u063a\u0645 \u0645\u06cc\u06ba \u062a\u0628\u062f\u06cc\u0644 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06c1\u06d2 \u062c\u0633\u06d2 \u0641\u0631\u0627\u0645\u0648\u0634 \u06a9\u0631\u0646\u0627 \u0627\u0646 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,26],"tags":[],"class_list":["post-19188","post","type-post","status-publish","format-standard","category-uttar-pradesh","category-uttar-pradesh-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/19188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=19188"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/19188\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=19188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=19188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=19188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}