{"id":19281,"date":"2014-05-29T19:34:29","date_gmt":"2014-05-29T14:04:29","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=19281"},"modified":"2014-05-29T19:34:29","modified_gmt":"2014-05-29T14:04:29","slug":"%db%81%d9%86%d8%af%d9%88%d8%b3%d8%aa%d8%a7%d9%86%db%8c-%d8%b4%db%8c%d8%a6%d8%b1-%d8%a8%d8%a7%d8%b2%d8%a7%d8%b1%d9%88%da%ba-%d9%85%db%8c%da%ba-%d8%ba%db%8c%d8%b1-%d9%85%d9%84%da%a9%db%8c-%d8%b3%d8%b1","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%db%81%d9%86%d8%af%d9%88%d8%b3%d8%aa%d8%a7%d9%86%db%8c-%d8%b4%db%8c%d8%a6%d8%b1-%d8%a8%d8%a7%d8%b2%d8%a7%d8%b1%d9%88%da%ba-%d9%85%db%8c%da%ba-%d8%ba%db%8c%d8%b1-%d9%85%d9%84%da%a9%db%8c-%d8%b3%d8%b1\/","title":{"rendered":"\u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0634\u06cc\u0626\u0631 \u0628\u0627\u0632\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u063a\u06cc\u0631 \u0645\u0644\u06a9\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a \u0633\u06d2 \u0645\u0639\u06cc\u0634\u062a \u06a9\u0648 \u0641\u0627\u0626\u062f\u06c1"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-17231\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/05\/company-shir-bazar.jpg\" alt=\"company shir bazar\" width=\"288\" height=\"230\" \/>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc(\u0628\u06be\u0627\u0634\u0627) \u0628\u06cc\u0631\u0648\u0646\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u0648\u06ba \u06a9\u06cc\u0644\u0626\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0634\u06cc\u0626\u0631 \u0628\u0627\u0632\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u06a9\u06d2 \u0636\u0648\u0627\u0628\u0637 \u06a9\u0648 \u0627\u0653\u0633\u0627\u0646 \u0628\u0646\u0627\u0626\u06d2 \u062c\u0627\u0646\u06d2 \u0633\u06d2 \u0645\u0639\u06cc\u0634\u062a \u06a9\u0648 \u06a9\u0627\u0641\u06cc \u0641\u0627\u0626\u062f\u06c1 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u0627\u0631\u0646\u06cc\u0644 \u06cc\u0648\u0646\u06cc\u0648\u0631\u0633\u0679\u06cc \u06a9\u06d2 \u0645\u0627\u06c1\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u0627\u062a \u0627\u06cc\u0634\u0648\u0631 \u067e\u0631\u0633\u0627\u062f \u0646\u06d2 \u06cc\u06c1 \u0628\u0627\u062a \u06a9\u06c1\u06cc \u06d4<br \/>\n\u0645\u0633\u0679\u0631 \u067e\u0631\u0633\u0627\u062f \u0646\u06d2 \u0627\u067e\u0646\u06cc \u06a9\u062a\u0627\u0628\u2019 \u062f\u06cc \u0688\u0627\u0644\u0631 \u0679\u0631\u06cc\u067e: \u06c1\u0627\u0648\u0654 \u062f\u06cc \u06cc\u0648 \u0627\u06cc\u0633 \u0688\u0627\u0644\u0631 \u0679\u0627\u0626\u0679\u0646\u0688 \u0627\u0679\u0633 \u06af\u0631\u067e \u0627\u0653\u0646 \u06af\u0644\u0648\u0628\u0644 \u0641\u0627\u0626\u0646\u0646\u0633\u2018 \u0645\u06cc\u06ba \u0644\u06a9\u06be\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0686\u06cc\u0646 \u06a9\u06d2 \u0645\u0639\u0627\u0645\u0644\u06c1 \u0645\u06cc\u06ba \u0635\u0648\u0631\u062a\u062d\u0627\u0644 \u0639\u0644\u0627\u062d\u062f\u06c1 \u06c1\u06d2 \u062c\u06c1\u0627\u06ba \u062f\u0648\u0633\u0631\u06d2 \u0645\u0645\u0627\u0644\u06a9 \u06a9\u06d2 \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u0648\u06ba \u06a9\u06cc \u0627\u06cc\u06a9\u0648\u06cc\u0679\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u067e\u0631 \u0641\u0648\u0631\u06cc \u067e\u0627\u0628\u0646\u062f\u06cc \u06c1\u06d2\u06d4 \u0645\u0633\u0679\u0631 \u067e\u0631\u0633\u0627\u062f \u0646\u06d2 \u0645\u0632\u06cc\u062f \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u063a\u06cc\u0631 \u0645\u0644\u06a9\u06cc \u067e\u0648\u0646\u062c\u06cc \u0633\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0634\u06cc\u0626\u0631 \u0628\u0627\u0632\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u06af\u06c1\u0631\u0627\u0626\u06cc \u0627\u0648\u0631 \u062a\u0631\u0644\u062a\u0627 \u0645\u06cc\u06ba \u0627\u0636\u0627\u0641\u06c1 \u06c1\u0648\u0627 \u06c1\u06d2\u06d4<br \/>\n\u067e\u06cc\u06af\u0648\u0626\u06cc\u0646 \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0633\u06d2 \u0634\u0627\u0626\u0639 \u06a9\u062a\u0627\u0628 \u0645\u06cc\u06ba \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u062a\u062d\u0631\u06cc\u0631 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u2019 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u062a\u062c\u0627\u0631\u062a \u06a9\u06cc\u0644\u0626\u06d2 \u06cc\u06c1 \u067e<br \/>\n\u0648\u0646\u062c\u06cc \u0627\u06cc\u06a9 \u0628\u06c1\u062a\u0631 \u0630\u0631\u06cc\u0639\u06c1 \u0628\u0646\u0627 \u06c1\u0648\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0633\u06cc \u067e\u0648\u0646\u062c\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u0635\u0631\u0641 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0628\u06cc\u0646\u06a9\u0646\u06af \u0646\u0638\u0627\u0645 \u067e\u0631 \u0645\u0646\u062d\u0635\u0631 \u06c1\u0648\u0646\u0627 \u067e\u0691\u062a\u0627 \u06c1\u06d2\u06d4 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0628\u06cc\u0646\u06a9\u0646\u06af \u0646\u0638\u0627\u0645 \u06a9\u06d2 \u067e\u0627\u0633 \u0645\u0644\u06a9 \u06a9\u06cc \u0628\u0691\u06cc \u06a9\u0645\u067e\u0646\u06cc\u0648\u06ba \u06a9\u06cc \u0645\u0627\u0644\u06cc \u0635\u0644\u0627\u062d\u06cc\u062a \u062f\u0631\u0633\u062a \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0635\u0644\u0627\u062d\u06cc\u062a \u06a9\u0627\u0641\u06cc \u0645\u062d\u062f\u0648\u062f \u06c1\u06d2\u2018\u06d4 \u0645\u0633\u0679\u0631 \u067e\u0631\u0633\u0627\u062f \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062a\u0645\u0627\u0645 \u0641\u0627\u0626\u062f\u0648\u06ba \u06a9\u06d2 \u0628\u0627\u0648\u062c\u0648\u062f \u060c \u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u0634\u06cc\u0626\u0631 \u0628\u0627\u0632\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u063a\u06cc\u0631 \u0645\u0644\u06a9\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u0628\u06c1\u0627\u0648\u0654 \u0628\u0691\u06be\u0646\u06d2 \u0633\u06d2 \u0634\u06cc\u0626\u0631 \u0628\u0627\u0632\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0627\u062a\u0627\u0631 \u0686\u0691\u06be\u0627\u0648\u0654 \u062a\u06cc\u0632 \u06c1\u0648\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0632\u0631\u0650 \u0645\u0628\u0627\u062f\u0644\u06c1 \u0628\u0627\u0632\u0627\u0631 \u0645\u06cc\u06ba \u0628\u06be\u06cc \u0627\u062a\u0627\u0631 \u0686\u0691\u06be\u0627\u0648\u0654 \u0627\u0653\u06cc\u0627 \u06c1\u06d2\u06d4 \u0627\u0633 \u0645\u06cc\u06ba \u0627\u0686\u06be\u06cc \u0628\u0627\u062a \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u063a\u06cc\u0631 \u0645\u0644\u06a9\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u0648\u06ba \u06a9\u0648 \u0628\u06be\u06cc \u0642\u06cc\u0645\u062a \u0627\u0648\u0631 \u0634\u06cc\u0626\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u062f\u0648\u0646\u0648\u06ba \u0637\u0631\u062d \u06a9\u06d2 \u062c\u0648\u06a9\u06be\u0645 \u0628\u0631\u062f\u0627\u0634\u062a \u06a9\u0631\u0646\u06d2 \u06c1\u0648\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0633\u06cc \u0644\u0626\u06d2 \u0627\u0633 \u0627\u062a\u0627\u0631 \u0686\u0691\u06be\u0627\u0648\u0654 \u06a9\u0627 \u067e\u0648\u0631\u0627 \u0628\u0648\u062c\u06be \u0635\u0631\u0641 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u067e\u0631 \u0646\u06c1\u06cc\u06ba \u067e\u0691\u062a\u0627 \u06c1\u06d2\u06d4\u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u0646\u0638\u0627\u0645 \u0645\u06cc\u06ba \u0645\u0632\u06cc\u062f \u0627\u0653\u0633\u0627\u0646 \u0628\u0646\u0627\u0626\u06d2 \u062c\u0627\u0646\u06d2 \u0633\u06d2 \u063a\u06cc\u0631 \u0645\u0644\u06a9\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0648 \u0627\u062c\u0627\u0632\u062a \u0645\u0644\u0646\u06d2 \u0633\u06d2 \u0645\u0644\u06a9 \u06a9\u06cc \u0645\u0639\u06cc\u0634\u062a \u06a9\u0648 \u0641\u0627\u0626\u062f\u06c1 \u06c1\u0648\u06af\u0627\u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc(\u0628\u06be\u0627\u0634\u0627) \u0628\u06cc\u0631\u0648\u0646\u06cc \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u0648\u06ba \u06a9\u06cc\u0644\u0626\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u0634\u06cc\u0626\u0631 \u0628\u0627\u0632\u0627\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0633\u0631\u0645\u0627\u06cc\u06c1 \u06a9\u0627\u0631\u06cc \u06a9\u06d2 \u0636\u0648\u0627\u0628\u0637 \u06a9\u0648 \u0627\u0653\u0633\u0627\u0646 \u0628\u0646\u0627\u0626\u06d2 \u062c\u0627\u0646\u06d2 \u0633\u06d2 \u0645\u0639\u06cc\u0634\u062a \u06a9\u0648 \u06a9\u0627\u0641\u06cc \u0641\u0627\u0626\u062f\u06c1 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u0627\u0631\u0646\u06cc\u0644 \u06cc\u0648\u0646\u06cc\u0648\u0631\u0633\u0679\u06cc \u06a9\u06d2 \u0645\u0627\u06c1\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u0627\u062a \u0627\u06cc\u0634\u0648\u0631 \u067e\u0631\u0633\u0627\u062f \u0646\u06d2 \u06cc\u06c1 \u0628\u0627\u062a \u06a9\u06c1\u06cc \u06d4 \u0645\u0633\u0679\u0631 \u067e\u0631\u0633\u0627\u062f \u0646\u06d2 \u0627\u067e\u0646\u06cc \u06a9\u062a\u0627\u0628\u2019 \u062f\u06cc \u0688\u0627\u0644\u0631 \u0679\u0631\u06cc\u067e: \u06c1\u0627\u0648\u0654 \u062f\u06cc \u06cc\u0648 \u0627\u06cc\u0633 \u0688\u0627\u0644\u0631 \u0679\u0627\u0626\u0679\u0646\u0688 \u0627\u0679\u0633 \u06af\u0631\u067e \u0627\u0653\u0646 \u06af\u0644\u0648\u0628\u0644 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,30],"tags":[],"class_list":["post-19281","post","type-post","status-publish","format-standard","category-business","category-business-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/19281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=19281"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/19281\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=19281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=19281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=19281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}