{"id":20876,"date":"2014-06-27T18:56:41","date_gmt":"2014-06-27T13:26:41","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=20876"},"modified":"2014-06-27T18:56:41","modified_gmt":"2014-06-27T13:26:41","slug":"%d8%b4%d8%b1%db%8c-%d9%86%d9%88%d8%a7%d8%b3%d9%86-%da%a9%db%8c-%d8%aa%d9%82%d8%b1%d8%b1%db%8c-%d8%b3%db%92-%d9%81%da%a9%d8%a7%d9%85%d8%a7%db%8c%d9%88%d8%b3","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%b4%d8%b1%db%8c-%d9%86%d9%88%d8%a7%d8%b3%d9%86-%da%a9%db%8c-%d8%aa%d9%82%d8%b1%d8%b1%db%8c-%d8%b3%db%92-%d9%81%da%a9%d8%a7%d9%85%d8%a7%db%8c%d9%88%d8%b3\/","title":{"rendered":"\u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u06cc \u062a\u0642\u0631\u0631\u06cc \u0633\u06d2 \u0641\u06a9\u0627\u0645\u0627\u06cc\u0648\u0633"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-20877\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/06\/srinivasan..jpg\" alt=\"srinivasan.\" width=\"214\" height=\"130\" \/>\u0645\u06cc\u0644\u0628\u0648\u0631\u0646\u06d4\u0628\u06cc\u0646 \u0627\u0644\u0627\u0642\u0648\u0627\u0645\u06cc \u06a9\u0631\u06a9\u0679 \u0627\u06cc\u0633\u0648\u0633\u06cc \u0627\u06cc\u0634\u0646 \u06a9\u06d2 \u0641\u06cc\u0688\u0631\u06cc\u0634\u0646( \u0641\u06a9\u0627)\u0646\u06d2 \u0627\u0653\u062c \u06a9\u06c1\u0627 \u06a9\u06c1 \u0648\u06c1 \u0627\u0653\u0626\u06cc \u0633\u06cc \u0633\u06cc \u0686\u06cc\u0626\u0631\u0645\u06cc\u0646 \u06a9\u06d2 \u0639\u06c1\u062f\u06d2 \u067e\u0631 \u0627\u06cc\u0646 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u06cc \u062a\u0642\u0631\u0631\u06cc \u0633\u06d2 \u0645\u0627\u06cc\u0648\u0633 \u06c1\u06d2\u06d4\u0627\u062f\u06be\u0631\u060c \u0646\u06cc\u0648\u0632\u06cc \u0644\u06cc\u0646\u0688 \u06a9\u0631\u06a9\u0679 \u06a9\u06d2 \u0688\u0627\u0626\u0631\u06cc\u06a9\u0679\u0631 \u0645\u0627\u0631\u0679\u0646 \u0633\u0646\u06cc\u0688\u0646 \u0646\u06d2 \u0627\u0633 \u0645\u062a\u0646\u0627\u0632\u0639\u06c1 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u06a9\u06be\u06cc\u0644 \u0645\u0646\u062a\u0638\u0645 \u06a9\u06cc \u062a\u0642\u0631\u0631\u06cc \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u06a9\u06cc\u06d4 \u0641\u06a9\u0627\u06a9\u06d2 \u0633\u0628\u06a9\u062f\u0648\u0634 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0635\u062f\u0631 \u067e\u0627\u0644 \u0645\u0627\u0631\u0634 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0639\u0627\u0644\u0645\u06cc \u0627\u062f\u0627\u0631\u06d2 \u06a9\u0648 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u0648 \u0627\u067e\u0646\u0627 \u0686\u06cc\u0626\u0631\u0645\u06cc\u0646 \u0645\u0646\u062a\u062e\u0628 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u067e\u06c1\u0644\u06d2 \u0627\u0646 \u067e\u0631 \u0644\u06af\u06d2 \u0627\u0644\u0632\u0627\u0645\u0627\u062a \u067e\u0631 \u0641\u06cc\u0635\u0644\u06c1 \u0627\u0653\u0646\u06d2 \u06a9\u0627 \u0627\u0646\u062a\u0638\u0627\u0631 \u06a9\u0631\u0646\u0627 \u0686\u0627\u06c1\u0626\u06d2 \u062a\u06be\u0627\u06d4 \u0645\u0627\u0631\u0634<br \/>\n\u0646\u06d2 \u06a9\u06c1\u0627 \u06c1\u0645 \u0646\u06d2 \u062d\u0627\u0644 \u06a9\u06d2 \u062f\u0646\u0648\u06ba \u0645\u06cc\u06ba \u0627\u0646\u062a\u0638\u0627\u0645\u06cc\u06c1 \u0627\u0648\u0631 \u0639\u0627\u0644\u0645\u06cc \u06a9\u0631\u06a9\u0679 \u06a9\u06cc \u0642\u06cc\u0627\u062f\u062a \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0646\u0626\u06d2 \u062f\u0648\u0631 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0646\u062f\u06af\u06cc \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0627\u0653\u0626\u06cc \u0633\u06cc \u0633\u06cc \u06a9\u06cc \u0633\u0637\u062d \u067e\u0631 \u06a9\u0627\u0641\u06cc \u062a\u0628\u062f\u06cc\u0644\u06cc \u062f\u06cc\u06a9\u06be\u0627 \u06c1\u06d2\u06d4 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u0627\u0633 \u0633\u0644\u0633\u0644\u06d2 \u0645\u06cc\u06ba \u0641\u06a9\u0627\u06a9\u06cc \u062d\u0627\u0644\u062a \u06c1\u0645 \u06a9\u0648 \u067e\u062a\u06c1 \u06c1\u06d2\u06d4\u06c1\u0645\u0627\u0631\u0627 \u0645\u0627\u0646\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0653\u0626\u06cc \u0633\u06cc \u0633\u06cc \u06a9\u06cc \u0637\u0631\u0641 \u0633\u06d2 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u0648 \u0686\u06cc\u0626\u0631\u0645\u06cc\u0646 \u0628\u0646\u0627\u0626\u06d2 \u062c\u0627\u0646\u06d2 \u0633\u06d2 \u067e\u06c1\u0644\u06d2 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646 \u0645\u06cc\u06ba \u0627\u0646\u06c1\u06cc\u06ba \u0644\u06d2 \u06a9\u0631 \u062c\u0627\u0631\u06cc \u062a\u0646\u0627\u0632\u0639 \u0633\u0644\u062c\u06be\u0646\u06d2 \u06a9\u0627 \u0627\u0646\u062a\u0638\u0627\u0631 \u06a9\u0631\u0646\u0627 \u0628\u06c1\u062a\u0631 \u06c1\u0648\u062a\u0627\u06d4 \u062a\u0627\u06c1\u0645 \u0646\u06cc\u0648\u0632\u06cc \u0644\u06cc\u0646\u0688 \u06a9\u0631\u06a9\u0679 \u06a9\u06d2 \u0688\u0627\u0626\u0631\u06cc\u06a9\u0679\u0631 \u0633\u0646\u06cc\u0688\u0646 \u0646\u06d2 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u0644\u0632\u0627\u0645 \u062b\u0627\u0628\u062a \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u0626\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0646\u06cc\u0648\u0632\u06cc \u0644\u06cc\u0646\u0688 \u0631\u06cc\u0688\u06cc\u0648 \u0633\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u062a\u06cc\u0646 \u06cc\u0627 \u0686\u0627\u0631 \u0645\u0627\u06c1 \u0645\u06cc\u06ba \u062a\u0641\u062a\u06cc\u0634 \u0645\u06a9\u0645\u0644 \u06c1\u0648 \u062c\u0627\u0626\u06d2 \u06af\u06cc \u0627\u0648\u0631 \u0627\u0633 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0639\u062f\u0627\u0644\u062a \u06a9\u0648 \u0628\u062a\u0627 \u062f\u06cc\u0627 \u062c\u0627\u0626\u06d2 \u06af\u0627 \u0627\u0648\u0631 \u0639\u062f\u0627\u0644\u062a \u0627\u0633\u06d2 \u0639\u0648\u0627\u0645\u06cc \u06a9\u0631\u06d2 \u06af\u06cc\u06d4 \u0627\u06af\u0631 \u0627\u0633 \u0648\u0642\u062a \u06a9\u0648\u0626\u06cc \u0645\u0633\u0626\u0644\u06c1 \u0627\u0653\u062a\u0627 \u06c1\u06d2 \u062a\u0648 \u0627\u0653\u0626\u06cc \u0633\u06cc \u0633\u06cc \u06a9\u0648 \u0627\u0633 \u0633\u06d2 \u0646\u0645\u0679\u0627 \u0686\u0627\u06c1\u0626\u06d2\u06d4\u00a0 \u0627\u0633 \u062f\u0631\u0645\u06cc\u0627\u0646\u060c \u0627\u0653\u0633\u0679\u0631\u06cc\u0644\u0648\u06cc \u0645\u06cc\u0688\u06cc\u0627 \u0646\u06d2 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u06cc \u062a\u0642\u0631\u0631\u06cc \u067e\u0631 \u0633\u062e\u062a \u0631\u062f \u0639\u0645\u0644 \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u06a9\u06cc\u0627 \u0627\u0648\u0631 \u0627\u062e\u0628\u0627\u0631\u0627\u062a \u0646\u06d2 \u06cc\u06c1\u0627\u06ba \u06a9\u06c1\u0627 \u06a9\u06c1 \u06cc\u06c1 \u0642\u062f\u0645 \u06a9\u0631\u06a9\u0679 \u06a9\u06cc \u0633\u0627\u06a9\u06be \u067e\u0631 \u062a\u0627\u0632\u06c1 \u062d\u0645\u0644\u06c1 \u06c1\u06d2\u06d4 \u062f\u06cc \u0627\u06cc\u062c \u0627\u062e\u0628\u0627\u0631 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u06af\u0631 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06cc\u06c1 \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u06cc\u06c1 \u062b\u0627\u0628\u062a \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u0686\u06be \u063a\u0644\u0637 \u0646\u06c1\u06cc\u06ba \u06a9\u06cc\u0627\u060c \u062a\u0648 \u0628\u06be\u06cc \u062d\u0642\u06cc\u0642\u062a \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u0627\u0653\u0626\u06cc \u0633\u06cc \u0633\u06cc \u06a9\u06d2 \u062f\u06cc\u06af\u0631 \u0627\u0631\u06a9\u0627\u0646 \u06a9\u06cc \u0637\u0631\u0641 \u0633\u06d2 \u0686\u06cc\u0626\u0631\u0645\u06cc\u0646 \u06a9\u06d2 \u0639\u06c1\u062f\u06d2 \u067e\u0631 \u0627\u0646\u06c1\u06cc\u06ba \u0645\u0642\u0631\u0631 \u06a9\u0631\u0646\u06d2 \u0633\u06d2 \u0627\u0633 \u06a9\u06be\u06cc\u0644 \u0633\u06d2 \u0628\u062f\u0639\u0646\u0648\u0627\u0646\u06cc \u062e\u062a\u0645 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0627\u0646 \u06a9\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062e\u0648\u0627\u06c1\u0634 \u0645\u06cc\u06ba \u06cc\u0642\u06cc\u0646 \u067e\u06cc\u062f\u0627 \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u062a\u0627 \u06c1\u06d2\u06d4 \u0627\u062e\u0628\u0627\u0631 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0653\u0626\u06cc \u0633\u06cc \u0633\u06cc \u06a9\u06d2 \u0646\u0626\u06d2 \u0686\u06cc\u0626\u0631\u0645\u06cc\u0646 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u0645\u06cc\u0644\u0628\u0648\u0631\u0646 \u0645\u06cc\u0679\u0646\u06af \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u06cc \u0645\u0648\u062c\u0648\u062f\u06af\u06cc \u06a9\u0631\u06a9\u0679 \u06a9\u06cc \u0633\u0627\u06a9\u06be \u067e\u0631 \u062a\u0627\u0632\u06c1 \u062d\u0645\u0644\u06c1 \u06c1\u06d2\u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u06cc\u0644\u0628\u0648\u0631\u0646\u06d4\u0628\u06cc\u0646 \u0627\u0644\u0627\u0642\u0648\u0627\u0645\u06cc \u06a9\u0631\u06a9\u0679 \u0627\u06cc\u0633\u0648\u0633\u06cc \u0627\u06cc\u0634\u0646 \u06a9\u06d2 \u0641\u06cc\u0688\u0631\u06cc\u0634\u0646( \u0641\u06a9\u0627)\u0646\u06d2 \u0627\u0653\u062c \u06a9\u06c1\u0627 \u06a9\u06c1 \u0648\u06c1 \u0627\u0653\u0626\u06cc \u0633\u06cc \u0633\u06cc \u0686\u06cc\u0626\u0631\u0645\u06cc\u0646 \u06a9\u06d2 \u0639\u06c1\u062f\u06d2 \u067e\u0631 \u0627\u06cc\u0646 \u0634\u0631\u06cc \u0646\u0648\u0627\u0633\u0646 \u06a9\u06cc \u062a\u0642\u0631\u0631\u06cc \u0633\u06d2 \u0645\u0627\u06cc\u0648\u0633 \u06c1\u06d2\u06d4\u0627\u062f\u06be\u0631\u060c \u0646\u06cc\u0648\u0632\u06cc \u0644\u06cc\u0646\u0688 \u06a9\u0631\u06a9\u0679 \u06a9\u06d2 \u0688\u0627\u0626\u0631\u06cc\u06a9\u0679\u0631 \u0645\u0627\u0631\u0679\u0646 \u0633\u0646\u06cc\u0688\u0646 \u0646\u06d2 \u0627\u0633 \u0645\u062a\u0646\u0627\u0632\u0639\u06c1 \u06c1\u0646\u062f\u0648\u0633\u062a\u0627\u0646\u06cc \u06a9\u06be\u06cc\u0644 \u0645\u0646\u062a\u0638\u0645 \u06a9\u06cc \u062a\u0642\u0631\u0631\u06cc \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u06a9\u06cc\u06d4 \u0641\u06a9\u0627\u06a9\u06d2 \u0633\u0628\u06a9\u062f\u0648\u0634 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0635\u062f\u0631 \u067e\u0627\u0644 \u0645\u0627\u0631\u0634 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,34],"tags":[],"class_list":["post-20876","post","type-post","status-publish","format-standard","category-sports","category-sport-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/20876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=20876"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/20876\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=20876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=20876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=20876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}