{"id":21584,"date":"2014-07-07T14:27:47","date_gmt":"2014-07-07T08:57:47","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=21584"},"modified":"2014-07-07T14:27:47","modified_gmt":"2014-07-07T08:57:47","slug":"%d8%b1%db%8c%d8%a7%d8%b3%d8%aa%db%8c-%d8%ad%da%a9%d9%88%d9%85%d8%aa-%d8%b3%db%92-%d8%aa%d9%86%d9%88-%d8%b4%d8%b1%d9%85%d8%a7-%d9%85%d8%b9%d8%a7%d9%85%d9%84%db%81-%da%a9%d8%a7-%d8%b3%db%8c-%d8%a8%db%8c","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%b1%db%8c%d8%a7%d8%b3%d8%aa%db%8c-%d8%ad%da%a9%d9%88%d9%85%d8%aa-%d8%b3%db%92-%d8%aa%d9%86%d9%88-%d8%b4%d8%b1%d9%85%d8%a7-%d9%85%d8%b9%d8%a7%d9%85%d9%84%db%81-%da%a9%d8%a7-%d8%b3%db%8c-%d8%a8%db%8c\/","title":{"rendered":"\u0631\u06cc\u0627\u0633\u062a\u06cc \u062d\u06a9\u0648\u0645\u062a \u0633\u06d2 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u0645\u0639\u0627\u0645\u0644\u06c1 \u06a9\u0627 \u0633\u06cc \u0628\u06cc \u0627\u0653\u0626\u06cc \u062c\u0627\u0646\u0686 \u06a9\u0627 \u0645\u0637\u0627\u0644\u0628\u06c1"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-21585\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/07\/tanu_sharma.jpg\" alt=\"tanu_sharma\" width=\"159\" height=\"159\" \/>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u0627\u0646\u0688\u06cc\u0627 \u0679\u06cc \u0648\u06cc \u0686\u06cc\u0646\u0644 \u06a9\u06cc \u0627\u06cc\u0646\u06a9\u0631 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0633\u06d2 \u0633\u0646\u0633\u062a\u06be\u0627\u0646 \u06a9\u06d2 \u0633\u06cc\u0646\u0626\u0631 \u0645\u0644\u0627\u0632\u0645\u06cc\u0646 \u067e\u0631 \u063a\u06cc\u0631 \u0627\u062e\u0644\u0627\u0642\u06cc \u06a9\u0627\u0645\u0648\u06ba \u06a9\u06cc\u0644\u0626\u06d2 \u062f\u0628\u0627\u0648\u0654 \u0688\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0627\u0644\u0632\u0627\u0645 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u06d2 \u0633\u0627\u0645\u0646\u06d2 \u0644\u06af\u0627\u0646\u06d2 \u06a9\u06d2 \u0628\u0627\u0648\u062c\u0648\u062f \u0645\u0644\u0632\u0645\u0627\u0646 \u06a9\u06cc \u06af\u0631\u0641\u062a\u0627\u0631\u06cc \u0646\u06c1 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u0653\u062c \u0627\u062a\u0648\u0627\u0631 \u06a9\u0648 \u0644\u06a9\u06be\u0646\u0648\u0654 \u062c\u06cc \u067e\u06cc \u0627\u0648 \u0648\u0627\u0642\u0639 \u06af\u0627\u0646\u062f\u06be\u06cc \u0645\u062c\u0633\u0645\u06c1 \u06a9\u06d2 \u0633\u0627\u0645\u0646\u06d2 \u0645\u062e\u062a\u0644\u0641 \u062a\u0646\u0638\u06cc\u0645\u0648\u06ba \u06a9\u06d2 \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0627\u0648\u0631 \u062f\u0627\u0646\u0634\u0648\u0631\u0648\u06ba \u0646\u06d2 \u06a9\u06cc\u0646\u0688\u0644 \u0645\u0627\u0631\u0686 \u0646\u06a9\u0627\u0644 \u06a9\u0631 \u0627\u062d\u062a\u062c\u0627\u062c \u06a9\u06cc\u0627\u06d4\u0627 \u062d\u062a\u062c\u0627\u062c \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u0648\u06ba \u0646\u06d2 \u067e\u0627\u0631\u0644\u06cc\u0645\u0627\u0646\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc\u06ba \u0627\u0646\u0688\u06cc\u0627 \u0679\u06cc \u0648\u06cc \u06a9\u06d2 \u0631\u0648\u0644 \u06a9\u06cc \u062c\u0627\u0646\u0686 \u06a9\u0631\u0627\u0648\u0654 \u0627\u06cc\u0641 \u0627\u0653\u0626\u06cc \u0627\u0631 \u0633\u06d2 \u0631\u062c\u062a \u0634\u0631\u0645\u0627 \u06a9\u06cc \u0628\u06cc\u0648\u06cc \u0631\u06cc\u062a\u0648 \u062f\u06be\u0648\u0646 \u06a9\u0627\u0646\u0627\u0645 \u06c1\u0679\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u067e\u0648\u0644\u06cc\u0633 \u0627\u0641\u0633\u0631 \u06a9\u0648 \u0645\u0639\u0637\u0644 \u06a9\u0631\u0648\u060c \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u0646\u0688\u06cc\u0627 \u0679\u06cc \u0648\u06cc \u06a9\u06d2 \u062f\u0628\u0627\u0648\u0654\u0645\u06cc\u06ba \u0644\u06a9\u06be\u06d2 \u06af\u0626\u06d2 \u0645\u0642\u062f\u0645\u06c1 \u06a9\u0648 \u062e\u0627\u0631\u062c \u06a9\u06cc\u0627 \u062c\u0627\u0626\u06d2\u06d4 \u0633\u0628 \u0627\u0646\u0633\u067e\u06a9\u0679\u0631 \u0627\u0631\u0648\u0646\u0627 \u0627\u0648\u0631 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u0645\u0639\u0627\u0645<br \/>\n\u0644\u06c1 \u0645\u06cc\u06ba \u0645\u0644\u0632\u0645\u0627\u0646 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06a9\u06be\u0691\u06cc \u0633\u0645\u0627\u062c\u0648\u0627\u062f\u06cc \u062d\u06a9\u0648\u0645\u062a \u0634\u0631\u0645 \u06a9\u0631\u0648\u06d4 \u062e\u0648\u0627\u062a\u06cc\u0646 \u0645\u062e\u0627\u0644\u0641 \u0627\u0646\u0688\u06cc\u0627 \u0679\u06cc \u0648\u06cc \u06a9\u0627 \u0648\u0627\u06a9 \u0627\u0653\u0648\u0654\u0679 \u06a9\u0631\u0648\u060c \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u0645\u0639\u0627\u0645\u0644\u06c1 \u06a9\u06cc \u0633\u06cc \u0628\u06cc \u0627\u0653\u0626\u06cc \u062c\u0627\u0646\u0686 \u06a9\u0631\u0627\u0648\u0654 \u0648\u063a\u06cc\u0631\u06c1 \u0646\u0639\u0631\u06d2 \u0644\u06a9\u06be\u06cc \u062a\u062e\u062a\u06cc\u0627\u06ba \u0644\u06d2 \u0631\u06a9\u06be\u06cc \u062a\u06be\u06cc\u06ba\u06d4 \u0645\u0638\u0627\u06c1\u0631\u06cc\u0646 \u0646\u06d2 \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u06a9\u0648 \u0628\u06be\u06cc\u062c\u06cc \u06af\u0626\u06cc \u0639\u0631\u0636\u062f\u0627\u0634\u062a \u0645\u06cc\u06ba \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u0645\u0639\u0627\u0645\u0644\u06c1 \u067e\u0648\u0631\u06cc \u0631\u06cc\u0627\u0633\u062a \u0645\u06cc\u06ba \u062e\u0648\u0627\u062a\u06cc\u0646 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u0646\u062a\u0638\u0627\u0645\u06cc \u062a\u062d\u0641\u0638 \u0645\u06cc\u06ba \u06c1\u0648 \u0631\u06c1\u06d2 \u062c\u0631\u0627\u0626\u0645 \u06a9\u06cc \u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u0645\u062b\u0627\u0644 \u06c1\u06d2\u06d4 \u062c\u0633 \u0645\u06cc\u06ba \u0627\u0646\u062a\u0638\u0627\u0645\u06cc\u06c1 \u06a9\u06be\u0644 \u06a9\u0631 \u0645\u062c\u0631\u0645\u06cc\u0646 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u0645\u06cc\u06ba \u06a9\u06be\u0691\u0627 \u062f\u06cc\u06a9\u06be \u0631\u06c1\u0627 \u06c1\u06d2\u06d4 \u0639\u0631\u0636\u062f\u0627\u0634\u062a \u0645\u06cc\u06ba \u0645\u0637\u0627\u0644\u0628\u06c1 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0686\u0648\u0646\u06a9\u06c1 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u0645\u0639\u0627\u0645\u0644\u06c1 \u0646\u0648\u0626\u06cc\u0688\u0627 \u0627\u062a\u0631\u067e\u0631\u062f\u06cc\u0634 \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u067e\u06cc\u0634 \u0627\u0653\u06cc\u0627 \u0627\u0633 \u0644\u0626\u06d2 \u0627\u0633 \u0645\u0639\u0627\u0645\u0644\u06c1 \u0645\u06cc\u06ba \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u062d\u06a9\u0648\u0645\u062a \u0633\u06cc \u0628\u06cc \u0627\u0653\u0626\u06cc \u062c\u0627\u0646\u0686 \u06a9\u06cc \u0645\u0646\u0638\u0648\u0631\u06cc \u062f\u06d2\u06d4 \u0627\u06cc\u0633\u0627 \u0627\u0633 \u0644\u0626\u06d2 \u0636\u0631\u0648\u0631\u06cc \u06c1\u06d2 \u06a9\u06c1 \u06cc\u06c1 \u0645\u0639\u0627\u0645\u0644\u06c1 \u067e\u0627\u0631\u0644\u06cc\u0645\u0627\u0646\u06cc \u0627\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u06c1\u0648\u0627 \u062a\u06be\u0627\u06d4 \u0645\u0638\u0627\u06c1\u0631\u06cc\u0646 \u0646\u06d2 \u067e\u0631\u06cc\u0633 \u06a9\u0648\u0646\u0633\u0644 \u0627\u0653\u0641 \u0627\u0646\u0688\u06cc\u0627 \u0633\u06d2 \u0645\u0637\u0627\u0644\u0628\u06c1 \u06a9\u06cc\u0627 \u06a9\u06c1 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u0646\u06d2 \u06af\u0632\u0634\u062a\u06c1 \u06f5\u060d\u0641\u0631\u0648\u0631\u06cc \u06a9\u0648 \u0627\u0646\u0688\u06cc\u0627 \u0679\u06cc \u0648\u06cc \u0686\u06cc\u0646\u0644 \u06a9\u0648\u062c\u0648\u0627\u0626\u0646 \u06a9\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u067e\u0627\u0631\u0644\u06cc\u0645\u0627\u0646\u06cc \u0627\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u06a9\u0648\u062f\u06cc\u06a9\u06be\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u062a\u0645\u0627\u0645 \u0686\u06cc\u0646\u0644\u0648\u06ba \u0646\u06d2 \u0646\u0626\u06cc \u062a\u0642\u0631\u0631\u06cc\u0627\u06ba \u06a9\u06cc \u062a\u06be\u06cc\u06ba\u06d4 \u0627\u06cc\u0633\u06d2 \u0645\u06cc\u06ba \u067e\u0631\u06cc\u0633 \u06a9\u0648\u0646\u0633\u0644 \u0627\u0653\u0641 \u0627\u0646\u0688\u06cc\u0627 \u06a9\u0648 \u0686\u0627\u06c1\u0626\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u0646 \u062a\u0645\u0627\u0645 \u062a\u0642\u0631\u0631\u06cc\u0648\u06ba \u067e\u0631\u0627\u06cc\u06a9 \u0646\u06af\u0631\u0627\u0646\u06cc \u06a9\u0645\u06cc\u0679\u06cc \u06a9\u0627 \u0642\u06cc\u0627\u0645 \u06a9\u0631\u06d2 \u0627\u0648\u0631 \u0627\u0646 \u06a9\u06d2 \u062d\u0627\u0644\u0627\u062a \u06a9\u0648\u0633\u0645\u062c\u06be\u0646\u06d2 \u06a9\u06cc \u06a9\u0648\u0634\u0634 \u06a9\u0631\u06d2 \u062a\u0627\u06a9\u06c1 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u062c\u06cc\u0633\u06cc \u062f\u06cc\u06af\u0631 \u0648\u0627\u0631\u062f\u0627\u062a \u0646\u06c1 \u06c1\u0648\u06ba\u06d4 \u0645\u0638\u0627\u06c1\u0631\u06cc\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u062c\u0633 \u0637\u0631\u06cc\u0642\u06c1 \u0633\u06d2 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u0627\u0648\u0631 \u0627\u0631\u0648\u0646\u0627 \u0631\u0627\u0626\u06d2 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u0648\u0627 \u0627\u0648\u0631 \u0627\u0646\u0635\u0627\u0641 \u0645\u06cc\u06ba \u0645\u0633\u0644\u0633\u0644 \u0631\u06a9\u0627\u0648\u0679 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u06a9\u0648\u0634\u0634\u06cc\u06ba \u06a9\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u06c1\u06cc\u06ba \u0627\u0633 \u0633\u06d2 \u067e\u0648\u0631\u06d2 \u0633\u0645\u0627\u062c \u0645\u06cc\u06ba \u063a\u0644\u0637 \u067e\u06cc\u063a\u0627\u0645 \u062c\u0627\u062a\u0627 \u06c1\u06d2 \u062c\u0633 \u06a9\u06d2 \u0633\u0628\u0628 \u06a9\u0648\u0626\u06cc \u0628\u06be\u06cc \u0644\u0691\u06a9\u06cc \u0645\u06cc\u0688\u06cc\u0627 \u0633\u0646\u0633\u062a\u06be\u0627\u0646 \u0627\u0648\u0631 \u067e\u0648\u0644\u06cc\u0633 \u0645\u062d\u06a9\u0645\u06c1 \u0645\u06cc\u06ba \u0646\u06c1\u06cc\u06ba \u062c\u0627\u0646\u0627 \u0686\u0627\u06c1\u06d2 \u06af\u06cc \u0627\u0648\u0631 \u0646\u06c1 \u06c1\u06cc \u06a9\u0648\u0626\u06cc \u0633\u0631\u067e\u0631\u0633\u062a \u0627\u067e\u0646\u06cc \u0628\u0686\u06cc\u0648\u06ba \u06a9\u0648 \u0627\u0633 \u0645\u06cc\u06ba \u0628\u06be\u06cc\u062c\u06d2 \u06af\u0627\u06d4 \u0645\u0638\u0627\u06c1\u0631\u06c1 \u0645\u06cc\u06ba \u0633\u062a\u06cc\u0646\u062f\u0631 \u06a9\u0645\u0627\u0631\u060c \u0645\u06cc\u06af \u0633\u06cc\u0633\u06d2 \u0627\u0639\u0632\u0627\u0632 \u0633\u06d2 \u0633\u0631\u0641\u0631\u0627\u0632 \u0633\u0645\u0627\u062c\u06cc \u06a9\u0627\u0631\u06a9\u0646 \u0633\u0646\u062f\u06cc\u067e \u067e\u0627\u0646\u0688\u06d2\u060c \u0646\u0627\u06af\u0631\u06a9 \u067e\u0631\u06cc\u0634\u062f \u06a9\u06d2 \u0631\u0627\u0645 \u06a9\u0631\u0634\u0646\u060c \u0645\u0632\u062f\u0648\u0631 \u0644\u06cc\u0688\u0631 \u06a9\u06d2 \u06a9\u06d2 \u0634\u06a9\u0644\u0627 \u060c \u0631\u0648\u0688\u0648\u06cc\u0632 \u0645\u0644\u0627\u0632\u0645\u06cc\u0646 \u06a9\u06d2 \u0644\u06cc\u0688\u0631 \u06c1\u0648\u0645\u06cc\u0646\u062f\u0631 \u0645\u0634\u0631\u0627\u060c \u067e\u0631\u062a\u0627\u067e \u06af\u0691\u06be \u06a9\u06d2 \u0634\u0645\u0633 \u062a\u0628\u0631\u06cc\u0632\u060c \u06c1\u0631\u062f\u0648\u0626\u06cc \u06a9\u06d2 \u0633\u0645\u0627\u062c\u06cc \u06a9\u0627\u0631\u06a9\u0646 \u0631\u0627\u062f\u06be\u06d2 \u0634\u06cc\u0627\u0645 \u06a9\u067e\u0648\u0631\u060c \u0631\u06c1\u0627\u0626\u06cc \u0645\u0646\u0686 \u06a9\u06d2 \u0635\u062f\u0631 \u0645\u062d\u0645\u062f \u0634\u0639\u06cc\u0628\u060c \u0627\u06d2 \u06a9\u06d2 \u0633\u0646\u06af\u06be\u060c \u0627\u06a9\u06be\u0644\u06cc\u0634 \u0633\u06a9\u0633\u06cc\u0646\u06c1\u060c \u063a\u0641\u0631\u0627\u0646 \u0635\u062f\u06cc\u0642\u06cc\u060c \u0627\u0631\u0648\u0646\u0627 \u0633\u0646\u06af\u06be\u060c \u0634\u0627\u06c1\u0646\u0648\u0627\u0632 \u0639\u0627\u0644\u0645\u060c \u06c1\u0631\u06d2 \u0631\u0627\u0645 \u0645\u0634\u0631\u0627\u060c \u0633\u06cc \u0628\u06cc \u062a\u0631\u067e\u0627\u0679\u06be\u06cc\u060c \u06a9\u0633\u0627\u0646 \u0644\u06cc\u0688\u0631 \u0634\u06cc\u0648\u0627 \u062c\u06cc \u0631\u0627\u0626\u06d2\u060c \u0631\u0627\u062c\u06cc\u0648 \u06cc\u0627\u062f\u0648 \u0648\u063a\u06cc\u0631\u06c1 \u0645\u0648\u062c\u0648\u062f \u062a\u06be\u06d2\u06d4<\/p>\n<p style=\"text-align: right;\">\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u0627\u0646\u0688\u06cc\u0627 \u0679\u06cc \u0648\u06cc \u0686\u06cc\u0646\u0644 \u06a9\u06cc \u0627\u06cc\u0646\u06a9\u0631 \u062a\u0646\u0648 \u0634\u0631\u0645\u0627 \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0633\u06d2 \u0633\u0646\u0633\u062a\u06be\u0627\u0646 \u06a9\u06d2 \u0633\u06cc\u0646\u0626\u0631 \u0645\u0644\u0627\u0632\u0645\u06cc\u0646 \u067e\u0631 \u063a\u06cc\u0631 \u0627\u062e\u0644\u0627\u0642\u06cc \u06a9\u0627\u0645\u0648\u06ba \u06a9\u06cc\u0644\u0626\u06d2 \u062f\u0628\u0627\u0648\u0654 \u0688\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0627\u0644\u0632\u0627\u0645 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u06d2 \u0633\u0627\u0645\u0646\u06d2 \u0644\u06af\u0627\u0646\u06d2 \u06a9\u06d2 \u0628\u0627\u0648\u062c\u0648\u062f \u0645\u0644\u0632\u0645\u0627\u0646 \u06a9\u06cc \u06af\u0631\u0641\u062a\u0627\u0631\u06cc \u0646\u06c1 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0627\u0653\u062c \u0627\u062a\u0648\u0627\u0631 \u06a9\u0648 \u0644\u06a9\u06be\u0646\u0648\u0654 \u062c\u06cc \u067e\u06cc \u0627\u0648 \u0648\u0627\u0642\u0639 \u06af\u0627\u0646\u062f\u06be\u06cc \u0645\u062c\u0633\u0645\u06c1 \u06a9\u06d2 \u0633\u0627\u0645\u0646\u06d2 \u0645\u062e\u062a\u0644\u0641 \u062a\u0646\u0638\u06cc\u0645\u0648\u06ba \u06a9\u06d2 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,28],"tags":[],"class_list":["post-21584","post","type-post","status-publish","format-standard","category-lucknow","category-lucknow-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/21584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=21584"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/21584\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=21584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=21584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=21584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}