{"id":23519,"date":"2014-07-30T18:39:20","date_gmt":"2014-07-30T13:09:20","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=23519"},"modified":"2014-07-30T18:39:20","modified_gmt":"2014-07-30T13:09:20","slug":"%d8%b1%d9%88%d8%b3-%da%a9%db%92-%d9%85%d8%b1%da%a9%d8%b2%db%8c-%d8%a8%db%8c%d9%86%da%a9-%da%a9%db%8c-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa%db%8c-%d8%a7%d8%af%d8%a7%d8%b1%d9%88%da%ba-%da%a9%d9%88%db%8c","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%b1%d9%88%d8%b3-%da%a9%db%92-%d9%85%d8%b1%da%a9%d8%b2%db%8c-%d8%a8%db%8c%d9%86%da%a9-%da%a9%db%8c-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa%db%8c-%d8%a7%d8%af%d8%a7%d8%b1%d9%88%da%ba-%da%a9%d9%88%db%8c\/","title":{"rendered":"\u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0631\u06a9\u0632\u06cc \u0628\u06cc\u0646\u06a9 \u06a9\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u062f\u0627\u0631\u0648\u06ba \u06a9\u0648\u06cc\u0642\u06cc\u0646 \u062f \u06c1\u0627\u0646\u06cc"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-23520\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/07\/central-Bank-1024x768.jpg\" alt=\"OLYMPUS DIGITAL CAMERA\" width=\"196\" height=\"147\" \/>\u0645\u0627\u0633\u06a9\u0648(\u0627\u06cc\u062c\u0646\u0633\u06cc) \u0627\u0645\u0631\u06cc\u06a9\u06cc \u067e\u0627\u0628\u0646\u062f\u06cc\u0648\u06ba \u06a9\u06cc \u0645\u0627\u0631 \u0633\u06d2 \u062f\u0648\u0686\u0627\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u062f\u0627\u0631\u0648\u06ba \u06a9\u0648 \u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0631\u06a9\u0632\u06cc \u0628\u06cc\u0646\u06a9 \u0646\u06d2 \u067e\u0648\u0631\u06d2 \u062a\u0639\u0627\u0648\u0646 \u06a9\u0627 \u06cc\u0642\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0627 \u06c1\u06d2\u06d4 \u062f\u0631\u06cc\u06ba \u0627\u062b\u0646\u0627\u0621 \u0645\u0627\u0633\u06a9\u0648 \u0645\u06cc\u06ba \u0627\u0653\u062c \u0634\u06cc\u0626\u0631 \u0628\u0627\u0632\u0627\u0631 \u0646\u06cc\u0686\u06d2 \u0627\u0653\u06af\u0626\u06d2\u06d4 \u0627\u0653\u0644 \u0644\u0627\u0626\u0646 \u0628\u06cc\u0627\u0646 \u0645\u06cc\u06ba \u0645\u0631\u06a9\u0632\u06cc \u0628\u06cc\u0646\u06a9 \u0646\u06d2 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u062f\u0627\u0631\u0648\u06ba \u06a9\u0648 \u0645\u0646\u0627\u0633\u0628 \u0645\u062f\u062f \u06a9\u0627 \u06cc\u0642\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0627 \u06c1\u06d2\u06d4 \u062c\u0628\u06a9\u06c1 \u067e\u0628\u0644\u06a9 \u0633\u06cc\u06a9\u0679\u0631 \u06a9\u0627 \u0648\u06cc \u0679\u06cc \u0628\u06cc \u0628\u06cc\u0646\u06a9 \u062c\u0648 \u0631\u0648\u0633 \u06a9\u0627 \u062f\u0648\u0633\u0631\u0627 \u0633\u0628 \u0633\u06d2 \u0628\u0691\u0627 \u0628\u06cc\u0646\u06a9 \u06c1\u06d2 \u06a9\u06d2 \u0634\u06cc\u0626\u0631\u0648\u06ba \u0645\u06cc\u06ba\u0627\u0653\u062c \u06af\u0631\u0627\u0648\u0679 \u0627\u0653\u0626\u06cc\u06d4 \u0627\u0633 \u06a9\u06d2 \u0639\u0644\u0627\u0648\u06c1 \u0645\u0644\u06a9 \u06a9\u0627 \u0627\u06cc\u06a9 \u062f\u06cc\u06af\u0631 \u0628\u06cc\u0646\u06a9 \u062c\u0633<br \/>\n\u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc\u0648\u06ba \u06a9\u0627 \u0627\u062b\u0631 \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06d2 \u0634\u06cc\u0626\u0631 \u0627\u0648\u067e\u0631 \u0686\u0644 \u0631\u06c1\u06d2 \u062a\u06be\u06d2 \u0627\u0645\u0631\u06cc\u06a9\u06cc \u062d\u06a9\u0627\u0645 \u0646\u06d2 \u06a9\u0644 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u0627\u0628\u0646\u062f\u06cc\u0648\u06ba \u0633\u06d2 \u0631\u0648\u0633 \u06a9\u06d2 \u0628\u06cc\u0646\u06a9\u0646\u06af \u0634\u0639\u0628\u06d2 \u06a9\u06cc \u062a\u06cc\u0633 \u0641\u06cc\u0635\u062f \u0627\u0645\u0644\u0627\u06a9 \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648\u06ba \u06af\u06cc\u06d4\u0645\u0644\u06cc\u0634\u06cc\u0627\u0626\u06cc \u0627\u0626\u06cc\u0631 \u0644\u0627\u0626\u0646\u0633 \u06a9\u06cc \u0627\u0691\u0627\u0646 \u06f1\u06f7\u06a9\u0648 \u0645\u0634\u0631\u0642\u06cc \u06cc\u0648\u06a9\u0631\u06cc\u0646 \u0645\u06cc\u06ba \u0645\u0627\u0631 \u06af\u0631\u0627\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u0645\u063a\u0631\u0628\u06cc \u0645\u0645\u0627\u0644\u06a9 \u06a9\u06d2 \u0627\u0641\u0633\u0631\u0627\u0646 \u0646\u06d2 \u0627\u0633 \u06a9\u06d2 \u0644\u0626\u06d2 \u0631\u0648\u0633 \u062d\u0627\u0645\u06cc \u0639\u0644\u06cc\u062d\u062f\u06af\u06cc \u067e\u0633\u0646\u062f\u0648\u06ba \u067e\u0631 \u0627\u0644\u0632\u0627\u0645 \u0639\u0627\u0626\u062f \u06a9\u06cc\u0627\u06c1\u06d2\u06d4 \u0627\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0631\u0648\u0633 \u0633\u06d2 \u0628\u06be\u06cc\u062c\u06cc \u06af\u0626\u06cc \u0645\u06cc\u0632\u0627\u0626\u0644 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u0637\u06cc\u0627\u0631\u06d2 \u06a9\u0648 \u0645\u0627\u0631 \u06af\u0631\u0627\u06cc\u0627\u06af\u06cc\u0627 \u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0627\u0633\u06a9\u0648(\u0627\u06cc\u062c\u0646\u0633\u06cc) \u0627\u0645\u0631\u06cc\u06a9\u06cc \u067e\u0627\u0628\u0646\u062f\u06cc\u0648\u06ba \u06a9\u06cc \u0645\u0627\u0631 \u0633\u06d2 \u062f\u0648\u0686\u0627\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u062f\u0627\u0631\u0648\u06ba \u06a9\u0648 \u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0631\u06a9\u0632\u06cc \u0628\u06cc\u0646\u06a9 \u0646\u06d2 \u067e\u0648\u0631\u06d2 \u062a\u0639\u0627\u0648\u0646 \u06a9\u0627 \u06cc\u0642\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0627 \u06c1\u06d2\u06d4 \u062f\u0631\u06cc\u06ba \u0627\u062b\u0646\u0627\u0621 \u0645\u0627\u0633\u06a9\u0648 \u0645\u06cc\u06ba \u0627\u0653\u062c \u0634\u06cc\u0626\u0631 \u0628\u0627\u0632\u0627\u0631 \u0646\u06cc\u0686\u06d2 \u0627\u0653\u06af\u0626\u06d2\u06d4 \u0627\u0653\u0644 \u0644\u0627\u0626\u0646 \u0628\u06cc\u0627\u0646 \u0645\u06cc\u06ba \u0645\u0631\u06a9\u0632\u06cc \u0628\u06cc\u0646\u06a9 \u0646\u06d2 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u062f\u0627\u0631\u0648\u06ba \u06a9\u0648 \u0645\u0646\u0627\u0633\u0628 \u0645\u062f\u062f \u06a9\u0627 \u06cc\u0642\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0627 \u06c1\u06d2\u06d4 \u062c\u0628\u06a9\u06c1 \u067e\u0628\u0644\u06a9 \u0633\u06cc\u06a9\u0679\u0631 \u06a9\u0627 \u0648\u06cc \u0679\u06cc \u0628\u06cc \u0628\u06cc\u0646\u06a9 \u062c\u0648 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,30],"tags":[],"class_list":["post-23519","post","type-post","status-publish","format-standard","category-business","category-business-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/23519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=23519"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/23519\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=23519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=23519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=23519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}