{"id":23694,"date":"2014-08-01T19:32:57","date_gmt":"2014-08-01T14:02:57","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=23694"},"modified":"2014-08-01T19:32:57","modified_gmt":"2014-08-01T14:02:57","slug":"%d9%85%d8%a7%d8%b1%d9%88%d8%aa%db%8c-%da%a9%db%8c-%d8%ac%d9%88%d9%84%d8%a7%d8%a6%db%8c-%d9%85%db%8c%da%ba-%d9%81%d8%b1%d9%88%d8%ae%d8%aa-%d9%85%db%8c%da%ba%db%b2%db%b2%d9%81%db%8c%d8%b5%d8%af-%da%a9","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d9%85%d8%a7%d8%b1%d9%88%d8%aa%db%8c-%da%a9%db%8c-%d8%ac%d9%88%d9%84%d8%a7%d8%a6%db%8c-%d9%85%db%8c%da%ba-%d9%81%d8%b1%d9%88%d8%ae%d8%aa-%d9%85%db%8c%da%ba%db%b2%db%b2%d9%81%db%8c%d8%b5%d8%af-%da%a9\/","title":{"rendered":"\u0645\u0627\u0631\u0648\u062a\u06cc \u06a9\u06cc \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba \u0641\u0631\u0648\u062e\u062a \u0645\u06cc\u06ba\u06f2\u06f2\u0641\u06cc\u0635\u062f \u06a9\u0627 \u0627\u0636\u0627\u0641\u06c1"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-21158\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/07\/maruti-car.jpg\" alt=\"maruti car\" width=\"216\" height=\"117\" \/>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc(\u0648\u0627\u0631\u062a\u0627)\u0645\u0644\u06a9 \u06a9\u06cc \u0645\u0634\u06c1\u0648\u0631 \u06a9\u0627\u0631\u06a9\u0645\u067e\u0646\u06cc \u0645\u0627\u0631\u0648\u062a\u06cc \u0633\u0648\u0632\u0648\u06a9\u06cc \u0627\u0646\u0688\u06cc\u0627 \u0644\u0645\u06cc\u0679\u06cc\u0688\u06a9\u06cc \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba\u06a9\u0644 \u0641\u0631\u0648\u062e\u062a \u06f7\u0621\u06f1\u060d\u0641\u06cc\u0635\u062f \u06a9\u06cc \u062a\u06cc\u0632\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0627\u06cc\u06a9 \u0644\u0627\u06a9\u06be \u06a9\u0648 \u067e\u0627\u0631\u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u06cc\u06a9 \u0644\u0627\u06a9\u06be \u0627\u06cc\u06a9 \u06c1\u0632\u0627\u0631 \u06f3\u06f8\u06f0\u06cc\u0648\u0646\u0679 \u067e\u0631 \u067e\u06c1\u0646\u0686 \u06af\u0626\u06cc \u06a9\u0645\u067e\u0646\u06cc \u0646\u06d2 \u0627\u0653\u062c \u0645\u0627\u06c1\u0627\u0646\u06c1 \u0641\u0631\u0648\u062e\u062a \u06a9\u06d2 \u0627\u0639\u062f\u0627\u062f\u0648\u0634\u0645\u0627\u0631 \u062c\u0627\u0631\u06cc \u06a9\u0626\u06d2\u06d4\u06af\u0632\u0634\u062a\u06c1 \u0633\u0627\u0644 \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba \u06a9\u0645\u067e\u0646\u06cc \u0646\u06d2 \u06f8\u06f3\u06c1\u0632\u0627\u0631\u06f2\u06f9\u06f9\u06a9\u0627\u0631\u06cc\u06ba \u0641\u0631\u0648\u062e\u062a \u06a9\u06cc\u06ba \u062a\u06be\u06cc\u06ba \u0645\u0627\u0631\u0648\u062a\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba \u06af\u06be\u0631\u06cc\u0644\u0648 \u0628\u0627\u0632\u0627\u0631 \u0645\u06cc\u06ba \u0627\u0633 \u06a9\u06cc \u0641\u0631\u0648\u062e\u062a \u06f4\u0621\u06f1\u06f4\u060d\u0641\u06cc\u0635\u062f \u06af\u0631\u0627\u0648\u0679 \u0633\u06d2 \u06f3\u06f3\u06f5\u06f8\u06f7\u0633\u06d2 \u06a9\u0645 \u06c1\u0648\u06a9\u0631 \u06f2\u06f8\u06f7\u06f5\u06f9\u06cc\u0648\u0646\u0679 \u0631\u06c1 \u06af\u0626\u06cc \u0644\u06cc\u06a9\u0646 \u06a9\u0645\u067e\u06cc\u06a9\u0679 \u0632\u0645\u0631\u06d2 \u06a9\u06cc \u0633\u0648\u0626\u0641\u0679\u060c\u0627\u06cc\u0633\u0679\u06cc\u0644\u0648\u060c \u0631\u06cc\u0679\u0632 \u06a9\u06cc \u0645\u0627\u0646\u06af \u0645\u06cc\u06ba \u06f2\u0621\u06f8\u06f1\u0641\u06cc\u0635\u062f \u06a9\u06cc \u0632\u0628\u0631\u062f\u0633\u062a \u062a\u06cc\u0632\u06cc \u0627\u0653\u0626\u06cc \u06d4 \u0627\u0646 \u06a9\u06cc \u0641\u0631\u0648\u062e\u062a \u06f1\u06f3\u06f8\u06f8\u06f2\u06a9\u06d2 \u0645\u0642\u0627\u0628\u0644\u06d2 \u06f2\u06f5\u06f1\u06f5\u06f6\u06cc\u0648\u0646\u0679 \u0631\u06c1\u06cc \u06d4\u06a9\u0645\u067e\u0646\u06cc \u06a9\u06cc \u0645\u0642\u0628\u0648\u0644 \u06a9\u0645\u067e\u06cc\u06a9\u0679 \u0633\u06cc\u0688\u0627\u0646 \u0688\u06cc\u0632\u0627\u0626\u0631 \u06a9\u06cc \u0641\u0631\u0648\u062e\u062a \u06f2\u0621\u06f2\u06f2\u0641\u06cc\u0635\u062f \u0628\u0691\u06be \u06a9\u0631 \u06f1\u06f5\u06f2\u06f4\u06f9\u06a9\u06d2 \u0645\u0642\u0627\u0628\u0644\u06d2 \u06f1\u06f8\u06f6\u06f3\u06f4\u06cc\u0648\u0646\u0679 \u0631\u06c1\u06cc\u06d4\u062f\u0631\u0645\u06cc\u0627\u0646\u06cc \u0633\u0627\u0626\u0632 \u06a9\u06cc \u0633\u06cc\u0688\u0627\u0646 \u0627\u06cc\u0633 \u0627\u06cc\u06a9\u0633 \u0641\u0648\u0631\u06a9\u06cc \u0641\u0631\u0648\u062e\u062a \u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u06f6\u0621\u06f2\u06f7\u0641\u06cc\u0635\u062f \u06a9\u0645 \u06c1\u0648\u06a9\u0631 \u06f3\u06f2\u06f2\u06a9\u06d2 \u0645\u0642\u0627\u0628\u0644\u06d2 \u0645\u06cc\u06ba \u06f2\u06f3\u06f3\u06af\u0627\u0691\u06cc \u0631\u06c1 \u06af\u0626\u06cc\u06d4\u062c\u067e\u0633\u06cc \u060c \u06af\u0631\u06cc\u0646\u0688 \u0648\u0679\u0627\u0631\u0627\u0627\u0648\u0631\u0627\u0631\u0679\u06cc\u06af\u0627 \u06a9\u06cc \u0641\u0631\u0648\u062e\u062a \u0645\u06cc\u06ba \u06f4\u0621\u06f2\u06f3 \u0641\u06cc\u0635\u062f \u06a9\u06cc \u062a\u06cc\u0632\u06cc \u0627\u0653\u0626\u06cc \u06d4 \u0627\u0646 \u06a9\u06cc \u0645\u0627\u0646\u06af \u06f4\u06f5\u06f6\u06f2 \u06a9\u06d2 \u0645\u0642\u0627\u0628\u0644<br \/>\n\u06d2 \u0645\u06cc\u06ba \u06f5\u06f6\u06f3\u06f1\u06cc\u0648\u0646\u0679 \u0631\u06c1\u06cc \u06d4\u0648\u06cc\u0646 \u0645\u06cc\u06ba \u0627\u0648\u0645\u0646\u06cc \u0627\u0648\u0631\u0627\u06cc\u06a9\u0648 \u06a9\u06cc \u0641\u0631\u0648\u062e\u062a \u06f8\u0621\u06f5\u06f4\u0641\u06cc\u0635\u062f \u06a9\u06cc \u062a\u06cc\u0632\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06f7\u06f5\u06f4\u06f3 \u0633\u06d2 \u0628\u0691\u06be \u06a9\u0631 \u062f\u0633 \u06c1\u0632\u0627\u0631 \u06a9\u0648 \u067e\u0627\u0631 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06f1\u06f6\u06f8\u06f0 \u060d\u06f1\u06cc\u0648\u0646\u0679 \u06c1\u0648\u06af\u0626\u06cc\u06d4<br \/>\n\u0648\u06c1\u06cc\u06ba \u062f\u0648\u0633\u0631\u06cc \u0628\u0691\u06cc \u06a9\u0645\u067e\u0646\u06cc \u06c1\u0646\u0688\u0626\u06cc \u0645\u0648\u0679\u0631\u0627\u0646\u0688\u06cc\u0627 \u0644\u0645\u06cc\u0679\u06cc\u0688\u06a9\u06cc \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba\u0641\u0631\u0648\u062e\u062a \u06af\u0632\u0634\u062a\u06c1 \u0633\u0627\u0644 \u06a9\u06d2 \u0627\u0633\u06cc \u0645\u0627\u06c1 \u06a9\u06d2 \u06f4\u06f8\u06f7\u06f0\u06f4 \u06a9\u06d2 \u0645\u0642\u0627\u0628\u0644\u06d2 \u0645\u06cc\u06ba \u06f4\u06f2\u0621\u06f1\u060d\u0641\u06cc\u0635\u062f \u06a9\u0645 \u06c1\u0648\u06a9\u0631 \u06f4\u06f8\u06f0\u06f1\u06f0\u06cc\u0648\u0646\u0679 \u0631\u06c1 \u06af\u0626\u06cc\u06d4\u06a9\u0645\u067e\u0646\u06cc \u06a9\u06cc \u0637\u0631\u0641 \u0633\u06d2 \u0627\u0653\u062c \u062c\u0627\u0631\u06cc \u0645\u0627\u06c1\u0627\u0646\u06c1 \u0641\u0631\u0648\u062e\u062a \u06a9\u06d2 \u0627\u0639\u062f\u0627\u062f\u0648\u0634\u0645\u0627\u0631 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06af\u06be\u0631\u06cc\u0644\u0648\u0628\u0627\u0632\u0627\u0631 \u0645\u06cc\u06ba\u0641\u0631\u0648\u062e\u062a \u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u06f6\u06f9\u0621\u06f1\u06f2\u060d\u0641\u06cc\u0635\u062f \u0632\u06cc\u0627\u062f\u06c1 \u0631\u06c1\u06cc \u06cc\u06c1 \u06f2\u06f5\u06f9\u06f6\u06f5\u06a9\u06d2 \u0645\u0642\u0627\u0628\u0644\u06d2 \u06f2\u06f9\u06f2\u06f6\u06f0\u06cc\u0648\u0646\u0679 \u067e\u0631 \u067e\u06c1\u0646\u0686 \u06af\u0626\u06cc \u0644\u06cc\u06a9\u0646 \u0628\u0631\u0627\u0653\u0645\u062f\u0627\u062a \u06f5\u06f4\u0621\u06f1\u06f7\u0641\u06cc\u0635\u062f \u06af\u0631 \u06a9\u0631 \u06f2\u06f2\u06f7\u06f3\u06f9\u0633\u06d2 \u06f1\u06f8\u06f7\u06f5\u06f0\u06cc\u0648\u0646\u0679 \u0631\u06c1\u06cc\u06d4\u062c\u0646\u0631\u0644 \u0645\u0648\u0679\u0631\u0633 \u0627\u0646\u0688\u06cc\u0627 \u06a9\u06cc \u0641\u0631\u0648\u062e\u062a \u0628\u06be\u06cc \u06f3\u06f2\u0621\u06f2\u06f7\u0641\u06cc\u0635\u062f \u06af\u0631 \u06a9\u0631 \u06f6\u06f5\u06f0\u06f3\u06cc\u0648\u0646\u0679 \u06f4\u06f7\u06f2\u06f6\u06cc\u0648\u0646\u0679 \u0631\u06c1\u06cc \u06af\u0626\u06cc\u06d4\u0627\u0633 \u0633\u0627\u0644 \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba \u06a9\u0645\u067e\u0646\u06cc \u0646\u06d2 \u06f1\u06f5\u06f6\u06f3\u0628\u06cc\u0679 \u0645\u0627\u0688\u0644 \u06a9\u06cc \u06a9\u0627\u0631\u06cc\u06ba \u0641\u0631\u0648\u062e\u062a \u06a9\u06cc\u06ba\u06d4 \u062c\u0628 \u06a9\u06c1 \u062a\u0648\u06cc\u0631\u0627\u06a9\u06cc \u062a\u0639\u062f\u0627\u062f \u06f1\u06f2\u06f2\u06f2\u06cc\u0648\u0646\u0679 \u0631\u06c1\u06cc\u06d4\u0634\u06cc\u0648\u0631\u0644\u06d2 \u0627\u0646\u062c\u0648\u0627\u0626\u06d2 \u06a9\u06cc \u0645\u0627\u0646\u06af \u06f8\u06f1\u06f2\u06cc\u0648\u0646\u0679 \u0631\u06c1\u06cc\u06d4\u06a9\u0645\u067e\u0646\u06cc \u06a9\u06d2 \u0646\u0627\u0626\u0628 \u0635\u062f\u0631 \u067e\u06cc \u0628\u0627\u0644\u06cc\u0646\u062f\u0631\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0648\u0646\u0686\u06cc \u0634\u0631\u062d \u0633\u0648\u062f \u0627\u0648\u0631 \u0627\u06cc\u0646\u062f\u06be\u0646 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u0632\u06cc\u0627\u062f\u06c1 \u0631\u06c1\u0646\u06d2 \u0633\u06d2 \u06a9\u0627\u0631\u0628\u0627\u0632\u0627\u0631\u0645\u06cc\u06ba \u062a\u06cc\u0632\u06cc \u0646\u06c1\u06cc\u06ba\u0645\u0644 \u067e\u0627\u0631\u06c1\u06cc \u06c1\u06d2\u06d4 \u0645\u0627\u0646\u0633\u0648\u0646 \u06a9\u06d2 \u06a9\u0645\u0632\u0648\u0631\u0631\u06c1\u0646\u06d2 \u0633\u06d2 \u062f\u06cc\u06c1\u06cc \u0639\u0644\u0627\u0642\u0648\u06ba \u0627\u0648\u0631\u0679\u06cc\u0626\u0631 \u06f2\u0634\u06c1\u0631\u0648\u06ba\u0645\u06cc\u06ba \u0686\u06be\u0648\u0679\u06cc \u06a9\u0627\u0631\u0648\u06ba \u06a9\u06cc \u0645\u0627\u0646\u06af \u06a9\u0645 \u06c1\u06d2 \u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u06a9\u0627\u0631\u0628\u0627\u0632\u0627\u0631 \u06a9\u06cc\u0644\u0626\u06d2 \u0686\u06cc\u0644\u0646\u062c\u0648\u06ba \u0633\u06d2 \u0628\u06be\u0631\u0627\u0648\u0642\u062a \u062a\u06c1\u0648\u0627\u0631\u06cc \u0633\u06cc\u0632\u0646 \u0634\u0631\u0648\u0639 \u06c1\u0648\u0646\u06d2 \u062a\u06a9 \u0628\u0631\u0642\u0631\u0627\u0631 \u0631\u06c1\u06d2 \u06af\u0627\u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc(\u0648\u0627\u0631\u062a\u0627)\u0645\u0644\u06a9 \u06a9\u06cc \u0645\u0634\u06c1\u0648\u0631 \u06a9\u0627\u0631\u06a9\u0645\u067e\u0646\u06cc \u0645\u0627\u0631\u0648\u062a\u06cc \u0633\u0648\u0632\u0648\u06a9\u06cc \u0627\u0646\u0688\u06cc\u0627 \u0644\u0645\u06cc\u0679\u06cc\u0688\u06a9\u06cc \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba\u06a9\u0644 \u0641\u0631\u0648\u062e\u062a \u06f7\u0621\u06f1\u060d\u0641\u06cc\u0635\u062f \u06a9\u06cc \u062a\u06cc\u0632\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0627\u06cc\u06a9 \u0644\u0627\u06a9\u06be \u06a9\u0648 \u067e\u0627\u0631\u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u06cc\u06a9 \u0644\u0627\u06a9\u06be \u0627\u06cc\u06a9 \u06c1\u0632\u0627\u0631 \u06f3\u06f8\u06f0\u06cc\u0648\u0646\u0679 \u067e\u0631 \u067e\u06c1\u0646\u0686 \u06af\u0626\u06cc \u06a9\u0645\u067e\u0646\u06cc \u0646\u06d2 \u0627\u0653\u062c \u0645\u0627\u06c1\u0627\u0646\u06c1 \u0641\u0631\u0648\u062e\u062a \u06a9\u06d2 \u0627\u0639\u062f\u0627\u062f\u0648\u0634\u0645\u0627\u0631 \u062c\u0627\u0631\u06cc \u06a9\u0626\u06d2\u06d4\u06af\u0632\u0634\u062a\u06c1 \u0633\u0627\u0644 \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba \u06a9\u0645\u067e\u0646\u06cc \u0646\u06d2 \u06f8\u06f3\u06c1\u0632\u0627\u0631\u06f2\u06f9\u06f9\u06a9\u0627\u0631\u06cc\u06ba \u0641\u0631\u0648\u062e\u062a \u06a9\u06cc\u06ba \u062a\u06be\u06cc\u06ba \u0645\u0627\u0631\u0648\u062a\u06cc \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u062c\u0648\u0644\u0627\u0626\u06cc \u0645\u06cc\u06ba \u06af\u06be\u0631\u06cc\u0644\u0648 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,30],"tags":[],"class_list":["post-23694","post","type-post","status-publish","format-standard","category-business","category-business-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/23694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=23694"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/23694\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=23694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=23694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=23694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}