{"id":25406,"date":"2014-08-22T15:50:39","date_gmt":"2014-08-22T10:20:39","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=25406"},"modified":"2014-08-22T15:50:39","modified_gmt":"2014-08-22T10:20:39","slug":"%d8%a8%db%8c-%d8%ac%db%92-%d9%be%db%8c%d8%8c-%d8%b3%d9%86%da%af%da%be-%da%a9%db%92-%d8%b3%d8%a7%d8%aa%da%be-%d9%85%d9%84-%da%a9%d8%b1-%d8%b3%d8%a7%d8%b2%d8%b4-%da%a9%d8%b1%d8%b1%db%81%db%8c-%db%81","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%a8%db%8c-%d8%ac%db%92-%d9%be%db%8c%d8%8c-%d8%b3%d9%86%da%af%da%be-%da%a9%db%92-%d8%b3%d8%a7%d8%aa%da%be-%d9%85%d9%84-%da%a9%d8%b1-%d8%b3%d8%a7%d8%b2%d8%b4-%da%a9%d8%b1%d8%b1%db%81%db%8c-%db%81\/","title":{"rendered":"\u0628\u06cc \u062c\u06d2 \u067e\u06cc\u060c \u0633\u0646\u06af\u06be \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u0644 \u06a9\u0631 \u0633\u0627\u0632\u0634 \u06a9\u0631\u0631\u06c1\u06cc \u06c1\u06d2 \u0628\u06cc \u0627\u06cc\u0633 \u067e\u06cc"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-19725\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/06\/Rajendra-Chaudhary.jpg\" alt=\"-Rajendra-Chaudhary\" width=\"169\" height=\"149\" \/>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u0633\u0645\u0627\u062c\u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u0646\u06d2 \u0627\u0653\u062c \u06a9\u06c1\u0627\u06a9\u06c1 \u0631\u06cc\u0627\u0633\u062a\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0634\u0631\u0648\u0639 \u0633\u06d2 \u06c1\u06cc \u0627\u0653\u0631 \u0627\u06cc\u0633 \u0627\u06cc\u0633 \u0627\u0648\u0631 \u0628\u06cc \u062c\u06d2 \u067e\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u0644 \u06a9\u0631 \u0628\u06cc \u0627\u06cc\u0633 \u067e\u06cc \u0645\u0646\u0638\u0645 \u0637\u0648\u0631 \u067e\u0631 \u06cc\u06c1 \u06a9\u0627\u0645 \u06a9\u0631 \u0631\u06c1\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0645\u062e\u0627\u0644\u0641 \u062a\u0634\u06c1\u06cc\u0631 \u06a9\u0648 \u06c1\u0648\u0627 \u062f\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u06c1\u06d2\u06d4 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0631\u06cc\u0627\u0633\u062a\u06cc \u062a\u0631\u062c\u0645\u0627\u0646 \u0631\u0627\u062c\u0646\u062f\u0631 \u0686\u0648\u062f\u06be\u0631\u06cc \u0646\u06d2 \u0627\u0653\u062c \u062c\u0627\u0631\u06cc \u0627\u06cc\u06a9 \u0628\u06cc\u0627\u0646 \u0645\u06cc\u06ba \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0646 \u067e\u0627\u0631\u0679\u06cc\u0648\u06ba \u0646\u06d2 \u0627\u0628\u06be\u06cc \u06af\u0632\u0634\u062a\u06c1 \u062f\u0646\u0648\u06ba \u0628\u062f\u0627\u06cc\u0648\u06ba \u0645\u06cc\u06ba \u062f\u0648 \u0644\u0691\u06a9\u06cc\u0648\u06ba\u06a9\u06cc \u0645\u0648\u062a \u06a9\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u06a9\u0648 \u062a\u0634\u06c1\u06cc\u0631 \u06a9\u0631 \u06a9\u06d2 \u063a\u06cc\u0631 \u0645\u0644\u06a9\u0648\u06ba \u0645\u06cc\u06ba \u0628\u062f\u0646\u0627\u0645\u06cc \u06a9\u0631\u0627\u0626\u06cc\u06d4<br \/>\n\u0628\u062f\u0627\u06cc\u0648\u06ba \u06a9\u06d2 \u06a9\u0679\u0631\u0627 \u0633\u0639\u0627\u062f\u062a \u06af\u0646\u062c \u0648\u0627\u0631\u062f\u0627\u062a \u0645\u06cc\u06ba \u0644\u0691\u06a9\u06cc\u0648\u06ba \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0627\u0653\u0628\u0631\u0648\u0631\u06cc\u0632\u06cc \u06a9\u06cc \u062a\u0635\u062f\u06cc\u0642 \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u0626\u06cc \u062c\u0628\u06a9\u06c1 \u0633\u0627\u0628\u0642 \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u0645\u0627\u06cc\u0627\u0648\u062a\u06cc\u060c \u0645\u0631\u06a9\u0632\u06cc \u0648\u0632\u06cc\u0631 \u0631\u0627\u0645 \u0648\u0644\u0627\u0633 \u067e\u0627\u0633\u0648\u0627\u0646\u060c \u0633\u0627\u0628\u0642 \u0644\u0648\u06a9 \u0633\u0628\u06be\u0627 \u0627\u0633\u067e\u06cc\u06a9\u0631 \u0645\u06cc\u0631\u0627 \u06a9\u0645\u0627\u0631 \u0627\u0648\u0631 \u06a9\u0627\u0646\u06af\u0631\u06cc\u0633 \u06a9\u06d2 \u0646\u0627\u0626\u0628 \u0635\u062f\u0631 \u0631\u0627\u06c1\u0644 \u06af\u0627\u0646\u062f\u06be\u06cc \u0646\u06d2 \u0648\u06c1\u0627\u06ba \u062c\u0627\u06a9\u0631 \u0627\u0633 \u0648\u0627\u0631\u062f\u0627\u062a \u0645\u06cc\u06ba \u0631\u06cc\u0627\u0633\u062a\u06cc \u062d\u06a9\u0648\u0645\u062a \u067e\u0631 \u062a\u0645\u0627\u0645 \u0627\u0644\u0632\u0627\u0645\u0627\u062a \u0639\u0627\u0626\u062f \u06a9\u0626\u06d2 \u062a\u06be\u06d2\u06d4 \u0627\u0646 \u062a\u0645\u0627\u0645 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0627\u0628 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u062c\u06be\u0648\u0679\u06d2 \u0627\u0644\u0632\u0627\u0645 \u0639\u0627\u0626\u062f \u06a9\u0631\u0646\u06d2 \u06a9\u06cc\u0644\u0626\u06d2 \u0645\u0639\u0627\u0641\u06cc \u0645\u0627\u0646\u06af\u0646\u06cc \u0686\u0627\u06c1\u0626\u06d2\u06d4 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u06a9\u06c1\u0627\u06a9\u06c1 \u06a9\u0627\u0646\u0679\u06be (\u0645\u0631\u0627\u062f\u0627\u0653\u0628\u0627\u062f) \u060c \u0645\u06cc\u0631\u0679\u06be\u060c \u0633\u06c1\u0627\u0631\u0646\u067e\u0648\u0631 \u06a9\u06cc \u0648\u0627\u0631\u062f\u0627\u062a\u0648\u06ba\u06a9\u0648 \u0628\u06be\u06cc \u0628\u0691\u06be\u0627 \u0686\u0691\u06be\u0627\u06a9\u0631 \u067e\u06cc\u0634 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u0644\u06cc\u06a9\u0646 \u062f\u06be\u06cc\u0631\u06d2 \u062f\u06be\u06cc\u0631\u06d2 \u063a\u0644\u0637 \u062a\u0634\u06c1\u06cc\u0631 \u06a9\u06cc \u0642\u0644\u0639\u06cc \u06a9\u06be\u0644\u0646\u06d2 \u0644\u06af\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0628\u062f\u0646\u0627\u0645 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u0648\u06ba \u06a9\u06d2 \u0686\u06c1\u0631\u0648\u06ba \u067e\u0631 \u062e\u0648\u062f \u06c1\u06cc \u06a9\u0627\u0644\u06a9\u06be \u0644\u06af\u0646\u06d2 \u0644\u06af\u06cc \u06c1\u06d2\u06d4 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u062a\u0631\u062c\u0645\u0627\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u0627\u06a9\u06be\u0644\u06cc\u0634 \u06cc\u0627\u062f\u0648<br \/>\n\u0646\u06d2 \u062d\u0644\u0641 \u0644\u06cc\u062a\u06d2 \u06c1\u06cc \u0631\u06cc\u0627\u0633\u062a \u06a9\u06cc \u062a\u0631\u0642\u06cc \u06a9\u0627 \u0639\u06c1\u062f \u0644\u06cc\u0627 \u062a\u06be\u0627\u06d4<br \/>\n\u0632\u0631\u0627\u0639\u062a \u0627\u0648\u0631 \u0635\u0646\u0639\u062a \u06a9\u06cc \u0641\u0631\u0627\u06c1\u0645\u06cc \u06a9\u06cc \u062a\u0641\u0635\u06cc\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0645\u0627\u062c \u06a9\u06d2 \u06c1\u0631 \u0637\u0628\u0642\u06c1 \u06a9\u06d2 \u0645\u0641\u0627\u062f\u06a9\u06cc \u0627\u0633\u06a9\u06cc\u0645\u0648\u06ba \u06a9\u0648 \u0639\u0645\u0644 \u0645\u06cc\u06ba \u0644\u0627\u06a9\u0631 \u0648\u0632\u06cc\u0631 \u0627\u0639\u0644\u06cc\u0670 \u0646\u06d2 \u0631\u06cc\u0627\u0633\u062a \u06a9\u0648 \u0628\u062f\u062d\u0627\u0644\u06cc \u0633\u06d2 \u0627\u0628\u0627\u0631\u0646\u06d2 \u06a9\u06cc \u0628\u06be\u0631\u067e\u0648\u0631\u06a9\u0648\u0634\u0634 \u06a9\u06cc \u06c1\u06d2\u06d4 \u062f\u06c1\u0627\u0626\u06cc\u0648\u06ba \u062a\u06a9 \u06a9\u0627\u0646\u06af\u0631\u06cc\u0633\u060c \u0628\u06cc \u062c\u06d2 \u067e\u06cc \u0627\u0648\u0631 \u0628\u06cc \u0627\u06cc\u0633 \u067e\u06cc \u06a9\u06d2 \u062f\u0648\u0631 \u0627\u0642\u062a\u062f\u0627\u0631 \u0645\u06cc\u06ba \u0631\u06cc\u0627\u0633\u062a \u0628\u06cc\u0645\u0627\u0631 \u0627\u0648\u0631 \u067e\u0633\u0645\u0627\u0646\u062f\u06c1 \u0631\u06cc\u0627\u0633\u062a \u0628\u0646\u06cc \u0631\u06c1\u06cc\u06d4 \u06cc\u06c1 \u067e\u0627\u0631\u0679\u06cc\u0627\u06ba \u0646\u06c1\u06cc\u06ba \u0686\u0627\u06c1\u062a\u06cc \u06c1\u06cc\u06ba \u06a9\u06c1 \u0627\u062a\u0631\u067e\u0631\u062f\u06cc\u0634 \u06a9\u0627 \u0634\u0645\u0627\u0631 \u0627\u062a\u0645 \u067e\u0631\u062f\u06cc\u0634 \u0645\u06cc\u06ba \u06c1\u0648\u06d4 \u0627\u0633\u06cc \u0644\u0626\u06d2 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06cc \u062a\u0631\u0642\u06cc \u06a9\u06d2 \u0631\u0627\u0633\u062a\u06d2 \u0645\u06cc\u06ba \u0631\u0648\u0691\u0627 \u0627\u0679\u06a9\u0627\u0646\u06d2 \u06a9\u06cc \u0633\u0627\u0632\u0634\u06cc\u06ba \u06a9\u0631 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4 \u0633\u06c1\u0627\u0631\u0646\u067e\u0648\u0631 \u0645\u06cc\u06ba \u06c1\u0648\u0626\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u06a9\u06cc \u062c\u0627\u0646\u0686 \u0631\u067e\u0648\u0631\u0679 \u0633\u06d2 \u0628\u06be\u06cc \u067e\u062a\u06c1 \u0686\u0644\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1\u0627\u06ba \u0628\u06cc \u062c\u06d2 \u067e\u06cc \u0648\u0627\u0644\u0648\u06ba \u0646\u06d2 \u06c1\u06cc \u0641\u0633\u0627\u062f \u06a9\u0631\u0627\u06cc\u0627 \u062a\u06be\u0627\u06d4<br \/>\n\u06a9\u0627\u0646\u0679\u06be \u0645\u06cc\u06ba \u0644\u0627\u0648\u0654\u0688 \u0627\u0633\u067e\u06cc\u06a9\u0631 \u06a9\u0648 \u0644\u06cc\u06a9\u0631 \u062a\u0646\u0627\u0648\u0654 \u067e\u06cc\u062f\u0627 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u0627\u0648\u0631 \u062c\u06c1\u0627\u06ba\u0628\u06be\u06cc \u0644\u0648\u06af \u0627\u0653\u067e\u0633\u06cc \u062e\u06cc\u0631 \u0633\u06af\u0627\u0644\u06cc \u06a9\u06d2 \u062c\u0630\u0628\u06c1 \u0633\u06d2 \u0631\u06c1\u062a\u06d2 \u062a\u06be\u06d2 \u0628\u06cc \u062c\u06d2 \u067e\u06cc\u060c \u0627\u0653\u0631\u0627\u06cc\u0633 \u0627\u06cc\u0633 \u0648\u06c1\u0627\u06ba \u0641\u0631\u0642\u06c1 \u0648\u0627\u0631\u0627\u0646\u06c1 \u0645\u0646\u0627\u0641\u0631\u062a \u067e\u06be\u06cc\u0644\u0627\u06a9\u0631 \u062e\u06cc\u0631 \u0633\u06af\u0627\u0644\u06cc \u06a9\u06d2 \u062c\u0630\u0628\u06c1 \u06a9\u0648 \u062a\u0648\u0691\u0646\u06d2 \u06a9\u06cc \u0633\u0627\u0632\u0634\u06cc\u06ba \u06a9\u0631\u062a\u06d2 \u067e\u0627\u0626\u06cc \u06af\u0626\u06cc \u06c1\u06cc\u06ba\u06d4<\/p>\n<p style=\"text-align: right;\">\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u0633\u0645\u0627\u062c\u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u0646\u06d2 \u0627\u0653\u062c \u06a9\u06c1\u0627\u06a9\u06c1 \u0631\u06cc\u0627\u0633\u062a\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0634\u0631\u0648\u0639 \u0633\u06d2 \u06c1\u06cc \u0627\u0653\u0631 \u0627\u06cc\u0633 \u0627\u06cc\u0633 \u0627\u0648\u0631 \u0628\u06cc \u062c\u06d2 \u067e\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u0644 \u06a9\u0631 \u0628\u06cc \u0627\u06cc\u0633 \u067e\u06cc \u0645\u0646\u0638\u0645 \u0637\u0648\u0631 \u067e\u0631 \u06cc\u06c1 \u06a9\u0627\u0645 \u06a9\u0631 \u0631\u06c1\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0645\u062e\u0627\u0644\u0641 \u062a\u0634\u06c1\u06cc\u0631 \u06a9\u0648 \u06c1\u0648\u0627 \u062f\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u06c1\u06d2\u06d4 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0631\u06cc\u0627\u0633\u062a\u06cc \u062a\u0631\u062c\u0645\u0627\u0646 \u0631\u0627\u062c\u0646\u062f\u0631 \u0686\u0648\u062f\u06be\u0631\u06cc \u0646\u06d2 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,28],"tags":[],"class_list":["post-25406","post","type-post","status-publish","format-standard","category-lucknow","category-lucknow-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/25406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=25406"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/25406\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=25406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=25406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=25406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}