{"id":26229,"date":"2014-08-29T15:31:34","date_gmt":"2014-08-29T10:01:34","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=26229"},"modified":"2014-08-29T15:31:34","modified_gmt":"2014-08-29T10:01:34","slug":"%da%af%d8%a6%d9%88-%da%a9%d8%b4%db%8c-%da%a9%db%8c-%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d9%be%d8%b1-%da%a9%d8%b4%db%8c%d8%af-%da%af%db%8c-%d8%8c-%d8%aa%db%8c%d9%86-%d9%85%d8%b4%d8%aa%d8%a8%db%81","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%da%af%d8%a6%d9%88-%da%a9%d8%b4%db%8c-%da%a9%db%8c-%d9%88%d8%a7%d8%b1%d8%af%d8%a7%d8%aa-%d9%be%d8%b1-%da%a9%d8%b4%db%8c%d8%af-%da%af%db%8c-%d8%8c-%d8%aa%db%8c%d9%86-%d9%85%d8%b4%d8%aa%d8%a8%db%81\/","title":{"rendered":"\u06af\u0626\u0648 \u06a9\u0634\u06cc \u06a9\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u067e\u0631 \u06a9\u0634\u06cc\u062f \u06af\u06cc \u060c \u062a\u06cc\u0646 \u0645\u0634\u062a\u0628\u06c1 \u0627\u0641\u0631\u0627\u062f \u062d\u0631\u0627\u0633\u062a \u0645\u06cc\u06ba"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8523\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/02\/arest2.jpg\" alt=\"arest2\" width=\"259\" height=\"194\" \/>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u0645\u0644\u06cc\u062d \u0627\u0653\u0628\u0627\u062f \u06a9\u06d2 \u0633\u0646\u062f\u06be\u0631\u0648\u0627 \u06af\u0627\u0648\u0654\u06ba \u0645\u06cc\u06ba \u06af\u0626\u0648 \u06a9\u0634\u06cc \u06a9\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u06a9\u0648 \u0644\u06cc\u06a9\u0631 \u0627\u0653\u062c \u06af\u0627\u0648\u0654\u06ba \u0645\u06cc\u06ba \u06a9\u0634\u06cc\u062f\u06af\u06cc \u067e\u06cc\u062f\u0627 \u06c1\u0648 \u06af\u0626\u06cc\u06d4\u0627\u0633 \u0648\u0627\u0631\u062f\u0627\u062a \u0633\u06d2 \u0646\u0627\u0631\u0627\u0636 \u0644\u0648\u06af\u0648\u06ba \u0646\u06d2 \u0639\u0644\u0627\u0642\u06c1 \u06a9\u06cc \u062f\u06a9\u0627\u0646\u06cc\u06ba \u0628\u0646\u062f \u06a9\u0631\u062f\u06cc\u06ba \u0627\u0648\u0631 \u0645\u0644\u06cc\u062d \u0627\u0653\u0628\u0627\u062f \u062a\u06be\u0627\u0646\u06c1 \u06a9\u0627 \u06af\u06be\u06cc\u0631\u0627\u0648\u0654 \u0628\u06be<br \/>\n\u06cc \u06a9\u06cc\u0627\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0627\u0633 \u0645\u0639\u0627\u0645\u0644\u06c1 \u0645\u06cc\u06ba \u062a\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u06a9\u0648 \u062d\u0631\u0627\u0633\u062a \u0645\u06cc\u06ba \u0628\u06be\u06cc \u0644\u06cc\u0627\u06c1\u06d2\u06d4 \u06a9\u0634\u06cc\u062f\u06af\u06cc \u06a9\u06d2 \u067e\u06cc\u0634 \u0646\u0638\u0631 \u0639\u0644\u0627\u0642\u06c1 \u0645\u06cc\u06ba \u067e\u0648\u0644\u06cc\u0633 \u0641\u0648\u0631\u0633 \u062a\u0639\u06cc\u0646\u0627\u062a \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4<br \/>\n\u0627\u06cc\u0633 \u067e\u06cc \u062f\u06cc\u06c1\u0627\u062a \u062d\u0628\u06cc\u0628 \u0627\u0644\u062d\u0633\u0646 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0633\u0646\u062f\u06be\u0631\u0648\u0627 \u06af\u0627\u0648\u0654\u06ba\u0645\u06cc\u06ba\u0648\u0627\u0642\u0639 \u06a9\u06a9\u06c1\u0631\u06cc\u0627\u06ba \u062a\u0627\u0644\u0627\u0628 \u06a9\u06d2 \u0646\u0632\u062f\u06cc\u06a9 \u0627\u0653\u062c \u0635\u0628\u062d \u06a9\u0686\u06be \u0628\u0686\u06d2 \u0631\u0641\u0639 \u062d\u0627\u062c\u062a \u06a9\u06cc\u0644\u0626\u06d2 \u06af\u0626\u06d2 \u062a\u06be\u06d2\u06d4 \u0628\u0686\u0648\u06ba \u06a9\u0648 \u0627\u06cc\u06a9 \u06af\u0627\u0626\u06d2 \u06a9\u0627 \u06a9\u0679\u0627 \u06c1\u0648\u0627 \u0633\u0631 \u062a\u0627\u0644\u0627\u0628 \u06a9\u06d2 \u0646\u0632\u062f\u06cc\u06a9 \u0627\u0648\u0631 \u0686\u0627\u0631 \u0633\u0631 \u062a\u0627\u0644\u0627\u0628 \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u062f\u06a9\u06be\u0627\u0626\u06cc \u062f\u06cc\u0626\u06d2\u06d4 \u0628\u0686\u0648\u06ba \u0646\u06d2 \u0627\u0633 \u0628\u0627\u062a \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u06af\u0627\u0648\u0654\u06ba \u0648\u0627\u0644\u0648\u06ba \u06a9\u0648 \u062f\u06cc \u062a\u0648 \u06af\u0627\u0648\u0654\u06ba \u0648\u0627\u0644\u06d2 \u062a\u0627\u0644\u0627\u0628 \u06a9\u06d2 \u0646\u0632\u062f\u06cc\u06a9 \u062c\u0645\u0639 \u06c1\u0648 \u06af\u0626\u06d2\u06d4 \u06af\u0626\u0648 \u06a9\u0634\u06cc \u06a9\u06cc \u0627\u0637\u0644\u0627\u0639 \u067e\u0648\u0631\u06d2 \u0639\u0644\u0627\u0642\u06c1 \u0645\u06cc\u06ba \u0627\u0653\u06af \u06a9\u06cc \u0637\u0631\u062d \u067e\u06be\u06cc\u0644 \u06af\u0626\u06cc \u0644\u0648\u06af \u06af\u06be\u0631\u0648\u06ba \u0633\u06d2 \u0628\u0627\u06c1\u0631 \u0646\u06a9\u0644 \u0627\u0653\u0626\u06d2\u06d4 \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u062a\u06d2 \u06c1\u06cc \u0645\u0648\u0642\u0639 \u067e\u0631 \u0645\u0644\u06cc\u062d \u0627\u0653\u0628\u0627\u062f \u067e\u0648\u0644\u06cc\u0633 \u0628\u06be\u06cc \u067e\u06c1\u0646\u0686 \u06af\u0626\u06cc\u06d4 \u062a\u0641\u062a\u06cc\u0634 \u06a9\u06d2 \u0628\u0639\u062f \u062a\u0627\u0644\u0627\u0628 \u0633\u06d2 \u06a9\u0686\u06be \u0641\u0627\u0635\u0644\u06c1 \u067e\u0631 \u0645\u0642\u0635\u0648\u062f \u06a9\u06d2 \u06a9\u06be\u06cc\u062a \u0645\u06cc\u06ba \u0628\u0646\u06d2 \u0679\u06cc\u0646 \u0634\u06cc\u0688 \u0645\u06cc\u06ba \u0645\u0648\u06cc\u0634\u06cc\u0648\u06ba \u06a9\u06d2 \u0628\u0627\u0642\u06cc\u0627\u062a \u067e\u0691\u06d2 \u06c1\u0648\u0626\u06d2 \u0648\u0627\u0631\u062f\u0627\u062a \u06a9\u06d2 \u0628\u0639\u062f \u067e\u0648\u0631\u06d2 \u0639\u0644\u0627\u0642\u06c1 \u0645\u06cc\u06ba \u06a9\u0634\u06cc\u062f\u06af\u06cc \u067e\u06cc\u062f\u0627 \u06c1\u0648\u06af\u0626\u06cc\u06d4<br \/>\n\u0633\u06cc\u06a9\u0691\u0648\u06ba \u06a9\u06cc \u062a\u0639\u062f\u0627\u062f \u0645\u06cc\u06ba \u06af\u0627\u0648\u0654\u06ba \u0648\u0627\u0644\u06d2 \u0645\u0644\u06cc\u062d \u0627\u0653\u0628\u0627\u062f \u062a\u06be\u0627\u0646\u06c1 \u067e\u06c1\u0646\u0686 \u0627\u0648\u0631 \u062a\u06be\u0627\u0646\u06c1 \u06a9\u0627 \u06af\u06be\u06cc\u0631\u0627\u0648\u0654 \u06a9\u06cc\u0627\u060c \u0648\u06c1\u06cc\u06ba \u06a9\u0634\u06cc\u062f\u06af\u06cc \u06a9\u06d2 \u067e\u06cc\u0634 \u0646\u0638\u0631 \u0639\u0644\u0627\u0642\u06c1 \u06a9\u06cc \u0633\u0628\u06be\u06cc \u062f\u06a9\u0627\u0646\u06cc\u06ba \u0628\u06be\u06cc \u0628\u0646\u062f \u06a9\u0631 \u062f\u06cc \u06af\u0626\u06cc\u06ba\u06d4 \u0627\u0637\u0644\u0627\u0639 \u0645\u0644\u0646\u06d2 \u067e\u0631 \u0627\u06cc\u0633 \u067e\u06cc \u062f\u06cc\u06c1\u0627\u062a \u060c \u0633\u06cc \u0627\u0648 \u0645\u0644\u06cc\u062d \u0627\u0653\u0628\u0627\u062f \u0627\u0648\u0631 \u0627\u0646\u062a\u0638\u0627\u0645\u06cc\u06c1 \u06a9\u06d2 \u0627\u0641\u0633\u0631 \u0628\u06be\u06cc \u067e\u06c1\u0646\u0686 \u06af\u0626\u06d2\u06d4 \u0645\u0638\u0627\u06c1\u0631\u06cc\u0646 \u0645\u0644\u0632\u0645\u0627\u0646 \u06a9\u06cc \u06af\u0631\u0641\u062a\u0627\u0631\u06cc \u06a9\u0627 \u0645\u0637\u0627\u0644\u0628\u06c1 \u06a9\u0631 \u0631\u06c1\u06d2 \u062a\u06be\u06d2\u06d4<br \/>\n\u067e\u0648\u0644\u06cc\u0633 \u0627\u0648\u0631 \u0627\u0646\u062a\u0638\u0627\u0645\u06cc\u06c1 \u06a9\u06d2 \u0627\u0641\u0633\u0631\u0627\u0646 \u0646\u06d2 \u062c\u0644\u062f \u06a9\u0627\u0631\u0631\u0648\u0627\u0626\u06cc \u06a9\u06cc \u06cc\u0642\u06cc\u0646 \u062f\u06c1\u0627\u0646\u06cc \u06a9\u0631\u0627\u06a9\u0631 \u06a9\u0633\u06cc \u0637\u0631\u062d \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u062e\u0627\u0645\u0648\u0634 \u06a9\u0631\u0627\u06cc\u0627\u06d4 \u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u0644\u06cc\u062d \u0627\u0653\u0628\u0627\u062f \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0645\u0642\u0635\u0648\u062f\u060c \u0634\u0627\u062f\u0627\u0628 \u0627\u0648\u0631 \u0639\u0627\u0644\u0645 \u0646\u0627\u0645 \u06a9\u06d2 \u062a\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u06a9\u0648 \u067e\u0648\u0686\u06be \u06af\u0686\u06be \u06a9\u06cc\u0644\u0626\u06d2 \u062d\u0631\u0627\u0633\u062a \u0645\u06cc\u06ba \u0644\u06d2 \u0644\u06cc\u0627 \u06c1\u06d2\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0627\u0641\u0633\u0631\u0627\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06af\u0627\u0648\u0654\u06ba \u0645\u06cc\u06ba \u0645\u0627\u062d\u0648\u0644 \u062e\u0631\u0627\u0628 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc\u0644\u0626\u06d2 \u06a9\u0633\u06cc \u0646\u06d2 \u0627\u0633 \u0637\u0631\u062d \u06a9\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u0627\u0646\u062c\u0627\u0645 \u062f\u06cc \u06c1\u06d2\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0645\u0644\u0632\u0645\u0627\u0646 \u06a9\u06cc \u0646\u0634\u0627\u0646\u062f\u06c1\u06cc \u06a9\u0631 \u0631\u06c1\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0633\u0628\u06be\u06cc \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u06a9\u0627\u0631\u0631\u0648\u0627\u0626\u06cc \u06a9\u06cc \u062c\u0627\u0626\u06d2 \u06af\u06cc\u06d4 \u0648\u06c1\u06cc\u06ba \u06af\u0627\u0648\u0654\u06ba \u0645\u06cc\u06ba \u06a9\u0634\u06cc\u062f\u06af\u06cc \u06a9\u0648 \u062f\u06cc\u06a9\u06be\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u067e\u0648\u0644\u06cc\u0633 \u0641\u0648\u0631\u0633 \u06a9\u0648 \u0628\u06be\u06cc \u062a\u0639\u06cc\u0646\u0627\u062a \u06a9\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4<\/p>\n<p style=\"text-align: right;\">\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4 (\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u0645\u0644\u06cc\u062d \u0627\u0653\u0628\u0627\u062f \u06a9\u06d2 \u0633\u0646\u062f\u06be\u0631\u0648\u0627 \u06af\u0627\u0648\u0654\u06ba \u0645\u06cc\u06ba \u06af\u0626\u0648 \u06a9\u0634\u06cc \u06a9\u06cc \u0648\u0627\u0631\u062f\u0627\u062a \u06a9\u0648 \u0644\u06cc\u06a9\u0631 \u0627\u0653\u062c \u06af\u0627\u0648\u0654\u06ba \u0645\u06cc\u06ba \u06a9\u0634\u06cc\u062f\u06af\u06cc \u067e\u06cc\u062f\u0627 \u06c1\u0648 \u06af\u0626\u06cc\u06d4\u0627\u0633 \u0648\u0627\u0631\u062f\u0627\u062a \u0633\u06d2 \u0646\u0627\u0631\u0627\u0636 \u0644\u0648\u06af\u0648\u06ba \u0646\u06d2 \u0639\u0644\u0627\u0642\u06c1 \u06a9\u06cc \u062f\u06a9\u0627\u0646\u06cc\u06ba \u0628\u0646\u062f \u06a9\u0631\u062f\u06cc\u06ba \u0627\u0648\u0631 \u0645\u0644\u06cc\u062d \u0627\u0653\u0628\u0627\u062f \u062a\u06be\u0627\u0646\u06c1 \u06a9\u0627 \u06af\u06be\u06cc\u0631\u0627\u0648\u0654 \u0628\u06be \u06cc \u06a9\u06cc\u0627\u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0627\u0633 \u0645\u0639\u0627\u0645\u0644\u06c1 \u0645\u06cc\u06ba \u062a\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u06a9\u0648 \u062d\u0631\u0627\u0633\u062a \u0645\u06cc\u06ba \u0628\u06be\u06cc \u0644\u06cc\u0627\u06c1\u06d2\u06d4 \u06a9\u0634\u06cc\u062f\u06af\u06cc \u06a9\u06d2 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,28],"tags":[],"class_list":["post-26229","post","type-post","status-publish","format-standard","category-lucknow","category-lucknow-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/26229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=26229"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/26229\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=26229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=26229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=26229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}