{"id":26903,"date":"2014-09-05T17:19:03","date_gmt":"2014-09-05T11:49:03","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=26903"},"modified":"2014-09-05T17:19:03","modified_gmt":"2014-09-05T11:49:03","slug":"%d8%b1%d9%88%d8%b6%db%81-%d8%b1%d8%b3%d9%88%d9%84-%da%a9%db%8c-%d9%85%d9%86%d8%aa%d9%82%d9%84%db%8c-%da%a9%db%8c-%d8%a7%d9%81%d9%88%d8%a7%db%81-%d8%aa%d9%86%d8%a7%d8%b2%d8%b9-%d9%be%da%be%db%8c%d9%84","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%b1%d9%88%d8%b6%db%81-%d8%b1%d8%b3%d9%88%d9%84-%da%a9%db%8c-%d9%85%d9%86%d8%aa%d9%82%d9%84%db%8c-%da%a9%db%8c-%d8%a7%d9%81%d9%88%d8%a7%db%81-%d8%aa%d9%86%d8%a7%d8%b2%d8%b9-%d9%be%da%be%db%8c%d9%84\/","title":{"rendered":"\u0631\u0648\u0636\u06c1 \u0631\u0633\u0648\u0644 \u06a9\u06cc \u0645\u0646\u062a\u0642\u0644\u06cc \u06a9\u06cc \u0627\u0641\u0648\u0627\u06c1 \u062a\u0646\u0627\u0632\u0639 \u067e\u06be\u06cc\u0644\u0627 \u0646\u06d2 \u06a9\u06cc \u06a9\u0648\u0634\u0634"},"content":{"rendered":"<p style=\"text-align: right;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-26904\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/09\/9f68b59d-db6c-4acd-9ea8-41b6c093d011_16x9_600x338.jpg\" alt=\"9f68b59d-db6c-4acd-9ea8-41b6c093d011_16x9_600x338\" width=\"332\" height=\"187\" srcset=\"https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/09\/9f68b59d-db6c-4acd-9ea8-41b6c093d011_16x9_600x338.jpg 600w, https:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/09\/9f68b59d-db6c-4acd-9ea8-41b6c093d011_16x9_600x338-300x169.jpg 300w\" sizes=\"auto, (max-width: 332px) 100vw, 332px\" \/>\u0627\u0644\u062d\u0631\u0645\u06cc\u0646 \u0627\u0644\u0634\u0631\u06cc\u0641\u06cc\u0646 \u06a9\u06d2 \u0646\u06af\u0631\u0627\u0646 \u0627\u062f\u0627\u0631\u06d2 \u06a9\u06cc &#8216;\u0627\u0644\u0639\u0631\u0628\u06cc\u06c1&#8217; \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u0648\u0636\u0627\u062d\u062a<\/strong><\/p>\n<p style=\"text-align: right;\"><strong>\u063a\u06cc\u0631 \u0645\u0644\u06a9\u06cc \u0627\u062e\u0628\u0627\u0631\u0627\u062a \u0645\u06cc\u06ba \u0645\u0631\u0642\u062f \u0631\u0633\u0648\u0644 \u0627\u0648\u0631 \u062d\u064f\u062c\u0631\u06c1 \u0646\u0628\u06cc \u0635\u0644\u06cc \u0627\u0644\u0644\u06c1 \u0639\u0644\u06cc\u06c1 \u0648\u0633\u0644\u0645 \u06a9\u06cc \u0645\u062a\u0628\u0627\u062f\u0644 \u0645\u0642\u0627\u0645 \u067e\u0631 \u0645\u0646\u062a\u0642\u0644\u06cc \u06a9\u06cc \u0627\u0641\u0648\u0627\u06c1\u0648\u06ba \u06a9\u06d2 \u0628\u0639\u062f \u0627\u0644<br \/>\n\u062d\u0631\u0645\u06cc\u0646 \u0627\u0644\u0634\u0631\u06cc\u0641\u06cc\u0646 \u06a9\u06d2 \u0646\u06af\u0631\u0627\u0646 \u0627\u062f\u0627\u0631\u06d2 \u0646\u06d2 \u062f\u0648 \u0679\u0648\u06a9 \u0627\u0644\u0641\u0627\u0638 \u0645\u06cc\u06ba \u0627\u0646 \u062e\u0628\u0631\u0648\u06ba \u06a9\u06cc \u062a\u0631\u062f\u06cc\u062f \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0642\u0628\u0631 \u0631\u0633\u0648\u0644 \u06a9\u06cc \u0645\u0646\u062a\u0642\u0644\u06cc \u06a9\u0627 \u06a9\u0648\u0626\u06cc \u0641\u06cc\u0635\u0644\u06c1 \u06c1\u0648\u0627 \u0627\u0648\u0631 \u0646\u06c1 \u06c1\u06cc \u0627\u06cc\u0633\u0627 \u06c1\u0648 \u06af\u0627\u06d4 \u06cc\u06c1 \u0627\u06cc\u06a9 \u0634\u062e\u0635 \u06a9\u06cc \u0631\u0627\u0626\u06d2 \u062a\u06be\u06cc \u062c\u0633\u06d2 \u0645\u0628\u0627\u0644\u063a\u06c1 \u0622\u0631\u0627\u0626\u06cc \u06a9\u06cc \u062d\u062f \u062a\u06a9 \u0627\u0686\u06be\u0627\u0644 \u06a9\u0631 \u0627\u06cc\u06a9 \u0646\u06cc\u0627 \u062a\u0646\u0627\u0632\u0639 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0633\u0627\u0632\u0634 \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4<\/strong><br \/>\n<strong>\u0645\u0633\u062c\u062f \u062d\u0631\u0627\u0645 \u0627\u0648\u0631 \u0645\u0633\u062c\u062f \u0646\u0628\u0648\u06cc \u06a9\u06d2 \u0646\u06af\u0631\u0627\u06ba \u0627\u062f\u0627\u0631\u06d2 \u06a9\u06d2 \u062a\u0631\u062c\u0645\u0627\u0646 \u0627\u062d\u0645\u062f \u0627\u0644\u0645\u0646\u0635\u0648\u0631\u06cc \u0646\u06d2 \u0627\u0644\u0639\u0631\u0628\u06cc\u06c1 \u0688\u0627\u0679 \u0646\u06cc\u0679 \u0633\u06d2 \u06af\u0641\u062a\u06af\u0648 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0648\u0636\u0627\u062d\u062a \u06a9\u06cc \u06c1\u06d2 \u06a9\u06c1 \u062d\u062c\u0631\u06c1 \u0646\u0628\u06cc \u0635\u0644\u06cc \u0627\u0644\u0644\u06c1 \u0639\u0644\u06cc\u06c1 \u0648\u0633\u0644\u0645 \u06a9\u06cc \u06a9\u0633\u06cc \u062f\u0648\u0633\u0631\u06d2 \u0645\u0642\u0627\u0645 \u067e\u0631 \u0645\u0646\u062a\u0642\u0644\u06cc \u06a9\u0627 \u06a9\u0648\u0626\u06cc \u067e\u0631\u0648\u06af\u0631\u0627\u0645 \u0646\u06c1\u06cc\u06ba \u0628\u0646\u0627\u06cc\u0627 \u06af\u06cc\u0627 \u0627\u0648\u0631 \u0646\u06c1 \u06c1\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06cc \u0637\u0631\u0641 \u0633\u06d2 \u0627\u06cc\u0633\u06cc \u06a9\u0648\u0626\u06cc \u0645\u062a\u0646\u0627\u0632\u0639\u06c1 \u062a\u062c\u0648\u06cc\u0632 \u062f\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4 \u0645\u0633\u062c\u062f \u0646\u0628\u0648\u06cc \u06a9\u06cc \u062a\u0648\u0633\u06cc\u0639 \u0633\u06d2\u0645\u062a\u0639\u0644\u0642 \u0627\u06cc\u06a9 \u0631\u067e\u0648\u0631\u0679 \u06a9\u06cc \u062a\u06cc\u0627\u0631\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0627\u0646\u062c\u06cc\u0646\u06cc\u0626\u0631 \u06a9\u06cc \u0631\u0627\u0626\u06d2 \u062a\u06be\u06cc \u06a9\u06c1 \u062a\u0648\u0633\u06cc\u0639\u06cc \u06a9\u0627\u0645 \u06a9\u06d2 \u0628\u0627\u0639\u062b \u0631\u0648\u0636\u06c1 \u0631\u0633\u0648\u0644 \u0645\u062a\u0627\u062b\u0631 \u06c1\u0648 \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u060c \u0627\u0633 \u067e\u06c1\u0644\u0648 \u0633\u06d2 \u0642\u0628\u0631 \u0631\u0633\u0648\u0644 \u06a9\u06cc \u062c\u06af\u06c1 \u06a9\u06cc \u062a\u0628\u062f\u06cc\u0644\u06cc \u06a9\u06cc \u0628\u0627\u062a \u0633\u0627\u0645\u0646\u06d2 \u0622\u0626\u06cc \u062a\u06be\u06cc\u06d4<\/strong><br \/>\n<strong>\u062a\u0631\u062c\u0645\u0627\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0633\u0639\u0648\u062f\u06cc \u062d\u06a9\u0648\u0645\u062a \u0627\u0633\u0644\u0627\u0645 \u06a9\u06cc \u062e\u0627\u062f\u0645 \u0627\u0648\u0631 \u0627\u0644\u062d\u0631\u0645\u06cc\u0646 \u0627\u0644\u0634\u0631\u06cc\u0641\u06cc\u0646 \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u06a9\u06cc \u0630\u0645\u06c1 \u062f\u0627\u0631 \u06c1\u06d2\u06d4 \u0627\u0633 \u0646\u0648\u0639\u06cc\u062a \u06a9\u06cc \u0645\u062a\u0646\u0627\u0632\u0639\u06c1 \u062a\u062c\u0627\u0648\u06cc\u0632 \u067e\u0631 \u0639\u0645\u0644 \u06a9\u06cc\u0627 \u062c\u0627 \u0633\u06a9\u062a\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0646\u06c1 \u06c1\u06cc \u0627\u0633 \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u06a9\u06cc \u062c\u0627\u0626\u06d2 \u06af\u06cc\u06d4 \u06a9\u0633\u06cc \u0641\u0631\u062f \u0648\u0627\u062d\u062f \u06a9\u06cc \u0631\u0627\u0626\u06d2 \u06a9\u0648 \u062d\u06a9\u0648\u0645\u062a \u067e\u0631 \u062a\u06be\u0648\u067e\u0646\u06d2 \u06a9\u06cc \u06a9\u0648\u0634\u0634 \u0646\u06c1 \u06a9\u06cc \u062c\u0627\u0626\u06d2\u06d4<\/strong><br \/>\n<strong>\u062a\u0631\u062c\u0645\u0627\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0627\u0644\u062d\u0631\u0645\u06cc\u0646 \u0627\u0644\u0634\u0631\u06cc\u0641\u06cc\u0646 \u06a9\u06d2 \u0633\u0631 \u067e\u0631\u0633\u062a \u0627\u062f\u0627\u0631\u06d2 \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0633\u06d2 \u0630\u0631\u0627\u0626\u0639 \u0627\u0628\u0644\u0627\u063a \u0627\u0648\u0631 \u0639\u0648\u0645 \u0627\u0644\u0646\u0627\u0633 \u06a9\u0648 \u0622\u06af\u0627\u06c1 \u06a9\u06cc\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0642\u0628\u0631\u0644 \u0631\u0633\u0648\u0644 \u06a9\u06cc \u0645\u062a\u0628\u0627\u062f\u0644 \u0645\u0642\u0627\u0645 \u067e\u0631 \u0645\u0646\u062a\u0642\u0644\u06cc \u06a9\u06cc \u0627\u0641\u0648\u0627\u06c1\u0648\u06ba \u067e\u0631 \u06a9\u0627\u0646 \u0646\u06c1 \u062f\u06be\u0631\u06cc\u06ba \u0628\u0644\u06a9\u06c1 \u062d\u0642\u0627\u0626\u0642 \u06a9\u0648 \u0633\u0627\u0645\u0646\u06d2 \u0631\u06a9\u06be\u06cc\u06ba\u06d4 \u0645\u0631\u0642\u062f \u0631\u0633\u0648\u0644 \u0635\u0644\u06cc \u0627\u0644\u0644\u06c1 \u0639\u0644\u06cc\u06c1 \u0648\u0633\u0644\u0645 \u06a9\u06cc \u06a9\u0633\u06cc \u0628\u06be\u06cc \u062f\u0648\u0633\u0631\u06d2 \u0645\u0642\u0627\u0645 \u067e\u0631 \u0645\u0646\u062a\u0642\u0644\u06cc \u0645\u0645\u06a9\u0646 \u06c1\u06cc \u0646\u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0646\u06c1 \u06c1\u06cc \u0627\u0633 \u067e\u0631 \u06a9\u0648\u0626\u06cc \u0628\u0627\u062a \u06a9\u06cc \u062c\u0627\u0646\u06cc \u0686\u0627\u06c1\u06cc\u06d2\u06d4 \u0627\u0633 \u0646\u0648\u0639\u06cc\u062a \u06a9\u06cc \u062e\u0628\u0631\u06cc\u06ba \u0627\u0648\u0631 \u0627\u0641\u0648\u0627\u06c1\u06cc\u06ba \u067e\u06be\u06cc\u0644\u0627\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0641\u062a\u0646\u06c1 \u067e\u0631\u0648\u0631 \u0644\u0648\u06af \u06c1\u06cc\u06ba \u062c\u0648 \u0627\u067e\u0646\u06d2 \u0645\u0630\u0645\u0648\u0645 \u0645\u0642\u0627\u0635\u062f \u06a9\u06cc \u062a\u06a9\u0645\u06cc\u0644 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0645\u0633\u0644\u0645\u0627\u0646\u0648\u06ba \u0645\u06cc\u06ba \u062a\u0646\u0627\u0632\u0639\u0627\u062a \u06a9\u0648 \u06c1\u0648\u0627 \u062f\u06d2 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba\u06d4<\/strong><br \/>\n<strong>\u062e\u06cc\u0627\u0644 \u0631\u06c1\u06d2 \u06a9\u06c1 \u062d\u0627\u0644 \u06c1\u06cc \u0645\u06cc\u06ba \u0628\u0631\u0637\u0627\u0646\u06cc\u06c1 \u06a9\u06d2 \u062f\u0648 \u0627\u062e\u0628\u0627\u0631\u0627\u062a \u0646\u06d2 \u0627\u06cc\u06a9 \u062e\u0628\u0631 \u0634\u0627\u0626\u0639 \u06a9\u06cc \u062a\u06be\u06cc \u062c\u0633 \u0645\u06cc\u06ba \u062f\u0639\u0648\u06cc\u0670 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u062a\u06be\u0627 \u06a9\u06c1 \u0633\u0639\u0648\u062f\u06cc \u062d\u06a9\u0648\u0645\u062a \u0645\u0633\u062c\u062f \u0646\u0628\u0648\u06cc \u06a9\u06cc \u062a\u0648\u0633\u06cc\u0639 \u06a9\u06d2 \u0645\u0646\u0635\u0648\u0628\u06d2 \u06a9\u06d2 \u062a\u062d\u062a \u0642\u0628\u0631\u0644 \u0631\u0633\u0648\u0644 \u06a9\u06cc \u0645\u062a\u0628\u0627\u062f\u0644 \u0645\u0642\u0627\u0645 \u067e\u0631 \u0645\u0646\u062a\u0642\u0644\u06cc \u06a9\u0627 \u0627\u0631\u0627\u062f\u06c1 \u0631\u06a9\u06be\u062a\u06cc \u06c1\u06d2\u06d4<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0644\u062d\u0631\u0645\u06cc\u0646 \u0627\u0644\u0634\u0631\u06cc\u0641\u06cc\u0646 \u06a9\u06d2 \u0646\u06af\u0631\u0627\u0646 \u0627\u062f\u0627\u0631\u06d2 \u06a9\u06cc &#8216;\u0627\u0644\u0639\u0631\u0628\u06cc\u06c1&#8217; \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u0648\u0636\u0627\u062d\u062a \u063a\u06cc\u0631 \u0645\u0644\u06a9\u06cc \u0627\u062e\u0628\u0627\u0631\u0627\u062a \u0645\u06cc\u06ba \u0645\u0631\u0642\u062f \u0631\u0633\u0648\u0644 \u0627\u0648\u0631 \u062d\u064f\u062c\u0631\u06c1 \u0646\u0628\u06cc \u0635\u0644\u06cc \u0627\u0644\u0644\u06c1 \u0639\u0644\u06cc\u06c1 \u0648\u0633\u0644\u0645 \u06a9\u06cc \u0645\u062a\u0628\u0627\u062f\u0644 \u0645\u0642\u0627\u0645 \u067e\u0631 \u0645\u0646\u062a\u0642\u0644\u06cc \u06a9\u06cc \u0627\u0641\u0648\u0627\u06c1\u0648\u06ba \u06a9\u06d2 \u0628\u0639\u062f \u0627\u0644 \u062d\u0631\u0645\u06cc\u0646 \u0627\u0644\u0634\u0631\u06cc\u0641\u06cc\u0646 \u06a9\u06d2 \u0646\u06af\u0631\u0627\u0646 \u0627\u062f\u0627\u0631\u06d2 \u0646\u06d2 \u062f\u0648 \u0679\u0648\u06a9 \u0627\u0644\u0641\u0627\u0638 \u0645\u06cc\u06ba \u0627\u0646 \u062e\u0628\u0631\u0648\u06ba \u06a9\u06cc \u062a\u0631\u062f\u06cc\u062f \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0642\u0628\u0631 \u0631\u0633\u0648\u0644 \u06a9\u06cc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,47,39,38],"tags":[],"class_list":["post-26903","post","type-post","status-publish","format-standard","category-highlighted-news","category-marque","category-special","category-special-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/26903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=26903"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/26903\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=26903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=26903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=26903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}