{"id":33121,"date":"2014-11-27T19:11:13","date_gmt":"2014-11-27T13:41:13","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=33121"},"modified":"2014-11-27T19:11:13","modified_gmt":"2014-11-27T13:41:13","slug":"%d8%a8%d8%a7%d8%b2%d8%a7%d8%b1-%d9%85%db%8c%da%ba-%d9%86%d8%a6%db%92-%d8%a2%d9%84%d9%88-%da%a9%db%8c-%d8%a2%d9%85%d8%af-%d8%b3%db%92-%d9%82%db%8c%d9%85%d8%aa%d9%88%da%ba-%d9%85%db%8c%da%ba-%da%a9","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%a8%d8%a7%d8%b2%d8%a7%d8%b1-%d9%85%db%8c%da%ba-%d9%86%d8%a6%db%92-%d8%a2%d9%84%d9%88-%da%a9%db%8c-%d8%a2%d9%85%d8%af-%d8%b3%db%92-%d9%82%db%8c%d9%85%d8%aa%d9%88%da%ba-%d9%85%db%8c%da%ba-%da%a9\/","title":{"rendered":"\u0628\u0627\u0632\u0627\u0631 \u0645\u06cc\u06ba \u0646\u0626\u06d2 \u0622\u0644\u0648 \u06a9\u06cc \u0622\u0645\u062f \u0633\u06d2 \u0642\u06cc\u0645\u062a\u0648\u06ba \u0645\u06cc\u06ba \u06a9\u0645\u06cc"},"content":{"rendered":"<p style=\"text-align: right;\"><a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/02\/aalu.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8534\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/02\/aalu.jpg\" alt=\"aalu\" width=\"259\" height=\"194\" \/><\/a>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc (\u0648\u0627\u0631\u062a\u0627) \u0628\u0627\u0632\u0627\u0631\u0645\u06cc\u06ba \u0646\u0626\u06d2 \u0622\u0644\u0648 \u06a9\u06cc \u0622\u0645\u062f \u0628\u0691\u06be\u0646\u06d2 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u06cc \u0627\u0633 \u06a9\u06cc \u062a\u06be\u0648\u06a9 \u0645\u06cc\u06ba\u062e\u0627\u0635\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u06af\u0631\u0648\u0627\u0679 \u062f\u06cc\u06a9\u06be\u06cc \u062c\u0627\u0631\u06cc \u06c1\u06d2\u06d4 \u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u06a9\u06be\u0644\u06d2 \u0628\u0627\u0632\u0627\u0631 \u06a9\u06d2 \u062f\u0627\u0645 \u0627\u0628\u06be\u06cc \u0627\u0646\u062a\u06d2 \u0646\u06cc\u0686\u06d2 \u0646\u06c1\u06cc\u06ba \u0622\u0626\u06d2 \u06c1\u06cc\u06ba \u06d4 \u062a\u06be\u0648\u06a9 \u0645\u0646\u0688\u06cc \u0645\u06cc\u06ba \u062a\u06be\u0648\u06a9 \u0622\u0644\u0648 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u06f1\u06f2\u0633\u06d2 \u06f1\u06f5 \u0631\u0648\u067e\u0626\u06d2 \u0641\u06cc \u06a9\u0644\u0648 \u0628\u062a\u0627\u0626\u06cc \u062c\u0627\u0631\u06c1\u06cc \u06c1\u06d2\u06d4 \u062c\u0628\u06a9\u06c1 \u06a9\u06be\u0644\u06d2 \u0628\u0627\u0632\u0627\u0631\u0645\u06cc\u06ba \u06cc\u06c1 \u0627\u0628 \u0628\u06be\u06cc \u06f2\u06f5 \u0633\u06d2 \u06f3\u06f5 \u0631\u0648\u067e\u0626\u06d2 \u0641\u06cc \u06a9\u0644\u0648 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u0642\u0627\u0626\u0645 \u06c1\u06d2\u06d4 \u0627\u06cc\u0634\u06cc\u0627 \u06a9\u06cc \u0633\u0628 \u0633\u06d2 \u0628\u0691\u06cc \u0645\u0646\u0688\u06cc \u0622\u0632\u0627\u062f \u067e\u0648\u0631 \u0645\u0646\u0688\u06cc \u06a9\u06d2 \u0635\u062f\u0631 \u0631\u0627\u062c\u06cc\u0646\u062f\u0631 \u0634\u0631\u0645\u0627 \u0646\u06d2 \u06cc\u0648\u0646\u06cc\u0648\u0627\u0631\u062a\u0627 \u0633\u06d2 \u06af\u0641\u062a\u06af\u0648 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0646\u0626\u06d2 \u0622\u0644\u0648 \u06a9\u06cc \u0622\u0645\u062f \u0645\u06cc\u06ba \u062a\u06cc\u0632\u06cc \u0622\u0646\u06d2 \u0644\u06af\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0622\u0626\u0646\u062f\u06c1 \u0622\u0679\u06be \u062f\u0633 \u0631\u0648\u0632 \u0645\u06cc\u06ba \u06cc\u06c1 \u06a9\u0627\u0641\u06cc \u0645\u0642\u062f\u0627\u0631\u0645\u06cc\u06ba \u0622\u0646\u06d2 \u0644\u06af\u06d2 \u06af\u0627\u06d4 \u0627\u0646\u06be\u0648\u06ba\u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0646\u06cc\u0627 \u0622\u0644\u0648 \u0641\u06cc \u0627\u0644\u062d\u0627\u0644 \u067e\u0646\u062c\u0627\u0628 \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0633\u06d2 \u0622\u0631\u06c1\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0622\u0626\u0646\u062f\u06c1 \u06a9\u0686\u06be \u0631\u0648\u0632 \u0645\u06cc\u06ba \u06c1\u0631\u06cc\u0627\u0646\u06c1 \u0627\u0648\u0631 \u0627\u062a\u0631\u067e\u0631\u062f\u06cc\u0634 \u0633\u06d2 \u0628\u06be\u06cc \u0622\u0644\u0648 \u06a9\u06cc \u0622\u0645\u062f \u0634\u0631\u0648\u0639 \u06c1\u0648\u0646\u06d2 \u06a9\u06cc \u0627\u0645\u06cc\u062f \u06c1\u06d2\u06d4 \u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u06a9\u0686\u06be \u0631\u0648\u0632 \u0645\u06cc\u06ba \u0627\u0633 \u06a9\u06cc \u062a\u06be\u0648\u06a9 \u0642\u06cc\u0645\u062a \u06f1\u06f0 \u0631\u0648\u067e\u0626\u06d2 \u0641\u06cc \u06a9\u0644\u0648 \u0633\u06d2 \u0628\u06be\u06cc \u0646\u06cc\u0686\u06d2 \u0622\u0646\u06d2 \u06a9\u06cc \u0627\u0645\u06cc\u062f \u06c1\u06d2\u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u0626\u06cc \u062f\u06c1\u0644\u06cc (\u0648\u0627\u0631\u062a\u0627) \u0628\u0627\u0632\u0627\u0631\u0645\u06cc\u06ba \u0646\u0626\u06d2 \u0622\u0644\u0648 \u06a9\u06cc \u0622\u0645\u062f \u0628\u0691\u06be\u0646\u06d2 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u06cc \u0627\u0633 \u06a9\u06cc \u062a\u06be\u0648\u06a9 \u0645\u06cc\u06ba\u062e\u0627\u0635\u06cc \u0642\u06cc\u0645\u062a\u0648\u06ba \u06af\u0631\u0648\u0627\u0679 \u062f\u06cc\u06a9\u06be\u06cc \u062c\u0627\u0631\u06cc \u06c1\u06d2\u06d4 \u062d\u0627\u0644\u0627\u0646\u06a9\u06c1 \u06a9\u06be\u0644\u06d2 \u0628\u0627\u0632\u0627\u0631 \u06a9\u06d2 \u062f\u0627\u0645 \u0627\u0628\u06be\u06cc \u0627\u0646\u062a\u06d2 \u0646\u06cc\u0686\u06d2 \u0646\u06c1\u06cc\u06ba \u0622\u0626\u06d2 \u06c1\u06cc\u06ba \u06d4 \u062a\u06be\u0648\u06a9 \u0645\u0646\u0688\u06cc \u0645\u06cc\u06ba \u062a\u06be\u0648\u06a9 \u0622\u0644\u0648 \u06a9\u06cc \u0642\u06cc\u0645\u062a \u06f1\u06f2\u0633\u06d2 \u06f1\u06f5 \u0631\u0648\u067e\u0626\u06d2 \u0641\u06cc \u06a9\u0644\u0648 \u0628\u062a\u0627\u0626\u06cc \u062c\u0627\u0631\u06c1\u06cc \u06c1\u06d2\u06d4 \u062c\u0628\u06a9\u06c1 \u06a9\u06be\u0644\u06d2 \u0628\u0627\u0632\u0627\u0631\u0645\u06cc\u06ba \u06cc\u06c1 \u0627\u0628 \u0628\u06be\u06cc \u06f2\u06f5 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,30],"tags":[],"class_list":["post-33121","post","type-post","status-publish","format-standard","category-business","category-business-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/33121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=33121"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/33121\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=33121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=33121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=33121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}