{"id":37118,"date":"2015-01-23T18:22:37","date_gmt":"2015-01-23T12:52:37","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=37118"},"modified":"2015-01-23T18:22:37","modified_gmt":"2015-01-23T12:52:37","slug":"%d9%82%d8%a7%d9%86%d9%88%d9%86-%d8%b3%d8%a7%d8%b2-%da%a9%d9%88%d9%86%d8%b3%d9%84-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d9%a4%d9%a0%d9%a3-%d9%85%db%8c%da%ba-%d9%a3%d9%a9%d9%a9-%d8%a7%d8%b1","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d9%82%d8%a7%d9%86%d9%88%d9%86-%d8%b3%d8%a7%d8%b2-%da%a9%d9%88%d9%86%d8%b3%d9%84-%d8%a7%d9%86%d8%aa%d8%ae%d8%a7%d8%a8%d8%a7%d8%aa-%d9%a4%d9%a0%d9%a3-%d9%85%db%8c%da%ba-%d9%a3%d9%a9%d9%a9-%d8%a7%d8%b1\/","title":{"rendered":"\u0642\u0627\u0646\u0648\u0646 \u0633\u0627\u0632 \u06a9\u0648\u0646\u0633\u0644 \u0627\u0646\u062a\u062e\u0627\u0628\u0627\u062a: \u0664\u0660\u0663 \u0645\u06cc\u06ba \u0663\u0669\u0669 \u0627\u0631\u0627\u06a9\u06cc\u0646 \u0627\u0633\u0645\u0628\u0644\u06cc \u0646\u06d2 \u06a9\u06cc \u0648\u0648\u0679\u0646\u06af"},"content":{"rendered":"<p style=\"text-align: right;\"><strong>\u0644\u06a9\u06be\u0646\u0624. \u0627\u062a\u0631 \u067e\u0631\u062f\u06cc\u0634 \u0627\u0633\u0645\u0628\u0644\u06cc \u06a9\u06d2 \u0627\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u0645\u06cc\u06ba \u0622\u062c \u062d\u06a9\u0645\u0631\u0627\u06ba \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u06cc \u0628\u06c1\u0648\u062c\u0646 \u0633\u0645\u0627\u062c \u067e\u0627\u0679\u064a\u060c \u0628\u06cc \u062c\u06d2 \u067e\u06cc\u060c \u06a9\u0627\u0646\u06af\u0631\u06cc\u0633 \u0627\u0648\u0631 \u0631\u0627\u0634\u0679\u0631\u06cc\u06c1 \u0644\u0648\u06a9 \u062f\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u062f\u06cc\u06af\u0631 <a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2015\/01\/vidhan-parishad.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-37119\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2015\/01\/vidhan-parishad.jpg\" alt=\"vidhan parishad\" width=\"338\" height=\"259\" \/><\/a>\u0645\u0645\u0628\u0631\u0627\u0646 \u0627\u0633\u0645\u0628\u0644\u06cc \u0646\u06d2 \u06a9\u0627\u0641\u06cc \u062f\u0644\u0686\u0633\u067e\u06cc \u062f\u06a9\u06be\u0627\u0626\u06cc. \u0627\u062a\u0631 \u067e\u0631\u062f\u06cc\u0634 \u0627\u0633\u0645\u0628\u0644\u06cc \u06a9\u06cc 12 \u0646\u0634\u0633\u062a\u0648\u06ba \u06a9\u06d2 \u0644\u0626\u06d2 \u0622\u062c \u0664\u0660\u0663 \u0648\u0648\u0679\u0631\u0648\u06ba (\u0631\u06a9\u0646 \u0627\u0633\u0645\u0628\u0644\u06cc) \u0645\u06cc\u06ba \u0633\u06d2 \u0663\u0669\u0669 \u0646\u06d2 \u0648\u0648\u0679 \u0688\u0627\u0644\u06d2.<\/strong><\/p>\n<p style=\"text-align: right;\"><strong>\u0628\u06cc\u0645\u0627\u0631\u06cc \u06a9\u06d2 \u0686\u0644\u062a\u06d2 \u0627\u06cc\u0633 \u067e\u06cc \u06a9\u06d2 \u0648\u0642\u0627\u0631 \u0627\u062d\u0645\u062f \u0634\u0627\u06c1 \u0648 \u0645\u062d\u0628\u062a \u0631\u0648\u0634\u0646\u06cc \u0627\u0648\u0631 \u067e\u06cc\u0633 \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0627\u06a9\u06be\u0644\u06cc\u0634 \u0633\u0646\u06af\u06be \u0627\u0648\u0631 \u0646\u0627\u0645\u0632\u062f \u0631\u06a9\u0646 \u067e\u06cc\u0679\u0631 \u0646\u06d2 \u0646\u06c1\u06cc\u06ba \u0688\u0627\u0644\u0627 \u0648\u0648\u0679. \u0648\u0648\u0679 \u0688\u0627\u0644\u0646\u06d2 \u0648\u0627\u0644\u0648\u06ba \u0645\u06cc\u06ba \u0628\u06cc \u0627\u06cc\u0633 \u067e\u06cc \u06a9\u06d2 \u0631\u06a9\u0646 \u0627\u0633\u0645\u0628\u0644\u06cc \u0688\u0627\u06a9\u0679\u0631 \u0648\u062c\u06d2 \u06a9\u0645\u0627\u0631 \u0628\u06be\u06cc \u06c1\u06cc\u06ba \u062c\u0648 \u06a9\u06c1 \u0628\u06c1\u0631\u0627\u0626\u0686 \u06a9\u06d2 \u0627\u06cc\u06a9 \u0646\u0648\u062c\u0648\u0627\u0646 \u06a9\u06d2 \u0642\u062a\u0644 \u06a9\u06d2 \u0645\u0639\u0627\u0645\u0644\u06d2 \u0645\u06cc\u06ba \u0641\u0631\u0627\u0631 \u0686\u0644 \u0631\u06c1\u06d2 \u06c1\u06cc\u06ba. \u0627\u0633\u0645\u0628\u0644\u06cc \u0645\u06cc\u06ba \u0627\u06cc\u0633 \u067e\u06cc \u06a9\u06d2 \u0662\u0662\u0669\u060c \u0628\u06c1\u0648\u062c\u0646 \u0633\u0645\u0627\u062c \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0668\u0660\u060c \u0628\u06cc \u062c\u06d2 \u067e\u06cc \u06a9\u06d2 \u0664\u0661\u060c \u06a9\u0627\u0646\u06af\u0631\u06cc\u0633 \u06a9\u06d2\u0662\u0668\u060c \u0631\u0627\u0634\u0679\u0631\u06cc\u06c1 \u0644\u0648\u06a9 \u062f\u0644 \u06a9\u06d2 \u0622\u0679\u06be\u060c \u067e\u06cc\u0633 \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0686\u0627\u0631\u060c \u0642\u0648\u0645\u06cc \u0627\u062a\u062d\u0627\u062f \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u062f\u0648\u060c \u0627\u062a\u062d\u0627\u062f \u0645\u0644\u062a \u06a9\u0648\u0646\u0633\u0644\u060c \u062a\u0631\u0646\u0645\u0648\u0644 \u06a9\u0627\u0646\u06af\u0631\u06cc\u0633\u060c \u0627\u06cc\u0646 \u0633\u06cc \u067e\u06cc \u0627\u0648\u0631 \u0627\u067e\u0646\u0627 \u062f\u0644 \u06a9\u06d2 \u0627\u06cc\u06a9 \u0627\u06cc\u06a9 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0686\u06be \u0622\u0632\u0627\u062f \u0645\u0645\u0628\u0631 \u0627\u0633\u0645\u0628\u0644\u06cc \u067e\u0648\u0644\u0646\u06af \u06a9\u0631\u06cc\u06ba \u06af\u06d2. \u0627\u06cc\u06a9 \u0646\u0627\u0645\u0632\u062f \u0631\u06a9\u0646 \u0627\u0633\u0645\u0628\u0644\u06cc \u0628\u06be\u06cc \u06c1\u06cc\u06ba. \u0627\u0633 \u0628\u0627\u0631 \u0627\u0644\u06cc\u06a9\u0634\u0646 \u0645\u06cc\u06ba \u0661\u0662 \u0633\u06cc\u0679 \u06a9\u06d2 \u0644\u0626\u06d2 \u0661\u0663 \u062f\u0639\u0648\u06cc\u062f\u0627\u0631 \u0645\u06cc\u062f\u0627\u0646 \u0645\u06cc\u06ba \u06c1\u06cc\u06ba. \u0627\u0633\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u067e\u0648\u0644\u0646\u06af \u06c1\u0648 \u0631\u06c1\u0627 \u06c1\u06d2. \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u0633\u06d2 \u0648\u0632\u06cc\u0631 \u0635\u062d\u062a \u0627\u062d\u0645\u062f \u062d\u0633\u0646\u060c \u0631\u0645\u06cc\u0634 \u06cc\u0627\u062f\u0648\u060c \u0648\u0631\u06cc\u0646\u062f\u0631 \u0633\u0646\u06af\u06be \u06af\u0648\u062c\u0631\u060c \u0627\u0634\u0648\u06a9 \u0648\u0627\u062c\u067e\u0626\u06cc\u060c \u0688\u0627\u06a9\u0679\u0631 \u0633\u0631\u0648\u062c\u0646\u064a \u0627\u06af\u0631\u0648\u0627\u0644\u060c \u0635\u0627\u062d\u0628 \u0633\u0646\u06af\u06be \u0633\u06cc\u0646\u06cc\u060c \u0631\u0627\u0645\u062c\u062a\u0646 \u0631\u0627\u062c \u0628\u06be\u0631 \u0627\u0648\u0631 \u0627\u0634\u0648 \u0645\u0644\u06a9. \u0628\u06c1\u0648\u062c\u0646 \u0633\u0645\u0627\u062c \u067e\u0627\u0631\u0679\u06cc \u0633\u06d2 \u0646\u0633\u06cc\u0645 \u0627\u0644\u062f\u06cc\u0646 \u0635\u062f\u06cc\u0642\u06cc\u060c \u062f\u06be\u0631\u0645 \u0648\u06cc\u0631 \u0627\u0634\u0648\u06a9 \u0648 \u067e\u0631\u062f\u06cc\u067e \u062c\u0627\u0679\u0648 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc\u06c1 \u062c\u0646\u062a\u0627 \u067e\u0627\u0631\u0679\u06cc \u0633\u06d2 \u0644\u06a9\u0634\u0645\u0646 \u0622\u0686\u0627\u0631\u06cc\u06c1 \u0648 \u062f\u064a\u0627\u0634\u0643\u0631 \u0633\u0646\u06af\u06be \u0645\u06cc\u062f\u0627\u0646 \u0645\u06cc\u06ba \u06c1\u06cc\u06ba.<\/strong><br \/>\n<strong>\u06a9\u0627\u0646\u06af\u0631\u06cc\u0633 \u0627\u0648\u0631 \u0631\u0627\u0634\u0679\u0631\u06cc\u06c1 \u0644\u0648\u06a9 \u062f\u0644 \u0646\u06d2 \u0627\u0633 \u0628\u0627\u0631 \u0627\u067e\u0646\u06d2 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631 \u0646\u06c1\u06cc\u06ba \u0627\u062a\u0627\u0631\u06d2 \u06c1\u06cc\u06ba. \u06a9\u0627\u0646\u06af\u0631\u06cc\u0633 \u0633\u06d2 \u062d\u06a9\u0645\u0631\u0627\u0646 \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u0648 \u06a9\u06be\u0644\u0627 \u062d\u0645\u0627\u06cc\u062a \u06a9\u06cc \u06c1\u06d2 \u062c\u0628\u06a9\u06c1 \u0631\u0627\u0634\u0679\u0631\u06cc\u06c1 \u0644\u0648\u06a9 \u062f\u0644 \u0628\u06c1\u0648\u062c\u0646 \u0633\u0645\u0627\u062c \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0648\u06ba \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u0645\u06cc\u06ba \u06c1\u06d2. \u0627\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u06a9\u06d2 \u0644\u0626\u06d2 \u0622\u0626\u06cc \u0627\u06d2 \u0627\u06cc\u0633 \u0627\u0641\u0633\u0631 \u0627\u0645\u062a \u06af\u06be\u0648\u0634 \u0645\u0634\u0627\u06c1\u062f \u0645\u0642\u0631\u0631 \u06c1\u06cc\u06ba.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u06a9\u06be\u0646\u0624. \u0627\u062a\u0631 \u067e\u0631\u062f\u06cc\u0634 \u0627\u0633\u0645\u0628\u0644\u06cc \u06a9\u06d2 \u0627\u0646\u062a\u062e\u0627\u0628\u0627\u062a \u0645\u06cc\u06ba \u0622\u062c \u062d\u06a9\u0645\u0631\u0627\u06ba \u0633\u0645\u0627\u062c \u0648\u0627\u062f\u06cc \u067e\u0627\u0631\u0679\u06cc \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u06cc \u0628\u06c1\u0648\u062c\u0646 \u0633\u0645\u0627\u062c \u067e\u0627\u0679\u064a\u060c \u0628\u06cc \u062c\u06d2 \u067e\u06cc\u060c \u06a9\u0627\u0646\u06af\u0631\u06cc\u0633 \u0627\u0648\u0631 \u0631\u0627\u0634\u0679\u0631\u06cc\u06c1 \u0644\u0648\u06a9 \u062f\u0644 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u062f\u06cc\u06af\u0631 \u0645\u0645\u0628\u0631\u0627\u0646 \u0627\u0633\u0645\u0628\u0644\u06cc \u0646\u06d2 \u06a9\u0627\u0641\u06cc \u062f\u0644\u0686\u0633\u067e\u06cc \u062f\u06a9\u06be\u0627\u0626\u06cc. \u0627\u062a\u0631 \u067e\u0631\u062f\u06cc\u0634 \u0627\u0633\u0645\u0628\u0644\u06cc \u06a9\u06cc 12 \u0646\u0634\u0633\u062a\u0648\u06ba \u06a9\u06d2 \u0644\u0626\u06d2 \u0622\u062c \u0664\u0660\u0663 \u0648\u0648\u0679\u0631\u0648\u06ba (\u0631\u06a9\u0646 \u0627\u0633\u0645\u0628\u0644\u06cc) \u0645\u06cc\u06ba \u0633\u06d2 \u0663\u0669\u0669 \u0646\u06d2 \u0648\u0648\u0679 \u0688\u0627\u0644\u06d2. \u0628\u06cc\u0645\u0627\u0631\u06cc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47,27,26],"tags":[],"class_list":["post-37118","post","type-post","status-publish","format-standard","category-marque","category-uttar-pradesh","category-uttar-pradesh-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/37118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=37118"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/37118\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=37118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=37118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=37118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}