{"id":37605,"date":"2015-01-29T17:35:34","date_gmt":"2015-01-29T12:05:34","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=37605"},"modified":"2015-01-29T17:35:34","modified_gmt":"2015-01-29T12:05:34","slug":"%d8%a8%db%8c-%d8%a8%db%8c-%d8%a7%db%92-%d8%b7%d8%a7%d9%84%d8%a8-%d8%b9%d9%84%d9%85-%d8%a7%d8%a8%da%be%db%8c%d8%b4%db%8c%da%a9-%da%a9%db%92-%d9%82%d8%aa%d9%84-%d9%85%db%8c%da%ba-%d8%a7%db%8c%da%a9","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%a8%db%8c-%d8%a8%db%8c-%d8%a7%db%92-%d8%b7%d8%a7%d9%84%d8%a8-%d8%b9%d9%84%d9%85-%d8%a7%d8%a8%da%be%db%8c%d8%b4%db%8c%da%a9-%da%a9%db%92-%d9%82%d8%aa%d9%84-%d9%85%db%8c%da%ba-%d8%a7%db%8c%da%a9\/","title":{"rendered":"\u0628\u06cc \u0628\u06cc \u0627\u06d2 \u0637\u0627\u0644\u0628 \u0639\u0644\u0645 \u0627\u0628\u06be\u06cc\u0634\u06cc\u06a9 \u06a9\u06d2 \u0642\u062a\u0644 \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u06af\u0631\u0641\u062a\u0627\u0631"},"content":{"rendered":"<p style=\"text-align: right;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-10877\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/02\/arest.jpg\" alt=\"arest\" width=\"299\" height=\"168\" \/>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4(\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06a9\u0631\u0634\u0646\u0627 \u0646\u06af\u0631 \u0639\u0644\u0627\u0642\u06c1 \u0645\u06cc\u06ba \u0631\u06c1\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0628\u06cc \u0628\u06cc \u0627\u06d2 \u0637\u0627\u0644\u0628 \u0639\u0644\u0645 \u0627\u0628\u06be\u06cc\u0634\u06cc\u06a9 \u0633\u0646\u06af\u06be \u06a9\u06d2 \u0642\u062a\u0644 \u06a9\u06d2 \u0645\u0639\u0627\u0645\u0644\u06d2 \u0645\u06cc\u06ba \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0628\u062f\u06be \u06a9\u0648 \u0627\u06cc\u06a9 \u0645\u0644\u0632\u0645 \u06a9\u0648 \u06af\u0631\u0641\u062a\u0627\u0631 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0627\u0633 \u06a9\u06d2 \u067e\u0627\u0633 \u0633\u06d2 \u0648\u0627\u0631\u062f\u0627\u062a \u0645\u06cc\u06ba \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u06cc \u06af\u0626\u06cc \u06a9\u0627\u0631 \u0628\u06be\u06cc \u0628\u0631\u0627\u0653\u0645\u062f \u06a9\u06cc \u06c1\u06d2 \u06d4 \u0627\u0633 \u0645\u0639\u0627\u0645\u0644\u06d2 \u0645\u06cc\u06ba \u0627\u0628\u06be\u06cc \u0627\u06c1\u0645 \u0645\u0644\u0632\u0645 \u0633\u0645\u06cc\u062a \u06a9\u0626\u06cc \u062f\u06cc\u06af\u0631 \u0644\u0648\u06af \u0641\u0631\u0627\u0631 \u06c1\u06cc\u06ba \u06d4 \u0633\u0631\u0648\u062c\u0646\u06cc \u0646\u06af\u0631 \u06a9\u06d2 \u0631\u06c1\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u062f\u0627\u0631\u0648\u063a\u06c1 \u0646\u0631\u06cc\u0646\u062f\u0631 \u0628\u06c1\u0627\u062f\u0631 \u0633\u0646\u06af\u06be \u06a9\u0627 \u0628\u06cc\u0679\u0627 \u0627\u0628\u06be\u06cc\u0634\u06cc\u06a9 \u0633\u0646\u06af\u06be \u062f\u06c1\u0631\u0627\u062f\u0648\u0646 \u0645\u06cc\u06ba \u0631\u06c1 \u06a9\u0631 \u0628\u06cc \u0628\u06cc \u0627\u06d2 \u06a9\u06cc \u067e\u0691\u06be\u0627\u0626\u06cc \u06a9\u0631\u062a\u0627\u062a\u06be\u0627\u06d4\u0648\u06c1 \u06f2\u06f5\u062f\u0633\u0645\u0628\u0631 \u06a9\u0648 \u0627\u067e\u0646\u06d2 \u06af\u06be\u0631 \u0627\u0653\u06cc\u0627\u062a\u06be\u0627\u06d4 \u06f3\u06f1\u062f\u0633\u0645\u0628\u0631 \u06a9\u0648\u0648\u06c1 \u0633\u0627\u0644 \u0646\u0648 \u06a9\u06cc \u067e\u0627\u0631\u0679\u06cc \u0645\u0646\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u0626\u06d2 \u06af\u06be\u0631 \u0633\u06d2 \u0646\u06a9\u0644\u0627\u062a\u06be\u0627 \u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u06a9\u0648\u0631\u0627\u062a \u06a9\u0648 \u0648\u06c1 \u0646\u06cc\u0645 \u0645\u0631\u062f\u06c1<br \/>\n\u062d\u0627\u0644\u062a \u0645\u06cc\u06ba \u0639\u0627\u0644\u0645 \u0628\u0627\u063a \u0628\u0633 \u0627\u0633\u0679\u06cc\u0634\u0646 \u06a9\u06d2 \u067e\u0627\u0633 \u067e\u0691\u0627 \u0645\u0644\u0627 \u06d4 \u0627\u0633 \u06a9\u0648 \u0639\u0644\u0627\u062c \u06a9\u06d2 \u0644\u0626\u06d2 \u067e\u0631\u0627\u0626\u06cc\u0648\u06cc\u0679 \u0627\u0633\u067e\u062a\u0627\u0644 \u0645\u06cc\u06ba \u062f\u0627\u062e\u0644 \u06a9\u0631\u0627\u06cc\u0627 \u06af\u06cc\u0627 \u062a\u06be\u0627\u06d4\u062c\u06c1\u0627\u06ba \u0627\u0633 \u06a9\u06cc \u0645\u0648\u062a \u06c1\u0648\u06af\u0626\u06cc \u062a\u06be\u06cc \u06d4 \u06a9\u0646\u0628\u06c1 \u0627\u0648\u0631 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0627\u0628\u06be\u06cc\u0634\u06cc\u06a9 \u06a9\u06cc \u0645\u0648\u062a \u06a9\u0648 \u0633\u0691\u06a9 \u062d\u0627\u062f\u062b\u06c1 \u0645\u0627\u0646\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u0633 \u06a9\u06cc \u0627\u0653\u062e\u0631\u06cc \u0631\u0633\u0648\u0645 \u0627\u062f\u0627 \u06a9\u0631\u062f\u06cc \u062a\u06be\u06cc \u06d4\u0686\u0646\u062f \u0631\u0648\u0632 \u0628\u0639\u062f \u06a9\u0646\u0628\u06c1 \u0648\u0627\u0644\u0648\u06ba \u06a9\u0648 \u067e\u062a\u06c1 \u0686\u0644\u0627\u06a9\u06c1 \u0627\u0628\u06be\u06cc\u0634\u06cc\u06a9 \u06a9\u0627 \u0642\u062a\u0644 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u062a\u06be\u0627 \u06d4<\/strong><br \/>\n<strong> \u0627\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u0646 \u0644\u0648\u06af\u0648\u06ba \u0646\u06d2 \u06a9\u0631\u0634\u0646\u0627\u0646\u06af\u0631 \u06a9\u0648\u062a\u0648\u0627\u0644\u06cc \u0633\u06d2 \u0633\u06cc\u0641 \u0631\u0636\u0627\u0633\u0645\u06cc\u062a \u0646\u0627\u0645\u0639\u0644\u0648\u0645 \u0646\u0648\u062c\u0648\u0627\u0646\u0648\u06ba \u06a9\u06d2 \u062e\u0644\u0627\u0641 \u0642\u062a\u0644 \u06a9\u06cc \u0631\u067e\u0648\u0631\u0679 \u062f\u0631\u062c \u06a9\u0631\u0627\u0626\u06cc \u062a\u06be\u06cc \u06d4 \u0645\u062c\u0633\u0679\u0631\u06cc\u0679 \u06a9\u06d2 \u062d\u06a9\u0645 \u067e\u0631 \u0627\u0628\u06be\u06cc\u0634\u06cc\u06a9 \u06a9\u06cc \u0644\u0627\u0634 \u0642\u0628\u0631\u0633\u06d2 \u0646\u06a9\u0627\u0644\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0627\u0633 \u06a9\u0627 \u067e\u0648\u0633\u0679 \u0645\u0627\u0631\u0679\u0645 \u06a9\u0631\u0627\u06cc\u0627 \u06af\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u0648\u06c1\u06cc\u06ba \u0627\u0633 \u0645\u0639\u0627\u0645\u0644\u06c1 \u0645\u06cc\u06ba \u0644\u0627\u067e\u0631\u0648\u0627\u0626\u06cc \u0628\u0631\u062a\u0646\u06d2 \u06a9\u06d2 \u0627\u0644\u0632\u0627\u0645 \u0645\u06cc\u06ba \u0627\u0646\u0633\u067e\u06a9\u0679\u0631 \u06a9\u0631\u0634\u0646\u0627 \u0646\u06af\u0631 \u0648\u06a9\u0627\u0633 \u067e\u0627\u0646\u0688\u06d2 \u06a9\u0648 \u0627\u06cc\u0633 \u0627\u06cc\u0633 \u067e\u06cc \u0646\u06d2 \u0645\u0639\u0637\u0644 \u06a9\u0631\u062f\u06cc\u0627 \u062a\u06be\u0627\u06d4 \u0645\u0639\u0627\u0645\u0644\u06c1 \u06a9\u06cc \u062a\u0641\u062a\u06cc\u0634 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u067e\u0648\u0644\u06cc\u0633 \u06a9\u0648 \u0648\u06cc\u0628\u06be\u0648 \u0633\u0646\u06af\u06be \u060c\u0648\u0646\u06d2 \u0633\u0646\u06af\u06be \u0627\u0648\u0631 \u06a9\u0631\u0634\u0646\u0627 \u0646\u06af\u0631 \u0627\u06cc\u0644 \u0688\u06cc \u0627\u06d2 \u06a9\u0627\u0644\u0648\u0646\u06cc \u06a9\u06d2 \u0631\u06c1\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0631\u0648\u06c1\u062a \u0634\u0631\u0645\u0627 \u06a9\u06d2 \u0648\u0627\u0631\u062f\u0627\u062a \u0645\u06cc\u06ba \u0634\u0627\u0645\u0644 \u06c1\u0648\u0646\u06d2 \u06a9\u0627\u067e\u062a\u06c1 \u0686\u0644\u0627 \u06d4\u0628\u062f\u06be \u06a9\u0648 \u06a9\u0631\u0634\u0646\u0627 \u0646\u06af\u0631 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0645\u0644\u0632\u0645 \u0631\u0648\u06c1\u062a \u0634\u0631\u0645\u0627 \u06a9\u0648 \u0627\u0633 \u06a9\u06d2 \u06af\u06be\u0631 \u0633\u06d2 \u06af\u0631\u0641\u062a\u0627\u0631 \u06a9\u06cc\u0627 \u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0642\u062a\u0644 \u0645\u06cc\u06ba \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u06cc \u06af\u0626\u06cc \u0633\u0648\u0641\u0679 \u0688\u06cc\u0632\u0627\u0626\u0631 \u06a9\u0627\u0631 \u0628\u06be\u06cc \u0628\u0631\u0627\u0653\u0645\u062f \u06a9\u06cc \u06c1\u06d2 \u06d4 \u0648\u06c1\u06cc\u06ba \u0627\u0628\u06be\u06cc \u062e\u0627\u0635 \u0645\u0644\u0632\u0645 \u0633\u06cc\u0641 \u0631\u0636\u0627\u0633\u0645\u06cc\u062a \u062f\u06cc\u06af\u0631 \u0644\u0648\u06af \u0641\u0631\u0627\u0631 \u06c1\u06cc\u06ba \u06d4<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4(\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06a9\u0631\u0634\u0646\u0627 \u0646\u06af\u0631 \u0639\u0644\u0627\u0642\u06c1 \u0645\u06cc\u06ba \u0631\u06c1\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0628\u06cc \u0628\u06cc \u0627\u06d2 \u0637\u0627\u0644\u0628 \u0639\u0644\u0645 \u0627\u0628\u06be\u06cc\u0634\u06cc\u06a9 \u0633\u0646\u06af\u06be \u06a9\u06d2 \u0642\u062a\u0644 \u06a9\u06d2 \u0645\u0639\u0627\u0645\u0644\u06d2 \u0645\u06cc\u06ba \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0628\u062f\u06be \u06a9\u0648 \u0627\u06cc\u06a9 \u0645\u0644\u0632\u0645 \u06a9\u0648 \u06af\u0631\u0641\u062a\u0627\u0631 \u06a9\u06cc\u0627 \u06c1\u06d2 \u06d4 \u067e\u0648\u0644\u06cc\u0633 \u0646\u06d2 \u0627\u0633 \u06a9\u06d2 \u067e\u0627\u0633 \u0633\u06d2 \u0648\u0627\u0631\u062f\u0627\u062a \u0645\u06cc\u06ba \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u06cc \u06af\u0626\u06cc \u06a9\u0627\u0631 \u0628\u06be\u06cc \u0628\u0631\u0627\u0653\u0645\u062f \u06a9\u06cc \u06c1\u06d2 \u06d4 \u0627\u0633 \u0645\u0639\u0627\u0645\u0644\u06d2 \u0645\u06cc\u06ba \u0627\u0628\u06be\u06cc \u0627\u06c1\u0645 \u0645\u0644\u0632\u0645 \u0633\u0645\u06cc\u062a \u06a9\u0626\u06cc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,28],"tags":[],"class_list":["post-37605","post","type-post","status-publish","format-standard","category-lucknow","category-lucknow-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/37605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=37605"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/37605\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=37605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=37605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=37605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}