{"id":40557,"date":"2015-03-11T17:07:39","date_gmt":"2015-03-11T11:37:39","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=40557"},"modified":"2015-03-11T17:07:39","modified_gmt":"2015-03-11T11:37:39","slug":"%da%af%d9%88%d9%85%d8%aa%db%8c-%d8%b5%d9%81%d8%a7%d8%a6%db%8c-%da%a9%db%8c%d9%84%d8%a6%db%92-%d8%a8%d8%a7-%db%81%d8%b1-%d8%b3%db%92-%d9%85%d9%86%da%af%d8%a7%d8%a6%db%8c-%d8%ac%d8%a7%d8%a6%db%8c%da%ba","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%da%af%d9%88%d9%85%d8%aa%db%8c-%d8%b5%d9%81%d8%a7%d8%a6%db%8c-%da%a9%db%8c%d9%84%d8%a6%db%92-%d8%a8%d8%a7-%db%81%d8%b1-%d8%b3%db%92-%d9%85%d9%86%da%af%d8%a7%d8%a6%db%8c-%d8%ac%d8%a7%d8%a6%db%8c%da%ba\/","title":{"rendered":"\u06af\u0648\u0645\u062a\u06cc \u0635\u0641\u0627\u0626\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u0628\u0627 \u06c1\u0631 \u0633\u06d2 \u0645\u0646\u06af\u0627\u0626\u06cc \u062c\u0627\u0626\u06cc\u06ba \u06af\u06cc \u0645\u0634\u06cc\u0646\u06cc\u06ba"},"content":{"rendered":"<p style=\"text-align: right;\"><strong> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-38988\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2015\/02\/Gomti-river.jpg\" alt=\"Gomti river\" width=\"186\" height=\"140\" \/>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4(\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u06af\u0648\u0645\u062a\u06cc \u0635\u0641\u0627\u0626\u06cc \u0645\u06c1\u0645 \u06a9\u06d2 \u062a\u062d\u062a \u06af\u0648\u0645\u062a\u06cc \u06a9\u0648 \u0635\u0627\u0641 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0634\u0631\u0648\u0639\u0627\u062a\u06cc \u062f\u0648\u0631 \u0646\u06d2 \u062a\u06cc\u0632\u06cc \u067e\u06a9\u0691 \u0644\u06cc \u06c1\u06d2\u06d4 \u06a9\u0691\u06cc\u0627 \u06af\u06be\u0627\u0679 \u0633\u06d2 \u06af\u0648\u0645\u062a\u06cc \u0628\u06cc\u0631\u0627\u062c \u062a\u06a9 \u0645\u0634\u06cc\u0646\u0648\u06ba \u06a9\u0648 \u0644\u06af\u0627\u06a9\u0631 \u06a9\u0627\u0645 \u0634\u0631\u0648\u0639 \u06a9\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2 \u0644\u06cc\u06a9\u0646 \u0627\u0628\u06be\u06cc \u0627\u0641\u0633\u0631\u0627\u0646 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0635\u0641\u0627\u0626\u06cc \u0645\u06c1\u0645 \u06a9\u0627 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u0645\u0631\u062d\u0644\u06c1 \u06c1\u06d2\u060c\u0627\u0633 \u0645\u06c1\u0645 \u06a9\u0648 \u06a9\u0627\u0645\u06cc\u0627\u0628 \u0628\u0646\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0628\u0691\u06cc \u0633\u06d2 \u0628\u0691\u06cc \u0645\u0634\u06cc\u0646\u0648\u06ba \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u067e\u0691\u06d2 \u06af\u06cc \u0627\u0633 \u06a9\u06cc\u0644\u0626\u06d2 \u0627\u0653\u0628\u067e\u0627\u0634\u06cc \u0645\u062d\u06a9\u0645\u06c1 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06c1 \u06a9\u0627\u0645 \u0634\u0631\u0648\u0639 \u06a9\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4<\/strong><br \/>\n<strong>\u0645\u062d\u06a9\u0645\u06c1 \u0630\u0627\u062a\u06cc \u0630\u0631\u0627\u0626\u0639 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0635\u0641\u0627\u0626\u06cc \u0645\u06c1\u0645 \u06a9\u06d2 \u067e\u0644\u0627\u0646\u0646\u06af \u0627\u0633\u0679\u06cc\u062c \u0645\u06cc\u06ba \u0633\u0631\u0648\u06d2 \u0686\u0644 \u0631\u06c1\u0627 \u06c1\u06d2 \u0627\u0633 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u06cc \u067e\u0644\u0627\u0646\u0646\u06af \u0688\u06cc\u0632\u0627\u0626\u0646 \u062a\u06cc\u0627\u0631 \u06a9\u06cc \u062c\u0627 \u0631\u06c1\u06cc \u06c1\u06d2\u060c \u0635\u0641\u0627\u0626\u06cc \u0645\u06c1\u0645 \u06a9\u06d2 \u067e\u06c1\u0644\u06d2 \u0645\u0631\u062d\u0644\u06c1 \u0645\u06cc\u06ba \u0627\u0646 \u062a\u0645\u0627\u0645 \u06a9\u0627\u0645\u0648\u06ba \u06a9\u0648 \u067e\u0648\u0631\u0627 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u06a9\u0627\u0645\u0648\u06ba \u0645\u06cc\u06ba \u062a\u06cc\u0632\u06cc \u067e\u06a9\u0691\u0648\u0627\u0646\u06d2 \u06a9\u06cc \u062a\u06cc\u0627\u0631\u06cc \u0686\u0644 \u0631\u06c1\u06cc \u06c1\u06d2\u06d4 \u0627\u0633 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u06cc \u0645\u062d\u06a9\u0645\u06c1 \u062c\u0627\u062a\u06cc \u0627\u0641\u0633\u0631\u0627\u0646 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06cc\u06c1 \u0628\u06c1\u062a \u06c1\u06cc \u0645\u0634\u06a9\u0644 \u06a9\u0627\u0645 \u06c1\u06d2\u06d4 \u0627\u0633 \u0648\u062c\u06c1 \u0633\u06d2 \u06c1\u0645\u06cc\u06ba \u0631\u0691\u06a9\u06cc \u0627\u0648\u0631 \u0628\u0627\u0645\u0628\u06d2 \u0627\u0646\u062c\u06cc\u0646\u0626\u0631\u0646\u06af \u062a\u0646\u0638\u06cc\u0645\u0648\u06ba \u0633\u06d2 \u0645\u062f\u062f \u0644\u06cc\u0646\u06cc \u067e\u0691\u06d2 \u06af\u06cc\u06d4\u0627\u0633 \u06a9\u06cc\u0644\u0626\u06d2 \u0645\u062d\u06a9\u0645\u06c1 \u062f\u0648\u0646\u0648\u06ba \u062a\u0646\u0638\u06cc\u0645\u0648\u06ba \u0633\u06d2 \u0633\u0645\u062c\u06be\u0648\u062a\u06c1 \u06a9\u0631\u06d2 \u06af\u0627\u06d4 \u0628\u062a\u0627\u06cc\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0645\u062d\u06a9\u0645\u06c1 \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0633\u06d2 \u06af\u0648\u0645\u062a\u06cc \u0635\u0641\u0627\u0626\u06cc \u06a9\u06cc\u0644\u0626\u06d2 \u062a\u06cc\u0646 \u0628\u0644\u0627\u06a9\u0648\u06ba \u0645\u06cc\u06ba \u062a\u0642\u0633\u06cc\u0645 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4<br \/>\n\u067e\u06c1\u0644\u0627 \u062d\u0635\u06c1 \u06a9\u0691\u06cc\u0627 \u06af\u06be\u0627\u0679 \u0639\u0644\u0627\u0642\u06c1 \u0645\u06cc\u06ba\u060c \u062f\u0648\u0633\u0631\u0627 \u0644\u06a9\u06be\u0646\u0648\u0654 \u0628\u0644\u0627\u06a9 -\u06f2 \u0644\u06a9\u0634\u0645\u0646 \u0645\u06cc\u0644\u06c1 \u0639\u0644\u0627\u0642\u06c1\u060c \u062a\u06cc\u0633\u0631\u0627 \u0646\u0634\u0627\u0637 \u06af\u0646\u062c \u0633\u06d2 \u06c1\u0646\u0648\u0645\u0627\u0646 \u0633\u06cc\u062a\u0648 \u062a\u06a9 \u062a\u0642\u0633\u06cc\u0645 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4 \u0627\u0646 \u062a\u0645\u0627\u0645 \u0628\u0644\u0627\u06a9\u0648\u06ba \u06a9\u06d2 \u06a9\u0627\u0645\u0648\u06ba \u06a9\u06cc \u062f\u06cc\u06a9\u06be \u0628\u06be\u0627\u0644 \u06a9\u06cc\u0644\u0626\u06d2 \u0645\u062a\u0639\u0644\u0642\u06c1 \u0628\u0644\u0627\u06a9 \u0627\u0641\u0633\u0631\u0648\u06ba \u06a9\u06cc \u062a\u0639\u06cc\u0646\u0627\u062a\u06cc \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4<\/strong><br \/>\n<strong>\u0645\u062d\u06a9\u0645\u06c1 \u062c\u0627\u062a\u06cc \u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06af\u0648\u0645\u062a\u06cc \u0635\u0641\u0627\u0626\u06cc \u06a9\u0627 \u06a9\u0627\u0645 \u0628\u06cc\u062d\u062f \u0645\u0634\u06a9\u0644 \u06c1\u06d2 \u0627\u0633\u06d2 \u06a9\u0633\u06cc \u062a\u0646\u06c1\u0627 \u0645\u062d\u06a9\u0645\u06c1 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06c1 \u0627\u0646\u062c\u0627\u0645 \u0646\u06c1\u06cc\u06ba \u062f\u06cc\u0627 \u062c\u0627 \u0633\u06a9\u062a\u0627 \u06c1\u06d2 \u0627\u0646 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06a9\u0627\u0645 \u06a9\u0648 \u067e\u0648\u0631\u0627 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc\u0644\u0626\u06d2 \u0627\u0679\u06be\u0627\u0631\u06c1 \u0645\u0627\u06c1 \u06a9\u0627 \u0648\u0642\u062a \u062f\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2 \u0627\u06cc\u0633\u06d2 \u0645\u06cc\u06ba \u0627\u0633 \u06a9\u0627\u0645 \u06a9\u0648 \u067e\u0648\u0631\u0627 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc\u0644\u0626\u06d2 \u06a9\u0626\u06cc \u06a9\u0645\u067e\u0646\u06cc\u0648\u06ba \u0633\u06d2 \u0633\u0645\u062c\u06be\u0648\u062a\u06c1 \u06c1\u0648\u0646\u06d2 \u06a9\u06cc \u0627\u0645\u06cc\u062f \u06c1\u06d2\u06d4 \u0627\u0646 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0635\u0641\u0627\u0626\u06cc \u06a9\u06d2 \u06a9\u0627\u0645 \u06a9\u0648 \u0639\u0627\u0645 \u0645\u0634\u06cc\u0646\u0648\u06ba \u0633\u06d2 \u0646\u06c1\u06cc\u06ba \u06a9\u06cc\u0627 \u062c\u0627 \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u06d4 \u0627\u06cc\u0633\u06d2 \u062d\u0627\u0644\u0627\u062a \u0645\u06cc\u06ba \u0645\u062d\u06a9\u0645\u06c1 \u06a9\u0627 \u062c\u0633 \u06a9\u0645\u067e\u0646\u06cc \u0633\u06d2 \u0645\u0639\u0627\u06c1\u062f\u06c1 \u06c1\u0648\u06af\u0627 \u0627\u0633 \u067e\u0631 \u0679\u0631\u06cc\u0632\u0631 \u0627\u0648\u0631 \u0627\u06cc\u06af\u0632\u06cc \u0648\u06cc\u0679\u0631 \u0645\u0634\u06cc\u0646\u0648\u06ba \u06a9\u0648 \u0645\u0646\u06af\u0627\u0646\u06d2 \u06a9\u0627 \u062f\u0628\u0627\u0648\u0654 \u0628\u0646\u0627\u06cc\u0627 \u062c\u0627\u0626\u06d2 \u06af\u0627\u06d4 \u0627\u06cc\u06a9 \u0627\u0641\u0633\u0631 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06cc\u06c1 \u0627\u06cc\u0633\u06cc \u0645\u0634\u06cc\u0646\u06cc\u06ba \u06c1\u0648\u062a\u06cc \u06c1\u06cc\u06ba \u062c\u0648\u067e\u0627\u0646\u06cc \u0645\u06cc\u06ba \u0631\u06c1\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0635\u0641\u0627\u0626\u06cc \u06a9\u06d2 \u06a9\u0627\u0645 \u06a9\u0648 \u067e\u0648\u0631\u06cc \u0637\u0631\u062d \u0633\u06d2 \u06a9\u0631 \u0633\u06a9\u062a\u06cc \u06c1\u06cc\u06ba\u06d4 \u0627\u0641\u0633\u0631\u0627\u0646 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u067e\u0644\u0627\u0646\u0646\u06af \u0627\u0633\u0679\u06cc\u062c \u0633\u0631\u0648\u06d2 \u0627\u0648\u0631 \u0688\u06cc\u0632\u0627\u0626\u0646 \u062a\u06cc\u0627\u0631 \u06a9\u0626\u06d2 \u062c\u0627\u0646\u06d2 \u0633\u06d2 \u0642\u0628\u0644 \u06c1\u0645\u06cc\u06ba \u06af\u0648\u0645\u062a\u06cc \u0635\u0641\u0627\u0626\u06cc \u06a9\u06d2 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u0645\u0631\u062d\u0644\u06c1 \u0645\u06cc\u06ba \u0635\u0641\u0627\u0626\u06cc \u06a9\u06d2 \u06a9\u0627\u0645\u0648\u06ba \u06a9\u0648 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u0686\u0627\u0644\u06cc\u0633 \u0641\u06cc\u0635\u062f \u062a\u06a9 \u067e\u0648\u0631\u0627 \u06a9\u0631 \u0644\u06cc\u0646\u0627 \u06c1\u06d2 \u0627\u0633 \u06a9\u06cc\u0644\u0626\u06d2 \u06a9\u0691\u06cc\u0627 \u06af\u06be\u0627\u0679\u060c \u0644\u06a9\u0634\u0645\u0646 \u0645\u06cc\u0644\u06c1\u060c \u0628\u06be\u06cc\u0646\u0633\u0627 \u06a9\u0646\u0688 \u0633\u0645\u06cc\u062a \u06a9\u0626\u06cc \u062f\u06cc\u06af\u0631 \u0645\u0632\u06cc\u062f \u0628\u06cc\u0631\u0627\u062c\u0648\u06ba \u067e\u0631 \u0645\u0634\u06cc\u0646\u0648\u06ba \u06a9\u0648 \u0644\u06af\u0627\u06a9\u0631 \u06a9\u0627\u0645 \u06a9\u0631\u0627\u06cc\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4<\/strong><br \/>\n<strong> \u06a9\u0691\u06cc\u0627 \u06af\u06be\u0627\u0679 \u067e\u0631 \u062a\u0639\u06cc\u0646\u0627\u062a \u0627\u0633\u0633\u0679\u0646\u0679 \u0627\u0646\u062c\u06cc\u0646\u0626\u0631 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06cc\u06c1\u0627\u06ba \u067e\u0631 \u0635\u0641\u0627\u0626\u06cc \u06a9\u06d2 \u06a9\u0627\u0645 \u06a9\u0648 \u062a\u0642\u0631\u06cc\u0628\u0627\u064b \u067e\u0648\u0631\u0627\u06a9\u0631 \u0644\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u06cc\u06c1\u0627\u06ba \u0627\u06cc\u06a9 \u0679\u06cc\u0644\u06c1 \u06c1\u06d2 \u062c\u0633\u06d2 \u06a9\u0627\u0679\u0646\u06d2 \u06a9\u0627 \u06a9\u0627\u0645 \u06a9\u06cc\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u06c1\u06d2 \u0627\u0633 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u06cc \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u06cc\u06c1\u0627\u06ba \u067e\u0631 \u0645\u0688 \u0644\u0641\u0679\u0631 \u0645\u0634\u06cc\u0646 \u0633\u0645\u06cc\u062a \u062f\u06cc\u06af\u0631 \u0645\u0634\u06cc\u0646\u0648\u06ba \u0633\u06d2 \u06a9\u0627\u0645 \u06a9\u0631\u0627\u06cc\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4 \u06a9\u0691\u06cc\u0627 \u06af\u06be\u0627\u0679 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06c1\u06cc \u06af\u0648\u0645\u062a\u06cc \u06a9\u0646\u0627\u0631\u06d2 \u0688\u0627\u0644\u06cc \u06af\u0646\u062c \u067e\u0644\u060c \u0644\u06a9\u0634\u0645\u0646 \u0645\u06cc\u0644\u06c1\u060c \u0634\u06c1\u06cc\u062f \u0627\u0633\u0645\u0627\u0631\u06a9 \u0633\u0645\u06cc\u062a \u06a9\u0626\u06cc \u062f\u06cc\u06af\u0631 \u0645\u0642\u0627\u0645\u0627\u062a \u067e\u0631 \u0646\u062f\u06cc \u06a9\u0646\u0627\u0631\u06d2 \u062c\u06d2 \u0633\u06cc \u0628\u06cc \u0627\u0648\u0631 \u062f\u06cc\u06af\u0631 \u0645\u0634\u06cc\u0646\u0648\u06ba \u06a9\u0648 \u0644\u06af\u0627\u06a9\u0631 \u06a9\u0627\u0645 \u06a9\u06cc\u0627 \u062c\u0627 \u0631\u06c1\u0627 \u06c1\u06d2\u06d4 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u06cc\u06c1\u0627\u06ba \u067e\u0631 \u0628\u0646\u06d2 \u06f1\u06f1\u06f5 \u0645\u06cc\u0679\u0631 \u0637\u0648\u06cc\u0644 \u063a\u06cc\u0631 \u0645\u0633\u062a\u0642\u0644 \u0628\u0627\u0646\u062f\u06be \u06a9\u0648 \u062c\u0648\u0646 \u062a\u06a9 \u0628\u0646\u0627\u0626\u06d2 \u0631\u06a9\u06be\u0646\u06d2 \u06a9\u06cc \u06c1\u062f\u0627\u06cc\u062a \u062f\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0644\u06a9\u06be\u0646\u0648\u0654\u06d4(\u0646\u0627\u0645\u06c1 \u0646\u06af\u0627\u0631)\u06d4 \u06af\u0648\u0645\u062a\u06cc \u0635\u0641\u0627\u0626\u06cc \u0645\u06c1\u0645 \u06a9\u06d2 \u062a\u062d\u062a \u06af\u0648\u0645\u062a\u06cc \u06a9\u0648 \u0635\u0627\u0641 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0634\u0631\u0648\u0639\u0627\u062a\u06cc \u062f\u0648\u0631 \u0646\u06d2 \u062a\u06cc\u0632\u06cc \u067e\u06a9\u0691 \u0644\u06cc \u06c1\u06d2\u06d4 \u06a9\u0691\u06cc\u0627 \u06af\u06be\u0627\u0679 \u0633\u06d2 \u06af\u0648\u0645\u062a\u06cc \u0628\u06cc\u0631\u0627\u062c \u062a\u06a9 \u0645\u0634\u06cc\u0646\u0648\u06ba \u06a9\u0648 \u0644\u06af\u0627\u06a9\u0631 \u06a9\u0627\u0645 \u0634\u0631\u0648\u0639 \u06a9\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2 \u0644\u06cc\u06a9\u0646 \u0627\u0628\u06be\u06cc \u0627\u0641\u0633\u0631\u0627\u0646 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0635\u0641\u0627\u0626\u06cc \u0645\u06c1\u0645 \u06a9\u0627 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u0645\u0631\u062d\u0644\u06c1 \u06c1\u06d2\u060c\u0627\u0633 \u0645\u06c1\u0645 \u06a9\u0648 \u06a9\u0627\u0645\u06cc\u0627\u0628 \u0628\u0646\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0628\u0691\u06cc \u0633\u06d2 \u0628\u0691\u06cc \u0645\u0634\u06cc\u0646\u0648\u06ba \u06a9\u06cc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,28],"tags":[],"class_list":["post-40557","post","type-post","status-publish","format-standard","category-lucknow","category-lucknow-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/40557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=40557"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/40557\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=40557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=40557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=40557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}