{"id":40953,"date":"2015-03-17T19:19:19","date_gmt":"2015-03-17T13:49:19","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=40953"},"modified":"2015-03-17T19:19:19","modified_gmt":"2015-03-17T13:49:19","slug":"%d9%88%d9%b9%d8%a7%d9%85%d9%86-%da%88%db%8c-%da%a9%db%8c-%d8%b2%db%8c%d8%a7%d8%af%d8%aa%db%8c-%d8%a8%da%be%db%8c-%d8%a8%d9%86-%d8%b3%da%a9%d8%aa%db%8c-%db%81%db%92-%d9%85%d9%88%d8%aa-%da%a9%d8%a7","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d9%88%d9%b9%d8%a7%d9%85%d9%86-%da%88%db%8c-%da%a9%db%8c-%d8%b2%db%8c%d8%a7%d8%af%d8%aa%db%8c-%d8%a8%da%be%db%8c-%d8%a8%d9%86-%d8%b3%da%a9%d8%aa%db%8c-%db%81%db%92-%d9%85%d9%88%d8%aa-%da%a9%d8%a7\/","title":{"rendered":"\u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0632\u06cc\u0627\u062f\u062a\u06cc \u0628\u06be\u06cc \u0628\u0646 \u0633\u06a9\u062a\u06cc \u06c1\u06d2 \u0645\u0648\u062a \u06a9\u0627 \u0633\u0628\u0628"},"content":{"rendered":"<p style=\"text-align: right;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-40954\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2015\/03\/vitamin-di-tablete.jpg\" alt=\"vitamin di tablete\" width=\"275\" height=\"183\" \/>\u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0632\u06cc\u0627\u062f\u062a\u06cc \u062f\u0644 \u06a9\u06d2 \u062f\u0648\u0631\u06d2 \u0627\u0648\u0631 \u0641\u0627\u0644\u062c \u06a9\u06d2 \u062e\u0637\u0631\u06d2 \u06a9\u0648 \u0628\u0691\u06be\u0627 \u062f\u06cc\u062a\u06cc \u06c1\u06d2\u06d4\u06a9\u0648\u067e\u0646 \u06c1\u06cc\u06af\u0646 \u06cc\u0648\u0646\u06cc\u0648\u0631\u0633\u0679\u06cc \u06a9\u06d2 \u0645\u062d\u0642\u0642\u06cc\u0646 \u0646\u06d2 \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0632\u06cc\u0627\u062f\u062a\u06cc \u0627\u0648\u0631 \u0642\u0644\u0628\u06cc \u0627\u0645\u0648\u0627\u062a \u06a9\u06cc \u0627\u0639\u0644\u06cc\u0670 \u0633\u0637\u062d \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062a\u0639\u0644\u0642 \u06a9\u06cc\u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u062e\u0628\u0631\u062f\u0627\u0631 \u06a9\u06cc\u0627 \u06c1\u06d2\u06d4\u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u0633\u0648\u0631\u062c \u06a9\u06cc \u0631\u0648\u0634\u0646\u06cc \u06a9\u06d2 \u0631\u062f\u0639\u0645\u0644 \u0645\u06cc\u06ba \u062c\u0644\u062f \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u0628\u0646\u062a\u0627 \u06c1\u06d2 \u062c\u0628\u06a9\u06c1 \u06cc\u06c1 \u062a\u06cc\u0644\u060c \u062f\u0648\u062f\u06be\u060c \u0627\u0646\u0688\u06d2\u060c \u0627\u0646\u0627\u062c \u0627\u0648\u0631 \u0633\u067e\u0644\u06cc\u0645\u0646\u0679\u0633 \u0645\u06cc\u06ba \u0628\u06be\u06cc \u0645\u0644\u062a\u0627 \u06c1\u06d2\u06d4 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc\u0644\u0634\u06cc\u0645 \u0627\u0648\u0631 \u0641\u0627\u0633\u0641\u06cc\u0679 \u06a9\u0648 \u06a9\u0646\u0679\u0631\u0648\u0644 \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u062f\u062f \u06a9\u0631\u062a\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u067e\u0679\u06be\u0648\u06ba \u0627\u0648\u0631 \u062f\u0627\u0646\u062a\u0648\u06ba \u06a9\u0648 \u0645\u0636\u0628\u0648\u0637 \u0628\u0646\u0627\u062a\u0627 \u06c1\u06d2\u06d4 \u0633\u0648\u0631\u062c \u06a9\u06cc \u0631\u0648\u0634\u0646\u06cc \u06a9\u06cc \u06a9\u0645\u06cc \u0633\u06d2 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06d2 \u06a9\u0645\u06cc \u06a9\u0648 \u0635\u062d\u062a \u06a9\u06d2 \u0627\u06c1\u0645 \u0645\u0633\u0627\u0626\u0644 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u062c\u0627\u0646\u0627 \u062c\u0627\u062a\u0627 \u06c1\u06d2 \u0644\u06cc\u06a9\u0646 \u0646\u0626\u06d2 \u0645\u0637\u0627\u0644\u0639\u06d2 \u0633\u06d2 \u0638\u0627\u06c1\u0631 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u06af\u0631\u0686\u06c1 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u06a9\u0645\u06cc \u0627\u0648\u0631 \u0645\u0648\u062a \u06a9\u06cc \u0634\u0631\u062d \u06a9\u0627 \u062a\u0639\u0644\u0642 \u0627\u0633\u06cc \u0637\u0631\u062d \u0645\u0648\u062c\u0648\u062f \u06c1\u06d2 \u062c\u0628\u06a9\u06c1 \u0646\u0626\u06cc \u0628\u0627\u062a \u06cc\u06c1 \u06c1\u06d2 \u06a9\u06c1 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0632\u06cc\u0627\u062f\u062a\u06cc \u06a9\u0627 \u0628\u06be\u06cc \u0645\u0648\u062a \u06a9\u06d2 \u062e\u0637\u0631\u06d2 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u062a\u0639\u0644\u0642 \u062a\u06be\u0627\u06d4 \u06cc\u06c1 \u062a\u062d\u0642\u06cc\u0642 &#8216;\u062c\u0631\u0646\u0644 \u0627\u0653\u0641 \u0627\u06cc\u0646\u0688\u0648 \u06a9\u0631\u06cc\u0646\u0648\u0644\u0648\u062c\u06cc \u0627\u06cc\u0646\u0688 \u0645\u06cc\u0679\u0627 \u0628\u0648\u0644\u0632\u0645&#8217; \u0645\u06cc\u06ba \u0634\u0627\u0626\u0639 \u06c1\u0648\u0626\u06cc \u06c1\u06d2 \u062c\u0633 \u0645\u06cc\u06ba \u062a\u062c\u0632\u06cc\u06c1 \u06a9\u0627\u0631\u0648\u06ba \u0646\u06d2 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0633\u0637\u062d \u06a9\u06cc \u067e\u06cc\u0645\u0627\u0626\u0634 \u06a9\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u06a9\u0645\u06cc \u0627\u0648\u0631 \u0632\u06cc\u0627\u062f\u062a\u06cc \u062f\u0648\u0646\u0648\u06ba \u06a9\u0648 \u0635\u062d\u062a \u06a9\u06d2 \u0644\u06cc\u06cc\u062e\u0637\u0631\u0646\u0627\u06a9 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0627 \u06c1\u06d2\u06d4\u0645\u0627\u06c1\u0631\u06cc\u0646 \u0646\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0632\u06cc\u0627\u062f\u062a\u06cc \u062f\u0644 \u06a9\u06cc \u0635\u062d\u062a \u06a9\u06d2 \u0644\u06cc\u06d2 \u062e\u0637\u0631\u0646\u0627\u06a9 \u06c1\u06d2 \u062c\u0628\u06a9\u06c1 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u06a9\u0645\u06cc \u06c1\u0688\u06cc\u0648\u06ba \u0645\u06cc\u06ba \u0633\u06d2 \u06a9\u06cc\u0644\u0634\u06cc\u0645 \u06a9\u0648 \u06c1\u0679\u0627 \u062f\u06cc\u062a\u06cc \u06c1\u06d2 \u062c\u0633 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u06c1\u0688\u06cc\u0627\u06ba \u06a9\u0645\u0632\u0648\u0631 \u06c1\u0648 \u0633\u06a9\u062a\u06cc \u06c1\u06cc\u06ba\u06d4\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u067e\u06cc\u0679\u0631 \u0634\u0648\u0627\u0631\u0632 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0627\u06af\u0631 \u0627\u0653\u067e \u06a9\u06d2 \u062e\u0648\u0646 \u0645\u06cc\u06ba \u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0633\u0637\u062d \u0632\u06cc\u0627\u062f\u06c1 \u06c1\u06d2 \u062a\u0648 \u0627\u0633 \u06a9\u0627 \u0627\u0653\u067e \u06a9\u06cc \u0635\u062d\u062a \u067e\u0631 \u0628\u0631\u0627 \u0627\u062b\u0631\u067e\u0691\u062a\u0627 \u06c1\u06d2 \u062e\u0627\u0635 \u0637\u0648\u0631 \u067e\u0631 \u062c\u0648 \u0644\u0648\u06af \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u06af\u0648\u0644\u06cc\u0648\u06ba \u06a9\u0627 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u0637\u0648\u06cc\u0644 \u0639\u0631\u0635\u06d2 \u062a\u06a9 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0646 \u06a9\u06d2 \u062c\u0633\u0645 \u0645\u06cc\u06ba \u06a9\u06cc\u0644\u0634\u06cc\u0645 \u06a9\u06cc \u0627\u0636\u0627\u0641\u06cc \u0645\u0642\u062f\u0627\u0631 \u062c\u0630\u0628 \u06c1\u0648\u0646\u06d2 \u06a9\u06cc \u0648\u062c\u06c1 \u0633\u06d2 \u06af\u0631\u062f\u0648\u06ba \u06a9\u0648 \u0646\u0642\u0635\u0627\u0646 \u067e\u06c1\u0646\u0686 \u0633\u06a9\u062a\u0627 \u06c1\u06d2\u06d4\u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u0645\u0632\u06cc\u062f \u06a9\u06c1\u0627 \u06a9\u06c1 &#8220;\u06c1\u0645 \u0646\u06d2 \u06f2\u06f4\u06f7\u0621\u06f5\u06f7\u06f4\u0688\u06cc\u0646\u06cc\u0634 \u0627\u0641\u0631\u0627\u062f \u0645\u06cc\u06ba \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0633\u0637\u062d \u06a9\u06cc \u067e\u06cc\u0645\u0627\u0626\u0634 \u06a9\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0628\u062a\u062f\u0627\u0626\u06cc \u062e<br \/>\n\u0648\u0646 \u06a9\u06d2 \u0646\u0645\u0648\u0646\u06d2 \u0644\u06cc\u0646\u06d2 \u06a9\u06d2 \u0628\u0639\u062f \u0633\u0627\u062a \u0633\u0627\u0644 \u06a9\u06d2 \u0639\u0631\u0635\u06d2 \u062a\u06a9 \u0627\u0646 \u0645\u06cc\u06ba \u0627\u0645\u0648\u0627\u062a \u06a9\u06cc \u0634\u0631\u062d \u06a9\u0627 \u062a\u062c\u0632\u06cc\u06c1 \u06a9\u06cc\u0627 \u06c1\u06d2\u060c \u0627\u0633 \u062f\u0648\u0631\u0627\u0646 \u0645\u062c\u0645\u0648\u0639\u06cc \u0637\u0648\u0631 \u067e\u0631 \u06f1\u06f6\u0621\u06f6\u06f4\u06f5\u060d \u0627\u0645\u0648\u0627\u062a \u06c1\u0648\u0626\u06cc\u06ba\u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u067e\u06cc\u0679\u0631 \u0634\u0648\u0627\u0631\u0632 \u0646\u06d2 \u0628\u062a\u0627\u06cc\u0627 \u06a9\u06c1 \u0627\u0646\u06be\u0648\u06ba \u0646\u06d2 \u0645\u0631\u06cc\u0636\u0648\u06ba \u06a9\u06cc \u0645\u0648\u062a \u06a9\u06cc \u0648\u062c\u0648\u06c1\u0627\u062a \u062c\u0627\u0646\u0646\u06d2 \u06a9\u06cc \u06a9\u0648\u0634\u0634 \u06a9\u06cc \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0646 \u06a9\u06cc \u0645\u0648\u062a \u0627\u0648\u0631 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0633\u0637\u062d \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062a\u0639\u0644\u0642 \u062f\u06cc\u06a9\u06be\u0627 \u06c1\u06d2\u06d4\u0645\u0632\u06cc\u062f \u0628\u0631\u0627\u0653\u06ba \u0646\u062a\u06cc\u062c\u06d2 \u0633\u06d2 \u0645\u0639\u0644\u0648\u0645 \u06c1\u0648\u0627 \u06a9\u06c1 \u062c\u0646 \u0645\u06cc\u06ba \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0633\u0637\u062d\u06f1\u06f0\u06f0 \u0646\u06cc\u0646\u0648 \u06af\u0631\u0627\u0645 \u0641\u06cc \u0644\u06cc\u0679\u0631 \u0633\u06d2 \u0627\u0648\u067e\u0631 \u062a\u06be\u06cc \u0627\u0646 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u0645\u0631\u0627\u0636 \u0642\u0644\u0628 \u0627\u0648\u0631 \u0641\u0627\u0644\u062c \u06a9\u0627 \u062e\u0637\u0631\u06c1 \u0628\u0691\u06be\u0627 \u06c1\u0648\u0627 \u062a\u06be\u0627\u06d4\u0628\u0642\u0648\u0644 \u067e\u0631\u0648\u0641\u06cc\u0633\u0631 \u067e\u06cc\u0679\u0631 \u0634\u0648\u0627\u0631\u0632 \u0627\u06af\u0631 \u0627\u0653\u067e \u06a9\u0627 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06f5\u06f0\u0633\u06d2 \u06a9\u0645 \u0627\u0648\u0631\u06f1\u06f0\u06f0 \u0646\u06cc\u0646\u0648 \u06af\u0631\u0627\u0645 \u0641\u06cc \u0644\u06cc\u0679\u0631 \u06c1\u06d2 \u062a\u0648 \u0627\u0633 \u0633\u06d2 \u0645\u0648\u062a \u06a9\u0627 \u0628\u0691\u0627 \u062e\u0637\u0631\u06c1 \u062c\u0691\u0627 \u06c1\u0648\u0627 \u06c1\u06d2\u06d4\u062c\u0628\u06a9\u06c1 \u062f\u0648\u0633\u0631\u06d2 \u0644\u0641\u0638\u0648\u06ba \u0645\u06cc\u06ba \u06a9\u06c1\u0627 \u062c\u0627\u0633\u06a9\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0633\u0637\u062d \u0628\u06c1\u062a \u06a9\u0645 \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u0646\u06cc \u0686\u0627\u06c1\u06cc\u0626\u06d2 \u0627\u0648\u0631 \u0646\u0627 \u06c1\u06cc \u0627\u0633 \u06a9\u06cc \u062e\u0648\u0646 \u0645\u06cc\u06ba \u0633\u0637\u062d \u0628\u0644\u0646\u062f \u06c1\u0648\u0646\u06cc \u0686\u0627\u06c1\u06cc\u0626\u06d2 \u0628\u0644\u06a9\u06c1 \u0627\u0633 \u06a9\u06cc \u0633\u0637\u062d \u06f5\u06f0\u060d\u0627\u0648\u0631 \u06f1\u06f0\u06f0 \u0646\u06cc\u0646\u0648\u06af\u0631\u0627\u0645 \u0641\u06cc \u0644\u06cc\u0679\u0631 \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u06c1\u0648\u0646\u06cc \u0686\u0627\u06c1\u06cc\u0626\u06d2\u06d4\u062a\u062d\u0642\u06cc\u0642 \u0633\u06d2 \u0638\u0627\u06c1\u0631 \u06c1\u0648\u0627 \u06c1\u06d2 \u06a9\u06c1\u06f7\u06f0\u0646\u06cc\u0646\u0648 \u06af\u0631\u0627\u0645 \u0641\u06cc \u0644\u06cc\u0679\u0631 \u0633\u0628 \u0633\u06d2 \u0628\u06c1\u062a\u0631 \u0633\u0637\u062d \u06a9\u06cc \u062f\u0644\u06cc\u0644 \u06c1\u06d2\u06d4\u0645\u062d\u0642\u0642\u06cc\u0646 \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0645\u0637\u0627\u0644\u0639\u06c1 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0627\u0633 \u0644\u062d\u0627\u0638 \u0633\u06d2 \u0628\u06c1\u062a \u0627\u06c1\u0645 \u06c1\u06d2 \u06a9\u06cc\u0648\u06ba \u06a9\u06c1 \u0644\u0648\u06af\u0648\u06ba \u0645\u06cc\u06ba \u0648\u0679\u0627\u0645\u0646 \u06a9\u06cc\u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0628\u0691\u06cc \u062f\u0644\u0686\u0633\u067e\u06cc \u067e\u0627\u0626\u06cc \u062c\u0627\u062a\u06cc \u06c1\u06d2 \u062c\u0648 \u0627\u0633 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u06a9\u0648 \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u0627\u0633 \u0628\u0627\u062a \u06a9\u0627 \u062e\u0648\u062f \u0641\u06cc\u0635\u0644\u06c1 \u06a9\u0631 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba \u06a9\u06c1 \u0627\u0646\u06be\u06cc\u06ba \u0648\u0679\u0627\u0645\u0646\u0632 \u0645\u0679\u06be\u0627\u0626\u06cc \u06a9\u06cc \u0637\u0631\u062d \u06a9\u06be\u0627\u062a\u06d2 \u0631\u06c1\u0646\u0627 \u0686\u0627\u06c1\u06cc\u0626\u06d2 \u06cc\u0627 \u067e\u06be\u0631 \u0627\u0633\u06d2 \u0686\u06be\u0648\u0691\u0646\u0627 \u06c1\u06d2\u06d4\u0627\u0644\u0628\u062a\u06c1 \u0628\u06c1\u062a\u0631 \u0645\u062d\u0633\u0648\u0633 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u0633\u067e\u0644\u06cc\u0645\u0646\u0679\u0633 \u0627\u067e\u0646\u06d2 \u0645\u0639\u0627\u0644\u062c \u06a9\u06d2 \u0645\u0634\u0648\u0631\u06d2 \u0633\u06d2 \u06c1\u06cc \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u06a9\u0631\u0646\u06cc \u0686\u0627\u06c1\u06cc\u0626\u06d2\u06d4<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0627\u06c1\u0631\u06cc\u0646 \u06a9\u0627 \u06a9\u06c1\u0646\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0632\u06cc\u0627\u062f\u062a\u06cc \u062f\u0644 \u06a9\u06d2 \u062f\u0648\u0631\u06d2 \u0627\u0648\u0631 \u0641\u0627\u0644\u062c \u06a9\u06d2 \u062e\u0637\u0631\u06d2 \u06a9\u0648 \u0628\u0691\u06be\u0627 \u062f\u06cc\u062a\u06cc \u06c1\u06d2\u06d4\u06a9\u0648\u067e\u0646 \u06c1\u06cc\u06af\u0646 \u06cc\u0648\u0646\u06cc\u0648\u0631\u0633\u0679\u06cc \u06a9\u06d2 \u0645\u062d\u0642\u0642\u06cc\u0646 \u0646\u06d2 \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u06a9\u06cc \u0632\u06cc\u0627\u062f\u062a\u06cc \u0627\u0648\u0631 \u0642\u0644\u0628\u06cc \u0627\u0645\u0648\u0627\u062a \u06a9\u06cc \u0627\u0639\u0644\u06cc\u0670 \u0633\u0637\u062d \u06a9\u06d2 \u062f\u0631\u0645\u06cc\u0627\u0646 \u062a\u0639\u0644\u0642 \u06a9\u06cc\u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u062e\u0628\u0631\u062f\u0627\u0631 \u06a9\u06cc\u0627 \u06c1\u06d2\u06d4\u0648\u0679\u0627\u0645\u0646 \u0688\u06cc \u0633\u0648\u0631\u062c \u06a9\u06cc \u0631\u0648\u0634\u0646\u06cc \u06a9\u06d2 \u0631\u062f\u0639\u0645\u0644 \u0645\u06cc\u06ba \u062c\u0644\u062f \u06a9\u06d2 \u0627\u0646\u062f\u0631 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45,44],"tags":[],"class_list":["post-40953","post","type-post","status-publish","format-standard","category-health","category-health-news"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/40953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=40953"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/40953\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=40953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=40953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=40953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}