{"id":9724,"date":"2014-02-18T16:52:33","date_gmt":"2014-02-18T11:22:33","guid":{"rendered":"http:\/\/dailyaag.com\/phase2\/?p=9724"},"modified":"2014-02-18T16:52:33","modified_gmt":"2014-02-18T11:22:33","slug":"%d8%a7%d8%b3-%d8%b3%db%92-%d9%be%db%81%d9%84%db%92-%d8%a2%d9%be-%d9%86%db%92-%da%a9%d8%a8%da%be%db%8c-%d9%86%db%81%db%8c%da%ba-%d8%af%db%8c%da%a9%da%be%d8%a7-%db%81%d9%88%da%af%d8%a7-%d8%b1%db%8c","status":"publish","type":"post","link":"https:\/\/dailyaag.com\/phase2\/%d8%a7%d8%b3-%d8%b3%db%92-%d9%be%db%81%d9%84%db%92-%d8%a2%d9%be-%d9%86%db%92-%da%a9%d8%a8%da%be%db%8c-%d9%86%db%81%db%8c%da%ba-%d8%af%db%8c%da%a9%da%be%d8%a7-%db%81%d9%88%da%af%d8%a7-%d8%b1%db%8c\/","title":{"rendered":"\u0627\u0633 \u0633\u06d2 \u067e\u06c1\u0644\u06d2 \u0622\u067e \u0646\u06d2 \u06a9\u0628\u06be\u06cc \u0646\u06c1\u06cc\u06ba \u062f\u06cc\u06a9\u06be\u0627 \u06c1\u0648\u06af\u0627 \u0631\u06cc\u06a9\u06be\u0627 \u06a9\u0627 \u06cc\u06c1 \u0631\u0648\u067e"},"content":{"rendered":"<p style=\"text-align: right;\">\u0645\u0645\u0628\u0626\u06cc . \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba \u0646\u06c1 \u06a9\u06c1 \u0639\u0645\u0631 \u0686\u06be\u067e\u0627\u0626\u06d2 \u0646\u06c1\u06cc\u06ba \u0686\u06be\u067e\u062a\u064a . \u06c1\u0645\u06cc\u0634\u06c1 \u06c1\u06cc \u06af\u062c\u0631\u0627 \u060c \u0644\u0627\u0644\u06cc \u060c \u0643\u0627\u0646\u062c\u064a\u0648\u0631\u0645 \u0633\u0627\u0691\u06cc \u0627\u0648\u0631 \u0632\u06cc\u0648\u0631\u0627\u062a \u0633\u06d2 \u0622\u0631\u0627\u0633\u062a\u06c1 \u0631\u06c1\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0631\u06cc\u06a9\u06be\u0627 \u06a9\u0648 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u06a9\u06cc\u0627 \u0622\u067e \u0627\u0646 \u06a9\u06cc \u0639\u0645\u0631 \u06a9\u0627 \u0627\u0646\u062f\u0627\u0632\u06c1 \u0644\u06af\u0627 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba \u061f \u0631\u06cc\u06a9\u06be\u0627 \u0628\u0627\u0644\u06cc \u0648\u0648\u0688 \u06a9\u06cc \u0627\u06cc\u06a9 \u0627\u06cc\u0633\u06cc \u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u06c1\u06cc\u06ba \u062c\u0648 \u0639\u0645\u0631 \u06a9\u06d2 \u0627\u0633 \u067e\u0691\u0627\u0648 \u0645\u06cc\u06ba \u0628\u06be\u06cc \u0627\u062a\u0646\u06cc \u06c1\u06cc \u062e\u0648\u0628\u0635\u0648\u0631\u062a \u0644\u06af\u062a\u06cc \u06c1\u06cc\u06ba . \u0644\u06cc\u06a9\u0646 \u0644\u0627\u0626\u0646 \u06a9\u06cc \u062d\u0627\u0644 \u06c1\u06cc \u0645\u06cc\u06ba \u0627\u0626\u06cc \u0627\u06cc\u06a9 \u062a\u0635\u0648\u06cc\u0631 \u0646\u06d2 \u0627\u0646 \u06a9\u06cc \u0628\u0691\u06be\u062a\u06cc \u06c1\u0648\u0626\u06cc \u0639\u0645\u0631 \u06a9\u06cc \u062c\u06be\u0644\u06a9 \u0627\u0646 \u06a9\u06d2 \u0686\u06c1\u0631\u06d2 \u067e\u0631 \u062f\u06a9\u06be\u0627 \u062f\u06cc <a href=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/02\/rekha.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9725\" alt=\"rekha\" src=\"http:\/\/dailyaag.com\/phase2\/wp-content\/uploads\/2014\/02\/rekha.jpg\" width=\"645\" height=\"340\" \/><\/a>.<\/p>\n<p style=\"text-align: right;\">\u0627\u0645\u062a\u06cc\u0627\u0632 \u0639\u0644\u06cc \u06a9\u06cc \u0641\u0644\u0645 \u06c1\u0627\u0626\u06cc \u0648\u06d2 \u06a9\u06cc \u0627\u0633\u067e\u06cc\u0634\u0644 \u0627\u0633\u06a9\u0631\u06cc\u0646\u0646\u06af \u0645\u06cc\u06ba \u0634\u0627\u0645\u0644 \u06c1\u0648\u0626\u06cc \u0631\u06cc\u06a9\u06be\u0627 \u0627\u06cc\u0633\u06d2 \u0627\u0648\u062a\u0627\u0631 \u0645\u06cc\u06ba \u0646\u0638\u0631 \u0622\u0626\u06cc \u060c \u062c\u0648 \u0622\u067e \u0646\u06d2 \u067e\u06c1\u0644\u06d2 \u0646\u06c1\u06cc\u06ba \u062f\u06cc\u06a9\u06be\u0627 \u06c1\u0648\u06af\u0627 . \u06c1\u0645\u06cc\u0634\u06c1 \u0633\u062c &#8211; \u062f\u06be\u062c \u06a9\u06d2 \u06a9\u06cc\u0645\u0631\u06d2 \u06a9\u06d2 \u0633\u0627\u0645\u0646\u06d2 \u0622\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0644\u0627\u0626\u0646 \u0628\u063a\u06cc\u0631 \u0645\u06cc\u06a9 \u0627\u067e \u06a9\u06d2 \u0627\u0644\u06af \u06c1\u06cc \u062f\u06a9\u06be \u0631\u06c1\u06cc \u062a\u06be\u06cc . \u0627\u0646 \u06a9\u06d2 \u0686\u06c1\u0631\u06d2 \u067e\u0631 \u0627\u0646 \u06a9\u06cc \u0639\u0645\u0631 \u06a9\u0627 \u0627\u062b\u0631 \u0635\u0627\u0641 \u062f\u06a9\u06be\u0627\u0626\u06cc \u062f\u06d2 \u0631\u06c1\u0627 \u06c1\u06d2 . \u0631\u06cc\u06a9\u06be\u0627 \u0627\u0633\u06a9\u0631\u06cc\u0646\u0646\u06af \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0633\u0641\u06cc\u062f \u0631\u0646\u06af \u06a9\u06d2 \u06a9\u0631\u062a\u06d2 \u067e\u06d2\u062c\u0627\u0645\u06d2 \u0645\u06cc\u06ba \u0646\u0638\u0631 \u0622\u0626\u06cc\u06ba .<br \/>\n\u067e\u0691\u06be\u06cc\u06ba : \u0628\u06af \u0628\u06cc \u06cc\u06c1 \u06a9\u06cc\u0627 \u06a9\u0631 \u062f\u06cc\u0627 \u061f<br \/>\n\u0648\u06cc\u0633\u06d2 \u0631\u06cc\u06a9\u06be\u0627 \u06a9\u06cc \u0627\u067e\u0646\u06cc \u06c1\u06cc \u0627\u06cc\u06a9 \u0627\u062f\u0627 \u06c1\u06d2 . \u0648\u06c1 \u062c\u06cc\u0633\u06cc \u0628\u06be\u06cc \u0646\u0638\u0631 \u0622\u0626\u06d2 \u0627\u0648\u0631 \u062c\u0648 \u0628\u06be\u06cc \u067e\u06c1\u0646\u06d2 \u0627\u0646 \u06af\u0631\u06cc\u0633 \u06a9\u0628\u06be\u06cc \u06a9\u0645 \u0646\u06c1\u06cc\u06ba \u06c1\u0648\u062a\u0627 \u06c1\u06d2 .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0645\u0628\u0626\u06cc . \u06a9\u06c1\u062a\u06d2 \u06c1\u06cc\u06ba \u0646\u06c1 \u06a9\u06c1 \u0639\u0645\u0631 \u0686\u06be\u067e\u0627\u0626\u06d2 \u0646\u06c1\u06cc\u06ba \u0686\u06be\u067e\u062a\u064a . \u06c1\u0645\u06cc\u0634\u06c1 \u06c1\u06cc \u06af\u062c\u0631\u0627 \u060c \u0644\u0627\u0644\u06cc \u060c \u0643\u0627\u0646\u062c\u064a\u0648\u0631\u0645 \u0633\u0627\u0691\u06cc \u0627\u0648\u0631 \u0632\u06cc\u0648\u0631\u0627\u062a \u0633\u06d2 \u0622\u0631\u0627\u0633\u062a\u06c1 \u0631\u06c1\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0631\u06cc\u06a9\u06be\u0627 \u06a9\u0648 \u062f\u06cc\u06a9\u06be \u06a9\u0631 \u06a9\u06cc\u0627 \u0622\u067e \u0627\u0646 \u06a9\u06cc \u0639\u0645\u0631 \u06a9\u0627 \u0627\u0646\u062f\u0627\u0632\u06c1 \u0644\u06af\u0627 \u0633\u06a9\u062a\u06d2 \u06c1\u06cc\u06ba \u061f \u0631\u06cc\u06a9\u06be\u0627 \u0628\u0627\u0644\u06cc \u0648\u0648\u0688 \u06a9\u06cc \u0627\u06cc\u06a9 \u0627\u06cc\u0633\u06cc \u0627\u062f\u0627\u06a9\u0627\u0631\u06c1 \u06c1\u06cc\u06ba \u062c\u0648 \u0639\u0645\u0631 \u06a9\u06d2 \u0627\u0633 \u067e\u0691\u0627\u0648 \u0645\u06cc\u06ba \u0628\u06be\u06cc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,46,32],"tags":[],"class_list":["post-9724","post","type-post","status-publish","format-standard","category-entertainment","category-highlighted-news","category-film"],"_links":{"self":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/9724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/comments?post=9724"}],"version-history":[{"count":0,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/posts\/9724\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/media?parent=9724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/categories?post=9724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailyaag.com\/phase2\/wp-json\/wp\/v2\/tags?post=9724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}